{"id":1148271,"date":"2023-01-26T14:00:00","date_gmt":"2023-01-26T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1148271"},"modified":"2023-01-09T15:38:13","modified_gmt":"2023-01-09T18:38:13","slug":"plano-contas-rfb","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/","title":{"rendered":"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB"},"content":{"rendered":"\n<p>Ol\u00e1, amigos, tudo bem? Neste artigo aprenderemos um pouco acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP), com foco no concurso da <a href=\"https:\/\/www.gov.br\/receitafederal\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\">Receita Federal do Brasil (RFB)<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal-1024x536.jpg\" alt=\"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB\" class=\"wp-image-698463\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal-1024x536.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal-300x157.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal-768x402.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal-610x319.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB<\/figcaption><\/figure>\n\n\n\n<p>Primeiramente, devemos lembrar que o novo concurso da RFB teve seu edital publicado no m\u00eas de dezembro de 2022.<\/p>\n\n\n\n<p>As provas (objetiva e discursiva), por sua vez, est\u00e3o previstas para mar\u00e7o de 2023.<\/p>\n\n\n\n<p>Al\u00e9m disso, o edital ofertou 230 vagas para o cargo de Auditor-Fiscal e 469 vagas para o cargo de Analista-Tribut\u00e1rio.<\/p>\n\n\n\n<p>Quanto ao tema deste artigo, o conte\u00fado program\u00e1tico da disciplina de Contabilidade Aplicada ao Setor P\u00fablico (CASP) exige, expressamente, dos candidatos concorrentes para o cargo de Auditor-Fiscal, conhecimento acerca do PCASP.<\/p>\n\n\n\n<p>Por esse motivo, apresentaremos, a seguir, de forma resumida, os principais t\u00f3picos acerca dessa mat\u00e9ria.<\/p>\n\n\n\n<p>Vamos iniciar, portanto, o nosso estudo sobre o PCASP?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-e-o-plano-de-contas-aplicado-ao-setor-publico\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">O que \u00e9 o Plano de Contas Aplicado ao Setor P\u00fablico?<\/mark><\/strong><\/h2>\n\n\n\n<p>Em linhas gerais, os planos de contas consistem em um conjunto padronizado de contas cont\u00e1beis.<\/p>\n\n\n\n<p>A t\u00edtulo de exemplo, podemos imaginar como seria complicado entender as demonstra\u00e7\u00f5es cont\u00e1beis de uma companhia caso a cada novo per\u00edodo de reporte ela alterasse completamente as nomenclaturas das contas cont\u00e1beis, certo?<\/p>\n\n\n\n<p>Nesse mesmo contexto, imagine a dificuldade para consolidar informa\u00e7\u00f5es cont\u00e1beis entre empresas controladoras e controladas, caso cada uma adote um padr\u00e3o diferente para os seus registros.<\/p>\n\n\n\n<p>Portanto, o principal objetivo dos planos de contas consiste em padronizar os registros cont\u00e1beis, de forma que todos aqueles que adotarem um mesmo plano de contas \u201cfalem a mesma l\u00edngua\u201d.<\/p>\n\n\n\n<p>Assim, no contexto da contabilidade p\u00fablica, essa din\u00e2mica ocorre de forma similar. Ora, como seria poss\u00edvel, por exemplo, realizar a consolida\u00e7\u00e3o cont\u00e1bil nacional (de todos os entes federativos \u2013 Uni\u00e3o, Estados, DF e Munic\u00edpios) se cada um deles elaborasse demonstra\u00e7\u00f5es cont\u00e1beis conforme uma sistem\u00e1tica diferente?<\/p>\n\n\n\n<p>Nesse sentido, vale ressaltar que mesmo que todos os entes observem as normas t\u00e9cnicas de contabilidade, ainda faz-se necess\u00e1ria uma padroniza\u00e7\u00e3o de nomenclaturas e codifica\u00e7\u00f5es, a fim de possibilitar a sistematiza\u00e7\u00e3o dos registros cont\u00e1beis.<\/p>\n\n\n\n<p>Dessa forma, a Secretaria do Tesouro Nacional (STN) elaborou um Plano de Contas Aplicado ao Setor P\u00fablico (PCASP).<\/p>\n\n\n\n<p>Conforme o MCASP (9\u00aa ed.), o PCASP consiste na estrutura b\u00e1sica da escritura\u00e7\u00e3o cont\u00e1bil e permite os registros cont\u00e1beis de forma padronizada e sistematizada.<\/p>\n\n\n\n<p>Assim, esse Plano de Contas possibilita a elabora\u00e7\u00e3o das demonstra\u00e7\u00f5es cont\u00e1beis e demais relat\u00f3rios de forma muito mais f\u00e1cil e automatizada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Objetivos do Plano de Contas Aplicado ao Setor P\u00fablico<\/mark><\/strong><\/h2>\n\n\n\n<p>Conforme aprendemos anteriormente, o principal objetivo do PCASP consiste na padroniza\u00e7\u00e3o dos lan\u00e7amentos cont\u00e1beis. Dessa forma, torna-se mais f\u00e1cil a apresenta\u00e7\u00e3o e a elabora\u00e7\u00e3o das demonstra\u00e7\u00f5es, bem como a sua interpreta\u00e7\u00e3o pelos usu\u00e1rios.<\/p>\n\n\n\n<p>Todavia, o MCASP (9\u00aa ed.) cita outros objetivos diretamente relacionados \u00e0 elabora\u00e7\u00e3o do Plano de Contas Aplicado ao Setor P\u00fablico.<\/p>\n\n\n\n<p>Assim, haja vista a import\u00e2ncia desse assunto para a prova de RFB, cita-se os principais objetivos descritos no manual, acerca do referido Plano de Contas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Proporcionar a padroniza\u00e7\u00e3o dos registros\/demonstra\u00e7\u00f5es cont\u00e1beis;<\/li><li>Distinguir as contas de natureza patrimonial, or\u00e7ament\u00e1ria e de controle (conforme estudaremos a seguir);<\/li><li>Observar as necessidades de todos os entes federativos (sem desconsiderar as suas respectivas peculiaridades). Nesse sentido, cada ente federativo pode, inclusive, desdobrar as contas cont\u00e1beis criadas pela STN (observada a m\u00ednima padroniza\u00e7\u00e3o obrigat\u00f3ria) a fim de atender \u00e0s suas necessidades;<\/li><li>Proporcionar meios para a consolida\u00e7\u00e3o nacional das contas;<\/li><li>Possibilitar a presta\u00e7\u00e3o de contas e a elabora\u00e7\u00e3o de demonstrativos e relat\u00f3rios acerca do setor p\u00fablico;<\/li><li>Contribuir para a tomada de decis\u00e3o, bem como para a transpar\u00eancia e o controle social.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Alcance do Plano de Contas Aplicado ao Setor P\u00fablico<\/mark><\/strong><\/h2>\n\n\n\n<p>Pessoal, para o novo concurso da RFB devemos ficar atentos quanto a uma poss\u00edvel \u201cpegadinha\u201d envolvendo o alcance do Plano de Contas Aplicado ao Setor P\u00fablico.<\/p>\n\n\n\n<p>Em regra, o PCASP consiste em um plano de contas de utiliza\u00e7\u00e3o obrigat\u00f3ria em \u00e2mbito dos \u00f3rg\u00e3os da administra\u00e7\u00e3o direta.<\/p>\n\n\n\n<p>Todavia, quanto \u00e0s entidades da administra\u00e7\u00e3o indireta, o MCASP esclarece que a sua utiliza\u00e7\u00e3o obrigat\u00f3ria se restringe \u00e0s autarquias, funda\u00e7\u00f5es, fundos e empresas estatais dependentes.<\/p>\n\n\n\n<p>Nesse sentido, vale rememorar as disposi\u00e7\u00f5es da Lei de Responsabilidade Fiscal (LRF) acerca das estatais dependentes.<\/p>\n\n\n\n<p>Conforme a legisla\u00e7\u00e3o, consistem em estatais dependentes aquelas que, al\u00e9m de controladas pelo poder p\u00fablico, recebem dele recursos financeiros para o atendimento de despesas com pessoal, de custeio em geral ou de capital (exclu\u00eddos os aumentos de participa\u00e7\u00e3o acion\u00e1ria).<\/p>\n\n\n\n<p>Portanto, para o concurso da RFB, devemos saber que, para as empresas estatais independentes, o MCASP deixa claro que a utiliza\u00e7\u00e3o do Plano de Contas Aplicado ao Setor P\u00fablico \u00e9 facultativa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Natureza da informa\u00e7\u00e3o cont\u00e1bil no Plano de Contas Aplicado ao Setor P\u00fablico<\/mark><\/strong><\/h2>\n\n\n\n<p>Talvez o aspecto mais importante acerca do Plano de Contas do Setor P\u00fablico para o concurso da RFB seja conhecer as naturezas das informa\u00e7\u00f5es cont\u00e1beis. Por isso, dedicaremos alguns par\u00e1grafos deste artigo para discorrer acerca deste t\u00f3pico.<\/p>\n\n\n\n<p>Primeiramente, vale esclarecer que o PCASP se estrutura, atualmente, em tr\u00eas naturezas de informa\u00e7\u00f5es cont\u00e1beis, a saber:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">PATRIMONIAL:<\/mark><\/strong> consiste no registro das contas cont\u00e1beis que evidenciam fatos financeiros e n\u00e3o financeiros relativos ao patrim\u00f4nio p\u00fablico (varia\u00e7\u00f5es quantitativas e qualitativas).<\/li><li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">OR\u00c7AMENT\u00c1RIA:<\/mark><\/strong> por sua vez, registra as informa\u00e7\u00f5es relativas ao planejamento or\u00e7ament\u00e1rio e \u00e0 sua execu\u00e7\u00e3o.<\/li><li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">CONTROLE:<\/mark><\/strong> consiste nos registros de fatos que possam vir a modificar o patrim\u00f4nio p\u00fablico, bem como as informa\u00e7\u00f5es tipicamente relacionadas ao controle.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Codifica\u00e7\u00e3o do Plano de Contas Aplicado ao Setor P\u00fablico<\/mark><\/strong><\/h2>\n\n\n\n<p>Conforme aprendemos anteriormente, um dos objetivos do PCASP consiste na padroniza\u00e7\u00e3o dos lan\u00e7amentos cont\u00e1beis. Para isso, utiliza-se uma codifica\u00e7\u00e3o num\u00e9rica a fim, inclusive, de possibilitar a sua automatiza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Assim, as contas cont\u00e1beis, no PCASP, possuem 9 d\u00edgitos, desdobrados em 7 n\u00edveis, conforme detalhado a seguir:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1\u00b0 N\u00edvel (1 d\u00edgito): Classe.<\/li><li>2\u00b0 N\u00edvel (1 d\u00edgito): Grupo.<\/li><li>3\u00ba N\u00edvel (1 d\u00edgito): Subgrupo.<\/li><li>4\u00ba N\u00edvel (1 d\u00edgito): T\u00edtulo.<\/li><li>5\u00ba N\u00edvel (1 d\u00edgito): Subt\u00edtulo.<\/li><li>6\u00ba N\u00edvel (2 d\u00edgitos): Item.<\/li><li>7\u00ba N\u00edvel (2 d\u00edgitos): Subitem.<\/li><\/ul>\n\n\n\n<p>Quanto \u00e0 codifica\u00e7\u00e3o das contas cont\u00e1beis, o principal aspecto exigido pelas bancas examinadoras refere-se ao enquadramento das classes de contas conforme a natureza da informa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Portanto, para o concurso da RFB, devemos saber que o Plano de Contas Aplicado ao Setor P\u00fablico estabelece que existem 8 classes de contas. Assim, integram a natureza de informa\u00e7\u00e3o patrimonial as contas de classe 1 a 4. Al\u00e9m disso, comp\u00f5em a natureza de informa\u00e7\u00e3o or\u00e7ament\u00e1ria as classes 5 a 6, enquanto a natureza de controle \u00e9 representada pelas classes 7 a 8.<\/p>\n\n\n\n<p>Ademais, deve-se conhecer tamb\u00e9m as nomenclaturas aplicadas \u00e0s classes de contas, bem como a sua natureza quanto ao aspecto credor ou devedor.<\/p>\n\n\n\n<p>Assim, o aluno deve decorar a seguinte rela\u00e7\u00e3o referente \u00e0s classes de contas do PCASP:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1 \u2013 Ativo (natureza devedora);<\/li><li>2 \u2013 Passivo (natureza credora);<\/li><li>3 \u2013 Varia\u00e7\u00f5es patrimoniais diminutivas (natureza devedora);<\/li><li>4 \u2013 Varia\u00e7\u00f5es patrimoniais aumentativas (natureza credora);<\/li><li>5 \u2013 Controles da aprova\u00e7\u00e3o do planejamento e or\u00e7amento (natureza devedora);<\/li><li>6 \u2013 Controles da execu\u00e7\u00e3o do planejamento e or\u00e7amento (natureza credora);<\/li><li>7 \u2013 Controles devedores (natureza devedora);<\/li><li>8 \u2013 Controles credores (natureza credora).<\/li><\/ul>\n\n\n\n<p>Nesse sentido, para facilitar o entendimento, a tabela seguinte ilustra o enquadramento das classes de contas de acordo com a sua natureza de informa\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"216\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/05010200\/pcasp-classes-de-contas.jpg\" alt=\"Classes de contas do Plano de Contas do Setor P\u00fablico para a RFB.\" class=\"wp-image-1039746\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/05010200\/pcasp-classes-de-contas.jpg 708w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/05010200\/pcasp-classes-de-contas-300x92.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/05010200\/pcasp-classes-de-contas-610x186.jpg 610w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><figcaption>Classes de contas do PCASP <br \/>Fonte: MCASP (9\u00aa ed.)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Consolida\u00e7\u00e3o das contas cont\u00e1beis<\/mark><\/strong><\/h2>\n\n\n\n<p>Outro objetivo muito importante do Plano de Contas Aplicado ao Setor P\u00fablico (j\u00e1 citado anteriormente) refere-se \u00e0 consolida\u00e7\u00e3o das contas p\u00fablicas.<\/p>\n\n\n\n<p>Nesse sentido, o 5\u00ba n\u00edvel (subt\u00edtulo) das contas de natureza patrimonial (1 a 4) do PCASP exerce significativo papel para atendimento deste objetivo.<\/p>\n\n\n\n<p>Conforme o MCASP (9\u00aa ed.), o subt\u00edtulo consiste no mecanismo de segrega\u00e7\u00e3o inclu\u00eddo na codifica\u00e7\u00e3o do PCASP para identificar as transa\u00e7\u00f5es que devem ou n\u00e3o constar da consolida\u00e7\u00e3o.<\/p>\n\n\n\n<p>Sobre isso, o principal aspecto a ser observado para o concurso da RFB, acerca do Plano de Contas, para fins de consolida\u00e7\u00e3o, refere-se \u00e0 codifica\u00e7\u00e3o do subt\u00edtulo.<\/p>\n\n\n\n<p>Portanto, devemos decorar os seguintes subt\u00edtulos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1 (x.x.x.x.1.xx.xx): <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">CONSOLIDA\u00c7\u00c3O<\/mark><\/strong> \u2013 refere-se aos saldos das contas que devem ser constar nos demonstrativos consolidados do or\u00e7amento fiscal e da seguridade social (OFSS);<\/li><li>2 (x.x.x.x.2.xx.xx): <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">INTRA OFSS<\/mark><\/strong> \u2013 saldos exclu\u00eddos da consolida\u00e7\u00e3o do OFSS do mesmo ente p\u00fablico.<\/li><li>3 (x.x.x.x.3.xx.xx): <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">INTER OFSS (UNI\u00c3O)<\/mark><\/strong> \u2013 saldos exclu\u00eddos da consolida\u00e7\u00e3o do OFSS de entes p\u00fablicos distintos (referentes a transa\u00e7\u00f5es entre o ente p\u00fablico e a Uni\u00e3o).<\/li><li>4 (x.x.x.x.4.xx.xx): <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">INTER OFSS (ESTADO)<\/mark><\/strong> \u2013 saldos exclu\u00eddos da consolida\u00e7\u00e3o do OFSS de entes p\u00fablicos distintos (referentes a transa\u00e7\u00f5es entre o ente p\u00fablico e um Estado).<\/li><li>5 (x.x.x.x.5.xx.xx): <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">INTER OFSS (MUNIC\u00cdPIO)<\/mark><\/strong> \u2013 saldos exclu\u00eddos da consolida\u00e7\u00e3o do OFSS de entes p\u00fablicos distintos (referentes a transa\u00e7\u00f5es entre o ente p\u00fablico e um Munic\u00edpio).<\/li><\/ul>\n\n\n\n<p>Dessa forma, para efeitos de consolida\u00e7\u00e3o nacional, inclui-se apenas as contas de subt\u00edtulo 1.<\/p>\n\n\n\n<p>Por outro lado, no caso de consolida\u00e7\u00f5es realizadas em \u00e2mbito de entes p\u00fablicos, inclui-se as contas de subt\u00edtulos 1, 3, 4 e 5, excluindo-se apenas a de subt\u00edtulo 2.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Regras de Integridade do Plano de Contas Aplicado ao Setor P\u00fablico<\/mark><\/strong><\/h2>\n\n\n\n<p>Por fim, para o concurso da RFB, vale citar que o MCASP (9\u00aa ed.) disp\u00f5e acerca da exist\u00eancia de quatro regras de integridade relativas ao Plano de Contas Aplicado ao Setor P\u00fablico.<\/p>\n\n\n\n<p>Nesse sentido, a regra dos <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">LAN\u00c7AMENTOS CONT\u00c1BEIS<\/mark><\/strong> indica que os registros cont\u00e1beis devem observar o m\u00e9todo das partidas dobradas para cada natureza de informa\u00e7\u00e3o. Por exemplo, n\u00e3o pode haver lan\u00e7amento a d\u00e9bito em conta da classe 1 (ativo) em contrapartida de cr\u00e9dito em conta de natureza 8 (controles credores). Sobre isso, devemos observar que a classe 1 refere-se \u00e0 natureza patrimonial da informa\u00e7\u00e3o, enquanto a classe 8 \u00e0 natureza de controle.<\/p>\n\n\n\n<p>Por outro lado, a regra dos <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">PAGAMENTOS E RECEBIMENTOS<\/mark> <\/strong>indica que as contas com atributo permanente (P) somente podem sofrer movimenta\u00e7\u00e3o em face de conta de VPA, conta de VPD ou de conta com atributo financeiro (F) para reclassifica\u00e7\u00e3o do ativo\/passivo ou para troca de atributo.<\/p>\n\n\n\n<p>Ademais, a regra do <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">DESENVOLVIMENTO DE EQUA\u00c7\u00d5ES CONT\u00c1BEIS<\/mark><\/strong> trata acerca de algumas equa\u00e7\u00f5es utilizadas para confer\u00eancia da integridade dos lan\u00e7amentos. Todavia, haja vista essas equa\u00e7\u00f5es n\u00e3o serem alvo comum de exig\u00eancia em concursos p\u00fablicos, optamos por n\u00e3o tecer maiores coment\u00e1rios.<\/p>\n\n\n\n<p>Por fim, a regra da <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">CONSIST\u00caNCIA DOS REGISTROS E SALDOS<\/mark><\/strong> refere-se ao acompanhamento, an\u00e1lise e consist\u00eancia dos saldos das contas, inclusive mediante an\u00e1lise dos balancetes. Conforme o MCASP (9\u00aa ed.), essa an\u00e1lise pode decorrer da verifica\u00e7\u00e3o quanto \u00e0 exist\u00eancia de saldos invertidos, de classifica\u00e7\u00e3o inadequada de receitas e despesas, de saldos irris\u00f3rios, da utiliza\u00e7\u00e3o indevida de contas cont\u00e1beis e da exist\u00eancia de \u201coutros saldos cont\u00e1beis\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Conclus\u00e3o<\/mark><\/strong><\/h2>\n\n\n\n<p>Chegamos ao fim deste artigo sobre o Plano de Contas Aplicado ao Setor P\u00fablico para a Receita Federal do Brasil (RFB).<\/p>\n\n\n\n<p>At\u00e9 o pr\u00f3ximo artigo.<\/p>\n\n\n\n<p>Grande abra\u00e7o.<\/p>\n\n\n\n<p><strong>Rafael Chaves<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-receita-federal\/#\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Receita Federal<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, amigos, tudo bem? Neste artigo aprenderemos um pouco acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP), com foco no concurso da Receita Federal do Brasil (RFB). Primeiramente, devemos lembrar que o novo concurso da RFB teve seu edital publicado no m\u00eas de dezembro de 2022. As provas (objetiva e discursiva), por sua [&hellip;]<\/p>\n","protected":false},"author":2261,"featured_media":698463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220182],"tags":[],"tax_estado":[219963],"class_list":["post-1148271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-federal","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB<\/title>\n<meta name=\"description\" content=\"Aprenda os principais t\u00f3picos acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) para o concurso da Receita Federal do Brasil (RFB).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB\" \/>\n<meta property=\"og:description\" content=\"Aprenda os principais t\u00f3picos acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) para o concurso da Receita Federal do Brasil (RFB).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Ferreira Chaves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Ferreira Chaves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\"},\"author\":{\"name\":\"Rafael Ferreira Chaves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1\"},\"headline\":\"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB\",\"datePublished\":\"2023-01-26T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\"},\"wordCount\":1984,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Federal (RFB e AFT)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\",\"name\":\"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg\",\"datePublished\":\"2023-01-26T17:00:00+00:00\",\"description\":\"Aprenda os principais t\u00f3picos acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) para o concurso da Receita Federal do Brasil (RFB).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg\",\"width\":1200,\"height\":628,\"caption\":\"concurso Receita federal cronograma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1\",\"name\":\"Rafael Ferreira Chaves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"caption\":\"Rafael Ferreira Chaves\"},\"description\":\"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB","description":"Aprenda os principais t\u00f3picos acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) para o concurso da Receita Federal do Brasil (RFB).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/","og_locale":"pt_BR","og_type":"article","og_title":"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB","og_description":"Aprenda os principais t\u00f3picos acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) para o concurso da Receita Federal do Brasil (RFB).","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-01-26T17:00:00+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg","type":"image\/jpeg"}],"author":"Rafael Ferreira Chaves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafael Ferreira Chaves","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/"},"author":{"name":"Rafael Ferreira Chaves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1"},"headline":"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB","datePublished":"2023-01-26T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/"},"wordCount":1984,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg","articleSection":["Concursos P\u00fablicos","Fiscal - Federal (RFB e AFT)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/","name":"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg","datePublished":"2023-01-26T17:00:00+00:00","description":"Aprenda os principais t\u00f3picos acerca do Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) para o concurso da Receita Federal do Brasil (RFB).","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/03\/22153002\/concurso-receita-federal.jpg","width":1200,"height":628,"caption":"concurso Receita federal cronograma"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/plano-contas-rfb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Plano de Contas Aplicado ao Setor P\u00fablico: resumo para a RFB"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1","name":"Rafael Ferreira Chaves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","caption":"Rafael Ferreira Chaves"},"description":"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1148271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2261"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1148271"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1148271\/revisions"}],"predecessor-version":[{"id":1148742,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1148271\/revisions\/1148742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/698463"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1148271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1148271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1148271"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1148271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}