{"id":1145481,"date":"2023-01-19T14:00:00","date_gmt":"2023-01-19T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1145481"},"modified":"2023-01-05T15:44:49","modified_gmt":"2023-01-05T18:44:49","slug":"resumo-de-legitima-defesa","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/","title":{"rendered":"Leg\u00edtima Defesa: Resumo para Carreiras Policiais"},"content":{"rendered":"\n<p><\/p><p><\/p><p><\/p><p><\/p><p><\/p><p><\/p><p><\/p><p><span style=\"font-size: revert; color: initial;\">Neste artigo sobre <\/span>a leg\u00edtima defesa<span style=\"font-size: revert; color: initial;\">, encerraremos nossa s\u00e9rie sobre as excludentes de ilicitude, tema fundamental para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.   <\/span>   <\/p><p><span style=\"font-size: revert; color: initial;\">Os concursos da \u00e1rea de Seguran\u00e7a P\u00fablica prometem in\u00fameras vagas nos pr\u00f3ximos meses.<\/span><\/p>\n\n\n\n<p>Confira <a style=\"font-size: revert;\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-de-policia\/\">aqui <\/a>o levantamento realizado pela equipe do Estrat\u00e9gia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"643\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/19093209\/policia.jpeg\" alt=\"Leg\u00edtima Defesa: Resumo para Carreiras Policiais\" class=\"wp-image-1080588\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/19093209\/policia.jpeg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/19093209\/policia-300x188.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/19093209\/policia-768x482.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/19093209\/policia-610x383.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/19093209\/policia-150x94.jpeg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Leg\u00edtima Defesa: Resumo para Carreiras Policiais<\/figcaption><\/figure>\n\n\n\n<p>T\u00f3picos a serem vistos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Excludentes de ilicitude<\/em><\/li><li><em>Leg\u00edtima Defesa<\/em><\/li><li><em>Formas de Leg\u00edtima Defesa<\/em><\/li><\/ul>\n\n\n\n<p>Vamos l\u00e1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-excludentes-de-ilicitude\"><em>EXCLUDENTES DE ILICITUDE   <\/em><\/h2>\n\n\n\n<p>Segundo a doutrina dominante, o crime, em seu conceito anal\u00edtico, comp\u00f5e-se de<strong> fato t\u00edpico, il\u00edcito e culp\u00e1vel.<\/strong> <\/p>\n\n\n\n<p>O segundo substrato do crime, <strong>ilicitude ou antijuridicidade, representa a contrariedade entre o comportamento do agente e o ordenamento jur\u00eddico.<\/strong><\/p>\n\n\n\n<p>Nas li\u00e7\u00f5es de Rog\u00e9rio Greco((GRECO, Rog\u00e9rio. C\u00f3digo penal comentado. 11. ed. 2017 Niter\u00f3i, RJ: Impetus, 2017)):<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00c9 a rela\u00e7\u00e3o de antagonismo, de contrariedade entre a conduta do agente e o ordenamento jur\u00eddico (ilicitude formal) que cause les\u00e3o, ou exponha a perigo de les\u00e3o, um bem juridicamente protegido (ilicitude material).<\/p><\/blockquote>\n\n\n\n<p>O C\u00f3digo Penal, em seu art. 23, elencou <strong>quatro causas excludentes da ilicitude(causas de justifica\u00e7\u00e3o):<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art. 23 &#8211; N\u00e3o h\u00e1 crime quando o agente pratica o fato:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p><p>I &#8211; em estado de necessidade;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p><p>II &#8211; em <strong>leg\u00edtima defesa;&nbsp;&nbsp;&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p><p>III &#8211; em estrito cumprimento de dever legal ou no exerc\u00edcio regular de direito.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p><\/blockquote>\n\n\n\n<p>Destaca-se que<strong> o C\u00f3digo Penal,<\/strong> em seus artigos 24 e 25, <strong>apenas definiu os conceitos de estado de necessidade e leg\u00edtima defesa<\/strong>, ficando as defini\u00e7\u00f5es das excludentes disciplinadas no art.23,III, a cargo da doutrina.<\/p>\n\n\n\n<p>Ademais, segundo entendimento doutrin\u00e1rio e jurisprudencial as excludentes de ilicitude n\u00e3o se restringem \u00e0s hip\u00f3teses elencadas no supracitado artigo, <strong>sendo admitidas causas supralegais de exclus\u00e3o da ilicitude<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-legitima-defesa\"><em>LEG\u00cdTIMA DEFESA<\/em><\/h2>\n\n\n\n<p>O conceito de leg\u00edtima defesa \u00e9 extra\u00eddo do art. 25 do C\u00f3digo Penal, <em>in verbis:<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&nbsp;&nbsp; Art. 25 &#8211; Entende-se em leg\u00edtima defesa quem, <strong>usando moderadamente dos meios necess\u00e1rios, <\/strong>repele<strong> injusta agress\u00e3o, atual ou iminente, a direito seu ou de outrem<\/strong>.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/1980-1988\/L7209.htm#art25\">(Reda\u00e7\u00e3o dada pela Lei n\u00ba 7.209, de 11.7.1984)<\/a>&nbsp;&nbsp;&nbsp;&nbsp;<a href=\"http:\/\/portal.stf.jus.br\/processos\/detalhe.asp?incidente=6081690\">(Vide ADPF 779)<\/a><\/p><p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Par\u00e1grafo \u00fanico. Observados os requisitos previstos no&nbsp;<strong>caput<\/strong>&nbsp;deste artigo, considera-se tamb\u00e9m em leg\u00edtima defesa o agente de seguran\u00e7a p\u00fablica que repele agress\u00e3o ou risco de agress\u00e3o a v\u00edtima mantida ref\u00e9m durante a pr\u00e1tica de crimes.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2019-2022\/2019\/Lei\/L13964.htm#art2\">(Inclu\u00eddo pela Lei n\u00ba 13.964, de 2019)<\/a>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<a href=\"http:\/\/portal.stf.jus.br\/processos\/detalhe.asp?incidente=6081690\">(Vide ADPF 779)<\/a><\/p><\/blockquote>\n\n\n\n<p>Dessa forma, s\u00e3o requisitos:<\/p>\n\n\n\n<p><strong>a)injusta agress\u00e3o<\/strong> &#8211;  \u00c9 a<strong> conduta humana<\/strong> que lesiona ou exp\u00f5e a perigo interesse juridicamente protegido. Ressalta-se que n\u00e3o \u00e9 preciso que a conduta seja capitulada como crime para que seja considerada injusta, bastando sua contrariedade ao direito(ilicitude gen\u00e9rica).<\/p>\n\n\n\n<p>Note que \u00e9 necess\u00e1ria uma agress\u00e3o humana. Assim, matar animais n\u00e3o configura o referido instituto, podendo configurar estado de necessidade. Todavia, caso o animal seja utilizado como instrumento para um ataque, sendo provocado pelo agressor, pode-se configurar leg\u00edtima defesa, pois caracterizado um ato do homem;<\/p>\n\n\n\n<p><strong>b)agress\u00e3o atual ou iminente<\/strong>&#8211; A agress\u00e3o pode estar efetivamente acontecendo ou estar prestes a acontecer. Nesse sentido:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>N\u00e3o se constata a apontada contradi\u00e7\u00e3o na decis\u00e3o do Conselho de Senten\u00e7a que, embora tenha reconhecido que o paciente agiu em defesa pr\u00f3pria, <strong>entendeu que a agress\u00e3o da v\u00edtima n\u00e3o era atual ou iminente, afastando, nos termos do art. 25 do C\u00f3digo Penal, a caracteriza\u00e7\u00e3o da leg\u00edtima defesa, <\/strong>por aus\u00eancia de um dos seus elementos. <\/p><p>(STJ, HC 89513\/SP, Rel.\u00aa Min.\u00aa Laurita Vaz, 5\u00aa T., DJe 8\/2\/2010);<\/p><\/blockquote>\n\n\n\n<p><strong>c<\/strong>) <strong>tutela de direito pr\u00f3prio ou alheio<\/strong> &#8211; a leg\u00edtima defesa incide n\u00e3o apenas na prote\u00e7\u00e3o de bens jur\u00eddicos do pr\u00f3prio agente, mas tamb\u00e9m na de terceiros.<\/p>\n\n\n\n<p>Destaca-se que, com as altera\u00e7\u00f5es trazidas pelo Pacote Anticrime(Lei n. 13.869\/2019), foi positivada no C\u00f3digo Penal uma esp\u00e9cie de leg\u00edtima defesa de terceiros. Veja-se:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art.25, <strong>Par\u00e1grafo \u00fanico. <\/strong>Observados os requisitos previstos no caput deste artigo, <strong>considera-se tamb\u00e9m em leg\u00edtima defesa o agente de seguran\u00e7a p\u00fablica que repele agress\u00e3o ou risco de agress\u00e3o a v\u00edtima mantida ref\u00e9m durante a pr\u00e1tica de crimes.<\/strong><\/p><\/blockquote>\n\n\n\n<p>Apesar da altera\u00e7\u00e3o legislativa, nota-se que n\u00e3o houve uma consequ\u00eancia pr\u00e1tica, visto que a conduta j\u00e1 era albergada pelo instituto;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-uso-moderado-dos-meios-necessarios-legitima-defesa\"><em>USO MODERADO DOS MEIOS NECESS\u00c1RIOS<\/em> &#8211; <em>LEG\u00cdTIMA DEFESA<\/em><\/h3>\n\n\n\n<p><strong>d)meios necess\u00e1rios<\/strong> &#8211; \u00c9 aquele que est\u00e1 dispon\u00edvel ao agente e que menor dano causar\u00e1. Destaca-se que o meio necess\u00e1rio \u00e9 analisado \u00e0 luz do caso concreto, com esteio nos princ\u00edpios da proporcionalidade e da razoabilidade. <\/p>\n\n\n\n<p>Assim, se o agente tiver ao seu dispor diversos meios aptos a reprimir a injusta agress\u00e3o, dever\u00e1 optar pelo menos gravoso.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A leg\u00edtima defesa necessita que o uso dos meios necess\u00e1rios sejam suficientes para repelir a agress\u00e3o. Varia de simples admoesta\u00e7\u00e3o at\u00e9 o pr\u00f3prio uso de viol\u00eancia. <strong>No entanto, o defendente deve se utilizar, entre os meios de que disp\u00f5e para sua defesa, no momento da agress\u00e3o, aquele que menor les\u00e3o pode causar. <\/strong>Al\u00e9m disso, \u00e9 imperioso que seja moderado na rea\u00e7\u00e3o, que n\u00e3o use o meio de forma a cometer excesso na repulsa<br \/>(TJSC, AC 2013.002261-1, Rel. Des. Ricardo Roesler, j. 12\/3\/2013);<\/p><\/blockquote>\n\n\n\n<p><strong>e)modera\u00e7\u00e3o no uso dos meios necess\u00e1rios<\/strong> &#8211; n\u00e3o basta apenas que o agente selecione o meio adequado \u00e0 repulsa, sendo necess\u00e1rio agir com modera\u00e7\u00e3o, sob pena de incorrer em excesso. <\/p>\n\n\n\n<p>Assim, o agente n\u00e3o pode ultrapassar o suficiente para fazer cessar a injusta agress\u00e3o, sob pena de enquadramento no art.23, par\u00e1grafo \u00fanico, do C\u00f3digo Penal.<\/p>\n\n\n\n<p>Nas li\u00e7\u00f5es do brilhante doutrinador Rog\u00e9rio Greco(GRECO, Rog\u00e9rio.&nbsp;Curso de Direito Penal: Parte Geral.&nbsp;16 ed.&nbsp;Rio de Janeiro: Impetus, 2014):<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Assim, para que possamos verificar se o uso do meio necess\u00e1rio foi moderado ou n\u00e3o, \u00e9 preciso que tenhamos um marco, qual seja, o momento em que o agente consegue fazer cessar a agress\u00e3o que contra ele era praticada. Tudo o que fizer ap\u00f3s esse marco ser\u00e1 considerado excesso<\/strong>;<\/p><\/blockquote>\n\n\n\n<p><strong>g)elemento subjetivo<\/strong> &#8211; \u00e9 preciso que o agente saiba que atua nessa condi\u00e7\u00e3o, tendo a consci\u00eancia da agress\u00e3o injusta e desejando defender o direito amea\u00e7ado.<\/p>\n\n\n\n<p>Nas li\u00e7\u00f5es da jurisprud\u00eancia:<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>O depoimento da testemunha Adriano corroborou o depoimento de Jurema, afirmando que a v\u00edtima estava aparentemente embriagada, e que Isael havia chegado no local j\u00e1 armado. Nesse sentido, n\u00e3o h\u00e1  que se falar em leg\u00edtima defesa, pois n\u00e3o foram preenchidos os requisitos necess\u00e1rios para o seu reconhecimento. <strong>O r\u00e9u n\u00e3o agiu para defender-se, mas sim com o \u00fanico objetivo de levar o desafeto a \u00f3bito. A aus\u00eancia do requisito de ordem subjetiva leva \u00e0 exclus\u00e3o da leg\u00edtima defesa .<\/strong><\/p><p>(TJ-RJ, RSE 0126012-28.1998.8.19.0001, Rel. Des. Claudio Tavares de Oliveira Junior, DJe 05\/09\/2016).<\/p><\/blockquote>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-formas-de-legitima-defesa\"><em>FORMAS DE LEG\u00cdTIMA DEFESA<\/em><\/h2>\n\n\n\n<p>A doutrina elenca uma s\u00e9rie de classifica\u00e7\u00f5es para o instituto. Para fins estudo para os certames p\u00fablicos das carreiras policiais, seguem as mais importantes:<\/p>\n\n\n\n<p><strong>a)leg\u00edtima defesa pr\u00f3pria<\/strong> &#8211; ocorre nos casos em que o agente protege um direito ou interesse pr\u00f3prio;<\/p>\n\n\n\n<p><strong>b)leg\u00edtima defesa de terceiro<\/strong> &#8211; o autor do fato tutela um direito ou interesse alheio;<\/p>\n\n\n\n<p><strong>c)leg\u00edtima defesa real<\/strong> &#8211; a situa\u00e7\u00e3o de perigo, de fato, existe e dela o agente tem conhecimento; <\/p>\n\n\n\n<p><strong>d)leg\u00edtima defesa putativa<\/strong> &#8211; \u00c9 a imagin\u00e1ria. O agente sup\u00f5e a exist\u00eancia de uma injusta agress\u00e3o ou erra acerca dos limites da excludente. Aplicam-se as regras constantes do art. 20, \u00a7 1\u00ba, do C\u00f3digo Penal(erro de tipo permissivo) ou do art. 21 do C\u00f3digo Penal(erro de proibi\u00e7\u00e3o indireto).<br \/><\/p>\n\n\n\n<p><strong>e)leg\u00edtima defesa sucessiva &#8211; <\/strong>ocorre nos casos de <strong>excesso.<\/strong> O inicial agressor passa a ser agredido em raz\u00e3o de ter se excedido na leg\u00edtima defesa. <strong>Como o excesso constitui uma injusta agress\u00e3o, \u00e9 admitida pelo ordenamento jur\u00eddico p\u00e1trio.<\/strong><\/p>\n\n\n\n<p><strong>f)leg\u00edtima defesa real rec\u00edproca &#8211; N\u00e3o \u00e9 poss\u00edvel haver leg\u00edtima defesa real contra leg\u00edtima defesa real, <\/strong>uma vez que para a configura\u00e7\u00e3o do instituto \u00e9 necess\u00e1ria uma agress\u00e3o injusta e uma rea\u00e7\u00e3o l\u00edcita. Dessa forma, n\u00e3o \u00e9 poss\u00edvel que um comportamento seja l\u00edcito e il\u00edcito ao mesmo tempo.<\/p>\n\n\n\n<p><strong>g)leg\u00edtima defesa x estado de necessidade<\/strong> &#8211; N\u00e3o \u00e9 poss\u00edvel, visto que quem atua em estado de necessidade n\u00e3o pratica agress\u00e3o injusta. Assim, <strong>n\u00e3o cabe o instituto contra estado de necessidade.<\/strong><\/p>\n\n\n\n<p><strong>h)leg\u00edtima defesa real x leg\u00edtima defesa putativa &#8211; <\/strong>\u00c9 poss\u00edvel a coexist\u00eancia dos institutos, uma vez que o agente, embora imagine ser justa, pratica uma agress\u00e3o injusta ao agir em leg\u00edtima defesa imagin\u00e1ria(putativa).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando\"><em>FINALIZANDO<\/em><\/h2>\n\n\n\n<p>Chegamos ao fim do nosso resumo desse tema important\u00edssimo para carreiras policiais.<\/p>\n\n\n\n<p>Caso queira ter a mais completa prepara\u00e7\u00e3o para o seu concurso p\u00fablico, invista nos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\"><u>cursos completos <\/u><\/a>do <strong>Estrat\u00e9gia Concursos<\/strong>. L\u00e1 voc\u00ea encontrar\u00e1 tudo o que precisa para atingir o cargo dos seus sonhos.<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 essencial acompanhar a evolu\u00e7\u00e3o dos seus estudos por meio do <a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\">Sistema de Quest\u00f5es do Estrat\u00e9gia<\/a>, n\u00e3o deixe para marcar o \u201cx\u201d somente no dia da prova.<\/p>\n\n\n\n<p>Grande abra\u00e7o a todos.<\/p>\n\n\n\n<p>Victor Baio<\/p>\n\n\n\n<p><\/p><p><\/p><p><\/p><p><\/p><p><\/p><p><\/p><p><\/p><p> <\/p><p class=\"has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p><p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p><\/p><p><\/p><p><\/p><p><\/p><p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"assinatura-de-concursos\">Assinatura de Concursos<\/h3>\n\n\n\n<p>Assinatura de 1 ano ou 2 anos<a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASSINE AGORA<\/a><\/p>\n\n\n\n<p>Agora, confira as vagas e oportunidades dos&nbsp;<strong>concursos 2023<\/strong>&nbsp;navegando atrav\u00e9s do \u00edndice abaixo:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concursos-e-vagas-previstas-para-2023\">Concursos e vagas previstas para 2023:<\/h2>\n\n\n\n<ul class=\"wp-block-list\" id=\"indice\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#policial\">Concursos Policiais<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#fiscal\">Concursos Fiscais<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#controle\">Concursos Controle<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#tribunais\">Concursos Tribunais<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#ministerios-publicos\">Concursos em Minist\u00e9rios P\u00fablicos<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#defensorias-publicas\">Concursos em Defensorias<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#legislativa\">Concursos Legislativos<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#saude\">Concursos da \u00e1rea da Sa\u00fade<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#bancaria\">Concursos da \u00e1rea banc\u00e1ria<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#educacao\">Concursos da \u00e1rea da Educa\u00e7\u00e3o<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#prefeituras\">Concursos para Prefeituras<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#outros\">Concursos outras oportunidades<\/a><\/li><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#concursos-estado\">Concursos 2023 por Estado<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Leg\u00edtima Defesa: Resumo para Carreiras Policiais<\/p>\n","protected":false},"author":2343,"featured_media":927064,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220188,1988,220189,220190,220186,220187],"tags":[221252,221253],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1145481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-agente-penitenciario","category-policia","category-policial-guarda-civis","category-policial-peritos","category-policial-oficial","category-policial-pracas","tag-legitima-defesa-2","tag-resumo-legitima-defesa","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Leg\u00edtima Defesa: Resumo para Carreiras Policiais<\/title>\n<meta name=\"description\" content=\"Leg\u00edtima Defesa. Confira tudo o que voc\u00ea precisa saber para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leg\u00edtima Defesa: Resumo para Carreiras Policiais\" \/>\n<meta property=\"og:description\" content=\"Leg\u00edtima Defesa. Confira tudo o que voc\u00ea precisa saber para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Victor Baio do Carmo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Baio do Carmo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\"},\"author\":{\"name\":\"Victor Baio do Carmo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec\"},\"headline\":\"Leg\u00edtima Defesa: Resumo para Carreiras Policiais\",\"datePublished\":\"2023-01-19T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\"},\"wordCount\":1762,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg\",\"keywords\":[\"legitima defesa\",\"resumo leg\u00edtima defesa\"],\"articleSection\":[\"Policial (Agente Penitenci\u00e1rio)\",\"Policial (Agente, Escriv\u00e3o e Investigador)\",\"Policial (Guardas Civis)\",\"Policial (Peritos, Papiloscopistas)\",\"Policial (PM\/BM - Oficial)\",\"Policial (PM\/BM - Pra\u00e7as)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\",\"name\":\"Leg\u00edtima Defesa: Resumo para Carreiras Policiais\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg\",\"datePublished\":\"2023-01-19T17:00:00+00:00\",\"description\":\"Leg\u00edtima Defesa. Confira tudo o que voc\u00ea precisa saber para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg\",\"width\":1024,\"height\":768,\"caption\":\"Pir\u00e2mide de Glasser e o concurso da PC-MG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leg\u00edtima Defesa: Resumo para Carreiras Policiais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec\",\"name\":\"Victor Baio do Carmo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g\",\"caption\":\"Victor Baio do Carmo\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victorbaio93gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Leg\u00edtima Defesa: Resumo para Carreiras Policiais","description":"Leg\u00edtima Defesa. Confira tudo o que voc\u00ea precisa saber para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/","og_locale":"pt_BR","og_type":"article","og_title":"Leg\u00edtima Defesa: Resumo para Carreiras Policiais","og_description":"Leg\u00edtima Defesa. Confira tudo o que voc\u00ea precisa saber para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-01-19T17:00:00+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg","type":"image\/jpeg"}],"author":"Victor Baio do Carmo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Victor Baio do Carmo","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/"},"author":{"name":"Victor Baio do Carmo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec"},"headline":"Leg\u00edtima Defesa: Resumo para Carreiras Policiais","datePublished":"2023-01-19T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/"},"wordCount":1762,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg","keywords":["legitima defesa","resumo leg\u00edtima defesa"],"articleSection":["Policial (Agente Penitenci\u00e1rio)","Policial (Agente, Escriv\u00e3o e Investigador)","Policial (Guardas Civis)","Policial (Peritos, Papiloscopistas)","Policial (PM\/BM - Oficial)","Policial (PM\/BM - Pra\u00e7as)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/","name":"Leg\u00edtima Defesa: Resumo para Carreiras Policiais","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg","datePublished":"2023-01-19T17:00:00+00:00","description":"Leg\u00edtima Defesa. Confira tudo o que voc\u00ea precisa saber para a sua aprova\u00e7\u00e3o nos concursos das carreiras policiais.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/10175857\/policia-civil-2.jpg","width":1024,"height":768,"caption":"Pir\u00e2mide de Glasser e o concurso da PC-MG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-de-legitima-defesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Leg\u00edtima Defesa: Resumo para Carreiras Policiais"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec","name":"Victor Baio do Carmo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g","caption":"Victor Baio do Carmo"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victorbaio93gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1145481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2343"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1145481"}],"version-history":[{"count":19,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1145481\/revisions"}],"predecessor-version":[{"id":1148031,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1145481\/revisions\/1148031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/927064"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1145481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1145481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1145481"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1145481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}