{"id":112238,"date":"2018-03-19T16:05:17","date_gmt":"2018-03-19T19:05:17","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=112238"},"modified":"2018-03-19T18:50:42","modified_gmt":"2018-03-19T21:50:42","slug":"administrador-petrobras-questoes-de-sustentabilidade","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/","title":{"rendered":"Administrador &#8211; PETROBRAS &#8211; Quest\u00f5es de Sustentabilidade"},"content":{"rendered":"<p>Ol\u00e1, pessoal!<\/p>\n<p>Seguem as quest\u00f5es sobre desenvolvimento sustent\u00e1vel da prova de Administrador da Petrobras.<\/p>\n<p>&nbsp;<\/p>\n<p>Gabarito apresentado pela Banca Cesgranrio est\u00e1 OK! N\u00e3o vejo possibilidade de recursos.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>67 O \u00cdndice de Desenvolvimento Humano (IDH) e a Pegada Ecol\u00f3gica s\u00e3o indicadores \u00fateis para a avalia\u00e7\u00e3o do desenvolvimento sustent\u00e1vel dos pa\u00edses. Esses dois \u00edndices<\/strong><\/p>\n<p><strong>(A) t\u00eam uma correla\u00e7\u00e3o positiva, em grande parte dos pa\u00edses em desenvolvimento, apontando que a degrada\u00e7\u00e3o ambiental pode ser um dos motivos para o baixo desenvolvimento humano. <\/strong><\/p>\n<p><strong>(B) t\u00eam uma correla\u00e7\u00e3o positiva, em grande parte dos pa\u00edses desenvolvidos, apontando que esse desenvolvimento pode ter ocorrido \u00e0s custas da degrada\u00e7\u00e3o ambiental.<\/strong><\/p>\n<p><strong>(C) t\u00eam uma correla\u00e7\u00e3o negativa, na maior parte dos pa\u00edses, apontando que, quanto maior o desenvolvimento humano, menor ser\u00e1 a pegada ecol\u00f3gica.<\/strong><\/p>\n<p><strong>(D) t\u00eam uma correla\u00e7\u00e3o nula na maior parte dos pa\u00edses, indicando que o maior desenvolvimento est\u00e1 relacionado a um impacto ambiental nulo.<\/strong><\/p>\n<p><strong>(E) n\u00e3o devem ser analisados em conjunto, pois eles se referem a dimens\u00f5es da sustentabilidade que n\u00e3o se relacionam.<\/strong><\/p>\n<p><strong>Letra B.<\/strong><\/p>\n<p>A Pegada Ecol\u00f3gica (Ecological Footprint)\u00a0\u00e9 um indicador de sustentabilidade e o IDH o \u00cdndice de Desenvolvimento Humano.<\/p>\n<p>A pegada ecol\u00f3gica demonstra a quantidade de hectares globais de terra e \u00e1gua<br \/>\nnecess\u00e1rios para a manuten\u00e7\u00e3o da humanidade com um determinado padr\u00e3o de utiliza\u00e7\u00e3o dos<br \/>\nrecursos e emiss\u00e3o de rejeitos.<\/p>\n<p>O ideal seria um alto IDH com uma baixa pegada ecol\u00f3gica, no entanto os estudos demonstram que temos, em regra, uma correla\u00e7\u00e3o positiva entre os dois \u00edndices.<\/p>\n<p><strong>68 Muitas empresas t\u00eam desenvolvido os seus programas de responsabilidade social segundo a abordagem do triple bottom line, que se constitui na principal ferramenta do \u00cdndice de Sustentabilidade da Dow Jones (Dow Jones Sustainability Index) da Bolsa de Valores de Nova Iorque e do \u00cdndice de Sustentabilidade Social (ISE) da Bovespa. Dispon\u00edvel em: . Acesso em: 5 jan. 2018. Adaptado.<\/strong><\/p>\n<p><strong>A abordagem citada no texto refere-se a um conceito<\/strong><\/p>\n<p><strong>(A) baseado na busca de equil\u00edbrio entre resultado financeiro, responsabilidade social e ambiental, possibilitando a implementa\u00e7\u00e3o de indicadores que avaliem essas tr\u00eas dimens\u00f5es. <\/strong><\/p>\n<p><strong>(B) baseado nas mudan\u00e7as sociais, geradas pelos resultados econ\u00f4micos e financeiros decorrentes das suas atividades de responsabilidade social.<\/strong><\/p>\n<p><strong>(C) fundamentado pela ferramenta conhecida como 3P (profit, planet, performance), que implementa indicadores para auxiliar no gerenciamento dos resultados financeiros da empresa.<\/strong><\/p>\n<p><strong>(D) fundamentado na busca de equil\u00edbrio entre planejamento financeiro e responsabilidade social, possibilitando a implementa\u00e7\u00e3o do m\u00e9todo conhecido como 3P (plan, profit, people), que avalia o resultado da empresa considerando suas a\u00e7\u00f5es sociais.<\/strong><\/p>\n<p><strong>(E) implementado nas empresas listadas na Bolsa, para compor uma m\u00e9trica que avalie os resultados financeiros do ponto de vista dos investidores.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Letra A.<\/strong> Pessoal, o trip\u00e9 da sustentabilidade ou triple bottom line (TBL) \u00e9 composto pelos pilares ambiental, social e econ\u00f4mico.<\/p>\n<p>O TBL \u00e9 dividido em 3Ps: people, planet e profit.<\/p>\n<p>People: capital humano (aspecto social)<\/p>\n<p>Planet &#8211; capital natural (aspecto ambiental)<\/p>\n<p>Profit \u2013 lucro (aspecto econ\u00f4mico ou financeiro)<\/p>\n<p>O desenvolvimento sustent\u00e1vel busca harmonizar, conciliar, equilibrar aspectos financeiros (econ\u00f4micos), responsabilidade social e ambiental, possibilitando a implementa\u00e7\u00e3o de indicadores que avaliem essas tr\u00eas dimens\u00f5es.<\/p>\n<p>Espero que voc\u00eas tenham acertado!<\/p>\n<p>Prova de Engenheiro de Produ\u00e7\u00e3o:<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/engenheiro-de-producao-petrobras-questao-de-desenvolvimento-sustentavel\/\" target=\"_blank\" rel=\"noopener\">\u00a0https:\/\/www.estrategiaconcursos.com.br\/blog\/engenheiro-de-producao-petrobras-questao-de-desenvolvimento-sustentavel\/<\/a><\/p>\n<p>Prova de Advogado:\u00a0https:\/\/www.estrategiaconcursos.com.br\/blog\/advogado-petrobras-questoes-comentadas-de-direito-ambiental\/<\/p>\n<p>Abra\u00e7os e sucesso!!!<\/p>\n<p>Prof. Rosenval<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/profrosenval\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/profrosenval\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Seguem as quest\u00f5es sobre desenvolvimento sustent\u00e1vel da prova de Administrador da Petrobras. &nbsp; Gabarito apresentado pela Banca Cesgranrio est\u00e1 OK! N\u00e3o vejo possibilidade de recursos. &nbsp; 67 O \u00cdndice de Desenvolvimento Humano (IDH) e a Pegada Ecol\u00f3gica s\u00e3o indicadores \u00fateis para a avalia\u00e7\u00e3o do desenvolvimento sustent\u00e1vel dos pa\u00edses. Esses dois \u00edndices (A) t\u00eam [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[338,3446],"tax_estado":[],"class_list":["post-112238","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-cesgranrio","tag-concurso-petrobras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Administrador - PETROBRAS - Quest\u00f5es de Sustentabilidade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Administrador - PETROBRAS - Quest\u00f5es de Sustentabilidade\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal! Seguem as quest\u00f5es sobre desenvolvimento sustent\u00e1vel da prova de Administrador da Petrobras. &nbsp; Gabarito apresentado pela Banca Cesgranrio est\u00e1 OK! N\u00e3o vejo possibilidade de recursos. &nbsp; 67 O \u00cdndice de Desenvolvimento Humano (IDH) e a Pegada Ecol\u00f3gica s\u00e3o indicadores \u00fateis para a avalia\u00e7\u00e3o do desenvolvimento sustent\u00e1vel dos pa\u00edses. Esses dois \u00edndices (A) t\u00eam [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosenvaljr\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-19T19:05:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-19T21:50:42+00:00\" \/>\n<meta name=\"author\" content=\"Rosenval J\u00fanior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosenval J\u00fanior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/\"},\"author\":{\"name\":\"Rosenval J\u00fanior\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3489eb8fb39ff11193689cf7762b03b0\"},\"headline\":\"Administrador &#8211; PETROBRAS &#8211; Quest\u00f5es de Sustentabilidade\",\"datePublished\":\"2018-03-19T19:05:17+00:00\",\"dateModified\":\"2018-03-19T21:50:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/\"},\"wordCount\":596,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"keywords\":[\"Cesgranrio\",\"Concurso Petrobras\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/\",\"name\":\"Administrador - PETROBRAS - Quest\u00f5es de Sustentabilidade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"datePublished\":\"2018-03-19T19:05:17+00:00\",\"dateModified\":\"2018-03-19T21:50:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/administrador-petrobras-questoes-de-sustentabilidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Administrador &#8211; PETROBRAS &#8211; Quest\u00f5es de Sustentabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/3489eb8fb39ff11193689cf7762b03b0\",\"name\":\"Rosenval J\u00fanior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc38e7bcadccb99c8a28b35b027bdc6b8b6a65ee938a25ed335e3e31eed462e0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc38e7bcadccb99c8a28b35b027bdc6b8b6a65ee938a25ed335e3e31eed462e0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc38e7bcadccb99c8a28b35b027bdc6b8b6a65ee938a25ed335e3e31eed462e0?s=96&d=mm&r=g\",\"caption\":\"Rosenval J\u00fanior\"},\"description\":\"Graduado pela Universidade Federal de Vi\u00e7osa - UFV. P\u00f3s-graduado em Direito Ambiental. Graduado tamb\u00e9m em Gest\u00e3o Ambiental, com tr\u00eas especializa\u00e7\u00f5es na \u00e1rea ambiental. Mestrando em Engenharia Ambiental. Servidor p\u00fablico do Minist\u00e9rio da Justi\u00e7a e professor de Direito Ambiental, Meio Ambiente, Direito Agr\u00e1rio e Direito Urban\u00edstico para concursos p\u00fablicos. Professor de Direito Ambiental para o Exame de Ordem. Aprovado em 15 concursos p\u00fablicos na \u00e1rea de Meio Ambiente como Analista Ambiental do Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis - IBAMA; Analista Pericial - Especialidade Engenharia Florestal do Minist\u00e9rio P\u00fablico da Uni\u00e3o - MPU; Analista de Infraestrutura - \u00c1rea de Especializa\u00e7\u00e3o Ambiental do Departamento Nacional de Infraestrutura de Transportes - DNIT; Especialista em Regula\u00e7\u00e3o - \u00c1rea Engenharia Ambiental e Engenharia Florestal, com \u00eanfase em Meio Ambiente da Ag\u00eancia Nacional de Transportes Terrestres - ANTT; Consultor Legislativo em Meio Ambiente e Direito Ambiental, Organiza\u00e7\u00e3o Territorial, Desenvolvimento Urbano e Regional da C\u00e2mara dos Deputados; entre outros. Autor do livro \\\"Direito Ambiental para Concursos e Exame de Ordem\\\", Editora Juru\u00e1. Iniciou sua carreira no servi\u00e7o p\u00fablico federal em 2006, quando obteve aprova\u00e7\u00e3o em 1\u00b0 lugar para o cargo de engenheiro florestal da Casa Civil da Presid\u00eancia da Rep\u00fablica\\\/Arquivo Nacional. Alguns concursos em que foi aprovado: 1\u00b0 lugar para Analista do Minist\u00e9rio P\u00fablico de MG; 1\u00ba lugar para Engenheiro da Casa Civil da Presid\u00eancia da Rep\u00fablica; 1\u00b0 lugar para T\u00e9cnico em Recursos Naturais \u2013 n\u00edvel II \u2013 \u00c1rea Engenharia Florestal do IDAF; 2\u00b0 lugar para Analista Pericial do Minist\u00e9rio P\u00fablico da Uni\u00e3o - MPU; 2\u00b0 lugar para Analista em Reforma e Desenvolvimento Agr\u00e1rio do INCRA; 7\u00ba lugar Engenheiro J\u00fanior da Caixa Econ\u00f4mica Federal; 10\u00ba lugar para Analista Ambiental do Instituto Estadual de Florestas - IEF\\\/MG; 6\u00ba lugar para Analista de Infraestrutura (\u00c1rea de Especializa\u00e7\u00e3o Ambiental) do Departamento Nacional de Infraestrutura de Transportes \u2013 DNIT (Prova objetiva e discursiva); 2\u00b0 lugar para Perito Criminal da Pol\u00edcia Civil do Estado do Rio de Janeiro \u2013PCERJ (Resultado na Prova objetiva, TAF, Avalia\u00e7\u00e3o M\u00e9dica, e Psicot\u00e9cnico); 10\u00ba lugar para Perito Criminal da Pol\u00edcia Federal \u2013 DPF \u2013 \u00c1rea 9 (Resultado definitivo na prova objetiva e discursiva); 2\u00b0 lugar para Analista Ambiental do Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis \u2013 IBAMA (Prova objetiva e discursiva); 1\u00b0 lugar para Especialista em Regula\u00e7\u00e3o Engenharia Ambiental e Engenharia Florestal (com \u00eanfase em meio ambiente) da Ag\u00eancia Nacional de Transportes Terrestres - ANTT (Resultado da prova objetiva, discursiva e de t\u00edtulos); 10\u00ba lugar para Consultor Legislativo em Meio Ambiente e Direito Ambiental, Organiza\u00e7\u00e3o Territorial, Desenvolvimento Urbano e Regional da C\u00e2mara dos Deputados. (Resultado da prova objetiva, discursiva e de t\u00edtulos) Entre em contato comigo pelo facebook e pelo Youtube. Basta colocar na busca: Rosenval J\u00fanior. Ou copiar e colar o endere\u00e7o: www.facebook.com\\\/rosenvaljr Acesse o meu site e saiba mais: www.aprendadireitoambiental.com.br\",\"sameAs\":[\"http:\\\/\\\/www.aprendadireitoambiental.com.br\",\"https:\\\/\\\/www.facebook.com\\\/rosenvaljr\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/rosenvaljuniorestrategiaconcursos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Administrador - PETROBRAS - Quest\u00f5es de Sustentabilidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Administrador - PETROBRAS - Quest\u00f5es de Sustentabilidade","og_description":"Ol\u00e1, pessoal! Seguem as quest\u00f5es sobre desenvolvimento sustent\u00e1vel da prova de Administrador da Petrobras. &nbsp; Gabarito apresentado pela Banca Cesgranrio est\u00e1 OK! N\u00e3o vejo possibilidade de recursos. &nbsp; 67 O \u00cdndice de Desenvolvimento Humano (IDH) e a Pegada Ecol\u00f3gica s\u00e3o indicadores \u00fateis para a avalia\u00e7\u00e3o do desenvolvimento sustent\u00e1vel dos pa\u00edses. Esses dois \u00edndices (A) t\u00eam [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/rosenvaljr","article_published_time":"2018-03-19T19:05:17+00:00","article_modified_time":"2018-03-19T21:50:42+00:00","author":"Rosenval J\u00fanior","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rosenval J\u00fanior","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/"},"author":{"name":"Rosenval J\u00fanior","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/3489eb8fb39ff11193689cf7762b03b0"},"headline":"Administrador &#8211; PETROBRAS &#8211; Quest\u00f5es de Sustentabilidade","datePublished":"2018-03-19T19:05:17+00:00","dateModified":"2018-03-19T21:50:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/"},"wordCount":596,"commentCount":4,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["Cesgranrio","Concurso Petrobras"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/","name":"Administrador - PETROBRAS - Quest\u00f5es de Sustentabilidade","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-03-19T19:05:17+00:00","dateModified":"2018-03-19T21:50:42+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/administrador-petrobras-questoes-de-sustentabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Administrador &#8211; PETROBRAS &#8211; Quest\u00f5es de Sustentabilidade"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/3489eb8fb39ff11193689cf7762b03b0","name":"Rosenval J\u00fanior","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/dc38e7bcadccb99c8a28b35b027bdc6b8b6a65ee938a25ed335e3e31eed462e0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc38e7bcadccb99c8a28b35b027bdc6b8b6a65ee938a25ed335e3e31eed462e0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc38e7bcadccb99c8a28b35b027bdc6b8b6a65ee938a25ed335e3e31eed462e0?s=96&d=mm&r=g","caption":"Rosenval J\u00fanior"},"description":"Graduado pela Universidade Federal de Vi\u00e7osa - UFV. P\u00f3s-graduado em Direito Ambiental. Graduado tamb\u00e9m em Gest\u00e3o Ambiental, com tr\u00eas especializa\u00e7\u00f5es na \u00e1rea ambiental. Mestrando em Engenharia Ambiental. Servidor p\u00fablico do Minist\u00e9rio da Justi\u00e7a e professor de Direito Ambiental, Meio Ambiente, Direito Agr\u00e1rio e Direito Urban\u00edstico para concursos p\u00fablicos. Professor de Direito Ambiental para o Exame de Ordem. Aprovado em 15 concursos p\u00fablicos na \u00e1rea de Meio Ambiente como Analista Ambiental do Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis - IBAMA; Analista Pericial - Especialidade Engenharia Florestal do Minist\u00e9rio P\u00fablico da Uni\u00e3o - MPU; Analista de Infraestrutura - \u00c1rea de Especializa\u00e7\u00e3o Ambiental do Departamento Nacional de Infraestrutura de Transportes - DNIT; Especialista em Regula\u00e7\u00e3o - \u00c1rea Engenharia Ambiental e Engenharia Florestal, com \u00eanfase em Meio Ambiente da Ag\u00eancia Nacional de Transportes Terrestres - ANTT; Consultor Legislativo em Meio Ambiente e Direito Ambiental, Organiza\u00e7\u00e3o Territorial, Desenvolvimento Urbano e Regional da C\u00e2mara dos Deputados; entre outros. Autor do livro \"Direito Ambiental para Concursos e Exame de Ordem\", Editora Juru\u00e1. Iniciou sua carreira no servi\u00e7o p\u00fablico federal em 2006, quando obteve aprova\u00e7\u00e3o em 1\u00b0 lugar para o cargo de engenheiro florestal da Casa Civil da Presid\u00eancia da Rep\u00fablica\/Arquivo Nacional. Alguns concursos em que foi aprovado: 1\u00b0 lugar para Analista do Minist\u00e9rio P\u00fablico de MG; 1\u00ba lugar para Engenheiro da Casa Civil da Presid\u00eancia da Rep\u00fablica; 1\u00b0 lugar para T\u00e9cnico em Recursos Naturais \u2013 n\u00edvel II \u2013 \u00c1rea Engenharia Florestal do IDAF; 2\u00b0 lugar para Analista Pericial do Minist\u00e9rio P\u00fablico da Uni\u00e3o - MPU; 2\u00b0 lugar para Analista em Reforma e Desenvolvimento Agr\u00e1rio do INCRA; 7\u00ba lugar Engenheiro J\u00fanior da Caixa Econ\u00f4mica Federal; 10\u00ba lugar para Analista Ambiental do Instituto Estadual de Florestas - IEF\/MG; 6\u00ba lugar para Analista de Infraestrutura (\u00c1rea de Especializa\u00e7\u00e3o Ambiental) do Departamento Nacional de Infraestrutura de Transportes \u2013 DNIT (Prova objetiva e discursiva); 2\u00b0 lugar para Perito Criminal da Pol\u00edcia Civil do Estado do Rio de Janeiro \u2013PCERJ (Resultado na Prova objetiva, TAF, Avalia\u00e7\u00e3o M\u00e9dica, e Psicot\u00e9cnico); 10\u00ba lugar para Perito Criminal da Pol\u00edcia Federal \u2013 DPF \u2013 \u00c1rea 9 (Resultado definitivo na prova objetiva e discursiva); 2\u00b0 lugar para Analista Ambiental do Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis \u2013 IBAMA (Prova objetiva e discursiva); 1\u00b0 lugar para Especialista em Regula\u00e7\u00e3o Engenharia Ambiental e Engenharia Florestal (com \u00eanfase em meio ambiente) da Ag\u00eancia Nacional de Transportes Terrestres - ANTT (Resultado da prova objetiva, discursiva e de t\u00edtulos); 10\u00ba lugar para Consultor Legislativo em Meio Ambiente e Direito Ambiental, Organiza\u00e7\u00e3o Territorial, Desenvolvimento Urbano e Regional da C\u00e2mara dos Deputados. (Resultado da prova objetiva, discursiva e de t\u00edtulos) Entre em contato comigo pelo facebook e pelo Youtube. Basta colocar na busca: Rosenval J\u00fanior. Ou copiar e colar o endere\u00e7o: www.facebook.com\/rosenvaljr Acesse o meu site e saiba mais: www.aprendadireitoambiental.com.br","sameAs":["http:\/\/www.aprendadireitoambiental.com.br","https:\/\/www.facebook.com\/rosenvaljr"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rosenvaljuniorestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/112238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=112238"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/112238\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=112238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=112238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=112238"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=112238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}