{"id":111283,"date":"2018-03-14T08:14:17","date_gmt":"2018-03-14T11:14:17","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=111283"},"modified":"2018-09-18T16:13:08","modified_gmt":"2018-09-18T19:13:08","slug":"10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/","title":{"rendered":"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)"},"content":{"rendered":"<p style=\"text-align: justify;\">Fala pessoal, tudo bem? As provas do TJ\/SP Interior est\u00e3o chegando! Para voc\u00eas fecharem a prepara\u00e7\u00e3o com chave de ouro, estou disponibilizando aqui 10 quest\u00f5es recent\u00edssimas da banca VUNESP, aplicadas em concursos de 2018. S\u00e3o quest\u00f5es dos t\u00f3picos de\u00a0<strong>Matem\u00e1tica<\/strong> do edital, ok? O n\u00edvel de complexidade delas \u00e9 similar ao que voc\u00eas podem esperar para a prova do TJ. Bom trabalho!!<\/p>\n<p><strong>E ATEN\u00c7\u00c3O: NO S\u00c1BADO, V\u00c9SPERA DA PROVA, N\u00d3S FAREMOS UMA REVIS\u00c3O COMPLETA PELO YOUTUBE DO ESTRAT\u00c9GIA CONCURSOS!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 PREF. GAR\u00c7A \u2013 2018)<\/strong> Considere a seguinte situa\u00e7\u00e3o problema proposta em um curso de forma\u00e7\u00e3o de professores, ap\u00f3s discutirem-se conceitos associados a problemas de juros simples: Uma aplica\u00e7\u00e3o de um ano e meio foi feita no sistema de juros simples, a uma taxa de juros de 15% ao ano. Relacione os juros dessa aplica\u00e7\u00e3o ao capital aplicado. Ao resolver corretamente a situa\u00e7\u00e3o apresentada, chega-se \u00e0 conclus\u00e3o de que os juros da aplica\u00e7\u00e3o correspondem, do capital aplicado, a<\/p>\n<p style=\"text-align: justify;\">(A) 0,0225.<\/p>\n<p style=\"text-align: justify;\">(B) 0,225.<\/p>\n<p style=\"text-align: justify;\">(C) 2,25.<\/p>\n<p style=\"text-align: justify;\">(D) 22,5.<\/p>\n<p style=\"text-align: justify;\">(E) 225.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Temos uma aplica\u00e7\u00e3o no regime simples com taxa de j = 15% ao ano e prazo de t = 1,5 ano. Os juros correspondem a:<\/p>\n<p style=\"text-align: center;\">J = C x j x t<\/p>\n<p style=\"text-align: center;\">J = C x 0,15 x 1,5<\/p>\n<p style=\"text-align: center;\">J = C x 0,225<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Veja que os juros correspondem a 0,225 vezes o capital aplicado. Este \u00e9 nosso gabarito.<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: B<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Em uma empresa na qual s\u00e3o comercializados produtos natalinos, a m\u00e9dia aritm\u00e9tica das receitas mensais do 4\u00ba trimestre de 2016 foi igual ao triplo da m\u00e9dia aritm\u00e9tica das receitas mensais do trimestre imediatamente anterior. Se a receita total do segundo semestre de 2016 foi igual a 9 milh\u00f5es de reais, ent\u00e3o a receita total do 3\u00ba trimestre desse mesmo ano foi, em milh\u00f5es de reais, igual a<\/p>\n<p style=\"text-align: justify;\">(A) 2,0.<\/p>\n<p style=\"text-align: justify;\">(B) 2,25.<\/p>\n<p style=\"text-align: justify;\">(C) 2,75.<\/p>\n<p style=\"text-align: justify;\">(D) 3,0.<\/p>\n<p style=\"text-align: justify;\">(E) 3,25.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Se a m\u00e9dia do 4\u00ba trimestre foi o triplo da m\u00e9dia do 3\u00ba trimestre, tamb\u00e9m podemos dizer que a receita total do 4\u00ba trimestre (R4) foi o triplo da receita total do 3\u00ba trimestre (R3). Isto porque em ambos os casos n\u00f3s temos o mesmo per\u00edodo de tr\u00eas meses. Isto \u00e9,<\/p>\n<p style=\"text-align: center;\">R4 = 3 x R3<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Como a receita total do segundo semestre \u00e9 de 9 milh\u00f5es, temos:<\/p>\n<p style=\"text-align: center;\">R3 + R4 = 9<\/p>\n<p style=\"text-align: center;\">R3 + 3.R3 = 9<\/p>\n<p style=\"text-align: center;\">4.R3 = 9<\/p>\n<p style=\"text-align: center;\">R3 = 9\/4<\/p>\n<p style=\"text-align: center;\">R3 = 2,25 milh\u00f5es<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: B<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> De acordo com a previs\u00e3o elaborada, em dezembro de 2017 dever\u00e3o ser vendidas x unidades do produto P. Se o n\u00famero de unidades efetivamente vendidas for igual a y, haver\u00e1, em rela\u00e7\u00e3o a x, uma redu\u00e7\u00e3o de 20%. Entretanto, se o n\u00famero de unidades efetivamente vendidas for igual 2y, ent\u00e3o haver\u00e1, em rela\u00e7\u00e3o a x, um acr\u00e9scimo de<\/p>\n<p style=\"text-align: justify;\">(A) 40%.<\/p>\n<p style=\"text-align: justify;\">(B) 50%.<\/p>\n<p style=\"text-align: justify;\">(C) 60%.<\/p>\n<p style=\"text-align: justify;\">(D) 80%.<\/p>\n<p style=\"text-align: justify;\">(E) 100%.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Veja que y \u00e9 20% menor do que x, ou seja,<\/p>\n<p style=\"text-align: center;\">y = (1 \u2013 20%).x<\/p>\n<p style=\"text-align: center;\">y = 0,80x<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Multiplicando por 2 a equa\u00e7\u00e3o acima, temos:<\/p>\n<p style=\"text-align: center;\">2y = 2.0,80x<\/p>\n<p style=\"text-align: center;\">2y = 1,60x<\/p>\n<p style=\"text-align: center;\">2y = x + 0,60x<\/p>\n<p style=\"text-align: center;\">2y = x + 60%.x<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Temos um aumento de 60% em rela\u00e7\u00e3o a x.<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: C<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Um levantamento efetuado pelo departamento de compras de uma empresa encontrou tr\u00eas marcas diferentes, A, B e C, para um mesmo produto, sendo o pre\u00e7o unit\u00e1rio do produto da marca A igual \u00e0 metade da soma dos pre\u00e7os unit\u00e1rios dos produtos das marcas B e C. Se duas unidades da marca A, mais uma unidade da marca B e mais uma unidade da marca C custam, juntas, R$ 1.400,00, ent\u00e3o tr\u00eas unidades da marca A ir\u00e3o custar<\/p>\n<p style=\"text-align: justify;\">(A) R$ 1.050,00.<\/p>\n<p style=\"text-align: justify;\">(B) R$ 1.100,00.<\/p>\n<p style=\"text-align: justify;\">(C) R$ 1.150,00.<\/p>\n<p style=\"text-align: justify;\">(D) R$ 1.250,00.<\/p>\n<p style=\"text-align: justify;\">(E) R$ 1.300,00.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 O pre\u00e7o unit\u00e1rio do produto da marca A \u00e9 igual \u00e0 metade da soma dos pre\u00e7os unit\u00e1rios dos produtos das marcas B e C, ou seja,<\/p>\n<p style=\"text-align: center;\">A = (B+C)\/2<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Duas unidades da marca A, mais uma unidade da marca B e mais uma unidade da marca C custam, juntas, R$ 1.400,00:<\/p>\n<p style=\"text-align: center;\">2A + 1B + 1C = 1400<\/p>\n<p style=\"text-align: center;\">B + C = 1400 \u2013 2A<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Podemos substituir B + C por 1400 \u2013 2A na primeira equa\u00e7\u00e3o, ficando:<\/p>\n<p style=\"text-align: center;\">A = (B+C)\/2<\/p>\n<p style=\"text-align: center;\">A = (1400 &#8211; 2A)\/2<\/p>\n<p style=\"text-align: center;\">A = 700 \u2013 A<\/p>\n<p style=\"text-align: center;\">2A = 700<\/p>\n<p style=\"text-align: center;\">A = 350 reais<\/p>\n<p style=\"text-align: justify;\">Assim, tr\u00eas unidades da marca A ir\u00e3o custar:<\/p>\n<p style=\"text-align: center;\">3 x 350 = 1050 reais<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: A<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Em uma ind\u00fastria, 20 m\u00e1quinas iguais, de mesmo rendimento, produzem juntas 5000 parafusos iguais, em meia hora de funcionamento simult\u00e2neo e ininterrupto. Desse modo, para produzir 1000 unidades dos mesmos parafusos em uma hora, seria necess\u00e1rio o funcionamento, nas mesmas condi\u00e7\u00f5es operacionais, de apenas<\/p>\n<p style=\"text-align: justify;\">(A) 2 m\u00e1quinas.<\/p>\n<p style=\"text-align: justify;\">(B) 3 m\u00e1quinas.<\/p>\n<p style=\"text-align: justify;\">(C) 5 m\u00e1quinas.<\/p>\n<p style=\"text-align: justify;\">(D) 6 m\u00e1quinas.<\/p>\n<p style=\"text-align: justify;\">(E) 8 m\u00e1quinas.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Podemos esquematizar o problema assim:<\/p>\n<p style=\"text-align: justify;\">M\u00e1quinas\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Parafusos\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tempo (minutos)<\/p>\n<p style=\"text-align: justify;\">20\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5000\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 30<\/p>\n<p style=\"text-align: justify;\">M\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1000\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 60<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Quanto MAIS m\u00e1quinas trabalhando, podemos produzir MAIS parafusos em MENOS tempo. Devemos inverter a coluna do tempo, ficando:<\/p>\n<p style=\"text-align: justify;\">M\u00e1quinas\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Parafusos\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tempo (minutos)<\/p>\n<p style=\"text-align: justify;\">20\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 5000\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 60<\/p>\n<p style=\"text-align: justify;\">M\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1000\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 30<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Montando a propor\u00e7\u00e3o:<\/p>\n<p style=\"text-align: center;\">(20\/M) = (5000\/1000) x (60\/30)<\/p>\n<p style=\"text-align: center;\">20\/M = 5 x 2<\/p>\n<p style=\"text-align: center;\">20 = 10M<\/p>\n<p style=\"text-align: center;\">M = 2 m\u00e1quinas<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: A<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Uma prova de um processo seletivo tem o n\u00famero de quest\u00f5es e o tempo m\u00e1ximo de resolu\u00e7\u00e3o previamente determinados. Cristiano, que far\u00e1 a prova, concluiu que, se gastar exatamente 1 minuto e meio para resolver cada quest\u00e3o, ir\u00e1 terminar a prova 10 minutos antes do prazo m\u00e1ximo previsto. Entretanto, se gastar exatamente 2 minutos e 12 segundos para resolver cada quest\u00e3o, ir\u00e1 exceder em 18 minutos o prazo limite, o que n\u00e3o \u00e9 permitido. Se o hor\u00e1rio previsto para in\u00edcio da prova \u00e9 9h 45min, ent\u00e3o o hor\u00e1rio limite estipulado para a sua conclus\u00e3o \u00e9<\/p>\n<p style=\"text-align: justify;\">(A) 11h 15min.<\/p>\n<p style=\"text-align: justify;\">(B) 11h 10min.<\/p>\n<p style=\"text-align: justify;\">(C) 11h.<\/p>\n<p style=\"text-align: justify;\">(D) 10h 55min.<\/p>\n<p style=\"text-align: justify;\">(E) 10h 45min.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Se gastar exatamente 1 minuto e meio (90 segundos) para resolver cada quest\u00e3o, ir\u00e1 terminar a prova 10 minutos (600 segundos) antes do prazo m\u00e1ximo previsto. Portanto, o tempo total de prova, em segundos, \u00e9:<\/p>\n<p style=\"text-align: center;\">Tempo total = Nx90 + 600<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Veja que N \u00e9 o n\u00famero de quest\u00f5es da prova, que tamb\u00e9m n\u00e3o conhecemos.<\/p>\n<p style=\"text-align: justify;\">Se gastar exatamente 2 minutos e 12 segundos (132 segundos) para resolver cada quest\u00e3o, ir\u00e1 exceder em 18 minutos (1080 segundos) o prazo limite. Isto \u00e9,<\/p>\n<p style=\"text-align: center;\">Tempo total = Nx132 \u2013 1080<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Igualando as express\u00f5es para o tempo total, temos:<\/p>\n<p style=\"text-align: center;\">90N + 600 =132N \u2013 1080<\/p>\n<p style=\"text-align: center;\">1680 = 42N<\/p>\n<p style=\"text-align: center;\">N = 1680\/42<\/p>\n<p style=\"text-align: center;\">N = 40 quest\u00f5es<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 O tempo total \u00e9 de:<\/p>\n<p style=\"text-align: center;\">Tempo total = 90N + 600<\/p>\n<p style=\"text-align: center;\">Tempo total = 90.40 + 600<\/p>\n<p style=\"text-align: center;\">Tempo total = 3600 + 600<\/p>\n<p style=\"text-align: center;\">Tempo total = 4200 segundos<\/p>\n<p style=\"text-align: center;\">Tempo total = 70 x 60 segundos<\/p>\n<p style=\"text-align: center;\">Tempo total = 70 minutos<\/p>\n<p style=\"text-align: center;\">Tempo = 60 + 10 minutos<\/p>\n<p style=\"text-align: center;\">Tempo = 1 hora e 10 minutos<\/p>\n<p style=\"text-align: justify;\">Se o hor\u00e1rio previsto para in\u00edcio da prova \u00e9 9h 45min, ent\u00e3o o hor\u00e1rio limite estipulado para a sua conclus\u00e3o \u00e9 10h 55min.<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: D<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Uma empresa comprou um lote de envelopes e destinou 3\/8 deles ao setor A. Dos envelopes restantes, 4\/5 foram destinados ao setor B, e ainda restaram 75 envelopes. O n\u00famero total de envelopes do lote era<\/p>\n<p style=\"text-align: justify;\">(A) 760.<\/p>\n<p style=\"text-align: justify;\">(B) 720.<\/p>\n<p style=\"text-align: justify;\">(C) 700.<\/p>\n<p style=\"text-align: justify;\">(D) 640.<\/p>\n<p style=\"text-align: justify;\">(E) 600.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sendo E envelopes ao todo, sabemos que 3\/8 deles foram para o setor A, sobrando 5\/8 de E para os demais setores. Ou seja,<\/p>\n<p style=\"text-align: center;\">Sobra ap\u00f3s A =5E\/8<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Desta sobra, sabemos que 4\/5 foram destinados ao setor B, sobrando 1\/5. Ou seja,<\/p>\n<p style=\"text-align: center;\">Sobra ap\u00f3s B = (1\/5) x (5E\/8) = E\/8<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>Esta sobra corresponde a 75 envelopes. Ou seja,<\/p>\n<p style=\"text-align: center;\">75 = E\/8<\/p>\n<p style=\"text-align: center;\">E = 75 x 8<\/p>\n<p style=\"text-align: center;\">E = 600 envelopes<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: E<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Em uma caixa, h\u00e1 menos de 1000 livretos que ser\u00e3o empilhados, de modo que cada pilha contenha o mesmo n\u00famero de livretos. Durante a realiza\u00e7\u00e3o do servi\u00e7o, percebeu-se que era poss\u00edvel colocar, em cada pilha, ou 30, ou 50, ou 60 livretos, e n\u00e3o restaria livreto na caixa. O n\u00famero m\u00e1ximo de livretos que podem estar na caixa \u00e9<\/p>\n<p style=\"text-align: justify;\">(A) 740.<\/p>\n<p style=\"text-align: justify;\">(B) 800.<\/p>\n<p style=\"text-align: justify;\">(C) 860.<\/p>\n<p style=\"text-align: justify;\">(D) 900.<\/p>\n<p style=\"text-align: justify;\">(E) 960.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Repare que o n\u00famero de livretos deve ser divis\u00edvel por 30, 50 e 60. Observando as op\u00e7\u00f5es de resposta, vemos que N\u00c3O s\u00e3o divis\u00edveis por 50 os n\u00fameros das alternativas A (740), C\u00a0(860) e E (960).<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sobram as op\u00e7\u00f5es B e D, ou seja, 800 e 900. Veja que 800 n\u00e3o \u00e9 divis\u00edvel por 30. Logo, sobra apenas o n\u00famero 900. E veja ainda que 900 \u00e9 divis\u00edvel por 60. Esta \u00e9 a nossa resposta.<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: D<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Duas impressoras, A e B, imprimem juntas 1800 p\u00e1ginas em uma hora. Sabendo-se que a raz\u00e3o entre o n\u00famero de p\u00e1ginas impressas pela impressora A e o n\u00famero de p\u00e1ginas impressas pela impressora B, em uma hora, \u00e9 5\/7, ent\u00e3o o tempo necess\u00e1rio para que a impressora A imprima sozinha 2400 p\u00e1ginas \u00e9<\/p>\n<p style=\"text-align: justify;\">(A) 2 horas e 55 minutos.<\/p>\n<p style=\"text-align: justify;\">(B) 3 horas e 12 minutos.<\/p>\n<p style=\"text-align: justify;\">(C) 3 horas e 26 minutos.<\/p>\n<p style=\"text-align: justify;\">(D) 3 horas e 37 minutos.<\/p>\n<p style=\"text-align: justify;\">(E) 3 horas e 48 minutos.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sendo A e B as quantidades de p\u00e1ginas impressas em uma hora por cada impressora, vemos que:<\/p>\n<p style=\"text-align: center;\">A + B = 1800<\/p>\n<p style=\"text-align: center;\">B = 1800 \u2013 A<\/p>\n<p style=\"text-align: center;\">A\/B = 5\/7<\/p>\n<p style=\"text-align: center;\">7A = 5B<\/p>\n<p style=\"text-align: center;\">7A = 5.(1800 \u2013 A)<\/p>\n<p style=\"text-align: center;\">7A = 9000 \u2013 5A<\/p>\n<p style=\"text-align: center;\">12A = 9000<\/p>\n<p style=\"text-align: center;\">A = 750<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Em uma hora (60 minutos) a impressora A imprime 750 p\u00e1ginas. Para imprimir 2400 p\u00e1ginas, o tempo necess\u00e1rio \u00e9:<\/p>\n<p style=\"text-align: center;\">60 minutos &#8212;&#8212;&#8211; 750 p\u00e1ginas<\/p>\n<p style=\"text-align: center;\">N minutos &#8212;&#8212;&#8212;&#8211; 2400 p\u00e1ginas<\/p>\n<p style=\"text-align: center;\">60 x 2400 = N x 750<\/p>\n<p style=\"text-align: center;\">6 x 2400 = N x 75<\/p>\n<p style=\"text-align: center;\">2 x 2400 = N x 25<\/p>\n<p style=\"text-align: center;\">2 x 480 = N x 5<\/p>\n<p style=\"text-align: center;\">2 x 96 = N<\/p>\n<p style=\"text-align: center;\">N = 192 minutos<\/p>\n<p style=\"text-align: center;\">N = 180 + 12 minutos<\/p>\n<p style=\"text-align: center;\">N = 3 horas + 12 minutos<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: B<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>VUNESP \u2013 C\u00c2MARA DE DOIS C\u00d3RREGOS \u2013 2018)<\/strong> Um capital A, aplicado a juros simples com taxa de 9% ao ano, rende em 6 meses, os mesmos juros simples que um capital B aplicado a taxa de 0,8% ao m\u00eas, durante 9 meses. Sabendo-se que o capital A \u00e9 R$ 900,00 superior ao capital B, ent\u00e3o o valor do capital A \u00e9<\/p>\n<p style=\"text-align: justify;\">(A) R$ 2.500,00.<\/p>\n<p style=\"text-align: justify;\">(B) R$ 2.400,00.<\/p>\n<p style=\"text-align: justify;\">(C) R$ 2.200,00.<\/p>\n<p style=\"text-align: justify;\">(D) R$ 1.800,00.<\/p>\n<p style=\"text-align: justify;\">(E) R$ 1.500,00.<\/p>\n<p style=\"text-align: justify;\"><strong>RESOLU\u00c7\u00c3O:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>Sabemos que os juros das duas aplica\u00e7\u00f5es s\u00e3o iguais, ou seja,<\/p>\n<p style=\"text-align: center;\">J<sub>A<\/sub> = J<sub>B<\/sub><\/p>\n<p style=\"text-align: center;\">C<sub>A<\/sub> x j<sub>A<\/sub> x t<sub>A<\/sub> = C<sub>B<\/sub> x j<sub>B<\/sub> x t<sub>B<\/sub><\/p>\n<p style=\"text-align: center;\">(900 + C<sub>B<\/sub>) x 9% x 0,5 = C<sub>B<\/sub> x 0,8% x 9<\/p>\n<p style=\"text-align: center;\">(900 + C<sub>B<\/sub>) x 1% x 0,5 = C<sub>B<\/sub> x 0,8%<\/p>\n<p style=\"text-align: center;\">(900 + C<sub>B<\/sub>) x 1 x 0,5 = C<sub>B<\/sub> x 0,8<\/p>\n<p style=\"text-align: center;\">(900 + C<sub>B<\/sub>) x 0,5 = C<sub>B<\/sub> x 0,8<\/p>\n<p style=\"text-align: center;\">(900 + C<sub>B<\/sub>) x 5 = C<sub>B<\/sub> x 8<\/p>\n<p style=\"text-align: center;\">4500 + 5C<sub>B<\/sub> = 8C<sub>B<\/sub><\/p>\n<p style=\"text-align: center;\">4500 = 3C<sub>B<\/sub><\/p>\n<p style=\"text-align: center;\">1500 = C<sub>B<\/sub><\/p>\n<p style=\"text-align: justify;\"><sub>\u00a0<\/sub><\/p>\n<p style=\"text-align: justify;\"><sub>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/sub>Portanto, C<sub>A<\/sub> = C<sub>B<\/sub> + 900 = 1500 + 900 = 2400 reais.<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta: B<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fala pessoal, tudo bem? As provas do TJ\/SP Interior est\u00e3o chegando! Para voc\u00eas fecharem a prepara\u00e7\u00e3o com chave de ouro, estou disponibilizando aqui 10 quest\u00f5es recent\u00edssimas da banca VUNESP, aplicadas em concursos de 2018. S\u00e3o quest\u00f5es dos t\u00f3picos de\u00a0Matem\u00e1tica do edital, ok? O n\u00edvel de complexidade delas \u00e9 similar ao que voc\u00eas podem esperar para [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-111283","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)\" \/>\n<meta property=\"og:description\" content=\"Fala pessoal, tudo bem? As provas do TJ\/SP Interior est\u00e3o chegando! Para voc\u00eas fecharem a prepara\u00e7\u00e3o com chave de ouro, estou disponibilizando aqui 10 quest\u00f5es recent\u00edssimas da banca VUNESP, aplicadas em concursos de 2018. S\u00e3o quest\u00f5es dos t\u00f3picos de\u00a0Matem\u00e1tica do edital, ok? O n\u00edvel de complexidade delas \u00e9 similar ao que voc\u00eas podem esperar para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-14T11:14:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-18T19:13:08+00:00\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7\"},\"headline\":\"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)\",\"datePublished\":\"2018-03-14T11:14:17+00:00\",\"dateModified\":\"2018-09-18T19:13:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\"},\"wordCount\":1676,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\",\"name\":\"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-03-14T11:14:17+00:00\",\"dateModified\":\"2018-09-18T19:13:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/contatoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/","og_locale":"pt_BR","og_type":"article","og_title":"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)","og_description":"Fala pessoal, tudo bem? As provas do TJ\/SP Interior est\u00e3o chegando! Para voc\u00eas fecharem a prepara\u00e7\u00e3o com chave de ouro, estou disponibilizando aqui 10 quest\u00f5es recent\u00edssimas da banca VUNESP, aplicadas em concursos de 2018. S\u00e3o quest\u00f5es dos t\u00f3picos de\u00a0Matem\u00e1tica do edital, ok? O n\u00edvel de complexidade delas \u00e9 similar ao que voc\u00eas podem esperar para [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2018-03-14T11:14:17+00:00","article_modified_time":"2018-09-18T19:13:08+00:00","author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7"},"headline":"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)","datePublished":"2018-03-14T11:14:17+00:00","dateModified":"2018-09-18T19:13:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/"},"wordCount":1676,"commentCount":2,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/","name":"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-03-14T11:14:17+00:00","dateModified":"2018-09-18T19:13:08+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/10-questoes-vunesp-2018-para-o-tj-sp-matematica-e-raciocinio-logico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"10 quest\u00f5es VUNESP 2018 para o TJ\/SP (Matem\u00e1tica e Racioc\u00ednio L\u00f3gico)"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/cdad40b5818eb228a838461fcd656da7","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a413b22da0f5009c634f6c4586a2dbe5207074fd5becd88db5183b8069ef25e4?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/contatoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/111283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=111283"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/111283\/revisions"}],"predecessor-version":[{"id":141480,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/111283\/revisions\/141480"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=111283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=111283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=111283"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=111283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}