{"id":110833,"date":"2018-03-15T14:59:23","date_gmt":"2018-03-15T17:59:23","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=110833"},"modified":"2018-03-15T18:21:56","modified_gmt":"2018-03-15T21:21:56","slug":"prova-comentada-saneago-portugues","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/","title":{"rendered":"PROVA COMENTADA SANEAGO &#8211; PORTUGU\u00caS"},"content":{"rendered":"<p>Ol\u00e1, pessoal. Bom dia.<\/p>\n<p>Postei o coment\u00e1rio da \u00faltima prova da SANEAGO, realizada recentemente. A banca cobrou muitas quest\u00f5es de intelec\u00e7\u00e3o textual, com refer\u00eancia a figuras de linguagem, interpreta\u00e7\u00e3o de texto, tipologia textual, vocabul\u00e1rio e varia\u00e7\u00e3o lingu\u00edstica. Vale a pena revisar tais temas!<\/p>\n<p>Abra\u00e7o e sucesso na prova!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-104237\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png\" alt=\"\" width=\"724\" height=\"125\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png 724w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png 610w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/p>\n<p><strong>Leia o texto que segue para responder \u00e0s quest\u00f5es de 01 a 03.<\/strong><\/p>\n<p>Texto 1<\/p>\n<p><strong>Hist\u00f3ria da cria\u00e7\u00e3o<\/strong><\/p>\n<p>Os nossos s\u00e1bios disseram:<\/p>\n<p>\u201cNo come\u00e7o n\u00e3o existia o mundo. Existia o \u0197M\u0197KOHO \u00d1EK\u0197, (O Av\u00f4 do Mundo), ou seja, o Criador do Universo. Existia a \u0197M\u0197KOHO \u00d1EKO, a Irm\u00e3 do Criador do Universo, Av\u00f3 do Mundo. Existia o YE\u2019PA \u00d5AK\u0197H\u0197 (O Guia Revelador, que poderia ser traduzido como Deus na na\u00e7\u00e3o Tukana).<\/p>\n<p>O Criador do Universo perguntou \u00e0 sua irm\u00e3:<\/p>\n<p>\u2013 O que faremos desse imenso universo&#8230; Temos mundo, e como faremos para criar os primeiros homens na terra?<\/p>\n<p>\u2013 Desde o princ\u00edpio eu sou o ser feminino. Respondeu a irm\u00e3.<\/p>\n<p>\u2013 \u00c9 isso mesmo! Eu sou homem e sei disso. Disse o Criador do Universo, depois de refletir bastante.\u201d<\/p>\n<p>TUKANO, \u00c1lvaro. O mundo Tukano antes dos brancos \u2013 um mestre Tukano.<\/p>\n<ol>\n<li>1. Bras\u00edlia-DF: INCTI\/UnB\/CNPq, 2017. p. 44.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol>\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O \u2013 ADMINISTRADOR \/ 2018)<\/strong><\/li>\n<\/ol>\n<p>Do enunciado \u201cNo come\u00e7o n\u00e3o existia o mundo. Existia o \u0197M\u0197KOHO \u00d1EK\u0197, (O Av\u00f4 do Mundo)\u201d, infere-se que, para o povo Tukano,<\/p>\n<p>(A) o universo \u00e9 resultado de inven\u00e7\u00e3o mitol\u00f3gica.<\/p>\n<p>(B) existiu um plano superior de seres n\u00e3o humanos.<\/p>\n<p>(C) o mundo \u00e9 a representa\u00e7\u00e3o do universo n\u00e3o ind\u00edgena.<\/p>\n<p>(D) existiu um tempo-lugar anterior ao do mundo atual habitado.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>Se antes de existir o mundo como o conhecemos j\u00e1 existia outros seres, interagindo, conversando, decidindo sobre a cria\u00e7\u00e3o do mundo, podemos ent\u00e3o concluir que j\u00e1 existia um tempo-lugar anterior ao mundo atual habitado.<\/p>\n<p>Gabarito letra D.<\/p>\n<ol start=\"2\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>O texto apresenta a narra\u00e7\u00e3o da cria\u00e7\u00e3o do mundo em uma perspectiva<\/p>\n<p>(A) dial\u00f3gica, promovida pela intera\u00e7\u00e3o entre homem e mulher.<\/p>\n<p>(B) divinat\u00f3ria, em que seres fant\u00e1sticos s\u00e3o os protagonistas.<\/p>\n<p>(C) enigm\u00e1tica, envolvida nos mist\u00e9rios e segredos dos autores.<\/p>\n<p>(D) conspirat\u00f3ria, em que duas figuras mitol\u00f3gicas comp\u00f5em a trama.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>&nbsp;<\/p>\n<p>A narra\u00e7\u00e3o do texto divide claramente o g\u00eanero dos protagonistas. Existia o criador, do g\u00eanero masculino, e existia a irm\u00e3 dele, do g\u00eanero feminino. Ent\u00e3o temos essa rela\u00e7\u00e3o dial\u00f3gica entre homem e mulher. Veja:<\/p>\n<p>O Criador do Universo perguntou \u00e0 sua irm\u00e3:<\/p>\n<p>\u2013 O que faremos desse imenso universo&#8230; Temos mundo, e como faremos para criar os primeiros homens na terra?<\/p>\n<p>\u2013 Desde o princ\u00edpio eu sou o ser feminino. Respondeu a irm\u00e3.<\/p>\n<p>\u2013 \u00c9 isso mesmo! Eu sou homem e sei disso.<\/p>\n<p>Gabarito letra A.<\/p>\n<ol start=\"3\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>A autoria da narrativa sobre a cria\u00e7\u00e3o do mundo \u00e9 informada no texto<\/p>\n<p>(A) pela nomea\u00e7\u00e3o dos narradores e pelo destaque da forma cultural de tratamento.<\/p>\n<p>(B) pelo uso de marcadores discursivos e pela maneira social de rever\u00eancia aos anci\u00e3os.<\/p>\n<p>(C) pela indica\u00e7\u00e3o d\u00eaitica dos autores e pela \u00eanfase nos discursos diretos.<\/p>\n<p>(D) pelo emprego de aspas duplas e pela cita\u00e7\u00e3o da voz narrativa seguida de dois pontos.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>A narrativa \u00e9 atribu\u00edda aos s\u00e1bios:<\/p>\n<p><strong><em>Os nossos s\u00e1bios disseram (essa \u00e9 a voz narrativa, seguida de dois-pontos)<\/em><\/strong>:<\/p>\n<p>Ap\u00f3s esse trecho, todo o conte\u00fado est\u00e1 entre aspas, para indicar, pela pontua\u00e7\u00e3o, que essa narrativa \u00e9 reproduzida diretamente da fala dos s\u00e1bios. Em outras palavras, as aspas s\u00e3o utilizadas para indicar o discurso direto.<\/p>\n<p>Gabarito letra D.<\/p>\n<p>&nbsp;<\/p>\n<p>Leia o Texto 2 para responder \u00e0s quest\u00f5es de 04 a 06.<\/p>\n<p>&nbsp;<\/p>\n<p>Texto 2<\/p>\n<p>Eu comecei a fazer festa de reggae em 1975, com a minha radiola. Mas onde o reggae come\u00e7ou a se espalhar mesmo foi num s\u00edtio chamado Mato Grosso, por tr\u00e1s da Expoema. Ali foi o primeiro s\u00edtio que eu foquei. Depois eu toquei num festejo de Nossa Senhora do Bom Parto, que acontece todo ano, dia 2 de fevereiro, num lugar chamado Andiroba; fica antes de Mato Grosso. Foi dali que come\u00e7ou. A\u00ed, eu fui trazendo para os bairros e comecei a fazer festa no Salgueiro (antiga Escola de Samba no Sacav\u00e9m \u2013 n\u00e3o existe mais), na favela (s\u00f3 Samba) fazia festa no Sacav\u00e9m, tamb\u00e9m no festejo de Elzita (m\u00e3e-de-santo de um terreiro de mina no bairro Sacav\u00e9m) e trazia aquela multid\u00e3o do Retiro Natal, Monte Castelo, Liberdade, a turma que j\u00e1 participava das festas que eu fazia&#8230;<\/p>\n<p>DA SILVA, Carlos Benedito Rodrigues. Da terra das primaveras \u00e0 ilha do<\/p>\n<p>amor \u2013 reggae, lazer e identidade cultural. S\u00e3o Lu\u00eds: Pitomba, 2016. p.68.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"4\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>A composi\u00e7\u00e3o do Texto 2 \u00e9 caracterizada por uma sequ\u00eancia textual<\/p>\n<p>(A) argumentativa.<\/p>\n<p>(B) descritiva.<\/p>\n<p>(C) narrativa.<\/p>\n<p>(D) injuntiva.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>Temos um texto tipicamente narrativo, que traz uma sequ\u00eancia de a\u00e7\u00f5es sequenciais, com um narrador costurando um trecho de uma hist\u00f3ria.<\/p>\n<p>Observe que h\u00e1 verbos no pret\u00e9rito perfeito (comecei, toquei, fui), h\u00e1 uma clara divis\u00e3o temporal, com refer\u00eancias temporais (1975, depois, a\u00ed&#8230;). Gabarito letra C.<\/p>\n<ol start=\"5\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>Concorrem para o estabelecimento da coes\u00e3o do texto o emprego dos articuladores \u201cAli\u201d (linha 3), \u201cdali\u201d (linha 5) e \u201cA\u00ed\u201d (linha 5). O uso desses articuladores<\/p>\n<p>(A) torna o estilo lingu\u00edstico do texto informal e pr\u00f3ximo da oralidade.<\/p>\n<p>(B) denota desconhecimento dos recursos de articula\u00e7\u00e3o gramatical.<\/p>\n<p>(C) revela o n\u00edvel de escolaridade formal do autor do texto.<\/p>\n<p>(D) evidencia um marcador de varia\u00e7\u00e3o lingu\u00edstica diat\u00f3pica.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>Ali, Dali e A\u00ed s\u00e3o refer\u00eancias temporais t\u00edpicas da oralidade, da linguagem falada, informal, livre, espont\u00e2nea. Gabarito letra A.<\/p>\n<ol>\n<li>b) Usar linguagem informal n\u00e3o indica desconhecimento da l\u00edngua culta, pode ser apenas a linguagem adequada \u00e0 situa\u00e7\u00e3o espec\u00edfica de uma conversa descontra\u00edda.<\/li>\n<li>c) Vale o mesmo coment\u00e1rio acima.<\/li>\n<li>d) Varia\u00e7\u00e3o lingu\u00edstica diat\u00f3pica \u00e9 a varia\u00e7\u00e3o regional. N\u00e3o \u00e9 o que ocorre aqui, a varia\u00e7\u00e3o em tela \u00e9 situacional.<\/li>\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>Considerando-se os tempos verbais empregados no texto, infere-se que a temporalidade da narrativa \u00e9:<\/p>\n<p>(A) hipot\u00e9tica, com marcadores temporais imperfeitos do subjuntivo.<\/p>\n<p>(B) est\u00e1vel, com a predomin\u00e2ncia do pret\u00e9rito-perfeito do indicativo.<\/p>\n<p>(C) subjetiva, dependente da interpreta\u00e7\u00e3o do leitor.<\/p>\n<p>(D) psicol\u00f3gica, restrita \u00e0 imagina\u00e7\u00e3o do narrador.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>&nbsp;<\/p>\n<p>Essa quest\u00e3o complementa o reconhecimento do texto narrativo exigido na quest\u00e3o 4. Na narra\u00e7\u00e3o, h\u00e1 predomin\u00e2ncia de verbos no pret\u00e9rito perfeito, pois este indica que as a\u00e7\u00f5es foram conclu\u00eddas e sucedidas por outras a\u00e7\u00f5es, numa sequ\u00eancia. H\u00e1 tamb\u00e9m verbos no pret\u00e9rito imperfeito, indicando algumas a\u00e7\u00f5es que eram cont\u00ednuas\/reiteradas em determinados momentos da narrativa. Contudo, a divis\u00e3o temporal \u00e9 est\u00e1vel, homog\u00eanea, linear, uma a\u00e7\u00e3o imediatamente seguida de outra. Gabarito letra B.<\/p>\n<p>&nbsp;<\/p>\n<p>Leia o Texto 3 para responder \u00e0s quest\u00f5es de 7 a 10.<\/p>\n<p>&nbsp;<\/p>\n<p>Texto 3<\/p>\n<p>Resgatar as receitas \u00e9 convocar as \u201calmas\u201d com o perfume doce das damas-da-noite que habitam as frestas dos muros desgastados de adobe e as tortuosas ruas de pedras. Almas que habitam os quintais sombreados pelas mangueiras. \u00c9 evocar frases e sons retidos na argamassa das paredes de taipas. \u00c9 trazer novamente as luzes e o brilho das licoreiras de cristal e dos saraus no Pal\u00e1cio Conde dos Arcos. Ouvir ecos das vozes recitando poemas no Clube Liter\u00e1rio. \u00c9 sentir o calor do abra\u00e7o de despedida e o som dos p\u00e9s se arrastando na prociss\u00e3o. \u00c9, quase poss\u00edvel, ouvir o \u00f3rg\u00e3o e as velas escorrendo dos casti\u00e7ais na Igreja Boa Morte. Os latidos dos c\u00e3es no mercado. A voz long\u00ednqua do vendedor de bolo de arroz na tarde quente. As \u201calmas\u201d das coisas podem re-existir, tocar cora\u00e7\u00f5es, sussurrar lembran\u00e7as, habitar cozinhas modernas, pessoas diversas em outras cidades e pa\u00edses. S\u00f3 a Arte, aqui a arte culin\u00e1ria, permite esse tr\u00e2nsito, subvertendo o espa\u00e7o-tempo linear, conduzindo a mem\u00f3ria de cada um a lugares esquecidos, lugares nunca visitados \u2013 enriquecer o cotidiano trivial de cada um. Uma fatia de bolo pode sim, como diz Proust, conter toda uma inf\u00e2ncia, uma cidade, um estado e um pa\u00eds.<\/p>\n<p>LIMA, Ana Chrisitna da Rocha. N\u00e1dia K\u00f6ller \u2013 mem\u00f3rias e receitas de<\/p>\n<p>Goyaz. Goi\u00e2nia: Eclea, 2017. p. 13.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"7\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>Predominam no texto as caracter\u00edsticas da composi\u00e7\u00e3o liter\u00e1ria, e os sentidos, em todo o texto, s\u00e3o produzidos por meio do mecanismo da<\/p>\n<p>(A) pressuposi\u00e7\u00e3o.<\/p>\n<p>(B) sinestesia.<\/p>\n<p>(C) compara\u00e7\u00e3o.<\/p>\n<p>(D) sin\u00e9doque.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>O texto \u00e9 todo constru\u00eddo de met\u00e1foras, que s\u00e3o figuras de linguagem constitu\u00eddas de compara\u00e7\u00f5es impl\u00edcitas entre dois seres com caracter\u00edsticas em comum. Veja que poder\u00edamos at\u00e9 explicitar a compara\u00e7\u00e3o, devolvendo os conectivos comparativos:<\/p>\n<p><em>Resgatar as receitas \u00e9 <strong>como <\/strong>convocar as \u201calmas\u201d com o perfume doce das damas-da-noite que habitam as frestas dos muros desgastados de adobe e as tortuosas ruas de pedras. Almas que habitam os quintais sombreados pelas mangueiras. \u00c9 <strong>como<\/strong> evocar frases e sons retidos na argamassa das paredes de taipas.<\/em><\/p>\n<p>Muita gente achou que a resposta poderia ser \u201cSinestesia\u201d, porque h\u00e1 men\u00e7\u00e3o a \u201cperfume doce das damas da noite\u201d. Embora isso fa\u00e7a certo sentido, o enunciado diz \u201cpredominam\u201d e esta foi a \u00fanica vez em que ocorreu no texto uma mistura de sentidos, que caracteriza a Sinestesia. Gabarito letra C.<\/p>\n<ol start=\"8\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>O enunciado \u201c\u00c9 evocar frases e sons retidos na argamassa das paredes de taipas\u201d (linhas 3-4), situado no contexto geral do texto, tem o sentido de<\/p>\n<p>(A) evoca\u00e7\u00e3o de lembran\u00e7as.<\/p>\n<p>(B) express\u00e3o de ang\u00fastias.<\/p>\n<p>(C) intensifica\u00e7\u00e3o de desejos.<\/p>\n<p>(D) ensejo de esperan\u00e7as.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>Observem que o texto menciona lugares e cenas que ocorreram nesses lugares (igrejas, Pal\u00e1cios, Constru\u00e7\u00f5es). Essas lembran\u00e7as est\u00e3o \u2018entranhadas\u201d nos locais, em suas paredes, em suas \u00e1rvores, em suas ruas e seus objetos:<\/p>\n<p>Resgatar as receitas \u00e9 convocar as \u201calmas\u201d com o perfume doce das damas-da-noite que habitam as frestas dos <strong><em>muros<\/em><\/strong> desgastados de adobe e as tortuosas <strong><em>ruas<\/em><\/strong> de pedras. Almas que habitam os <strong><em>quintais<\/em><\/strong> sombreados pelas mangueiras. \u00c9 evocar frases e sons <strong><em>retidos na argamassa das paredes de taipas<\/em><\/strong>. \u00c9 trazer novamente as luzes e o brilho das licoreiras de cristal e dos saraus no <strong><em>Pal\u00e1cio<\/em><\/strong> Conde dos Arcos. Ouvir ecos das vozes recitando poemas no <strong><em>Clube Liter\u00e1rio<\/em><\/strong>. \u00c9 sentir o calor do abra\u00e7o de despedida e o som dos p\u00e9s se arrastando na p<strong><em>rociss\u00e3o<\/em><\/strong>. \u00c9, quase poss\u00edvel, ouvir o \u00f3rg\u00e3o e as <strong><em>velas escorrendo dos casti\u00e7ais na Igreja Boa Morte<\/em><\/strong>.<\/p>\n<p>Gabarito letra A.<\/p>\n<ol start=\"9\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>No enunciado \u201cUma fatia de bolo pode sim, como diz Proust, conter toda uma inf\u00e2ncia, uma cidade, um estado e um pa\u00eds\u201d (linha 14-15) \u201cuma fatia de bolo\u201d, por meton\u00edmia, \u00e9 o mesmo que<\/p>\n<p>(A) reposit\u00f3rio.<\/p>\n<p>(B) dep\u00f3sito.<\/p>\n<p>(C) estoque.<\/p>\n<p>(D) mem\u00f3ria.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>A fatia de bolo \u00e9 uma \u201creceita\u201d, que no contexto indica algo que pode evocar muitas mem\u00f3rias de cenas passadas. Veja:<\/p>\n<p>S\u00f3 a Arte, aqui a arte culin\u00e1ria, permite esse tr\u00e2nsito, subvertendo o espa\u00e7o-tempo linear, conduzindo a mem\u00f3ria de cada um a lugares esquecidos, lugares nunca visitados \u2013 enriquecer o cotidiano trivial de cada um. Uma fatia de bolo pode sim, como diz Proust, conter toda uma inf\u00e2ncia, uma cidade, um estado e um pa\u00eds.<\/p>\n<p>Ent\u00e3o, a \u201cfatia de bolo\u201d \u00e9 s\u00f3 uma substitui\u00e7\u00e3o do agente (o bolo) por seu efeito (fazer lembrar uma inf\u00e2ncia, uma cidade, um estado, um pa\u00eds).<\/p>\n<p>Gabarito letra D.<\/p>\n<ol start=\"10\">\n<li><strong>(UFG \/ SANEAGO \/ ANA. DE GEST\u00c3O &#8211; ADMINISTRADOR\/ 2018)<\/strong><\/li>\n<\/ol>\n<p>Em \u201cas frestas dos muros desgastados de adobe\u201d (linha 2), h\u00e1 um mecanismo de constru\u00e7\u00e3o de sentido que dificulta o entendimento da sequ\u00eancia destacada, porque<\/p>\n<p>(A) gera redund\u00e2ncia.<\/p>\n<p>(B) produz ambiguidade.<\/p>\n<p>(C) cria pressuposi\u00e7\u00e3o.<\/p>\n<p>(D) permite infer\u00eancia.<\/p>\n<p>Coment\u00e1rios:<\/p>\n<p>O texto gera ambiguidade, pois n\u00e3o sabemos se as frestas s\u00e3o \u201cde adobe\u201d, se os muros s\u00e3o \u201cde adobe\u201d, ou se os muros est\u00e3o desgastados \u201cde adobe\u201d (por causa do adobe).<\/p>\n<p>O fato \u00e9 que pouca gente sabia o que \u00e9 \u201cadobe\u201d, ent\u00e3o a ambiguidade ficaria ainda mais prejudicial ao texto.<\/p>\n<p>A prop\u00f3sito, vejamos:<\/p>\n<p>ADOBE- <strong>1.<\/strong>\u00a0Grilh\u00e3o preso a pe\u00e7a pesada de ferro, semelhante a um tijolo, us. antigamente para atar os p\u00e9s ou as pernas dos presos<\/p>\n<p>Gabarito letra B.<\/p>\n<p>Ent\u00e3o, \u00e9 isso!\u00a0Grande abra\u00e7o a todos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-104237\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png\" alt=\"\" width=\"724\" height=\"125\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png 724w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/01\/28150853\/M%C3%8DDIAS-SOCIAIS-FELIPE.png 610w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal. Bom dia. Postei o coment\u00e1rio da \u00faltima prova da SANEAGO, realizada recentemente. A banca cobrou muitas quest\u00f5es de intelec\u00e7\u00e3o textual, com refer\u00eancia a figuras de linguagem, interpreta\u00e7\u00e3o de texto, tipologia textual, vocabul\u00e1rio e varia\u00e7\u00e3o lingu\u00edstica. Vale a pena revisar tais temas! Abra\u00e7o e sucesso na prova! Leia o texto que segue para responder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-110833","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PROVA COMENTADA SANEAGO - PORTUGU\u00caS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROVA COMENTADA SANEAGO - PORTUGU\u00caS\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal. Bom dia. Postei o coment\u00e1rio da \u00faltima prova da SANEAGO, realizada recentemente. A banca cobrou muitas quest\u00f5es de intelec\u00e7\u00e3o textual, com refer\u00eancia a figuras de linguagem, interpreta\u00e7\u00e3o de texto, tipologia textual, vocabul\u00e1rio e varia\u00e7\u00e3o lingu\u00edstica. Vale a pena revisar tais temas! Abra\u00e7o e sucesso na prova! Leia o texto que segue para responder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-15T17:59:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-15T21:21:56+00:00\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"PROVA COMENTADA SANEAGO &#8211; PORTUGU\u00caS\",\"datePublished\":\"2018-03-15T17:59:23+00:00\",\"dateModified\":\"2018-03-15T21:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\"},\"wordCount\":2167,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\",\"name\":\"PROVA COMENTADA SANEAGO - PORTUGU\u00caS\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-03-15T17:59:23+00:00\",\"dateModified\":\"2018-03-15T21:21:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROVA COMENTADA SANEAGO &#8211; PORTUGU\u00caS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PROVA COMENTADA SANEAGO - PORTUGU\u00caS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/","og_locale":"pt_BR","og_type":"article","og_title":"PROVA COMENTADA SANEAGO - PORTUGU\u00caS","og_description":"Ol\u00e1, pessoal. Bom dia. Postei o coment\u00e1rio da \u00faltima prova da SANEAGO, realizada recentemente. A banca cobrou muitas quest\u00f5es de intelec\u00e7\u00e3o textual, com refer\u00eancia a figuras de linguagem, interpreta\u00e7\u00e3o de texto, tipologia textual, vocabul\u00e1rio e varia\u00e7\u00e3o lingu\u00edstica. Vale a pena revisar tais temas! Abra\u00e7o e sucesso na prova! Leia o texto que segue para responder [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2018-03-15T17:59:23+00:00","article_modified_time":"2018-03-15T21:21:56+00:00","author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"PROVA COMENTADA SANEAGO &#8211; PORTUGU\u00caS","datePublished":"2018-03-15T17:59:23+00:00","dateModified":"2018-03-15T21:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/"},"wordCount":2167,"commentCount":2,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/","name":"PROVA COMENTADA SANEAGO - PORTUGU\u00caS","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-03-15T17:59:23+00:00","dateModified":"2018-03-15T21:21:56+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-saneago-portugues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"PROVA COMENTADA SANEAGO &#8211; PORTUGU\u00caS"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/110833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=110833"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/110833\/revisions"}],"predecessor-version":[{"id":111579,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/110833\/revisions\/111579"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=110833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=110833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=110833"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=110833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}