{"id":110618,"date":"2018-03-11T20:31:28","date_gmt":"2018-03-11T23:31:28","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=110618"},"modified":"2018-03-12T09:33:02","modified_gmt":"2018-03-12T12:33:02","slug":"gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/","title":{"rendered":"Gabarito Extraoficial ABIN &#8211; Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP"},"content":{"rendered":"<p>Ol\u00e1, pessoal! Tudo joia?<\/p>\n<p>Nesse domingo (11\/03), tivemos a prova da ABIN.<\/p>\n<p>A prova veio pesada. N\u00e3o era para menos. O concurso da ABIN \u00e9 de alt\u00edssimo n\u00edvel, exigindo que os candidatos realmente demonstrassem conhecimento sobre as diferentes disciplinas.<\/p>\n<p>A seguir, comento as provas de Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia, Pol\u00edtica e Seguran\u00e7a e Direito Internacional P\u00fablico, apresentando um gabarito extraoficial. Vamos aguardar o gabarito oficial do CESPE para confirmar os nossos entendimentos.<\/p>\n<p>Abra\u00e7os,<\/p>\n<p>Ricardo Vale<\/p>\n<p><strong><em>&#8220;O segredo do sucesso \u00e9 a const\u00e2ncia no objetivo&#8221;.\u00a0<\/em><\/strong><\/p>\n<p><span style=\"color: #0000ff;\"><strong>DIREITO CONSTITUCIONAL<\/strong><\/span><\/p>\n<p><strong>No que se refere \u00e0 Administra\u00e7\u00e3o p\u00fablica e aos seus agentes, julgue os itens a seguir:<\/strong><\/p>\n<p><strong>33. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>De acordo com a Constitui\u00e7\u00e3o Federal de 1988, a partir de 2018, os gastos federais com a remunera\u00e7\u00e3o dos agentes p\u00fablicos federais s\u00f3 aumentar\u00e3o com base na infla\u00e7\u00e3o acumulada, levando em considera\u00e7\u00e3o o \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA).<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O examinador queria que o aluno tivesse algum conhecimento a respeito da Emenda Constitucional n\u00ba 95\/2016, que instituiu o Novo Regime Fiscal.<\/p>\n<p>Em linhas gerais, o que a EC n\u00ba 95\/2016 prev\u00ea \u00e9 um <strong><em>teto de gastos para a Administra\u00e7\u00e3o P\u00fablica Federal<\/em><\/strong>, aplicando-se a todos os Poderes (Executivo, Legislativo e Judici\u00e1rio), bem como a \u00f3rg\u00e3os com autonomia administrativa e financeira (Defensoria P\u00fablica da Uni\u00e3o, Minist\u00e9rio P\u00fablico da Uni\u00e3o e Tribunal de Contas da Uni\u00e3o).<\/p>\n<p>As despesas prim\u00e1rias, em cada um desses Poderes e \u00f3rg\u00e3os aut\u00f4nomos, <strong><em>n\u00e3o poder\u00e3o<\/em><\/strong>, a partir de 2018, <strong><em>superar o valor do limite do exerc\u00edcio anterior corrigido pelo IPCA<\/em><\/strong>. Cabe destacar que, quando se fala em \u201c<em>despesa prim\u00e1ria<\/em>\u201d, a refer\u00eancia \u00e9 ao conjunto de despesas com pessoal, custeio e investimentos.<\/p>\n<p>Voltando ao enunciado, a EC n\u00aa 95\/2016 <strong><em>n\u00e3o impede<\/em><\/strong> que os <u>gastos federais com remunera\u00e7\u00e3o<\/u> de agentes p\u00fablicos aumente mais do que infla\u00e7\u00e3o. O que ela pro\u00edbe que as despesas prim\u00e1rias da Uni\u00e3o, por Poder e \u00f3rg\u00e3o aut\u00f4nomo, cres\u00e7am em ritmo superior ao IPCA.<\/p>\n<p>Quest\u00e3o errada.<\/p>\n<p><strong>34. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>A Constitui\u00e7\u00e3o vigente proibiu o efeito repique, ato de computar uma vantagem pecuni\u00e1ria sobre outra \u2013 em cascata -, inclusive para os proventos de aposentadoria.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Segundo o art. 37, XIV, CF\/88, \u201c<em>os acr\u00e9scimos pecuni\u00e1rios percebidos por servidor p\u00fablico n\u00e3o ser\u00e3o computados nem acumulados para fins de concess\u00e3o de acr\u00e9scimos ulteriores\u201d. <\/em><\/p>\n<p>Jos\u00e9 Afonso da Silva, ao comentar esse dispositivo, explica que ele consiste na <strong><em>proibi\u00e7\u00e3o<\/em><\/strong> dos chamados <strong><em>efeitos \u201crepic\u00e3o&#8221; e \u201crepiqu\u00edssimo\u201d<\/em><\/strong>, que consistem na incid\u00eancia de adicionais sobre adicionais. Veda-se, assim, a perniciosa pr\u00e1tica dos \u201c<em>adicionais em cascata<\/em>\u201d. Segundo o STJ, a veda\u00e7\u00e3o ao \u201cefeito repique\u201d alcan\u00e7a, inclusive, os proventos de aposentadoria.<\/p>\n<p>Quest\u00e3o correta.<\/p>\n<p><strong>35. (CESPE \/ ABIN \u2013 2018) O militar da ativa ser\u00e1 transferido para a reserva, caso acumule dois cargos privativos de profissionais de sa\u00fade, mesmo que haja compatibilidade de hor\u00e1rios.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>\u00c9 poss\u00edvel que o militar da ativa acumule 2 (dois) cargos privativos de profissionais de sa\u00fade, desde que haja compatibilidade de hor\u00e1rios. Ele n\u00e3o ser\u00e1 transferido para a reserva em virtude disso. Quest\u00e3o errada.<\/p>\n<p><strong>36. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>O est\u00e1gio probat\u00f3rio inicia-se na data da posse do agente p\u00fablico, findando-se com o t\u00e9rmino do prazo de tr\u00eas anos. <\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O est\u00e1gio probat\u00f3rio tem in\u00edcio com a <strong><em>entrada em exerc\u00edcio<\/em><\/strong> do servidor p\u00fablico. Sua dura\u00e7\u00e3o \u00e9 de 3 (tr\u00eas) anos. Quest\u00e3o errada.<\/p>\n<p><strong>Julgue os itens que se seguem, relativos ao Poder Legislativo e \u00e0 defesa do Estado e das institui\u00e7\u00f5es democr\u00e1ticas.<\/strong><\/p>\n<p><strong>37. (CESPE \/ ABIN \u2013 2018) Segundo a doutrina, o estado de s\u00edtio deve estar embasado no princ\u00edpio fundante da necessidade.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>\u00c9 exatamente o que diz a doutrina. Tanto o estado de defesa quanto o estado de s\u00edtio devem obedecer os princ\u00edpios da <strong><em>necessidade, temporariedade e proporcionalidade<\/em><\/strong>. Quest\u00e3o correta.<\/p>\n<p><strong>38. (CESPE \/ ABIN \u2013 2018) O policiamento naval \u00e9 atribui\u00e7\u00e3o privativa da Marinha de Guerra, atividade de natureza meramente militar.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>No HC n\u00ba 68.928\/PA, o STF decidiu que a atividade de policiamento naval \u00e9 uma atividade secund\u00e1ria da Marinha de Guerra, possuindo <strong><em>car\u00e1ter meramente administrativo<\/em><\/strong>. N\u00e3o se pode atribuir a essa fun\u00e7\u00e3o natureza militar, apesar de ser desempenhada pela Marinha de Guerra. Quest\u00e3o errada.<\/p>\n<p><strong>39. (CESPE \/ ABIN \u2013 2018) \u00c9 necess\u00e1ria licen\u00e7a da Casa legislativa para que o parlamentar possa incorporar-se \u00e0s For\u00e7as Armadas, mesmo em tempos de guerra.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Segundo o art. 53, \u00a7 7\u00ba, CF\/88, \u201c<em>a incorpora\u00e7\u00e3o \u00e0s For\u00e7as Armadas de Deputados e Senadores, embora militares e <u>ainda que em tempo de guerra<\/u>, depender\u00e1 de <strong>pr\u00e9via licen\u00e7a<\/strong> da Casa respectiva<\/em>\u201d. Quest\u00e3o correta.<\/p>\n<p><strong>40. (CESPE \/ ABIN \u2013 2018) Durante o estado de defesa, \u00e9 permitida a incomunicabilidade do preso pelo prazo de at\u00e9 dez dias<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Na vig\u00eancia do estado de defesa, <strong><em>\u00e9 vedada<\/em><\/strong> a incomunicabilidade do preso (art. 136, \u00a7 3\u00ba, IV, CF\/88). Quest\u00e3o errada.<\/p>\n<p><strong>Acerca de ci\u00eancia e tecnologia, julgue os itens subsequentes.<\/strong><\/p>\n<p><strong>41. (CESPE \/ ABIN \u2013 2018) A Uni\u00e3o dever\u00e1 estabelecer pol\u00edtica pr\u00f3pria de incentivo \u00e0 pesquisa tecnol\u00f3gica preponderantemente em favor de pa\u00edses intitulados menos desenvolvidos<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Segundo o art. 218, \u00a7 2\u00ba, \u201c<em>a pesquisa tecnol\u00f3gica voltar-se-\u00e1 preponderantemente para a <u>solu\u00e7\u00e3o dos problemas brasileiros<\/u> e para o desenvolvimento do sistema produtivo nacional e regional<\/em>\u201d. Quest\u00e3o errada.<\/p>\n<p><strong>42. (CESPE \/ ABIN \u2013 2018) O Sistema Nacional de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o ser\u00e1 organizado em regime de coopera\u00e7\u00e3o com entidades p\u00fablicas ou privadas, podendo os estados, o Distrito Federal e os munic\u00edpios legislar concorrentemente sobre suas peculiaridades<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Essa quest\u00e3o est\u00e1 baseada no art. 219-B, CF\/88:<\/p>\n<p style=\"padding-left: 30px;\"><strong><em>Art. 219-B.<\/em><\/strong><em> O Sistema Nacional de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (SNCTI) ser\u00e1 organizado em <u>regime de colabora\u00e7\u00e3o entre entes, tanto p\u00fablicos quanto privados<\/u>, com vistas a promover o desenvolvimento cient\u00edfico e tecnol\u00f3gico e a inova\u00e7\u00e3o.\u00a0\u00a0<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>\u00a7 1\u00ba<\/em><\/strong><em> Lei federal dispor\u00e1 sobre as normas gerais do SNCTI.<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>\u00a7 2\u00ba<\/em><\/strong><em> Os <strong><u>Estados, o Distrito Federal e os Munic\u00edpios<\/u><\/strong> <u>legislar\u00e3o concorrentemente<\/u> sobre suas peculiaridades.<\/em><\/p>\n<p>Quest\u00e3o concorrente.<\/p>\n<p><strong>43. (CESPE \/ ABIN \u2013 2018) As empresas de fomento \u00e0 inova\u00e7\u00e3o poder\u00e3o receber tratamento priorit\u00e1rio em rela\u00e7\u00e3o a empresas de outros segmentos, inclusive pelo compartilhamento dos recursos humanos de \u00f3rg\u00e3os p\u00fablicos e de entidades privadas<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>N\u00e3o \u00e9 o que prev\u00ea o texto constitucional. O tratamento priorit\u00e1rio do Estado ser\u00e1 concedido \u00e0 <strong><em>pesquisa cient\u00edfica b\u00e1sica e tecnol\u00f3gica<\/em><\/strong> (art. 216, \u00a7 1\u00ba, CF\/88), e n\u00e3o \u00e0s empresas de fomento \u00e0 inova\u00e7\u00e3o em detrimento de outras empresas.<\/p>\n<p>Segundo o art. 219-A, \u201c<em>a Uni\u00e3o, os Estados, o Distrito Federal e os Munic\u00edpios poder\u00e3o firmar <u>instrumentos de coopera\u00e7\u00e3o<\/u> com \u00f3rg\u00e3os e entidades p\u00fablicos e com entidades privadas, <u>inclusive para o compartilhamento de recursos humanos especializados<\/u> e capacidade instalada, para a execu\u00e7\u00e3o de projetos de pesquisa, de desenvolvimento cient\u00edfico e tecnol\u00f3gico e de inova\u00e7\u00e3o, mediante contrapartida financeira ou n\u00e3o financeira assumida pelo ente benefici\u00e1rio, na forma da lei<\/em>\u201d.<\/p>\n<p>Quest\u00e3o errada.<\/p>\n<p><span style=\"color: #0000ff;\"><strong>LEGISLA\u00c7\u00c3O DE INTELIG\u00caNCIA<\/strong><\/span><\/p>\n<p><strong>Acerca da Estrat\u00e9gia e da Pol\u00edtica Nacional de Intelig\u00eancia, julgue os itens a seguir.<\/strong><\/p>\n<p><strong>44. (CESPE \/ ABIN \u2013 2018) A intelig\u00eancia \u00e9 uma atividade que deve possuir abrang\u00eancia para identificar oportunidades \u00e0 popula\u00e7\u00e3o do pa\u00eds. <\/strong><\/p>\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n<p>A abrang\u00eancia \u00e9 um pressuposto da atividade de intelig\u00eancia. Segundo a PNI, a atividade de Intelig\u00eancia deve possuir abrang\u00eancia tal que lhe <strong><em>possibilite identificar amea\u00e7as, riscos e oportunidades<\/em><\/strong> <u>ao Pa\u00eds e \u00e0 sua popula\u00e7\u00e3o<\/u>. Quest\u00e3o correta.<\/p>\n<p><strong>45. (CESPE \/ ABIN \u2013 2018) Enquanto a intelig\u00eancia \u00e9 a atividade que tem o objetivo de evitar as a\u00e7\u00f5es de intelig\u00eancia adversa, a contraintelig\u00eancia difunde conhecimentos sobre situa\u00e7\u00f5es que aconteceram dentro do territ\u00f3rio nacional de imediata influ\u00eancia sobre a a\u00e7\u00e3o governamental<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>O examinador inverteu os conceitos de \u201c<em>intelig\u00eancia<\/em>\u201d e \u201c<em>contraintelig\u00eancia<\/em>\u201d. A seguir, transcrevo as defini\u00e7\u00f5es da Pol\u00edtica Nacional de Intelig\u00eancia:<\/p>\n<p style=\"padding-left: 30px;\"><strong><em>I \u2013<\/em><\/strong><em>\u00a0<strong>Intelig\u00eancia:\u00a0<\/strong>atividade que objetiva produzir e difundir conhecimentos \u00e0s autoridades competentes, relativos a fatos e situa\u00e7\u00f5es que ocorram dentro e fora do territ\u00f3rio nacional, de imediata ou potencial influ\u00eancia sobre o processo decis\u00f3rio, a a\u00e7\u00e3o governamental e a salvaguarda da sociedade e do Estado;\u00a0<strong>\u00a0<\/strong><\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>II \u2013<\/em><\/strong><em>\u00a0<strong>Contraintelig\u00eancia:\u00a0<\/strong>atividade que objetiva prevenir, detectar, obstruir e neutralizar a Intelig\u00eancia adversa e as a\u00e7\u00f5es que constituam amea\u00e7a \u00e0 salvaguarda de dados, conhecimentos, pessoas, \u00e1reas e instala\u00e7\u00f5es de interesse da sociedade e do Estado.<\/em><\/p>\n<p>Quest\u00e3o errada.<\/p>\n<p><strong>46. (CESPE \/ ABIN \u2013 2018) A supervis\u00e3o da Pol\u00edtica Nacional de Intelig\u00eancia \u00e9 exercida pelo Gabinete de Seguran\u00e7a Institucional da Presid\u00eancia da Rep\u00fablica, cabendo a coordena\u00e7\u00e3o da atividade de intelig\u00eancia federal \u00e0 Ag\u00eancia Brasileira de Intelig\u00eancia (ABIN)<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>A supervis\u00e3o da execu\u00e7\u00e3o da Pol\u00edtica Nacional de Intelig\u00eancia (PNI) <strong><em>\u00e9 compet\u00eancia da CREDEN<\/em><\/strong> (C\u00e2mara de Rela\u00e7\u00f5es Exteriores e Defesa Nacional, do Conselho de Governo). O <strong><em>GSI<\/em><\/strong> (Gabinete de Seguran\u00e7a Institucional) \u00e9 respons\u00e1vel por coordenar as atividades de intelig\u00eancia federal. Quest\u00e3o errada.<\/p>\n<p><strong>47. (CESPE \/ ABIN \u2013 2018) O fortalecimento da educa\u00e7\u00e3o \u00e0 dist\u00e2ncia \u00e9 um dos objetivos estrat\u00e9gicos a serem atingidos pelo Sistema Brasileiro de Intelig\u00eancia (SISBIN) no cumprimento de sua miss\u00e3o<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>\u00c9 objetivo estrat\u00e9gico previsto na ENINT \u201c<em>fortalecer a educa\u00e7\u00e3o \u00e0 dist\u00e2ncia (EAD)<\/em>\u201d. Quest\u00e3o correta.<\/p>\n<p><strong>Com rela\u00e7\u00e3o ao SISBIN e \u00e0 estrutura regimental da ABIN, julgue os itens a seguir:<\/strong><\/p>\n<p><strong>48. (CESPE \/ ABIN \u2013 2018) \u00c0 ABIN, \u00f3rg\u00e3o central do SISBIN, cabe a representa\u00e7\u00e3o desse sistema perante o \u00f3rg\u00e3o de controle externo da atividade de intelig\u00eancia<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>Segundo o art. 10, IX, do Decreto n\u00ba 4.376\/2002, na condi\u00e7\u00e3o de \u00f3rg\u00e3o central do SISBIN, a ABIN tem a seu cargo representar o SISBIN perante o \u00f3rg\u00e3o de controle externo da atividade de intelig\u00eancia. Quest\u00e3o correta.<\/p>\n<p><strong>49. (CESPE \/ ABIN \u2013 2018) A incumb\u00eancia da ABIN de integrar as informa\u00e7\u00f5es e os conhecimentos fornecidos pelos membros do SISBIN inclui as atividades operacionais necess\u00e1rias ao planejamento e \u00e0 condu\u00e7\u00e3o das opera\u00e7\u00f5es militares das For\u00e7as Armadas, quando houver interesse da defesa nacional<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>Segundo o art. 10, par\u00e1grafo \u00fanico, do Decreto n\u00ba 4.376\/2002, <strong><em>excetua-se das atribui\u00e7\u00f5es da ABIN<\/em><\/strong> \u201c<em>a atividade de intelig\u00eancia operacional necess\u00e1ria ao planejamento e \u00e0 condu\u00e7\u00e3o de campanhas e opera\u00e7\u00f5es militares das For\u00e7as Armadas, no interesse da defesa nacional<\/em>\u201d. Quest\u00e3o errada.<\/p>\n<p><strong>50. (CESPE \/ ABIN \u2013 2018) Se a Corregedoria-Geral da ABIN receber representa\u00e7\u00e3o sobre irregularidade ou infra\u00e7\u00e3o disciplinar cometida por agente p\u00fablico em exerc\u00edcio na pr\u00f3pria ag\u00eancia, ela ter\u00e1 a compet\u00eancia de apur\u00e1-la, al\u00e9m de caber a ela o controle das atividades de correi\u00e7\u00e3o dos \u00f3rg\u00e3os do SISBIN<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>A Corregedoria-Geral da ABIN tem compet\u00eancia para \u201c<em>receber e apurar den\u00fancias e representa\u00e7\u00f5es sobre irregularidades e infra\u00e7\u00f5es disciplinares cometidas por agentes p\u00fablicos em exerc\u00edcio na ABIN<\/em>\u201d (art. 7\u00ba, I, Decreto 8.905\/2016). Al\u00e9m disso, \u00e9 respons\u00e1vel por controlar as atividades de correi\u00e7\u00e3o da ABIN (art. 7\u00ba, II, Decreto 8.905\/2016). Suas atribui\u00e7\u00f5es <strong><em>n\u00e3o alcan\u00e7am outros \u00f3rg\u00e3os do SISBIN<\/em><\/strong>. Quest\u00e3o errada.<\/p>\n<p><strong>Julgue os seguintes itens, referentes \u00e0 estrutura\u00e7\u00e3o do plano de carreira e cargos da ABIN.<\/strong><\/p>\n<p><strong>51. (CESPE \/ ABIN \u2013 2018) A progress\u00e3o funcional de um oficial de intelig\u00eancia ocorre quando ele passa do \u00faltimo padr\u00e3o de uma classe para o primeiro padr\u00e3o da classe imediatamente superior<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>O enunciado descreveu o conceito de \u201c<em>promo\u00e7\u00e3o funcional<\/em>\u201d. Era importante que o aluno soubesse a diferen\u00e7a entre progress\u00e3o e promo\u00e7\u00e3o. Esses conceitos poderiam ser retirados do art. 16, \u00a7 1\u00ba, Lei n\u00ba 11.776\/2008. Veja:<\/p>\n<p style=\"padding-left: 30px;\"><strong>a)<\/strong> <strong>Progress\u00e3o funcional<\/strong>: \u00e9 a passagem do servidor para o padr\u00e3o de vencimento imediatamente superior dentro de uma mesma classe<\/p>\n<p style=\"padding-left: 30px;\"><strong>b)<\/strong> <strong>Promo\u00e7\u00e3o funcional<\/strong>: a passagem do servidor do \u00faltimo padr\u00e3o de uma classe para o primeiro padr\u00e3o da classe imediatamente superior.<\/p>\n<p>Quest\u00e3o errada.<\/p>\n<p><strong>52. (CESPE \/ ABIN \u2013 2018) A propriedade intelectual decorrente do exerc\u00edcio das atribui\u00e7\u00f5es de um oficial de intelig\u00eancia \u00e9 exclusiva da Uni\u00e3o, bem como as decorrentes das atividades de alunos de cursos ministrados pela ABIN<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>\u00c9 exatamente o que prev\u00ea o art. 46, da Lei n\u00ba 11.776\/2008:<\/p>\n<p style=\"padding-left: 30px;\"><strong><em>Art. 46.\u00a0<\/em><\/strong><em> A propriedade intelectual criada por qualquer agente p\u00fablico em decorr\u00eancia do exerc\u00edcio de suas atribui\u00e7\u00f5es ou na condi\u00e7\u00e3o de representante da ABIN pertence exclusivamente \u00e0 Uni\u00e3o, a quem caber\u00e1 exercer a eventual prote\u00e7\u00e3o ou a divulga\u00e7\u00e3o do seu conte\u00fado, conforme disposto em ato do Diretor-Geral da ABIN.<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>Par\u00e1grafo \u00fanico.\u00a0<\/em><\/strong><em> O disposto no\u00a0caput\u00a0deste artigo aplica-se aos alunos de cursos ministrados pela ABIN, inclusive aos do curso de forma\u00e7\u00e3o integrante do concurso p\u00fablico para ingresso nos cargos de que tratam os incisos I e II do\u00a0caput do art. 2o\u00a0desta Lei<\/em>.<\/p>\n<p>Quest\u00e3o correta.<\/p>\n<p><strong>\u00a0<\/strong><strong>Acerca da Lei de Acesso \u00e0 Informa\u00e7\u00e3o (Lei n\u00ba 12.527\/2011), julgue os itens a seguir.<\/strong><\/p>\n<p><strong>53. (CESPE \/ ABIN \u2013 2018) No \u00e2mbito das For\u00e7as Armadas, a prerrogativa exclusiva de classifica\u00e7\u00e3o de uma informa\u00e7\u00e3o como ultrassecreta \u00e9 do Ministro de Estado da Defesa, podendo os comandantes da Marinha, do Ex\u00e9rcito e da Aeron\u00e1utica classic\u00e1-la como secreta ou reservada<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>Os Comandantes da Marinha, do Ex\u00e9rcito e da Aeron\u00e1utica t\u00eam compet\u00eancia para classificar informa\u00e7\u00f5es no <strong><em>grau ultrassecreto<\/em><\/strong> (art. 27, I, al\u00ednea \u201c<em>d<\/em>\u201d, da Lei n\u00ba 12.527\/2011). Quest\u00e3o errada.<\/p>\n<p><strong>54. (CESPE \/ ABIN \u2013 2018) Todos os \u00f3rg\u00e3os e entidades devem manter para consulta p\u00fablica, em suas sedes, exemplar de publica\u00e7\u00e3o anual do rol de documentos classificados em cada grau de sigilo, que devem ter identifica\u00e7\u00e3o para refer\u00eancia futura<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>\u00c9 o que prev\u00ea o art. 30, II, da Lei de Acesso \u00e0 Informa\u00e7\u00e3o. Veja:<\/p>\n<p style=\"padding-left: 30px;\"><strong><em>Art. 30.\u00a0<\/em><\/strong><em> A autoridade m\u00e1xima de cada \u00f3rg\u00e3o ou entidade publicar\u00e1, anualmente, em s\u00edtio \u00e0 disposi\u00e7\u00e3o na internet e destinado \u00e0 veicula\u00e7\u00e3o de dados e informa\u00e7\u00f5es administrativas, nos termos de regulamento:\u00a0<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>(&#8230;)\u00a0<\/em><\/strong><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>II &#8211;<\/em><\/strong><em> rol de documentos classificados em cada grau de sigilo, com identifica\u00e7\u00e3o para refer\u00eancia futura;\u00a0<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong>(&#8230;)<\/strong><\/p>\n<p style=\"padding-left: 30px;\"><strong>\u00a7 1<u><sup>o<\/sup><\/u>\u00a0<\/strong> Os \u00f3rg\u00e3os e entidades dever\u00e3o manter exemplar da publica\u00e7\u00e3o prevista no\u00a0<b>caput<\/b>\u00a0para consulta p\u00fablica em suas sedes.<\/p>\n<p>Quest\u00e3o correta.<\/p>\n<p><span style=\"color: #0000ff;\"><strong>POL\u00cdTICA E SEGURAN\u00c7A (ITEM 16)<\/strong><\/span><\/p>\n<p><strong>Julgue os itens que se seguem \u00e0 luz da Lei n\u00ba 6.634\/1979, que disp\u00f5e sobre a Faixa de Fronteira:<\/strong><\/p>\n<p><strong>121. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>S\u00e3o atividades que requerem anu\u00eancia pr\u00e9via do Conselho Nacional de Seguran\u00e7a para sua consecu\u00e7\u00e3o na Faixa de Fronteira a aliena\u00e7\u00e3o ou concess\u00e3o de terras p\u00fablicas; a instala\u00e7\u00e3o de meios de comunica\u00e7\u00e3o e esta\u00e7\u00f5es geradoras destinadas \u00e0 explora\u00e7\u00e3o de servi\u00e7os de radiodifus\u00e3o de sons ou radiodifus\u00e3o de sons e imagens; e a execu\u00e7\u00e3o de atividades de pesquisa, lavra, explora\u00e7\u00e3o e aproveitamento de recursos minerais por empresas<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>\u00c9 exatamente o que se extrai da leitura do art. 2\u00ba, da Lei n\u00ba 6.634\/1979:<\/p>\n<p style=\"padding-left: 30px;\"><strong><em>Art. 2\u00ba.<\/em><\/strong><em> Salvo com o assentimento pr\u00e9vio do Conselho de Seguran\u00e7a Nacional, ser\u00e1 vedada, na Faixa de Fronteira, a pr\u00e1tica dos atos referentes a:<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>I &#8211;<\/em><\/strong><em> aliena\u00e7\u00e3o e concess\u00e3o de terras p\u00fablicas, abertura de vias de transporte e instala\u00e7\u00e3o de meios de comunica\u00e7\u00e3o destinados \u00e0 explora\u00e7\u00e3o de servi\u00e7os de radiodifus\u00e3o de sons ou radiodifus\u00e3o de sons e imagens;<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>(&#8230;)<\/em><\/strong><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>IV &#8211;<\/em><\/strong><em> instala\u00e7\u00e3o de empresas que se dedicarem \u00e0s seguintes atividades:<\/em><\/p>\n<p style=\"padding-left: 30px;\"><strong><em>a)<\/em><\/strong><em> pesquisa, lavra, explora\u00e7\u00e3o e aproveitamento de recursos minerais, salvo aqueles de imediata aplica\u00e7\u00e3o na constru\u00e7\u00e3o civil, assim classificados no C\u00f3digo de Minera\u00e7\u00e3o<\/em>;<\/p>\n<p>O CESPE dever\u00e1 se basear na literalidade da norma e, por isso, a quest\u00e3o deve ser considerada correta.<\/p>\n<p>Entretanto, <strong><em>entendo que cabe recurso<\/em><\/strong>, uma vez que <strong><em>n\u00e3o existe mais o Conselho de Seguran\u00e7a Nacional<\/em><\/strong>, que foi sucedido pelo Conselho de Defesa Nacional (CDN). Acredito que a men\u00e7\u00e3o ao Conselho de Seguran\u00e7a Nacional, \u00f3rg\u00e3o inexistente atualmente, prejudicou o julgamento objetivo do item. Por isso, a quest\u00e3o merece ser anulada.<\/p>\n<p>Quest\u00e3o correta.<\/p>\n<p><strong>122. (CESPE\/ABIN \u2013 2018) <\/strong><strong>S\u00e3o atividades terminantemente vedadas na Faixa de Fronteira o estabelecimento de ind\u00fastrias que interessem \u00e0 Seguran\u00e7a Nacional; a aliena\u00e7\u00e3o e concess\u00e3o de terras p\u00fablicas a estrangeiros; e a posse por estrangeiros, como pessoa natural ou jur\u00eddica, de direitos de propriedade de im\u00f3veis rurais<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>N\u00e3o se pode dizer que essas atividades s\u00e3o terminantemente vedadas na Faixa de Fronteira. Elas podem ocorrer, desde que com o <strong><em>assentimento pr\u00e9vio<\/em><\/strong> do Conselho de Defesa Nacional. Quest\u00e3o errada.<\/p>\n<p><span style=\"color: #0000ff;\"><strong>DIREITO INTERNACIONAL P\u00daBLICO<\/strong><\/span><\/p>\n<p><strong>Sabendo que a Corte Internacional de Justi\u00e7a (CIJ) foi estabelecida pela Carta das Na\u00e7\u00f5es Unidas e \u00e9 considerada o principal \u00f3rg\u00e3o judici\u00e1rio no \u00e2mbito da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas, sendo poss\u00edvel extrair fontes do direito internacional p\u00fablico (DIP) do seu estatuto, julgue os itens subsecutivos<\/strong>.<\/p>\n<p><strong>123. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Na hip\u00f3tese de uma obriga\u00e7\u00e3o ser fundamentada no costume internacional e ser exigida em face de determinado Estado, este n\u00e3o poder\u00e1 defender-se invocando reserva feita em tratado com o mesmo conte\u00fado da norma consuetudin\u00e1ria<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>A <strong><em>parte que invoca o costume<\/em><\/strong> perante um Tribunal Internacional tem o <u>dever de provar a sua exist\u00eancia<\/u>, isto \u00e9, cabe a ela o \u00f4nus da prova. Para se defender, o outro Estado pode argumentar que <u>n\u00e3o est\u00e1 vinculado ao costume<\/u>, uma vez que formular reserva a tratado com o mesmo conte\u00fado da norma consuetudin\u00e1rio. Esse Estado ser\u00e1, nessa situa\u00e7\u00e3o, um objetor persistente. Quest\u00e3o errada.<\/p>\n<p><strong>124. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>A <em>opinio juris<\/em> atesta a obrigatoriedade do costume internacional na medida em que o simples fato de o Estado deixar de agir representa infra\u00e7\u00e3o \u00e0 norma costumeira. <\/strong><\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>A <em>opinio juris<\/em> \u00e9 o <strong><em>elemento subjetivo<\/em><\/strong> (psicol\u00f3gico) do costume internacional. \u00c9 a cren\u00e7a de que aquela pr\u00e1tica \u00e9 decorrente de um <strong><em>dever jur\u00eddico<\/em><\/strong>. Pode-se dizer, desse modo, que a <em>opinio juris<\/em> atesta a obrigatoriedade do costume internacional. Caso o Estado deixe de agir conforme aquela pr\u00e1tica, ele estar\u00e1 infringindo a norma costumeira. Quest\u00e3o correta.<\/p>\n<p><strong>125. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Por n\u00e3o se encontrarem inseridos no estatuto da CIJ, os atos unilaterais dos Estados, como o ato de reconhecimento do nascimento de outro Estado, possuem natureza pol\u00edtica, n\u00e3o se revestindo de obrigatoriedade normativa.<\/strong><\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>Os atos unilaterais dos Estados s\u00e3o reconhecidos como fontes de DIP, apesar de n\u00e3o estarem expressos no art. 38, do Estatuto da CIJ. Quest\u00e3o errada.<\/p>\n<p><strong>De acordo com a Conven\u00e7\u00e3o de Viena sobre o Direito dos Tratados, conclu\u00edda em 23 de maio de 1969, define-se por tratado internacional o \u201cacordo internacional conclu\u00eddo por escrito entre Estados e regido pelo direito internacional, quer conste de um instrumento \u00fanico, quer de dois ou mais instrumentos conexos, qualquer que seja sua denomina\u00e7\u00e3o espec\u00edfica. No que se refere a esse assunto, julgue os itens seguintes:<\/strong><\/p>\n<p><strong>126. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Reserva \u00e9 uma declara\u00e7\u00e3o unilateral feita expressamente com essa denomina\u00e7\u00e3o por um Estado no momento da assinatura, ratifica\u00e7\u00e3o, aceita\u00e7\u00e3o ou aprova\u00e7\u00e3o de um tratado, ou da ades\u00e3o a determinado tratado, com o objetivo de excluir ou modificar o efeito jur\u00eddico de certas disposi\u00e7\u00f5es do tratado no que se refere a sua aplica\u00e7\u00e3o a esse Estado.<\/strong><\/p>\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n<p>Pegadinha maldosa! Segundo a CV\/69, <strong><em>reserva<\/em><\/strong> significa uma declara\u00e7\u00e3o unilateral, <u>qualquer que seja a sua reda\u00e7\u00e3o ou denomina\u00e7\u00e3o<\/u>, feita por um Estado ao assinar, ratificar, aceitar ou aprovar um tratado, ou a ele aderir, com o objetivo de excluir ou modificar o efeito jur\u00eddico de certas disposi\u00e7\u00f5es do tratado em sua aplica\u00e7\u00e3o a esse Estado.<\/p>\n<p>Quest\u00e3o errada.<\/p>\n<p><strong>127. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>O Estado brasileiro reconhece a possibilidade de aplica\u00e7\u00e3o provis\u00f3ria de um tratado enquanto ele n\u00e3o entrar em vigor, desde que o pr\u00f3prio tratado assim disponha ou desde que os Estados negociadores assim tenham acordado por outra forma.<\/strong><\/p>\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n<p>O Brasil formulou reservas ao art. 25, da CV\/69, que estabelece a aplica\u00e7\u00e3o provis\u00f3ria de tratados. Assim, pode-se dizer que o Estado brasileiro <strong><em>n\u00e3o reconhece<\/em><\/strong> a possibilidade de aplica\u00e7\u00e3o provis\u00f3ria de um tratado. Quest\u00e3o errada.<\/p>\n<p><strong>128. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Admite-se excepcionalmente que um Estado possa invocar as disposi\u00e7\u00f5es de seu direito interno para o fim de justificar o inadimplemento de um tratado<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>Existe, sim, a <strong><em>possibilidade excepcional<\/em><\/strong> de que o Estado invoque disposi\u00e7\u00f5es de seu direito interno para justificar o inadimplemento de um tratado. Isso ser\u00e1 poss\u00edvel no caso de uma <strong><em>\u201cratifica\u00e7\u00e3o imperfeita\u201d<\/em><\/strong>, conforme previsto no art. 46, CV\/69. Veja que essa ressalva \u00e9 feita pelo art. 27, CV\/69. Abaixo transcrevemos os mencionados dispositivos:<\/p>\n<p style=\"padding-left: 30px;\"><strong>Artigo 27 Direito Interno e Observ\u00e2ncia de Tratados\u00a0<\/strong><\/p>\n<p style=\"padding-left: 30px;\">Uma parte n\u00e3o pode invocar as disposi\u00e7\u00f5es de seu direito interno para justificar o inadimplemento de um tratado. <u>Esta regra n\u00e3o prejudica o artigo 46<\/u>.<\/p>\n<p style=\"padding-left: 30px;\"><strong>(\u2026)<\/strong><\/p>\n<p style=\"padding-left: 30px;\"><strong>Artigo 46 Disposi\u00e7\u00f5es do Direito Interno sobre Compet\u00eancia para Concluir Tratados\u00a0<\/strong><\/p>\n<p style=\"padding-left: 30px;\">1. Um Estado n\u00e3o pode invocar o fato de que seu consentimento em obrigar-se por um tratado foi expresso em viola\u00e7\u00e3o de uma disposi\u00e7\u00e3o de seu direito interno sobre compet\u00eancia para concluir tratados, a n\u00e3o ser que essa viola\u00e7\u00e3o fosse manifesta e dissesse respeito a uma norma de seu direito interno de import\u00e2ncia fundamental.<\/p>\n<p>Quest\u00e3o correta.<\/p>\n<p><strong>129. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Ao defender a independ\u00eancia do direito internacional em rela\u00e7\u00e3o ao direito nacional, os dualistas o fazem levando em considera\u00e7\u00e3o exclusivamente as hip\u00f3teses de conflito entre um tratado em uma norma de direito interno<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>Para os dualistas, <u>n\u00e3o h\u00e1 que se falar em conflito<\/u> entre o direito internacional e o direito interno. Quest\u00e3o errada.<\/p>\n<p><strong>Considerando que a Conven\u00e7\u00e3o de Palermo (Decreto n\u00ba 5.015\/2004, que promulga a Conven\u00e7\u00e3o das Na\u00e7\u00f5es Unidas contra o Crime Organizado Transnacional) promove a coopera\u00e7\u00e3o para prevenir e combater mais eficazmente a criminalidade organizada transnacional, julgue os itens a seguir<\/strong>:<\/p>\n<p><strong>130. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Ao impedir a pr\u00e1tica de atos de um Estado no territ\u00f3rio de outro Estado, a Conven\u00e7\u00e3o de Palermo confirma a regra cl\u00e1ssica de exerc\u00edcio da jurisdi\u00e7\u00e3o nacional<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>\u00c9 exatamente isso. O art. 4\u00ba, da Conven\u00e7\u00e3o de Palermo, \u00e9 intitulado \u201c<strong><em>prote\u00e7\u00e3o da soberania<\/em><\/strong>\u201d. Segundo esse dispositivo, \u201c<em>o disposto na presente Conven\u00e7\u00e3o n\u00e3o autoriza qualquer Estado Parte a exercer, em territ\u00f3rio de outro Estado, jurisdi\u00e7\u00e3o ou fun\u00e7\u00f5es que o direito interno desse Estado reserve exclusivamente \u00e0s suas autoridades<\/em>\u201d. Essa \u00e9 regra cl\u00e1ssica de exerc\u00edcio da jurisdi\u00e7\u00e3o nacional: a de que a <strong><em>jurisdi\u00e7\u00e3o \u00e9 territorial<\/em><\/strong>. Quest\u00e3o correta.<\/p>\n<p><strong>131. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Considerando o princ\u00edpio de imputa\u00e7\u00e3o de responsabilidade pessoal, a Conven\u00e7\u00e3o de Palermo n\u00e3o admite a responsabiliza\u00e7\u00e3o penal de pessoa jur\u00eddica por pr\u00e1ticas de corrup\u00e7\u00e3o.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O art. 10, da Conven\u00e7\u00e3o de Palermo, admite a responsabiliza\u00e7\u00e3o penal de pessoas jur\u00eddicas que participem em infra\u00e7\u00f5es graves envolvendo um grupo criminoso organizado. Quest\u00e3o errada.<\/p>\n<p><strong>132. (CESPE \/ ABIN \u2013 2018) <\/strong><strong>Como forma de investiga\u00e7\u00e3o de infra\u00e7\u00f5es e identifica\u00e7\u00e3o de pessoas, admite-se a denominada entrega vigiada, que consiste na t\u00e9cnica de permitir que remessas il\u00edcitas ou suspeitas saiam do territ\u00f3rio de um ou mais Estados, os atravessem ou neles entrem, com o conhecimento e sob o controle das suas autoridades competentes<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O art. 20, da Conven\u00e7\u00e3o de Palermo, <strong><em>admite a utiliza\u00e7\u00e3o da t\u00e9cnica de entrega vigiada<\/em><\/strong>. Segundo a Conven\u00e7\u00e3o de Palermo, entrega vigiada \u00e9 a t\u00e9cnica que consiste em permitir que \u201c<em>remessas il\u00edcitas ou suspeitas saiam do territ\u00f3rio de um ou mais Estados, os atravessem ou neles entrem, com o conhecimento e sob o controle das suas autoridades competentes, com a finalidade de investigar infra\u00e7\u00f5es e identificar as pessoas envolvidas na sua pr\u00e1tica<\/em>\u201d. Quest\u00e3o correta.<\/p>\n<p><strong>\u201c<em>Guardadas as devidas propor\u00e7\u00f5es, a responsabilidade internacional do Estado sofreu a influ\u00eancia de acontecimentos que de certo modo a aproximaram das mudan\u00e7as verificadas no plano interno. O seu pressuposto \u00e9 a considera\u00e7\u00e3o de que o Estado \u00e9 sujeito de direitos e obriga\u00e7\u00f5es, apto, por isso, a responder pelos efeitos dos comportamentos que adota<\/em>\u201d.<\/strong><\/p>\n<p><strong>Alberto do Amaral J\u00fanior. Curso de direito internacional p\u00fablico, 4<sup>a<\/sup> ed. S\u00e3o Paulo, Atlas, 2013. p. 328<\/strong><\/p>\n<p><strong>Considerando o assunto do texto precedente, julgue os itens subsequentes.<\/strong><\/p>\n<p><strong>133. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>Tendo em vista a soberania e a supremacia constitucional, um Estado pode se eximir de eventual responsabilidade internacional perante outro Estado sob o argumento de defesa de suas normas constitucionais<\/strong>.<\/p>\n<p><strong>Coment\u00e1rios<\/strong>:<\/p>\n<p>O Estado <strong><em>n\u00e3o pode<\/em><\/strong> se eximir de eventual responsabilidade internacional sob o argumento de defesa de suas normas de direito internacional, ainda que estejam previstas na Constitui\u00e7\u00e3o. Quest\u00e3o errada.<\/p>\n<p><strong>134. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>Na hip\u00f3tese de um agente estatal, durante procedimento de investiga\u00e7\u00e3o, exorbitar de suas fun\u00e7\u00f5es, praticando atos que configurem tanto il\u00edcitos internacionais quanto nacionais, admite-se a responsabilidade internacional do Estado.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>A responsabilidade internacional do Estado se origina, com frequ\u00eancia, da conduta de agentes do Poder Executivo, quer essa conduta seja compat\u00edvel ou n\u00e3o com o direito interno. Assim, a conduta de agente estatal que exorbita de suas fun\u00e7\u00f5es <strong><em>gera responsabilidade internacional<\/em><\/strong> do Estado. Quest\u00e3o correta.<\/p>\n<p><strong>No que se refere \u00e0 imunidade de jurisdi\u00e7\u00e3o dos Estados e de agentes diplom\u00e1ticos e consulares, julgue os pr\u00f3ximos itens.<\/strong><\/p>\n<p><strong>135. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>Em raz\u00e3o da instrumentalidade das formas, admite-se a presun\u00e7\u00e3o da ren\u00fancia da imunidade de jurisdi\u00e7\u00e3o pelo Estado na fase de execu\u00e7\u00e3o de um processo judicial, quando houver o ato expresso de ren\u00fancia na fase de conhecimento do mesmo processo.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>A ren\u00fancia \u00e0 imunidade de jurisdi\u00e7\u00e3o <strong><em>n\u00e3o implica<\/em><\/strong> ren\u00fancia \u00e0 imunidade no processo de execu\u00e7\u00e3o, <u>em rela\u00e7\u00e3o ao qual se exigir\u00e1 nova ren\u00fancia<\/u>. Quest\u00e3o errada.<\/p>\n<p><strong>136. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>Conforme entendimento do Superior Tribunal de Justi\u00e7a, n\u00e3o \u00e9 poss\u00edvel a responsabiliza\u00e7\u00e3o, em territ\u00f3rio brasileiro, de Estado estrangeiro por ato de guerra, por tratar-se de manifesta\u00e7\u00e3o de ato de imp\u00e9rio.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>O STF e o STJ j\u00e1 decidiram que <u>n\u00e3o \u00e9 poss\u00edvel a responsabiliza\u00e7\u00e3o<\/u> de Estado estrangeiro por <strong><em>ato de guerra<\/em><\/strong>, tendo em vista tratar-se de manifesta\u00e7\u00e3o de ato de imp\u00e9rio. Quest\u00e3o correta.<\/p>\n<p><strong>137. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>C\u00f4nsul de Estado estrangeiro poder\u00e1 ser processado e julgado pelo Poder Judici\u00e1rio brasileiro no caso de praticar crime n\u00e3o relacionado a ato de of\u00edcio em territ\u00f3rio brasileiro.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Os funcion\u00e1rios consulares <strong><em>n\u00e3o<\/em><\/strong> <strong><em>podem ser presos em decorr\u00eancia de senten\u00e7a judici\u00e1ria definitiva<\/em><\/strong>, <u>salvo em raz\u00e3o de atos praticados fora do exerc\u00edcio de suas fun\u00e7\u00f5es oficiais<\/u>. Assim, podemos dizer que a imunidade penal dos funcion\u00e1rios consulares abrange apenas os atos praticados no exerc\u00edcio das fun\u00e7\u00f5es consulares. Em outras palavras, eles <strong><em>podem ser processados e julgados<\/em><\/strong> pelo Poder Judici\u00e1rio quando praticarem <strong><em>crimes n\u00e3o relacionados a ato de of\u00edcio<\/em><\/strong>. Quest\u00e3o correta.<\/p>\n<p><strong>Julgue os itens seguintes, a respeito da Declara\u00e7\u00e3o Universal dos Direitos Humanos e do direito internacional dos refugiados.<\/strong><\/p>\n<p><strong>138. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>Embora assegure todas as garantias de defesa, a Declara\u00e7\u00e3o Universal dos Direitos Humanos n\u00e3o garante de forma expressa a presun\u00e7\u00e3o de inoc\u00eancia at\u00e9 que a culpabilidade de algu\u00e9m tenha sido provada.<\/strong><\/p>\n<p><strong>Coment\u00e1rios: <\/strong><\/p>\n<p>Segundo o art. 11, par\u00e1grafo 1\u00ba, da DUDH, \u201c<em>todo ser humano acusado de um ato delituoso tem o <strong>direito de ser presumido inocente<\/strong> at\u00e9 que a sua culpabilidade tenha sido provada de acordo com a lei, em julgamento p\u00fablico no qual lhe tenham sido asseguradas todas as garantias necess\u00e1rias \u00e0 sua defesa<\/em>\u201d. Assim, a DUDH garante, <strong><em>de forma expressa<\/em><\/strong>, o princ\u00edpio da presun\u00e7\u00e3o de inoc\u00eancia. Quest\u00e3o errada.<\/p>\n<p><strong>139. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>De acordo com a legisla\u00e7\u00e3o brasileira, n\u00e3o pode ser considerado refugiado o indiv\u00edduo que, devido a fundados temores de persegui\u00e7\u00e3o por motivos de opini\u00f5es pol\u00edticas, se encontre fora de seu pa\u00eds de nacionalidade e n\u00e3o queira acolher-se \u00e0 prote\u00e7\u00e3o de tal pa\u00eds. <\/strong><\/p>\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n<p>Segundo o art. 1\u00ba, I, Lei n\u00ba 9.474\/97, <strong><em>ser\u00e1 reconhecido como refugiado<\/em><\/strong> \u201c<em>todo indiv\u00edduo que, devido a <u>fundados temores de persegui\u00e7\u00e3o<\/u> por motivos de ra\u00e7a, religi\u00e3o, nacionalidade, grupo social ou opini\u00f5es pol\u00edticas <u>encontre-se fora de seu pa\u00eds de nacionalidade<\/u> e n\u00e3o possa ou <u>n\u00e3o queira acolher-se \u00e0 prote\u00e7\u00e3o de tal pa\u00eds<\/u><\/em>\u201d. Quest\u00e3o errada.<\/p>\n<p><strong>140. (CESPE \/ ABIN \u2013 2018)<\/strong> <strong>Apesar de a Declara\u00e7\u00e3o Universal dos Direitos Humanos n\u00e3o ser considerada um tratado, a sua obrigatoriedade decorre de sua qualifica\u00e7\u00e3o como norma de <em>jus cogens<\/em>. <\/strong><\/p>\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n<p>A DUDH n\u00e3o \u00e9 um tratado internacional, mas sim uma decis\u00e3o de organiza\u00e7\u00e3o internacional. Do ponto de vista material, a DUDH \u00e9 considerada obrigat\u00f3ria. Segundo o Prof. Val\u00e9rio Mazzuoli, a DUDH \u00e9 considerada uma norma <em>jus cogens<\/em>. Parece-me que ser\u00e1 essa a posi\u00e7\u00e3o do CESPE, j\u00e1 que a pr\u00f3pria quest\u00e3o afirmou que a DUDH \u00e9 obrigat\u00f3ria. Quest\u00e3o correta.<\/p>\n<h1 style=\"text-align: center;\">Oficial de Intelig\u00eancia &#8211; \u00e1rea 1<span style=\"font-size: 24pt;\"><em><strong><br \/>\n<\/strong><\/em><\/span><\/h1>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><em><strong>Abaixo voc\u00ea confere o formul\u00e1rio para preenchimento do seu Gabarito.<br \/>\n<\/strong><\/em><\/span><\/p>\n<h1 style=\"text-align: center;\">\u00a0<iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfVvCNfo8q3-Gm8GvddhCNIgzqHiuDaEPQ0ADcodEPBhlHhkg\/viewform?embedded=true\" width=\"760\" height=\"500\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\">Carregando\u2026<\/iframe><\/h1>\n<h1 style=\"text-align: center;\">Confira seu resultado no Ranking!<\/h1>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><em><strong>Se voc\u00ea preencheu o formul\u00e1rio acima, seu nome ser\u00e1 listado aqui neste Ranking. Os resultados est\u00e3o sendo computados e atualizados a todo momento. Acompanhe seu resultado.<\/strong><\/em><\/span><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vS7Q1o4yBr1ueCNnd78dd_lITQWSz3WYKzHwxwR3eTkbvtIgGxpfLqRwby2PjiB5meldUarm7QAJme8\/pubhtml?widget=true&amp;headers=false\" width=\"760\" height=\"500\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Tudo joia? Nesse domingo (11\/03), tivemos a prova da ABIN. A prova veio pesada. N\u00e3o era para menos. O concurso da ABIN \u00e9 de alt\u00edssimo n\u00edvel, exigindo que os candidatos realmente demonstrassem conhecimento sobre as diferentes disciplinas. A seguir, comento as provas de Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia, Pol\u00edtica e Seguran\u00e7a e Direito [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-110618","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gabarito Extraoficial ABIN - Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabarito Extraoficial ABIN - Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, pessoal! Tudo joia? Nesse domingo (11\/03), tivemos a prova da ABIN. A prova veio pesada. N\u00e3o era para menos. O concurso da ABIN \u00e9 de alt\u00edssimo n\u00edvel, exigindo que os candidatos realmente demonstrassem conhecimento sobre as diferentes disciplinas. A seguir, comento as provas de Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia, Pol\u00edtica e Seguran\u00e7a e Direito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rvale01\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-11T23:31:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-12T12:33:02+00:00\" \/>\n<meta name=\"author\" content=\"Ricardo Vale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Vale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\"},\"author\":{\"name\":\"Ricardo Vale\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e\"},\"headline\":\"Gabarito Extraoficial ABIN &#8211; Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP\",\"datePublished\":\"2018-03-11T23:31:28+00:00\",\"dateModified\":\"2018-03-12T12:33:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\"},\"wordCount\":4951,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\",\"name\":\"Gabarito Extraoficial ABIN - Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-03-11T23:31:28+00:00\",\"dateModified\":\"2018-03-12T12:33:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabarito Extraoficial ABIN &#8211; Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e\",\"name\":\"Ricardo Vale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g\",\"caption\":\"Ricardo Vale\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rvale01\",\"https:\/\/x.com\/https:\/\/twitter.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardovaleestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gabarito Extraoficial ABIN - Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/","og_locale":"pt_BR","og_type":"article","og_title":"Gabarito Extraoficial ABIN - Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP","og_description":"Ol\u00e1, pessoal! Tudo joia? Nesse domingo (11\/03), tivemos a prova da ABIN. A prova veio pesada. N\u00e3o era para menos. O concurso da ABIN \u00e9 de alt\u00edssimo n\u00edvel, exigindo que os candidatos realmente demonstrassem conhecimento sobre as diferentes disciplinas. A seguir, comento as provas de Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia, Pol\u00edtica e Seguran\u00e7a e Direito [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/rvale01","article_published_time":"2018-03-11T23:31:28+00:00","article_modified_time":"2018-03-12T12:33:02+00:00","author":"Ricardo Vale","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Vale","Est. tempo de leitura":"25 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/"},"author":{"name":"Ricardo Vale","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e"},"headline":"Gabarito Extraoficial ABIN &#8211; Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP","datePublished":"2018-03-11T23:31:28+00:00","dateModified":"2018-03-12T12:33:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/"},"wordCount":4951,"commentCount":5,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/","name":"Gabarito Extraoficial ABIN - Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-03-11T23:31:28+00:00","dateModified":"2018-03-12T12:33:02+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-abin-direito-constitucional-legislacao-de-inteligencia-e-dip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gabarito Extraoficial ABIN &#8211; Direito Constitucional, Legisla\u00e7\u00e3o de Intelig\u00eancia e DIP"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c32e47dba2159cafe7796a9569a6ff7e","name":"Ricardo Vale","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a5658c798bb49dd53314263f59f38c192d73370fb65839a372c2ae9027be74?s=96&d=mm&r=g","caption":"Ricardo Vale"},"sameAs":["https:\/\/www.facebook.com\/rvale01","https:\/\/x.com\/https:\/\/twitter.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardovaleestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/110618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=110618"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/110618\/revisions"}],"predecessor-version":[{"id":110710,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/110618\/revisions\/110710"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=110618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=110618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=110618"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=110618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}