{"id":1102406,"date":"2022-11-02T08:14:00","date_gmt":"2022-11-02T11:14:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1102406"},"modified":"2022-10-17T15:39:01","modified_gmt":"2022-10-17T18:39:01","slug":"controle-judicial-inss","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/","title":{"rendered":"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS &#8211; resumo"},"content":{"rendered":"\n<p>Ol\u00e1, amigos. Neste resumo aprenderemos os principais t\u00f3picos acerca do <strong>CONTROLE JUDICIAL DA ADMINISTRA\u00c7\u00c3O P\u00daBLICA<\/strong>, com foco no novo certame do INSS.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss-1024x536.jpg\" alt=\"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo\" class=\"wp-image-698508\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss-1024x536.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss-300x157.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss-768x402.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss-610x319.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS &#8211; resumo<\/figcaption><\/figure>\n\n\n\n<p>Conforme amplamente divulgado pelo <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Estrat\u00e9gia Concursos<\/mark><\/strong>, o novo certame do <a href=\"https:\/\/www.gov.br\/inss\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\">Instituto Nacional do Seguro Social (INSS)<\/a> ser\u00e1 conduzido pelo <a href=\"https:\/\/www.cebraspe.org.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (CEBRASPE)<\/a>.<\/p>\n\n\n\n<p>Nesse sentido, o certame ofertou v\u00e1rias vagas para o cargo de T\u00e9cnico do Seguro Social, em diversas localidades do pa\u00eds. Para mais informa\u00e7\u00f5es, consulte o quadro de vagas presente no edital.<\/p>\n\n\n\n<p>Diante do exposto, trataremos neste artigo acerca de um t\u00f3pico muito importante para esse grande certame: o controle judicial da administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>Pode-se dizer que o controle judicial da administra\u00e7\u00e3o p\u00fablica \u00e9 um tema \u201ctransversal\u201d. Existe a possibilidade de exig\u00eancia tanto na prova de Direito Administrativo, quanto na prova de Direito Constitucional.<\/p>\n\n\n\n<p>Assim, vale ressaltar que o edital do certame citou expressamente esse tema (controle judicial) no conte\u00fado program\u00e1tico da disciplina de Direito Administrativo (item 8).<\/p>\n\n\n\n<p>Al\u00e9m disso, o conte\u00fado program\u00e1tico de Direito Constitucional citou, no item 2, as se\u00e7\u00f5es I e II do Cap\u00edtulo VII da Constitui\u00e7\u00e3o Federal (arts. 37 a 41), que tratam sobre a administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>Pessoal, ap\u00f3s esse breve pre\u00e2mbulo j\u00e1 conseguimos perceber a import\u00e2ncia do tema, certo?<\/p>\n\n\n\n<p>Nesse sentido, vamos iniciar o nosso resumo de hoje?<\/p>\n\n\n\n<p>Bons estudos!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-controle-judicial-da-administracao-publica-para-o-inss-o-que-e-controle\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Controle judicial da administra\u00e7\u00e3o p\u00fablica para o INSS: o que \u00e9 controle?<\/mark><\/strong><\/h2>\n\n\n\n<p>Em decorr\u00eancia da pr\u00f3pria ordem constitucional e dos princ\u00edpios que envolvem o Estado Democr\u00e1tico de Direito, existe l\u00f3gica em afirmar que a atua\u00e7\u00e3o da administra\u00e7\u00e3o p\u00fablica tamb\u00e9m se submete a controles.<\/p>\n\n\n\n<p>Conforme o preceito de Estado Democr\u00e1tico de Direito, em s\u00edntese, a ordem jur\u00eddica se aplica a todos, inclusive ao pr\u00f3prio Estado respons\u00e1vel pela sua cria\u00e7\u00e3o.<\/p>\n\n\n\n<p>Assim, a atua\u00e7\u00e3o da Administra\u00e7\u00e3o P\u00fablica se submete a v\u00e1rios tipos de controle, seja por ela pr\u00f3pria ou por outras inst\u00e2ncias controladoras.<\/p>\n\n\n\n<p>Nesse sentido, cita-se o princ\u00edpio administrativo da sindicabilidade que estabelece, justamente, a imposi\u00e7\u00e3o de controles sobre a atua\u00e7\u00e3o administrativa.<\/p>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Mas qual \u00e9 mesmo o conceito de controle?<\/mark><\/strong><\/p>\n\n\n\n<p>Pessoal, n\u00e3o existe na doutrina um conceito \u00fanico de controle. Todavia, podemos resumir o tema afirmando que <strong>controle consiste em comparar uma situa\u00e7\u00e3o existente com um crit\u00e9rio (aquilo que era esperado, considerando o ordenamento jur\u00eddico), a fim de evidenciar poss\u00edveis desvios ou constatar a sua adequa\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Controle judicial da administra\u00e7\u00e3o p\u00fablica para o INSS: quem controla a administra\u00e7\u00e3o?<\/mark><\/strong><\/h2>\n\n\n\n<p>Conforme apresentado anteriormente, a administra\u00e7\u00e3o p\u00fablica se submete a v\u00e1rios n\u00edveis de controle, inclusive, com fundamento no princ\u00edpio da sindicabilidade.<\/p>\n\n\n\n<p>Nesse sentido, a administra\u00e7\u00e3o p\u00fablica pode ser controlada, a depender da situa\u00e7\u00e3o, pelo Poder Legislativo, pelo Poder Judici\u00e1rio ou pela pr\u00f3pria administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>A t\u00edtulo de exemplo, podemos citar o art. 63, \u00a72\u00ba da Lei 9.784\/1999, que estabelece que independentemente do conhecimento de recurso administrativo, a administra\u00e7\u00e3o p\u00fablica pode rever, de of\u00edcio, o ato ilegal. Esse \u00e9 um cl\u00e1ssico exemplo do princ\u00edpio administrativo da autotutela.<\/p>\n\n\n\n<p>Al\u00e9m disso, podemos citar o controle realizado pela administra\u00e7\u00e3o Direta sobre as entidades da administra\u00e7\u00e3o indireta (tutela ou supervis\u00e3o ministerial). Nesse sentido, controla-se a atua\u00e7\u00e3o das entidades descentralizadas quanto ao atendimento das suas finalidades e dos programas de governo, apesar de n\u00e3o haver hierarquia.<\/p>\n\n\n\n<p>Ademais, existe tamb\u00e9m o controle realizado pelo Poder Legislativo sobre a administra\u00e7\u00e3o p\u00fablica. Por exemplo, quando o Congresso Nacional realiza a susta\u00e7\u00e3o de ato normativo do Poder Executivo que exorbite do seu poder regulamentar.<\/p>\n\n\n\n<p>Por fim, o controle judicial (foco deste artigo) decorre da atua\u00e7\u00e3o do Poder Judici\u00e1rio quanto \u00e0 legalidade do ato controlado.<\/p>\n\n\n\n<p>Portanto, caro aluno, perceba que a atua\u00e7\u00e3o administrativa pode ser controlada por v\u00e1rias inst\u00e2ncias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Controle da administra\u00e7\u00e3o p\u00fablica e a independ\u00eancia dos Poderes<\/mark><\/strong><\/h2>\n\n\n\n<p>Agora que j\u00e1 comentamos brevemente sobre as v\u00e1rias \u201cinst\u00e2ncias controladoras\u201d, alguns alunos podem se questionar acerca do preceito constitucional da independ\u00eancia dos Poderes.<\/p>\n\n\n\n<p>Ou seja, <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">ser\u00e1 que a exist\u00eancia do controle de um Poder sobre o outro afeta essa independ\u00eancia?<\/mark><\/strong><\/p>\n\n\n\n<p>A resposta \u00e9 n\u00e3o!<\/p>\n\n\n\n<p>Nesse sentido, devemos lembrar do sistema de freios e contrapesos (<em>checks and balances<\/em>). Assim, pela pr\u00f3pria Carta Magna, um Poder pode realizar controle sobre os demais como forma de garantir a atua\u00e7\u00e3o adequada de todos os Poderes constitu\u00eddos.<\/p>\n\n\n\n<p>Todavia, vale ressaltar que tal controle ocorre apenas nas hip\u00f3teses previstas na CF\/88.<\/p>\n\n\n\n<p>Portanto, n\u00e3o h\u00e1 que se falar em ofensa \u00e0 independ\u00eancia dos Poderes, j\u00e1 que o controle de um Poder sobre o outro ocorre apenas nos casos e formas estabelecidos no texto constitucional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Controle judicial da administra\u00e7\u00e3o p\u00fablica para o INSS: qual o fundamento constitucional do controle judicial?<\/mark><\/strong><\/h2>\n\n\n\n<p>Conforme aprendemos anteriormente, o controle da administra\u00e7\u00e3o p\u00fablica pelo Poder Judici\u00e1rio busca fundamento no texto constitucional. <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Mas onde?<\/mark><\/strong><\/p>\n\n\n\n<p>Existem v\u00e1rios trechos da Carta Magna que fundamentam a atua\u00e7\u00e3o judicial no controle da administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>Nesse sentido, o t\u00edtulo IV, cap\u00edtulo III, da CF\/88 destinou v\u00e1rios artigos para tratar sobre a organiza\u00e7\u00e3o e a atua\u00e7\u00e3o do Poder Judici\u00e1rio.<\/p>\n\n\n\n<p>Todavia, para fins de consolida\u00e7\u00e3o, podemos citar unicamente o princ\u00edpio da inafastabilidade da jurisdi\u00e7\u00e3o, previsto no art. 5\u00ba, XXXV, da CF\/88.<\/p>\n\n\n\n<p>Conforme o texto constitucional, a lei n\u00e3o poder\u00e1 afastar da aprecia\u00e7\u00e3o judicial qualquer les\u00e3o ou amea\u00e7a de les\u00e3o.<\/p>\n\n\n\n<p>Assim, aplicando o princ\u00edpio da inafastabilidade da jurisdi\u00e7\u00e3o para o controle da administra\u00e7\u00e3o p\u00fablica, podemos dizer que a atua\u00e7\u00e3o administrativa tamb\u00e9m se submete ao controle judicial diante da possibilidade de les\u00e3o ou amea\u00e7a de les\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Controle judicial da administra\u00e7\u00e3o p\u00fablica para o INSS: o controle judicial \u00e9 um tipo de controle externo?<\/mark><\/strong><\/h2>\n\n\n\n<p>Conforme as classifica\u00e7\u00f5es doutrin\u00e1rias aplic\u00e1veis ao controle da administra\u00e7\u00e3o, o controle pode ser externo ou interno, de acordo com a posi\u00e7\u00e3o do \u00f3rg\u00e3o controlador.<\/p>\n\n\n\n<p>Assim, o controle interno decorre da atua\u00e7\u00e3o de um \u00f3rg\u00e3o integrante do mesmo Poder do \u00f3rg\u00e3o controlado.<\/p>\n\n\n\n<p>Por exemplo, o controle realizado pela Controladoria Geral da Uni\u00e3o (CGU) sobre a atua\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade. Esse \u00e9 um controle interno, pois ambos os \u00f3rg\u00e3os integram o Poder Executivo Federal.<\/p>\n\n\n\n<p>Por outro lado, o conceito de controle externo abrange um sentido amplo e um sentido estrito.<\/p>\n\n\n\n<p>Assim, controle externo em sentido amplo consiste na atua\u00e7\u00e3o controladora de um Poder sobre outro. Por exemplo, quando o Poder Judici\u00e1rio realiza o controle de legalidade de um ato administrativo.<\/p>\n\n\n\n<p>Por outro lado, o controle externo em sentido estrito decorre da atua\u00e7\u00e3o do Poder Legislativo quanto \u00e0 fiscaliza\u00e7\u00e3o cont\u00e1bil, financeira, or\u00e7ament\u00e1ria, operacional e patrimonial da administra\u00e7\u00e3o direta e indireta.<\/p>\n\n\n\n<p>Pessoal, o conceito estrito de controle externo decorre da literalidade do texto constitucional. Nesse sentido, os arts. 70 e 71 da CF\/88 denominam de controle externo apenas aquele realizado pelo Congresso Nacional com aux\u00edlio do Tribunal de Contas da Uni\u00e3o (TCU).<\/p>\n\n\n\n<p>Portanto, no que tange ao controle judicial da administra\u00e7\u00e3o, o mais prov\u00e1vel \u00e9 que o CEBRASPE evite questionar diretamente se este \u00e9 ou n\u00e3o um controle externo, tendo em vista as duas acep\u00e7\u00f5es poss\u00edveis.<\/p>\n\n\n\n<p>Apesar disso, doutrinariamente e de forma gen\u00e9rica, \u00e9 correto afirmar que o controle judicial da administra\u00e7\u00e3o p\u00fablica consiste em um tipo de controle externo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Controle judicial da administra\u00e7\u00e3o p\u00fablica para o INSS: caracter\u00edsticas<\/mark><\/strong><\/h2>\n\n\n\n<p>Amigos, agora vamos dar in\u00edcio ao principal t\u00f3pico deste artigo. Trataremos acerca das caracter\u00edsticas do controle judicial da administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">QUANTO AO MOMENTO<\/mark><\/strong><\/h4>\n\n\n\n<p>O controle judicial da administra\u00e7\u00e3o p\u00fablica, em regra, quanto ao momento, ocorre a posteriori.<\/p>\n\n\n\n<p>Ou seja, no momento da interposi\u00e7\u00e3o da a\u00e7\u00e3o judicial cab\u00edvel, geralmente, o ato controlado j\u00e1 ocorreu.<\/p>\n\n\n\n<p>Por exemplo, imaginemos o caso de um servidor p\u00fablico que foi injustamente demitido e ingressou com a\u00e7\u00e3o judicial a fim de questionar a legalidade do ato de demiss\u00e3o e de requerer a reintegra\u00e7\u00e3o ao servi\u00e7o p\u00fablico. Perceba que, nesse caso, o ato de demiss\u00e3o j\u00e1 ocorreu quando o servidor p\u00fablico lesado buscou amparo judicial.<\/p>\n\n\n\n<p>Todavia, o controle judicial tamb\u00e9m pode ocorrer de forma pr\u00e9via (<em>a priori<\/em>). Por exemplo, mediante <em>habeas corpus <\/em>preventivo, quando o impetrante apenas vislumbra a possibilidade de ter seu direito de locomo\u00e7\u00e3o cerceado no futuro.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">QUANTO \u00c0 INICIATIVA<\/mark><\/strong><\/h4>\n\n\n\n<p>Por outro lado, quanto \u00e0 iniciativa, o controle judicial ocorre, salvo rar\u00edssimas exce\u00e7\u00f5es, mediante provoca\u00e7\u00e3o.<\/p>\n\n\n\n<p>Nesse sentido, vale lembrar que o Poder Judici\u00e1rio \u00e9, em regra, inerte e depende de provoca\u00e7\u00e3o para que possa se manifestar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">QUANTO \u00c0 NATUREZA<\/mark><\/strong><\/h4>\n\n\n\n<p>Ademais, acerca da natureza, o controle judicial sempre atua sobre o aspecto da legalidade do ato administrativo controlado.<\/p>\n\n\n\n<p>Em outras palavras, podemos dizer que o Poder Judici\u00e1rio \u00e9 incompetente para substituir o m\u00e9rito do ato administrativo.<\/p>\n\n\n\n<p>Por oportuno, devemos lembrar que o fato de o Poder Judici\u00e1rio n\u00e3o estar apto a substituir o m\u00e9rito administrativo n\u00e3o o impede de controlar os atos discricion\u00e1rios.<\/p>\n\n\n\n<p>Nesse sentido, ressalta-se que o ato discricion\u00e1rio n\u00e3o \u00e9 sin\u00f4nimo de ato arbitr\u00e1rio. Portanto, os atos discricion\u00e1rios tamb\u00e9m devem se materializar dentro dos limites estabelecidos pela lei. Caso isso n\u00e3o ocorra, tal ato conter\u00e1 v\u00edcio quanto \u00e0 sua legalidade, submetendo-se ao controle judicial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Conclus\u00e3o<\/mark><\/strong><\/h2>\n\n\n\n<p>Amigos, chegamos ao fim do nosso resumo de hoje sobre o controle judicial da administra\u00e7\u00e3o p\u00fablica para o INSS.<\/p>\n\n\n\n<p>Por oportuno, vale ressaltar que o objetivo deste conte\u00fado n\u00e3o \u00e9 substituir o estudo da aula completa sobre o tema, mas sim, apresentar um material resumido para contextualiza\u00e7\u00e3o da mat\u00e9ria.<\/p>\n\n\n\n<p>Portanto, \u00e9 imprescind\u00edvel o estudo da aula completa sobre o tema controle da administra\u00e7\u00e3o p\u00fablica no curso espec\u00edfico do <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Estrat\u00e9gia Concursos<\/mark><\/strong> para o INSS.<\/p>\n\n\n\n<p>Nos encontramos em um pr\u00f3ximo artigo.<\/p>\n\n\n\n<p>Grande abra\u00e7o.<\/p>\n\n\n\n<p><strong>Rafael Chaves<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><strong>Mais informa\u00e7\u00f5es: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-inss\/\" target=\"_blank\" rel=\"noreferrer noopener\">CONCURSO INSS<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, amigos. Neste resumo aprenderemos os principais t\u00f3picos acerca do CONTROLE JUDICIAL DA ADMINISTRA\u00c7\u00c3O P\u00daBLICA, com foco no novo certame do INSS. Conforme amplamente divulgado pelo Estrat\u00e9gia Concursos, o novo certame do Instituto Nacional do Seguro Social (INSS) ser\u00e1 conduzido pelo Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (CEBRASPE). [&hellip;]<\/p>\n","protected":false},"author":2261,"featured_media":698508,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220191],"tags":[],"tax_estado":[219963],"class_list":["post-1102406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-previdenciaria","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo<\/title>\n<meta name=\"description\" content=\"Estude os principais t\u00f3picos acerca do tema controle judicial da administra\u00e7\u00e3o p\u00fablica para o novo concurso do INSS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo\" \/>\n<meta property=\"og:description\" content=\"Estude os principais t\u00f3picos acerca do tema controle judicial da administra\u00e7\u00e3o p\u00fablica para o novo concurso do INSS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-02T11:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Ferreira Chaves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Ferreira Chaves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\"},\"author\":{\"name\":\"Rafael Ferreira Chaves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1\"},\"headline\":\"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS &#8211; resumo\",\"datePublished\":\"2022-11-02T11:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\"},\"wordCount\":1766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Previdenci\u00e1ria (INSS, PREVIC)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\",\"name\":\"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg\",\"datePublished\":\"2022-11-02T11:14:00+00:00\",\"description\":\"Estude os principais t\u00f3picos acerca do tema controle judicial da administra\u00e7\u00e3o p\u00fablica para o novo concurso do INSS.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Concurso INSS retifica\u00e7\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS &#8211; resumo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1\",\"name\":\"Rafael Ferreira Chaves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"caption\":\"Rafael Ferreira Chaves\"},\"description\":\"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo","description":"Estude os principais t\u00f3picos acerca do tema controle judicial da administra\u00e7\u00e3o p\u00fablica para o novo concurso do INSS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/","og_locale":"pt_BR","og_type":"article","og_title":"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo","og_description":"Estude os principais t\u00f3picos acerca do tema controle judicial da administra\u00e7\u00e3o p\u00fablica para o novo concurso do INSS.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-11-02T11:14:00+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg","type":"image\/jpeg"}],"author":"Rafael Ferreira Chaves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafael Ferreira Chaves","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/"},"author":{"name":"Rafael Ferreira Chaves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1"},"headline":"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS &#8211; resumo","datePublished":"2022-11-02T11:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/"},"wordCount":1766,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg","articleSection":["Concursos P\u00fablicos","Previdenci\u00e1ria (INSS, PREVIC)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/","name":"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS - resumo","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg","datePublished":"2022-11-02T11:14:00+00:00","description":"Estude os principais t\u00f3picos acerca do tema controle judicial da administra\u00e7\u00e3o p\u00fablica para o novo concurso do INSS.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/02\/22154356\/inss.jpg","width":1200,"height":628,"caption":"Concurso INSS retifica\u00e7\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/controle-judicial-inss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Controle Judicial da Administra\u00e7\u00e3o P\u00fablica para o INSS &#8211; resumo"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1","name":"Rafael Ferreira Chaves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","caption":"Rafael Ferreira Chaves"},"description":"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1102406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2261"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1102406"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1102406\/revisions"}],"predecessor-version":[{"id":1111122,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1102406\/revisions\/1111122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/698508"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1102406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1102406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1102406"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1102406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}