{"id":1099787,"date":"2022-09-26T09:00:00","date_gmt":"2022-09-26T12:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1099787"},"modified":"2022-09-30T15:26:16","modified_gmt":"2022-09-30T18:26:16","slug":"carta-aos-assinantes-100","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/","title":{"rendered":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 100"},"content":{"rendered":"\n<p class=\"has-text-align-right has-luminous-vivid-amber-background-color has-background\"><em>Confira, em nossa <strong>cent\u00e9sima<\/strong> carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso Sistema de Quest\u00f5es e as principais movimenta\u00e7\u00f5es de concursos.<\/em><\/p>\n\n\n\n<p>Ol\u00e1, pessoal. Tudo bem?<\/p>\n\n\n\n<p>Aqui \u00e9 o<strong> Prof. Diego Cerqueira <\/strong>em nossa <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">cent\u00e9sima carta aos Assinantes<\/mark><\/strong> do Estrat\u00e9gia Concursos.<\/p>\n\n\n\n<p>Um dos editais mais aguardados dos \u00faltimos anos era do concurso do <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">INSS<\/mark><\/strong>. Agora que foi publicado, voc\u00ea n\u00e3o pode perder mais tempo se quiser fazer parte do nosso seleto rol de aprovados. Para te ajudar nesta trajet\u00f3ria, a Coruja est\u00e1 com duas promo\u00e7\u00f5es, mas a melhor delas, <strong>acaba hoje<\/strong>. Um desconto de at\u00e9 40% al\u00e9m de 6 mentorias com a professora N\u00fabia Oliveira. N\u00e3o fique de fora e <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/inss-tecnico-do-seguro-social-101\/?utm_source=banner&amp;utm_medium=banner&amp;utm_campaign=ec-prev-vd-banner-inssedital-web-150922\">acesse aqui<\/a> para garantir a sua vaga.<\/p>\n\n\n\n<p>Al\u00e9m disso, a nossa equipe preparou um <a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/vade-mecum-inss-tecnico-de-seguro-social\/?utm_campaign=ec-prev-ld-banner-inss-ebk-150922&amp;utm_medium=banner&amp;utm_source=banner\">E-Book totalmente gratuito<\/a> com <strong>toda a legisla\u00e7\u00e3o<\/strong> prevista para o concurso do <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">INSS<\/mark><\/strong>.<\/p>\n\n\n\n<p>Voc\u00ea tem dificuldade com as Jurisprud\u00eancias? A partir de hoje, sempre \u00e0s 19h, o Professor Herbert Almeida e a Professora Nelma Fontana estar\u00e3o ao vivo com o <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Projeto Simplificando a Jurisprud\u00eancia<\/mark><\/strong>. \u00c9 a oportunidade que faltava para voc\u00ea dominar este tipo de conte\u00fado e sair na frente da concorr\u00eancia. <a href=\"https:\/\/gratis.estrategiaconcursos.com.br\/simplificando-a-jurisprudencia\/?utm_source=banner&amp;utm_medium=banner&amp;utm_campaign=ec-mpl-ld-banner-smpjuris-semesp-260922\">Clique aqui<\/a> e inscreva-se gratuitamente.<\/p>\n\n\n\n<p>Quer utilizar a metodologia dos aprovados? Fa\u00e7a parte da <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-purple-color\">Platinum 120 &#8211; O Atalho.<\/mark> <\/strong>Ser guiado por quem j\u00e1 conhece o caminho \u00e9 um verdadeiro atalho na prepara\u00e7\u00e3o. Aproveite essa super oportunidade e transforme os seus estudos em 120 dias! <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/assinatura-platinum-mensal-4-meses\/?utm_source=youtube&amp;utm_medium=descricao&amp;utm_campaign=ec-coa-vd-yt-geral-coach-180922\">N\u00e3o fique de fora<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sistema-de-questoes-do-estrategia\">Sistema de Quest\u00f5es do Estrat\u00e9gia<\/h2>\n\n\n\n<p>Na \u00faltima semana a nossa equipe do Sistema de Quest\u00f5es criou um artigo com provas anteriores para o seguinte concurso:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Banca FCC para a \u00c1rea Fiscal (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/7-provas-de-concursos-anteriores-fcc-area-fiscal\/\">Clique aqui!<\/a>)<\/li><\/ul>\n\n\n\n<p>Al\u00e9m disso, tivemos atualiza\u00e7\u00e3o com a inclus\u00e3o de mais quest\u00f5es nos seguintes artigos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Secretaria da Fazenda do Estado de Minas Gerais (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/questoes-ineditas-sefaz-mg\/\">Clique aqui!<\/a>)<\/li><li>Receita Federal do Brasil (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/questoes-ineditas-receita-federal\/\">Clique aqui!<\/a>)<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-agora-vamos-ver-as-principais-movimentacoes-de-concursos-da-ultima-semana\">Agora, vamos ver as principais movimenta\u00e7\u00f5es de concursos da \u00faltima semana?<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-seagri-df\/\">SEAGRI DF<\/a>: O edital do concurso p\u00fablico da Secretaria de Estado da Agricultura, Abastecimento e Desenvolvimento Rural do Distrito Federal (SEAGRI DF) foi publicado nesta sexta-feira (23\/9), com a oferta de 224 vagas imediatas e 618 oportunidades para forma\u00e7\u00e3o de cadastro de reserva. As oportunidades s\u00e3o destinadas aos cargos de Analista de Desenvolvimento e Fiscaliza\u00e7\u00e3o Agropecu\u00e1ria e T\u00e9cnico de Desenvolvimento e Fiscaliza\u00e7\u00e3o Agropecu\u00e1ria. J\u00e1 os sal\u00e1rios iniciais podem variar entre R$ 6.792,50 e R$ 10.670,00. Os interessados em participar da sele\u00e7\u00e3o devem realizar as inscri\u00e7\u00f5es no per\u00edodo de 26 de outubro e 30 de novembro, atrav\u00e9s do site da banca, o IADES. As taxas foram definidas de acordo com o grau de escolaridade do cargo pretendido. As provas ser\u00e3o aplicadas no dia 08 de janeiro de 2023.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cgdf\/\">CGDF<\/a>: Ap\u00f3s o Cebraspe ter sido oficializado como banca organizadora, iniciou-se a contagem regressiva para publica\u00e7\u00e3o do edital de abertura do concurso Controladoria Geral do Distrito Federal (CGDF). A previs\u00e3o \u00e9 entre os meses de outubro e novembro. A informa\u00e7\u00e3o foi repassada pela Secretaria de Economia do Distrito Federal \u00e0 equipe de jornalismo do Estrat\u00e9gia Concursos. A disputa ser\u00e1 pelas 87 vagas imediatas mais 147 em cadastro reserva no cargo de Auditor de Controle Interno, cujo sal\u00e1rio inicial \u00e9 de R$ 13.700,00. Al\u00e9m disso, a LDO de 2023 j\u00e1 prev\u00ea a nomea\u00e7\u00e3o de alguns aprovados nesse pr\u00f3ximo certame.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-sefaz-pe\/\">SEFAZ PE<\/a>: A Funda\u00e7\u00e3o Carlos Chagas (FCC) \u00e9 a banca respons\u00e1vel pelo concurso Sefaz PE! A dispensa de licita\u00e7\u00e3o que confirma a contrata\u00e7\u00e3o da empresa consta no Di\u00e1rio Oficial do Estado desta quarta-feira, 21 de setembro. Vale lembrar que a escolha da empresa j\u00e1 havia sido indicada no in\u00edcio de setembro, faltando apenas alguns tr\u00e2mites burocr\u00e1ticos para sua oficializa\u00e7\u00e3o. Agora, a expectativa \u00e9 pela produ\u00e7\u00e3o e publica\u00e7\u00e3o do novo edital da Secretaria de Estado da Fazenda de Pernambuco.S\u00e3o previstas 20 vagas para o cargo de Auditor Fiscal do Tesouro Estadual, o qual exige forma\u00e7\u00e3o de n\u00edvel superior. O sal\u00e1rio inicial \u00e9 de R$ 11.821,43. Al\u00e9m disso, conforme informa\u00e7\u00f5es obtidas anteriormente pelo Estrat\u00e9gia, atrav\u00e9s de fontes internas do \u00f3rg\u00e3o, a expectativa \u00e9 de que as provas sejam aplicadas em dezembro.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-agetransp-rj\/\">AGETRANSP RJ<\/a>: O concurso da Ag\u00eancia Reguladora de Servi\u00e7os P\u00fablicos Concedidos de Transportes do Rio de Janeiro est\u00e1 oficialmente autorizado! A informa\u00e7\u00e3o foi confirmada atrav\u00e9s do Di\u00e1rio Oficial do Estado desta sexta-feira, 23 de setembro. A sele\u00e7\u00e3o ser\u00e1 para provimento de 25 vagas, sendo 15 para o cargo de especialista em regula\u00e7\u00e3o, 05 para analistas t\u00e9cnicos e 05 para assistentes t\u00e9cnicos. Com a autoriza\u00e7\u00e3o do certame, o pr\u00f3ximo passo ser\u00e1 a forma\u00e7\u00e3o de uma comiss\u00e3o respons\u00e1vel pela contrata\u00e7\u00e3o da banca organizadora. Lembrando que a realiza\u00e7\u00e3o do concurso foi uma determina\u00e7\u00e3o da Delibera\u00e7\u00e3o n\u00ba 1164 \u00e0 Procuradoria Geral da Ag\u00eancia. A medida se faz necess\u00e1ria por conta dos cargos vagos, nunca ocupados, encontrados atualmente no quadro de servidores.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-seplan-rr\/\">SEPLAN RR<\/a>: Foi publicado o edital do primeiro concurso p\u00fablico da Secretaria de Planejamento e Or\u00e7amento de Roraima (Seplan RR). Conforme o documento, o \u00f3rg\u00e3o oferece 70 vagas para o cargo de Analista de Planejamento e Or\u00e7amento. As oportunidades s\u00e3o de n\u00edvel superior de forma\u00e7\u00e3o e distribu\u00eddas entre as especialidades de Planejamento e Or\u00e7amento e de Tecnologia da Informa\u00e7\u00e3o. J\u00e1 a remunera\u00e7\u00e3o inicial \u00e9 de R$ 5.853,23. Os interessados em participar da sele\u00e7\u00e3o devem realizar as inscri\u00e7\u00f5es no per\u00edodo de 28 de setembro a 21 de outubro, no site da banca organizadora, o Cebraspe. A taxa de inscri\u00e7\u00e3o foi estipulada no valor de R$ 78,80. Ademais, as provas objetivas est\u00e3o marcadas para o dia 08 de janeiro de 2023.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-militar-ms\/\">PM MS<\/a>:<a> <\/a>Foi publicado o edital do concurso PM MS com oferta de 520 vagas para os cargos de Soldado e Oficial. As oportunidades s\u00e3o para candidatos de n\u00edvel superior. Os sal\u00e1rios iniciais, enquanto Aluno, variam de R$ 2.252,25 a R$ 4.826,75. Os interessados em participar da sele\u00e7\u00e3o devem realizar as inscri\u00e7\u00f5es no per\u00edodo de 23 de setembro a 3 de novembro, no site da banca organizadora, IDECAN. A prova \u00e9 prevista no dia 4 de dezembro.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-bombeiros-ms\/\">Bombeiros MS<\/a>: Foi publicado o edital do concurso Bombeiros MS com oferta de 260 vagas para os cargos de Soldado e Oficial. As oportunidades s\u00e3o para candidatos de n\u00edvel superior. Os sal\u00e1rios iniciais, enquanto Aluno, variam de R$ 2.252,25 a R$ 4.826,75. Os interessados em participar da sele\u00e7\u00e3o devem realizar as inscri\u00e7\u00f5es no per\u00edodo de 23 de setembro a 3 de novembro, no site da banca organizadora, IDECAN. A prova \u00e9 prevista no dia 11 de dezembro.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-bnb\/\">BNB<\/a>: Um novo concurso BNB (Banco do Nordeste do Brasil) vem a\u00ed! Os tr\u00e2mites, inclusive, est\u00e3o bem adiantados visto que o Cebraspe foi contratado como banca organizadora. As oportunidades ser\u00e3o para o cargo de Especialista T\u00e9cnico \u2013 Analista de Sistema do Banco. O quantitativo de vagas, contudo, n\u00e3o foi revelado.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-bombeiro-rj-iuds-banca-soldado\/\">Bombeiros RJ<\/a>: O Instituto Universal de Desenvolvimento Social (IUDS) foi oficialmente confirmado como banca organizadora do novo concurso Bombeiros RJ. Segundo o Termo de Refer\u00eancia, s\u00e3o previstas 800 vagas para os cargos de Soldado (Combatente, Condutor e Operador de Viaturas, Art\u00edfice, Telecomunica\u00e7\u00f5es, Corneteiro e Mar\u00edtimo) e 3\u00ba Sargento (M\u00fasico).<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-alesc\/\">Alesc<\/a>: Foi divulgada dispensa de licita\u00e7\u00e3o que definiu a FGV como banca organizadora do concurso ALESC. Ser\u00e3o ofertadas 29 vagas para os cargos de Analista Legislativo III e Consultor Legislativo, os quais exigem forma\u00e7\u00e3o de n\u00edvel superior.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-pm-e-bombeiros-ba-banca-contratada\/\">PM e Bombeiros BA<\/a>: Foi divulgado o resumo de dispensa de licita\u00e7\u00e3o que define a banca organizadora dos concursos PM e Bombeiros BA. Segundo assessoria de comunica\u00e7\u00e3o, a Funda\u00e7\u00e3o Carlos Chagas (FCC) foi a contratada. Para a Pol\u00edcia Militar, ser\u00e3o contempladas 2 mil vagas para o cargo de Soldado. J\u00e1 para o Corpo de Bombeiros, s\u00e3o previstas 500 vagas, que devem ser distribu\u00eddas em diferentes \u00e1reas.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/cj.estrategia.com\/portal\/concurso-mpf-procurador\/\">MPF Procurador:<\/a> Foi publicado o edital MPF Procurador com 13 vagas para o cargo de Procurador da Rep\u00fablica. Os interessados em participar da sele\u00e7\u00e3o devem realizar as inscri\u00e7\u00f5es no per\u00edodo de 20 de setembro a 19 de outubro, no site da banca organizadora, MPF. As provas objetivas est\u00e3o previstas para acontecer em 27 de novembro de 2022<strong>. <\/strong>A etapa subjetiva ser\u00e1 realizada no per\u00edodo de 11 a 14 de mar\u00e7o de 2023.J\u00e1 as provas orais ser\u00e3o realizadas no per\u00edodo de 03 a 07 de julho de 2023.<\/li><li><a href=\"https:\/\/cj.estrategia.com\/portal\/concurso-mp-rj-promotor\/\">MP RJ Promotor: <\/a>&nbsp;Foi designada a promotora de justi\u00e7a Glaucia Maria da Costa Santana, como coordenadora, bem como os servidores Cristiane Sp\u00eado, Jos\u00e9 Reilnado, Rafael Viera e Samyra Cesar, para comporem a coordena\u00e7\u00e3o do XXXVII concurso MP RJ Promotor.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/cj.estrategia.com\/portal\/concurso-dpe-sp-defensor\/\">DPE SP Defensor: <\/a>&nbsp;O Conselho Superior da Defensoria P\u00fablica de SP deliberou, por unanimidade, ampliar o n\u00famero de vagas a serem disponibilizadas no novo concurso DPE SP Defensor, de 50 para 70 vagas, al\u00e9m daquelas que se abrirem no decorrer do concurso p\u00fablico ou do prazo de validade.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/cj.estrategia.com\/portal\/concurso-magistratura-sp\/\">Magistratura SP: <\/a>&nbsp;A desembargadora Maria de Lourdes Rachid Vaz e os desembargadores Vicente de Abreu e Milton Paula de Carvalho, v\u00e3o escolher em breve a presid\u00eancia da Comiss\u00e3o do 190\u00ba Concurso de Provas e T\u00edtulos para Ingresso na Magistratura de S\u00e3o Paulo. Em breve a composi\u00e7\u00e3o da comiss\u00e3o ser\u00e1 divulgada e o edital deve ser publicado ap\u00f3s a prova oral do 189\u00ba Concurso.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/cj.estrategia.com\/portal\/concurso-trf1-juiz\/\">TRF1 Juiz: <\/a>&nbsp;O&nbsp;Tribunal Regional Federal da 1\u00aa Regi\u00e3o&nbsp;informou \u00e0 equipe de jornalismo do Estrat\u00e9gia que o novo concurso TRF1 Juiz poder\u00e1 ter seu edital publicado neste ano. Inclusive, o \u00f3rg\u00e3o ainda confirmou que a escolha da banca organizadora segue em fase de defini\u00e7\u00e3o.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-trt-go\/\">TRT GO<\/a>: o presidente do Tribunal Regional do Trabalho de Goi\u00e1s voltou a reafirmar o compromisso de divulgar o novo edital de concurso p\u00fablico at\u00e9 outubro. Em nota encaminhada \u00e0 equipe de jornalismo do Estrat\u00e9gia Concursos no dia 20 de setembro, o representante afirmou que a banca organizadora ainda est\u00e1 em defini\u00e7\u00e3o mas a escolha deve \u201cocorrer muito em&nbsp; breve\u201d.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-dpe-sp\/\">DPE SP:<\/a> o edital para servidores da Defensoria P\u00fablica de S\u00e3o Paulo teve a Vunesp definida como banca organizadora. O edital ser\u00e1 para as carreiras de &nbsp;Oficial de Defensoria e Agente de Defensoria, de n\u00edveis m\u00e9dio e superior respectivamente.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/bolsonaro-veta-nivel-superior-para-tecnico-judiciario\/\">Concursos de Tribunais:<\/a> O presidente Jair Bolsonaro vetou a mudan\u00e7a de escolaridade para ingresso no cargo de T\u00e9cnico Judici\u00e1rio. &nbsp;Sendo assim, qualquer concurso p\u00fablico que ofere\u00e7a vagas para a carreira segue com requisito de n\u00edvel m\u00e9dio de escolaridade. A Federa\u00e7\u00e3o Nacional dos Trabalhadores do Judici\u00e1rio e MPU (Fenajufe), que buscava a altera\u00e7\u00e3o do requisito para n\u00edvel superior, promete pressionar o Congresso Nacional para que o veto seja derrubado.<\/li><\/ul>\n\n\n\n<p>Desejo a todos uma excelente semana de estudos!<\/p>\n\n\n\n<p>Abra\u00e7os,<strong>Prof. Diego Cerqueira<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira, em nossa cent\u00e9sima carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso Sistema de Quest\u00f5es e as principais movimenta\u00e7\u00f5es de concursos. Ol\u00e1, pessoal. Tudo bem? Aqui \u00e9 o Prof. Diego Cerqueira em nossa cent\u00e9sima carta aos Assinantes do Estrat\u00e9gia Concursos. Um dos editais mais aguardados dos \u00faltimos anos era do concurso do [&hellip;]<\/p>\n","protected":false},"author":1789,"featured_media":1099794,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1099787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carta aos Assinantes do Estrat\u00e9gia Concursos - 100<\/title>\n<meta name=\"description\" content=\"Confira, em nossa 100\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta aos Assinantes do Estrat\u00e9gia Concursos - 100\" \/>\n<meta property=\"og:description\" content=\"Confira, em nossa 100\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-30T18:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o Estrat\u00e9gia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o Estrat\u00e9gia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021\"},\"headline\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 100\",\"datePublished\":\"2022-09-26T12:00:00+00:00\",\"dateModified\":\"2022-09-30T18:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\"},\"wordCount\":1844,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\",\"name\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos - 100\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png\",\"datePublished\":\"2022-09-26T12:00:00+00:00\",\"dateModified\":\"2022-09-30T18:26:16+00:00\",\"description\":\"Confira, em nossa 100\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 100\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021\",\"name\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o Estrat\u00e9gia\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 100","description":"Confira, em nossa 100\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/","og_locale":"pt_BR","og_type":"article","og_title":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 100","og_description":"Confira, em nossa 100\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-09-26T12:00:00+00:00","article_modified_time":"2022-09-30T18:26:16+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png","type":"image\/png"}],"author":"Coordena\u00e7\u00e3o Estrat\u00e9gia","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o Estrat\u00e9gia","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/"},"author":{"name":"Coordena\u00e7\u00e3o Estrat\u00e9gia","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021"},"headline":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 100","datePublished":"2022-09-26T12:00:00+00:00","dateModified":"2022-09-30T18:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/"},"wordCount":1844,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/","name":"Carta aos Assinantes do Estrat\u00e9gia Concursos - 100","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png","datePublished":"2022-09-26T12:00:00+00:00","dateModified":"2022-09-30T18:26:16+00:00","description":"Confira, em nossa 100\u00aa carta aos assinantes, a nossa programa\u00e7\u00e3o semanal, as novidades do nosso SQ e as principais movimenta\u00e7\u00f5es de concursos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/23165139\/imagem-carta-aos-assinantes-3.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/carta-aos-assinantes-100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Carta aos Assinantes do Estrat\u00e9gia Concursos &#8211; 100"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5fab3b1fa4a358429e37bc50f74021","name":"Coordena\u00e7\u00e3o Estrat\u00e9gia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adff33ff18541ba37c900dd2b1e82dbfb0fe33d873b92636b4827a8da462feb3?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o Estrat\u00e9gia"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victor-tanakaaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1099787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1789"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1099787"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1099787\/revisions"}],"predecessor-version":[{"id":1099795,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1099787\/revisions\/1099795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1099794"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1099787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1099787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1099787"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1099787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}