{"id":1089066,"date":"2022-09-13T10:27:00","date_gmt":"2022-09-13T13:27:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1089066"},"modified":"2022-09-05T14:52:32","modified_gmt":"2022-09-05T17:52:32","slug":"resolucao-congresso-nacional-01-2006","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/","title":{"rendered":"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Confira neste artigo um resumo sobre a <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006<\/mark><\/strong>, para o concurso do <strong>Senado Federal<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/concurso-senado-federal-1.jpg\" alt=\"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006\" class=\"wp-image-1066699\" width=\"501\" height=\"282\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1-300x169.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1-610x343.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1-150x84.jpg 150w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><figcaption>Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ol\u00e1, pessoal! Tudo bem com voc\u00eas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O&nbsp;edital do&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/senado-federal-6\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso do Senado Federal<\/a><\/strong>&nbsp;finalmente foi publicado, para&nbsp;<strong>diversos cargos<\/strong>, com remunera\u00e7\u00e3o chegando a&nbsp;<strong>R$ 33.461,68<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa maneira, iremos realizar um <strong>resumo&nbsp;<\/strong>sobre um t\u00f3pico importante para este concurso: a&nbsp;<strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006<\/mark><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tamb\u00e9m pode conferir no nosso <strong>blog <\/strong>mais artigos sobre outros conte\u00fados para o concurso do Senado Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos l\u00e1!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-legislativo\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso Senado Federal<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/senado-federal-6\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n     \n\n  <\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-resolucao-do-congresso-nacional-01-2006\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">A Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006 disp\u00f5e sobre a <strong>Comiss\u00e3o Mista de Planos, Or\u00e7amentos P\u00fablicos e Fiscaliza\u00e7\u00e3o (CMO)<\/strong>, bem como sobre a <strong>tramita\u00e7\u00e3o <\/strong>dos projetos de lei relativos ao plano plurianual <strong>(PPA)<\/strong>, \u00e0s diretrizes or\u00e7ament\u00e1rias <strong>(LDO)<\/strong>, ao or\u00e7amento anual <strong>(LOA)<\/strong> e aos <strong>cr\u00e9ditos adicionais<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-comissao-mista-de-planos-orcamentos-publicos-e-fiscalizacao\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">A Comiss\u00e3o Mista de Planos, Or\u00e7amentos P\u00fablicos e Fiscaliza\u00e7\u00e3o<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Comiss\u00e3o Mista de Planos, Or\u00e7amentos P\u00fablicos e Fiscaliza\u00e7\u00e3o (CMO) \u00e9 uma das principais comiss\u00f5es permanentes do Congresso Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sua principal compet\u00eancia<strong> <\/strong>\u00e9 <strong>emitir parecer<\/strong> e <strong>deliberar<\/strong> sobre os <strong>projetos de lei<\/strong> relativos ao <strong>PPA<\/strong>, <strong>LDO<\/strong>, <strong>LOA <\/strong>e <strong>cr\u00e9ditos adicionais<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, ela tamb\u00e9m \u00e9 competente para <strong>emitir parecer<\/strong> e <strong>deliberar <\/strong>sobre:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>planos<\/strong> e <strong>programas <\/strong>nacionais, regionais e setoriais;<\/li><li><strong>documentos <\/strong>pertinentes ao acompanhamento e <strong>fiscaliza\u00e7\u00e3o <\/strong>da execu\u00e7\u00e3o or\u00e7ament\u00e1ria e financeira e da gest\u00e3o fiscal, especialmente sobre:<ul><li>os relat\u00f3rios de <strong>gest\u00e3o fiscal<\/strong>;<\/li><\/ul><ul><li>as informa\u00e7\u00f5es encaminhadas pelo Tribunal de Contas da Uni\u00e3o relativas \u00e0 <strong>fiscaliza\u00e7\u00e3o <\/strong>de obras e servi\u00e7os em que foram identificados ind\u00edcios de irregularidades graves e relacionados em anexo \u00e0 lei or\u00e7ament\u00e1ria anual, nos termos da lei de diretrizes or\u00e7ament\u00e1rias;<\/li><\/ul><ul><li>os relat\u00f3rios referentes aos atos de <strong>limita\u00e7\u00e3o de empenho<\/strong> e<strong> movimenta\u00e7\u00e3o financeira<\/strong>;<\/li><\/ul><ul><li>as <strong>informa\u00e7\u00f5es<\/strong> <strong>prestadas <\/strong>pelo Poder Executivo, ao Congresso Nacional.<\/li><\/ul><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-composicao-e-instalacao-da-cmo\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Composi\u00e7\u00e3o e instala\u00e7\u00e3o da CMO<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Comiss\u00e3o Mista de Planos, Or\u00e7amentos P\u00fablicos e Fiscaliza\u00e7\u00e3o ser\u00e1 composta tanto por <strong>Senadores <\/strong>quanto por <strong>Deputados Federais<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e3o <strong>40 membros titulares<\/strong>, sendo <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">30 Deputados Federais<\/mark><\/strong> e <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">10 Senadores<\/mark><\/strong>, com igual n\u00famero de suplentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a composi\u00e7\u00e3o da CMO, dever\u00e1 ser obedecido o crit\u00e9rio da<strong> proporcionalidade partid\u00e1ria<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o <strong>5\u00ba dia \u00fatil <\/strong>do m\u00eas de <strong>mar\u00e7o<\/strong>, os L\u00edderes <strong>indicar\u00e3o <\/strong>ao Presidente da Mesa do Congresso Nacional os <strong>membros <\/strong>titulares e suplentes em n\u00famero equivalente \u00e0 proporcionalidade de suas bancadas na CMO, sendo <strong>proibida <\/strong>que haja designa\u00e7\u00e3o de parlamentares membros titulares ou suplentes que integraram a <strong>Comiss\u00e3o anterior<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas e se n\u00e3o forem indicados parlamentares pelos L\u00edderes? Bom, neste caso, as vagas n\u00e3o preenchidas por partido ou bloco parlamentar ser\u00e3o ocupadas pelos parlamentares mais <strong>idosos<\/strong>, dentre os de <strong>maior n\u00famero de legislaturas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso o membro titular da CMO <strong>n\u00e3o comparecer<\/strong> durante a sess\u00e3o legislativa, por <strong>3 reuni\u00f5es consecutivas<\/strong> ou <strong>6 alternadas<\/strong>, ele ser\u00e1 <strong>desligado <\/strong>da comiss\u00e3o, salvo no caso de afastamento por miss\u00e3o oficial ou justificado por atestado m\u00e9dico. Ademais, o membro que for desligado n\u00e3o poder\u00e1 retornar \u00e0 comiss\u00e3o na mesma sess\u00e3o legislativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">INSTALA\u00c7\u00c3O<\/mark><\/strong>: A <strong>instala\u00e7\u00e3o<\/strong> da CMO e a <strong>elei\u00e7\u00e3o <\/strong>da respectiva Mesa devem ocorrer at\u00e9 a <strong>\u00faltima ter\u00e7a-feira<\/strong> do m\u00eas de <strong>mar\u00e7o <\/strong>de cada ano, sendo esta a data em que se encerra o mandato dos membros da comiss\u00e3o anterior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comites-permanentes\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Comit\u00eas Permanentes<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para ser desempenhada todas as fun\u00e7\u00f5es da CMO, ser\u00e3o constitu\u00eddos <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">quatro comit\u00eas permanentes<\/mark><\/strong>, sendo eles:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Comit\u00ea de Avalia\u00e7\u00e3o, <strong>Fiscaliza\u00e7\u00e3o <\/strong>e Controle da Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria;<\/li><li>Comit\u00ea de Avalia\u00e7\u00e3o da <strong>Receita<\/strong>;<\/li><li>Comit\u00ea de Avalia\u00e7\u00e3o das Informa\u00e7\u00f5es sobre <strong>Obras <\/strong>e Servi\u00e7os com Ind\u00edcios de Irregularidades Graves;<\/li><li>Comit\u00ea de Exame da Admissibilidade de <strong>Emendas<\/strong>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estes comit\u00eas ter\u00e3o no <strong>m\u00ednimo 5 e no m\u00e1ximo 10 membros<\/strong>, os quais ser\u00e3o indicados pelos L\u00edderes, havendo tamb\u00e9m a figura do coordenador em cada comit\u00ea, escolhido obrigatoriamente dentre seus membros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a>De modo similar \u00e0 CMO, a designa\u00e7\u00e3o dos membros e coordenadores dos comit\u00eas permanentes obedecer\u00e1 ao crit\u00e9rio da proporcionalidade partid\u00e1ria e ao da proporcionalidade dos membros de cada Casa na CMO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos agora verificar como ser\u00e1 a an\u00e1lise da LOA, LDO, PPA e Cr\u00e9ditos Adicionais na CMO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-projeto-de-lei-orcamentaria-anual\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Projeto de Lei Or\u00e7ament\u00e1ria Anual<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O PLOA ser\u00e1 dividido em diversas <strong>\u00e1reas tem\u00e1ticas<\/strong>, como sa\u00fade e educa\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso o Presidente da Rep\u00fablica deseje <strong>alterar <\/strong>o PLOA j\u00e1 enviado ao Congresso, a proposta de modifica\u00e7\u00e3o do projeto somente ser\u00e1 apreciada se recebida at\u00e9 o in\u00edcio da <strong>vota\u00e7\u00e3o <\/strong>do Relat\u00f3rio Preliminar na CMO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A CMO realizar\u00e1 <strong>audi\u00eancias p\u00fablicas <\/strong>para o debate e o aprimoramento do PLOA, sendo convidados Ministros ou representantes dos \u00f3rg\u00e3os de Planejamento, Or\u00e7amento e Fazenda do Poder Executivo e representantes dos \u00f3rg\u00e3os e entidades integrantes das \u00e1reas tem\u00e1ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dever\u00e3o ser avaliadas as <strong>receitas<\/strong> estimadas e as <strong>despesas <\/strong>fixadas no PLOA, durante a an\u00e1lise da comiss\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As <strong>Comiss\u00f5es Permanentes<\/strong> do Senado Federal e da C\u00e2mara dos Deputados, cujas compet\u00eancias estejam direta e materialmente relacionadas \u00e0 \u00e1rea de atua\u00e7\u00e3o pertinente \u00e0 estrutura da administra\u00e7\u00e3o p\u00fablica federal, poder\u00e3o apresentar <strong>emendas <\/strong>ao PLOA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m poder\u00e3o ser apresentadas emendas pelas <strong>Bancadas Estaduais<\/strong> no Congresso Nacional, relativas a mat\u00e9rias de interesse de cada Estado, devendo elas ser <strong>aprovadas<\/strong> por <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">3\/4 dos Deputados<\/mark><\/strong> e <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>2\/3 dos Senadores<\/strong><\/mark><strong> <\/strong>da respectiva <strong>Unidade da Federa\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, cada <strong>parlamentar <\/strong>tamb\u00e9m poder\u00e1 apresentar emendas, de modo individual, no limite de at\u00e9 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">25<\/mark><\/strong>, cabendo ao Parecer Preliminar fixar o valor total do conjunto das emendas a serem apresentadas, por mandato parlamentar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-projeto-de-lei-de-diretrizes-orcamentarias\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Projeto de Lei de Diretrizes Or\u00e7ament\u00e1rias<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De maneira similar ao PLOA, a proposta de modifica\u00e7\u00e3o do projeto de lei de diretrizes or\u00e7ament\u00e1rias (PLDO) enviada pelo Presidente da Rep\u00fablica ao Congresso Nacional apenas ser\u00e1 apreciada se recebida at\u00e9 o <strong>in\u00edcio <\/strong>da <strong>vota\u00e7\u00e3o <\/strong>do Relat\u00f3rio Preliminar na CMO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes da apresenta\u00e7\u00e3o do Relat\u00f3rio Preliminar da comiss\u00e3o, ser\u00e1 realizada<strong> audi\u00eancia p\u00fablica<\/strong> com o Ministro do Planejamento, Or\u00e7amento e Gest\u00e3o para discuss\u00e3o do projeto, sendo que o seu Presidente poder\u00e1 solicitar ao Ministro que encaminhe \u00e0 CMO, no prazo de at\u00e9 <strong>5 dias<\/strong> antes da audi\u00eancia, textos explicativos sobre assuntos relacionados ao projeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda em rela\u00e7\u00e3o ao Relat\u00f3rio Preliminar, nele dever\u00e1 constar a avalia\u00e7\u00e3o do cen\u00e1rio econ\u00f4mico-fiscal e social do PLDO, dos par\u00e2metros que foram utilizados para a sua elabora\u00e7\u00e3o e das informa\u00e7\u00f5es constantes de seus anexos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O PLDO tamb\u00e9m poder\u00e1 receber propostas de <strong>emendas <\/strong>da Comiss\u00e3o, da Bancada Estadual e Individuais, devendo ser observados os seguintes limites:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>at\u00e9 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">5 emendas<\/mark><\/strong>, para as <strong>Comiss\u00f5es Permanentes<\/strong> do Senado Federal e da C\u00e2mara dos Deputados;<\/li><li>at\u00e9 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">5 emendas<\/mark><\/strong>, para as <strong>Bancadas Estaduai<\/strong>s do Congresso Nacional;<\/li><li>at\u00e9 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">5 emendas<\/mark><\/strong> por <strong>parlamentar<\/strong>, individualmente.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">VEDA\u00c7\u00c3O<\/mark><\/strong>: Contudo, <strong>n\u00e3o <\/strong>ser\u00e3o admitidas emendas que proponham a inclus\u00e3o de a\u00e7\u00f5es <strong>n\u00e3o constantes<\/strong> da lei do <strong>plano plurianual<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-projeto-de-lei-do-plano-plurianual\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Projeto de Lei do Plano Plurianual<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O primeiro ponto a se destacar \u00e9 que o relat\u00f3rio deste projeto ser\u00e1 elaborado apenas por <strong>um \u00fanico Relator<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 poss\u00edvel a realiza\u00e7\u00e3o de <strong>audi\u00eancias p\u00fablicas regionais<\/strong>, pela CMO, com o intuito de debater o projeto, quando de interesse de Estado ou Regi\u00e3o Geogr\u00e1fica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As emendas para alterar o projeto de lei do plano plurianual poder\u00e3o ser apresentadas pela Comiss\u00e3o, Bancada Estadual ou individualmente, observado os seguintes limites:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>at\u00e9 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">5 emendas<\/mark><\/strong>, para as <strong>Comiss\u00f5es Permanentes<\/strong> do Senado Federal ou da C\u00e2mara dos Deputados;<\/li><li>at\u00e9 <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>5 emendas,<\/strong> <\/mark>para as <strong>Bancadas Estaduais<\/strong> do Congresso Nacional;<\/li><li>at\u00e9 <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">10 emendas<\/mark><\/strong> por <strong>parlamentar<\/strong>, individualmente.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">De modo a apoiar o relator na an\u00e1lise do projeto, poder\u00e1 ser constitu\u00eddo um <strong>comit\u00ea para apoio<\/strong> com o <strong>m\u00ednimo de 3 e o m\u00e1ximo de 10 integrantes<\/strong>, por ele indicados. Contudo, \u00e9 necess\u00e1rio que haja a obedi\u00eancia ao crit\u00e9rio da proporcionalidade partid\u00e1ria e ao da proporcionalidade dos membros de cada Casa na CMO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-projetos-de-lei-de-creditos-adicionais\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Projetos de Lei de Cr\u00e9ditos Adicionais<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os projetos de lei de cr\u00e9ditos adicionais apenas ser\u00e3o apreciados pela comiss\u00e3o <strong>at\u00e9 <\/strong>o dia <strong>20 de novembro<\/strong> de cada ano. Em rela\u00e7\u00e3o aos projetos sobre os quais a CMO n\u00e3o emitir parecer no prazo citado, eles dever\u00e3o ser apreciados pelo Plen\u00e1rio do Congresso Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os <strong>parlamentares<\/strong>, individualmente, poder\u00e3o apresentar emendas ao projeto, sendo limitado ao n\u00famero de <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">10 emendas<\/mark><\/strong> a cr\u00e9dito adicional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, algumas emendas <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">n\u00e3o ser\u00e3o admitidas<\/mark><\/strong>, como aquelas que:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>contemplarem programa\u00e7\u00e3o em unidade or\u00e7ament\u00e1ria <strong>n\u00e3o benefici\u00e1ria do cr\u00e9dito<\/strong>;<\/li><li>oferecerem como <strong>fonte <\/strong>de <strong>cancelamento compensat\u00f3rio<\/strong> programa\u00e7\u00e3o que:<ul><li>n\u00e3o conste do projeto de lei ou conste somente como cancelamento proposto; ou<\/li><\/ul><ul><li>integre dota\u00e7\u00e3o \u00e0 conta de recursos oriundos de opera\u00e7\u00f5es de cr\u00e9dito internas ou externas e as respectivas contrapartidas, ressalvados os casos decorrentes de corre\u00e7\u00e3o de erro ou de omiss\u00e3o de ordem t\u00e9cnica ou legal, devidamente comprovados;<\/li><\/ul><\/li><li><strong>propuserem<\/strong>:<ul><li>em projetos de lei de cr\u00e9dito suplementar, <strong>programa\u00e7\u00e3o nova<\/strong>;<\/li><\/ul><ul><li>em projetos de lei de cr\u00e9dito especial, a suplementa\u00e7\u00e3o de dota\u00e7\u00f5es <strong>j\u00e1 existentes<\/strong> na lei or\u00e7ament\u00e1ria;<\/li><\/ul><ul><li>em projetos de lei de cr\u00e9dito adicional, a <strong>anula\u00e7\u00e3o <\/strong>de dota\u00e7\u00f5es or\u00e7ament\u00e1rias constantes do anexo de cancelamento <strong>sem indicar<\/strong>, como compensa\u00e7\u00e3o, a programa\u00e7\u00e3o a ser cancelada no correspondente anexo de suplementa\u00e7\u00e3o;<\/li><\/ul><\/li><li>ocasionarem <strong>aumento<\/strong> no <strong>valor original <\/strong>do projeto.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Finalizando<\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bom, Pessoal! Chegamos ao final do resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006. Esperamos que tenham gostado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, ressaltamos a import\u00e2ncia da<strong>&nbsp;leitura na \u00edntegra desta resolu\u00e7\u00e3o<\/strong>, para a sua aprova\u00e7\u00e3o. Esse artigo \u00e9 apenas uma an\u00e1lise mais simplificada da norma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso queira se preparar para chegar&nbsp;<strong>competitivo&nbsp;<\/strong>nesta prova, invista nos&nbsp;<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/senado-federal-6\/\" target=\"_blank\" rel=\"noreferrer noopener\">cursos para Senado Federal<\/a><\/strong>&nbsp;do&nbsp;<strong>Estrat\u00e9gia Concursos<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00e1 voc\u00ea encontrar\u00e1&nbsp;<strong>aulas completas e detalhadas, com os melhores professores do mercado<\/strong>,&nbsp;de todos os t\u00f3picos exigidos no edital deste concurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a tamb\u00e9m o&nbsp;<a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sistema de Quest\u00f5es do Estrat\u00e9gia<\/strong><\/a>. Afinal, a \u00fanica maneira de&nbsp;<strong>consolidar o conte\u00fado&nbsp;<\/strong>de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da&nbsp;<strong>resolu\u00e7\u00e3o de quest\u00f5es.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bons estudos a todos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas-para-o-senado-federal\">Cursos e Assinaturas para o Senado Federal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-legislativo\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Concurso Senado Federal<\/h3>\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursosPorConcurso\/senado-federal-6\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\n        <\/div>\n      <\/div>\n     \n\n  <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div><\/div><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006, para o concurso do Senado Federal. Ol\u00e1, pessoal! Tudo bem com voc\u00eas? O&nbsp;edital do&nbsp;concurso do Senado Federal&nbsp;finalmente foi publicado, para&nbsp;diversos cargos, com remunera\u00e7\u00e3o chegando a&nbsp;R$ 33.461,68. Dessa maneira, iremos realizar um resumo&nbsp;sobre um t\u00f3pico importante para este concurso: a&nbsp;Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006. [&hellip;]<\/p>\n","protected":false},"author":1976,"featured_media":1066699,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[2017],"tags":[],"tax_estado":[219963],"class_list":["post-1089066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-legislativos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006<\/title>\n<meta name=\"description\" content=\"Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006, para o concurso do Senado Federal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006, para o concurso do Senado Federal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-13T13:27:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kassio Henrique Sobral Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kassio Henrique Sobral Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/\"},\"author\":{\"name\":\"Kassio Henrique Sobral Rocha\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f0c830e07cfe11c231c0ea5dbb036df5\"},\"headline\":\"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\\\/2006\",\"datePublished\":\"2022-09-13T13:27:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/\"},\"wordCount\":1849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/07\\\/26082143\\\/concurso-senado-federal-1.jpg\",\"articleSection\":[\"Legislativo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/\",\"name\":\"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\\\/2006\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/07\\\/26082143\\\/concurso-senado-federal-1.jpg\",\"datePublished\":\"2022-09-13T13:27:00+00:00\",\"description\":\"Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\\\/2006, para o concurso do Senado Federal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/07\\\/26082143\\\/concurso-senado-federal-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/07\\\/26082143\\\/concurso-senado-federal-1.jpg\",\"width\":768,\"height\":432,\"caption\":\"Concurso Senado: PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/resolucao-congresso-nacional-01-2006\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\\\/2006\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f0c830e07cfe11c231c0ea5dbb036df5\",\"name\":\"Kassio Henrique Sobral Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"caption\":\"Kassio Henrique Sobral Rocha\"},\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/kassio-rochayahoo-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006","description":"Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006, para o concurso do Senado Federal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006","og_description":"Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006, para o concurso do Senado Federal.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-09-13T13:27:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg","type":"image\/jpeg"}],"author":"Kassio Henrique Sobral Rocha","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Kassio Henrique Sobral Rocha","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/"},"author":{"name":"Kassio Henrique Sobral Rocha","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5"},"headline":"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006","datePublished":"2022-09-13T13:27:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/"},"wordCount":1849,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg","articleSection":["Legislativo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/","name":"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg","datePublished":"2022-09-13T13:27:00+00:00","description":"Confira neste artigo um resumo sobre a Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006, para o concurso do Senado Federal.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/26082143\/concurso-senado-federal-1.jpg","width":768,"height":432,"caption":"Concurso Senado: PL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resolucao-congresso-nacional-01-2006\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Senado: Resolu\u00e7\u00e3o do Congresso Nacional 01\/2006"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5","name":"Kassio Henrique Sobral Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","caption":"Kassio Henrique Sobral Rocha"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/kassio-rochayahoo-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1089066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1976"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1089066"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1089066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1066699"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1089066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1089066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1089066"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1089066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}