{"id":1088802,"date":"2022-10-11T09:43:00","date_gmt":"2022-10-11T12:43:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1088802"},"modified":"2022-10-10T15:58:06","modified_gmt":"2022-10-10T18:58:06","slug":"credito-adicional","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/","title":{"rendered":"Cr\u00e9dito adicional com foco no TCE-TO"},"content":{"rendered":"\n<p>Ol\u00e1, aluno (a)! Tudo bem? Na postagem de hoje iremos falar sobre os tipos de cr\u00e9dito adicional, assunto presente no edital para o concurso do Tribunal de Contas do Estado do Tocantins.<\/p>\n\n\n\n<p>Quem estuda a disciplina de Administra\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria ou Contabilidade P\u00fablica para concurso provavelmente j\u00e1 se deparou com esse t\u00f3pico do edital anteriormente. Ele tamb\u00e9m pode ser cobrado em outras disciplinas como, por exemplo, Direito Financeiro ou Or\u00e7amento P\u00fablico.<\/p>\n\n\n\n<p>Quando o t\u00f3pico de cr\u00e9ditos adicionais consta no edital, normalmente ele \u00e9 cobrado em, pelo menos, uma quest\u00e3o na prova objetiva e, por vezes, at\u00e9 mesmo na prova discursiva, pedindo o conceito de cada tipo de cr\u00e9dito adicional e exemplos. Por esse motivo \u00e9 importante revisar esse t\u00f3pico sempre que poss\u00edvel.<\/p>\n\n\n\n<p>Dada a import\u00e2ncia desse tema, aconselho que sigam atentos com a leitura desse artigo. Iremos realizar uma abordagem te\u00f3rica, seguida da resolu\u00e7\u00e3o de quest\u00f5es de concursos sobre o tema e, por fim, um breve resumo contendo os principais t\u00f3picos analisados.<\/p>\n\n\n\n<p>Nesse artigo ser\u00e1 contemplado os seguintes t\u00f3picos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Cr\u00e9dito suplementar;<\/li><li>Cr\u00e9dito Especial;<\/li><li>Cr\u00e9dito Extraordin\u00e1rio;<\/li><li>Recursos para abertura de cr\u00e9ditos adicionais;&nbsp;&nbsp;&nbsp;<\/li><li>Resumo.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tipos-de-creditos-adicionais\">Tipos de cr\u00e9ditos adicionais<\/h2>\n\n\n\n<p>Em primeiro lugar \u00e9 importante destacar que os cr\u00e9ditos adicionais podem ser classificados como suplementares, especiais ou extraordin\u00e1rios. Vejamos o que disp\u00f5e o artigo 41 da Lei n\u00b0 4.320\/64 que estatui normas gerais de Direito Financeiro:<\/p>\n\n\n\n<p><em>Art. 41. Os cr\u00e9ditos adicionais classificam-se em:<\/em><\/p>\n\n\n\n<p><em>I &#8211; suplementares, os destinados a ref\u00f4r\u00e7o de dota\u00e7\u00e3o or\u00e7ament\u00e1ria;<\/em><\/p>\n\n\n\n<p><em>II &#8211; especiais, os destinados a despesas para as quais n\u00e3o haja dota\u00e7\u00e3o or\u00e7ament\u00e1ria espec\u00edfica;<\/em><\/p>\n\n\n\n<p><em>III &#8211; extraordin\u00e1rios, os destinados a despesas urgentes e imprevistas, em caso de guerra, como\u00e7\u00e3o intestina ou calamidade p\u00fablica.<\/em><\/p>\n\n\n\n<p>Vamos ver mais abaixo com detalhes em que consiste cada um dos tipos de cr\u00e9dito adicional. Antes disso, vale a leitura tamb\u00e9m do artigo 40 da supracitada lei:<\/p>\n\n\n\n<p><em>Art. 40. S\u00e3o cr\u00e9ditos adicionais, as autoriza\u00e7\u00f5es de despesa n\u00e3o computadas ou insuficientemente dotadas na Lei de Or\u00e7amento.<\/em><\/p>\n\n\n\n<p>Dessa forma podemos ver que os cr\u00e9ditos adicionais podem consistir tanto em cr\u00e9ditos para os quais j\u00e1 havia dota\u00e7\u00e3o inicial na Lei Or\u00e7ament\u00e1ria Anual (LOA), como tamb\u00e9m para cobrir despesas que n\u00e3o estavam inicialmente previstas no or\u00e7amento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"919\" height=\"517\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png\" alt=\"Cr\u00e9ditos Adicionais\" class=\"wp-image-1088804\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png 919w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51-300x169.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51-768x432.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51-610x343.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51-150x84.png 150w\" sizes=\"auto, (max-width: 919px) 100vw, 919px\" \/><figcaption>Tipos de cr\u00e9dito adicional<\/figcaption><\/figure>\n\n\n\n<p>Vejamos agora em que consiste cada uma dessas classifica\u00e7\u00f5es de cr\u00e9ditos adicionais e as principais diferen\u00e7as entre elas. Preste aten\u00e7\u00e3o nos pr\u00f3ximos t\u00f3picos, pois eles costumam ser cobrados nas provas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-credito-adicional-credito-suplementar\">Cr\u00e9dito adicional: cr\u00e9dito suplementar<\/h2>\n\n\n\n<p>Em primeiro lugar vale ressaltar que os cr\u00e9ditos suplementares s\u00e3o destinados a refor\u00e7ar dota\u00e7\u00f5es que j\u00e1 est\u00e3o previstas no or\u00e7amento. Ou seja, n\u00e3o \u00e9 poss\u00edvel criar uma dota\u00e7\u00e3o nova com esse tipo de cr\u00e9dito.<\/p>\n\n\n\n<p>Para melhor compreens\u00e3o vejamos um exemplo, vamos supor que est\u00e1 previsto no or\u00e7amento uma dota\u00e7\u00e3o para a constru\u00e7\u00e3o de uma escola. Contudo, no decorrer do exerc\u00edcio financeiro, verifica-se que a dota\u00e7\u00e3o prevista no or\u00e7amento n\u00e3o seria suficiente para a realiza\u00e7\u00e3o desse investimento.<\/p>\n\n\n\n<p>Dessa forma, deve-se realizar um refor\u00e7o da dota\u00e7\u00e3o or\u00e7ament\u00e1ria de modo a conseguir concluir a constru\u00e7\u00e3o. Esse refor\u00e7o \u00e9 justamente o que chamamos de cr\u00e9dito suplementar. Note que, caso a dota\u00e7\u00e3o n\u00e3o estivesse prevista inicialmente no or\u00e7amento, ela n\u00e3o seria um cr\u00e9dito suplementar.<\/p>\n\n\n\n<p>\u00c9 importante destacar que, de acordo com a Lei 4.320\/64, esse tipo de cr\u00e9dito deve ser <strong>autorizado por lei e aberto por decreto executivo<\/strong>. A autoriza\u00e7\u00e3o da abertura de cr\u00e9dito suplementar pode estar na pr\u00f3pria Lei Or\u00e7ament\u00e1ria Anual.<\/p>\n\n\n\n<p><em>Art. 42. Os cr\u00e9ditos suplementares e especiais ser\u00e3o autorizados por lei e abertos por decreto executivo.<\/em><\/p>\n\n\n\n<p>Os&nbsp;cr\u00e9ditos adicionais suplementares ter\u00e3o vig\u00eancia adstrita ao exerc\u00edcio financeiro em que forem abertos, n\u00e3o comportando exce\u00e7\u00f5es como acontece com os cr\u00e9ditos especiais e extraordin\u00e1rios (veremos abaixo).<\/p>\n\n\n\n<p>Outro ponto que merece aten\u00e7\u00e3o \u00e9 que a<em> <\/em>abertura dos cr\u00e9ditos suplementares depende da exist\u00eancia de recursos dispon\u00edveis e devem ser devidamente justificados.<\/p>\n\n\n\n<p><em>Art. 43. A abertura dos cr\u00e9ditos suplementares e especiais depende da exist\u00eancia de recursos dispon\u00edveis para ocorrer a despesa e ser\u00e1 precedida de exposi\u00e7\u00e3o justificativa.<\/em><\/p>\n\n\n\n<p>Resumindo, <strong>os cr\u00e9ditos suplementares:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00e3o um refor\u00e7o da dota\u00e7\u00e3o or\u00e7ament\u00e1ria existente;<\/li><li>S\u00e3o autorizados por lei e abertos por decreto do Poder Executivo;<\/li><li>T\u00eam a vig\u00eancia limitada ao exerc\u00edcio financeiro em que for aberto;<\/li><li>Incorporam-se ao or\u00e7amento;<\/li><li>T\u00eam que indicar obrigatoriamente as fontes de recurso;<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-credito-adicional-credito-especial\">Cr\u00e9dito adicional: cr\u00e9dito especial<\/h2>\n\n\n\n<p>Ao contr\u00e1rio do que acontece no cr\u00e9dito suplementar, o cr\u00e9dito especial destina-se a despesas para as quais n\u00e3o haja dota\u00e7\u00e3o or\u00e7ament\u00e1ria espec\u00edfica. Assim, caso a despesa n\u00e3o esteja inicialmente prevista na LOA, ser\u00e1 necess\u00e1ria a abertura de um cr\u00e9dito especial para atend\u00ea-la.<\/p>\n\n\n\n<p>Assim como os cr\u00e9ditos suplementares, os especiais devem ser autorizados por lei e abertos por decreto executivo. A diferen\u00e7a aqui \u00e9 que a lei que aprova a abertura dos cr\u00e9ditos especiais n\u00e3o pode ser a pr\u00f3pria LOA. Al\u00e9m disso, esse tipo de cr\u00e9dito est\u00e1 sempre dependente da exist\u00eancia de recursos dispon\u00edveis e de justificativa pr\u00e9via.<\/p>\n\n\n\n<p>Ao contr\u00e1rio do cr\u00e9dito suplementar que tem sempre a vig\u00eancia restrita ao exerc\u00edcio financeiro em que forem abertos, o cr\u00e9dito especial pode, excepcionalmente, viger at\u00e9 o t\u00e9rmino do exerc\u00edcio financeiro subsequente. Isso acontece apenas se o ato de autoriza\u00e7\u00e3o for promulgado nos \u00faltimos quatro meses do exerc\u00edcio, casos em que, poder\u00e3o ser reabertos nos limites dos seus saldos.<\/p>\n\n\n\n<p>De acordo com o art. da Lei 4.320\/64 e tamb\u00e9m do art. 167, V, da CF\/1988:<\/p>\n\n\n\n<p><em>Art. 45. Os cr\u00e9ditos adicionais ter\u00e3o vig\u00eancia adstrita ao exerc\u00edcio financeiro em que forem abertos, salvo expressa disposi\u00e7\u00e3o legal em contr\u00e1rio, quanto aos especiais e extraordin\u00e1rios.<\/em><\/p>\n\n\n\n<p><em>Art. 167. (&#8230;)<\/em><\/p>\n\n\n\n<p><em>\u00a7 2\u00ba Os cr\u00e9ditos especiais e extraordin\u00e1rios ter\u00e3o vig\u00eancia no exerc\u00edcio financeiro em que forem autorizados, salvo se o ato de autoriza\u00e7\u00e3o for promulgado nos \u00faltimos quatro meses daquele exerc\u00edcio, caso em que, reabertos nos limites de seus saldos, ser\u00e3o incorporados ao or\u00e7amento do exerc\u00edcio financeiro subseq\u00fcente.<\/em><\/p>\n\n\n\n<p>Vale ressaltar que a reabertura do cr\u00e9dito \u00e9 facultativa, limitada ao saldo remanescente, e novo ato da Administra\u00e7\u00e3o P\u00fablica dever\u00e1 reabri-lo.<\/p>\n\n\n\n<p>Resumindo, os <strong>cr\u00e9ditos especiais:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00e3o utilizados quando n\u00e3o h\u00e1 dota\u00e7\u00e3o or\u00e7ament\u00e1ria espec\u00edfica;<\/li><li>S\u00e3o autorizados por lei e abertos por decreto do Poder Executivo;<\/li><li>S\u00e3o exce\u00e7\u00e3o ao princ\u00edpio da anualidade (quando abertos nos \u00faltimos quatro meses);<\/li><li>Conservam a sua especificidade;<\/li><li>T\u00eam que indicar obrigatoriamente as fontes de recurso;<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-credito-adicional-credito-extraordinario\">Cr\u00e9dito adicional: cr\u00e9dito extraordin\u00e1rio<\/h2>\n\n\n\n<p>Os cr\u00e9ditos extraordin\u00e1rios s\u00e3o os destinados a despesas urgentes e imprevis\u00edveis, tais como em caso de guerra, como\u00e7\u00e3o interna ou calamidade p\u00fablica (\u00a73\u00b0 do art. 167 da CF\/88):<\/p>\n\n\n\n<p><em>Art. 167 (&#8230;)<\/em><\/p>\n\n\n\n<p><em>\u00a7 3\u00ba A abertura de cr\u00e9dito extraordin\u00e1rio somente ser\u00e1 admitida para atender a despesas imprevis\u00edveis e urgentes, como as decorrentes de guerra, como\u00e7\u00e3o interna ou calamidade p\u00fablica, observado o disposto no art. 62.<\/em><\/p>\n\n\n\n<p>Um exemplo de abertura desse tipo de cr\u00e9dito foi durante a pandemia, em que foram abertos cr\u00e9ditos destinados \u00e0 a\u00e7\u00f5es de combate \u00e0 situa\u00e7\u00e3o enfrentada.<\/p>\n\n\n\n<p>Esse tipo de cr\u00e9dito \u00e9 aberto por medida provis\u00f3ria, no caso federal e de entes que possuem tal instrumento, e por decreto do Poder Executivo para os demais entes, devendo ser dado imediato conhecimento ao Poder Legislativo (Lei 4.320\/64):<\/p>\n\n\n\n<p><em>Art. 44. Os cr\u00e9ditos extraordin\u00e1rios ser\u00e3o abertos por decreto do Poder Executivo, que deles dara imediato conhecimento ao Poder Legislativo.<\/em><\/p>\n\n\n\n<p>Importante ressaltar que, tal como o cr\u00e9dito especial, esse tipo de cr\u00e9dito \u00e9 uma exce\u00e7\u00e3o ao princ\u00edpio da anualidade, uma vez que pode ser reaberto no exerc\u00edcio seguinte. Isso acontece apenas se o ato de autoriza\u00e7\u00e3o for promulgado nos \u00faltimos quatro meses do exerc\u00edcio.<\/p>\n\n\n\n<p>Ao contr\u00e1rio do cr\u00e9dito suplementar e especial, a indica\u00e7\u00e3o da fonte de recursos \u00e9 facultativa para o cr\u00e9dito extraordin\u00e1rio, ou seja, n\u00e3o depende da exist\u00eancia de fontes e recursos dispon\u00edveis para a sua abertura. Apesar disso, esse cr\u00e9dito deve possuir uma dota\u00e7\u00e3o limitada, n\u00e3o admitindo valores indeterminados. Caso se constate que o valor foi insuficiente, um novo cr\u00e9dito especial deve ser aberto.<\/p>\n\n\n\n<p>Resumindo, os <strong>cr\u00e9ditos extraordin\u00e1rios:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00e3o utilizados para atender despesas imprevis\u00edveis e urgentes;<\/li><li>S\u00e3o abertos por medida provis\u00f3ria ou decreto do Poder Executivo;<\/li><li>S\u00e3o exce\u00e7\u00e3o ao princ\u00edpio da anualidade (quando abertos nos \u00faltimos quatro meses);<\/li><li>Conservam a sua especificidade;<\/li><li>Indica\u00e7\u00e3o facultativa das fontes de recurso;<\/li><li>Independem de autoriza\u00e7\u00e3o legislativa pr\u00e9via;<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-recursos-para-abertura-de-creditos-adicionais\">Recursos para abertura de cr\u00e9ditos adicionais<\/h2>\n\n\n\n<p>Para os cr\u00e9ditos especiais e suplementares \u00e9 necess\u00e1ria a indica\u00e7\u00e3o pr\u00e9via dos recursos. Nesse sentido a Lei n\u00b0 4.320\/64 disp\u00f5e como recursos para a abertura de cr\u00e9ditos adicionais:<\/p>\n\n\n\n<p><em>Art. 43 (&#8230;)<\/em><\/p>\n\n\n\n<p><em>\u00a7 1\u00ba Consideram-se recursos para o fim deste artigo, desde que n\u00e3o comprometidos:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p><em>I &#8211; o super\u00e1vit financeiro apurado em balan\u00e7o patrimonial do exerc\u00edcio anterior;<\/em><\/p>\n\n\n\n<p><em>II &#8211; os provenientes de excesso de arrecada\u00e7\u00e3o;<\/em><\/p>\n\n\n\n<p><em>III &#8211; os resultantes de anula\u00e7\u00e3o parcial ou total de dota\u00e7\u00f5es or\u00e7ament\u00e1rias ou de cr\u00e9ditos adicionais, autorizados em Lei;<\/em><\/p>\n\n\n\n<p><em>IV &#8211; o produto de opera\u00e7\u00f5es de cr\u00e9dito autorizadas, em forma que juridicamente possibilite ao poder executivo realiz\u00e1-las.<\/em><\/p>\n\n\n\n<p>Vale destacar que o super\u00e1vit financeiro \u00e9 apurado em <strong>balan\u00e7o patrimonial, <\/strong>isso costuma ser \u201cpegadinha\u201d das bancas examinadoras, que trocam esse termo por balan\u00e7o financeiro. Al\u00e9m disso, reparem tamb\u00e9m que at\u00e9 mesmo a anula\u00e7\u00e3o de um cr\u00e9dito adicional pode servir como recurso para a abertura de outro.<\/p>\n\n\n\n<p>&nbsp;Al\u00e9m dessas fontes, a CF\/88 tamb\u00e9m considera a seguinte:<\/p>\n\n\n\n<p><em>Art. 166 (&#8230;)<\/em><\/p>\n\n\n\n<p><em>\u00a7 8.\u00ba Os recursos que, em <strong>decorr\u00eancia de veto, emenda ou rejei\u00e7\u00e3o<\/strong> do projeto de lei or\u00e7ament\u00e1ria anual, ficarem sem despesas correspondentes poder\u00e3o ser utilizados, conforme o caso, <strong>mediante cr\u00e9ditos especiais ou suplementares<\/strong>, com pr\u00e9via e espec\u00edfica autoriza\u00e7\u00e3o legislativa.<\/em><\/p>\n\n\n\n<p>Finalmente, tamb\u00e9m s\u00e3o considerados recursos para a abertura de cr\u00e9ditos adicionais aqueles provenientes da <strong>Reserva de Conting\u00eancia <\/strong>previstos na Lei Or\u00e7ament\u00e1ria Anual.<\/p>\n\n\n\n<p>N\u00e3o menosprezem o estudo desse t\u00f3pico (fontes de recurso para abertura de cr\u00e9ditos adicionais), pois a sua cobran\u00e7a \u00e9 recorrente nas provas de concursos p\u00fablicos.<\/p>\n\n\n\n<p>Em suma, s\u00e3o <strong>recursos para abertura de cr\u00e9ditos adicionais:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Super\u00e1vit financeiro apurado em balan\u00e7o patrimonial;<\/li><li>Excesso de arrecada\u00e7\u00e3o;<\/li><li>Anula\u00e7\u00e3o de dota\u00e7\u00e3o or\u00e7ament\u00e1ria;<\/li><li>Opera\u00e7\u00f5es de cr\u00e9dito autorizadas;<\/li><li>Decorrentes de veto, emenda ou rejei\u00e7\u00e3o do projeto da LOA;<\/li><li>Reserva de conting\u00eancia;<\/li><\/ul>\n\n\n\n<p>Por fim, vale salientar que se deve utilizar este artigo como complemento ao estudo, privilegiando, sempre, o material te\u00f3rico e as quest\u00f5es de concursos p\u00fablicos anteriores. Al\u00e9m disso, caso sinta necessidade, recomendo a visualiza\u00e7\u00e3o da videoaula sobre esse assunto.<\/p>\n\n\n\n<p>Na plataforma de assinantes do Estrat\u00e9gia existem v\u00eddeos sobre o tema de cr\u00e9ditos adicionais que podem te auxiliar no estudo. Como a banca do concurso para o TCE \u2013 TO j\u00e1 foi definida (Funda\u00e7\u00e3o Get\u00falio Vargas), aconselho resolver prioritariamente quest\u00f5es dessa banca examinadora.<\/p>\n\n\n\n<p>Bons estudos,<\/p>\n\n\n\n<p>Carlos Eduardo Cardoso.<\/p>\n\n\n\n<p>Consultor do Tesouro Estadual e Professor do Estrat\u00e9gia quest\u00f5es.<\/p>\n\n\n\n<p>Para mais dicas e materiais sobre concurso, siga-me no Instagram:<\/p>\n\n\n\n<p><a href=\"https:\/\/instagram.com\/profcarloseduardocardoso?igshid=YmMyMTA2M2Y=\" target=\"_blank\" rel=\"noreferrer noopener\">@profcarloseduardocardoso<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2022<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, aluno (a)! Tudo bem? Na postagem de hoje iremos falar sobre os tipos de cr\u00e9dito adicional, assunto presente no edital para o concurso do Tribunal de Contas do Estado do Tocantins. Quem estuda a disciplina de Administra\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria ou Contabilidade P\u00fablica para concurso provavelmente j\u00e1 se deparou com esse t\u00f3pico do edital [&hellip;]<\/p>\n","protected":false},"author":2472,"featured_media":1088804,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,214710],"tags":[894,221138,643,128304],"tax_estado":[219990],"class_list":["post-1088802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-tribunais-de-contas","tag-afo","tag-tce-to-2","tag-tribunais","tag-tribunal-de-contas","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cr\u00e9dito adicional concurso TCE-TO<\/title>\n<meta name=\"description\" content=\"Revis\u00e3o dos tipos de cr\u00e9dito adicional: suplementar, especial e extraordin\u00e1rio com foco no concurso do TCE TO\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9dito adicional com foco no TCE-TO\" \/>\n<meta property=\"og:description\" content=\"Revis\u00e3o dos tipos de cr\u00e9dito adicional: suplementar, especial e extraordin\u00e1rio com foco no concurso do TCE TO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-11T12:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png\" \/>\n\t<meta property=\"og:image:width\" content=\"919\" \/>\n\t<meta property=\"og:image:height\" content=\"517\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Eduardo Chagas Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Eduardo Chagas Cardoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\"},\"author\":{\"name\":\"Carlos Eduardo Chagas Cardoso\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5\"},\"headline\":\"Cr\u00e9dito adicional com foco no TCE-TO\",\"datePublished\":\"2022-10-11T12:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\"},\"wordCount\":2032,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png\",\"keywords\":[\"AFO\",\"TCE-TO\",\"tribunais\",\"Tribunal de Contas\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\",\"name\":\"Cr\u00e9dito adicional concurso TCE-TO\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png\",\"datePublished\":\"2022-10-11T12:43:00+00:00\",\"description\":\"Revis\u00e3o dos tipos de cr\u00e9dito adicional: suplementar, especial e extraordin\u00e1rio com foco no concurso do TCE TO\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png\",\"width\":919,\"height\":517},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00e9dito adicional com foco no TCE-TO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5\",\"name\":\"Carlos Eduardo Chagas Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g\",\"caption\":\"Carlos Eduardo Chagas Cardoso\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carloschagascardosogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cr\u00e9dito adicional concurso TCE-TO","description":"Revis\u00e3o dos tipos de cr\u00e9dito adicional: suplementar, especial e extraordin\u00e1rio com foco no concurso do TCE TO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/","og_locale":"pt_BR","og_type":"article","og_title":"Cr\u00e9dito adicional com foco no TCE-TO","og_description":"Revis\u00e3o dos tipos de cr\u00e9dito adicional: suplementar, especial e extraordin\u00e1rio com foco no concurso do TCE TO","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-10-11T12:43:00+00:00","og_image":[{"width":919,"height":517,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png","type":"image\/png"}],"author":"Carlos Eduardo Chagas Cardoso","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Carlos Eduardo Chagas Cardoso","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/"},"author":{"name":"Carlos Eduardo Chagas Cardoso","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5"},"headline":"Cr\u00e9dito adicional com foco no TCE-TO","datePublished":"2022-10-11T12:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/"},"wordCount":2032,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png","keywords":["AFO","TCE-TO","tribunais","Tribunal de Contas"],"articleSection":["Concursos P\u00fablicos","Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/","name":"Cr\u00e9dito adicional concurso TCE-TO","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png","datePublished":"2022-10-11T12:43:00+00:00","description":"Revis\u00e3o dos tipos de cr\u00e9dito adicional: suplementar, especial e extraordin\u00e1rio com foco no concurso do TCE TO","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/03074312\/image-51.png","width":919,"height":517},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/credito-adicional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9dito adicional com foco no TCE-TO"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5","name":"Carlos Eduardo Chagas Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g","caption":"Carlos Eduardo Chagas Cardoso"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carloschagascardosogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1088802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2472"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1088802"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1088802\/revisions"}],"predecessor-version":[{"id":1107617,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1088802\/revisions\/1107617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1088804"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1088802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1088802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1088802"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1088802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}