{"id":1086505,"date":"2022-09-26T08:01:00","date_gmt":"2022-09-26T11:01:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1086505"},"modified":"2022-09-05T15:42:40","modified_gmt":"2022-09-05T18:42:40","slug":"funcoes-estado-sefaz-mg","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/","title":{"rendered":"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal! Como voc\u00eas est\u00e3o? Hoje traremos mais uma parte importante da disciplina de economia para o pr\u00f3ximo concurso da SEFAZ-MG: as Fun\u00e7\u00f5es do Estado na Economia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"910\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-1024x910.jpg\" alt=\"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG\" class=\"wp-image-962664\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-1024x910.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-300x267.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-768x683.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-1536x1365.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-2048x1820.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-610x542.jpg 610w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG<\/figcaption><\/figure>\n\n\n\n<p>O grande nome da vis\u00e3o cl\u00e1ssica das fun\u00e7\u00f5es do estado, o fil\u00f3sofo e economista, <strong><a href=\"https:\/\/pt.wikipedia.org\/wiki\/Adam_Smith\">Adam Smith<\/a>, acreditava que a interven\u00e7\u00e3o do Estado na economia deveria ser m\u00ednima.<\/strong><\/p>\n\n\n\n<p>Essa corrente de pensamento \u00e9 conhecida pelo termo <em>laissez-faire<\/em><em> <\/em>(deixe fazer) e defendia a ideia de que seria necess\u00e1rio o desenvolvimento do livre com\u00e9rcio para o crescimento do capitalismo. <strong>Smith afirmava que o equil\u00edbrio do mercado seria garantido pela \u201cm\u00e3o invis\u00edvel\u201d da economia, a qual por si s\u00f3 faria com que a sa\u00fade econ\u00f4mica fosse preservada.<\/strong><\/p>\n\n\n\n<p>Essa vis\u00e3o cl\u00e1ssica delimita que o Estado deveria exercer apenas as fun\u00e7\u00f5es de <strong>Defesa Nacional<\/strong> e <strong>Justi\u00e7a<\/strong>.<\/p>\n\n\n\n<p>Por\u00e9m, j\u00e1 nos primeiros anos do s\u00e9culo XXI, <strong>a forma cl\u00e1ssica do mercado sem interven\u00e7\u00f5es na economia acabou levando a sociedade a situa\u00e7\u00f5es de crise<\/strong>.<\/p>\n\n\n\n<p>A forte concentra\u00e7\u00e3o da oferta nas m\u00e3os de poucos, al\u00e9m de prejudicar o consumidor, concentrava a renda e acabou resultando na forma\u00e7\u00e3o de monop\u00f3lios na ind\u00fastria, al\u00e9m de cart\u00e9is para fixa\u00e7\u00e3o de pre\u00e7os.<\/p>\n\n\n\n<p>Nesse contexto, em 1936, outro grande nome da economia ganhou notoriedade: <a href=\"https:\/\/pt.wikipedia.org\/wiki\/John_Maynard_Keynes\"><strong>John Maynard<\/strong> <strong>Keynes<\/strong><\/a>. Ele <strong>defendia uma interven\u00e7\u00e3o direta do governo na economia<\/strong>, inclusive por meio do aumento dos gastos p\u00fablicos em momentos de recess\u00e3o, al\u00e9m da regulamenta\u00e7\u00e3o dos mercados.<\/p>\n\n\n\n<p>De acordo com Keynes, o mercado n\u00e3o seria capaz de, sozinho, distribuir a renda de forma justa, prover os bens e servi\u00e7os de que a sociedade precisa e evitar as crises na economia.<\/p>\n\n\n\n<p>Portanto, ao longo do tempo ficou claro que <strong>equidade e efici\u00eancia econ\u00f4micas necessitam da presen\u00e7a do Estado para serem alcan\u00e7adas<\/strong>. O que refor\u00e7a a import\u00e2ncia tanto das pol\u00edticas p\u00fablicas, como da presen\u00e7a do Estado na cria\u00e7\u00e3o de mecanismo para fomentar a produ\u00e7\u00e3o, isto \u00e9, para alcan\u00e7ar a efici\u00eancia produtiva.<\/p>\n\n\n\n<p>Com base nesses novos pensamentos, surgiram, ent\u00e3o, tr\u00eas principais fun\u00e7\u00f5es do estado na economia mais aceitas atualmente. S\u00e3o elas as fun\u00e7\u00f5es <strong>alocativas<\/strong>, <strong>distributivas<\/strong> e <strong>estabilizadoras<\/strong>.<\/p>\n\n\n\n<p>Veremos a seguir um pouco de cada uma dessas tr\u00eas Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-funcao-alocativa\"><strong>Fun\u00e7\u00e3o Alocativa<\/strong><\/h2>\n\n\n\n<p>A fun\u00e7\u00e3o alocativa do Estado na economia consiste, basicamente, na regula\u00e7\u00e3o ou fornecimento de bens p\u00fablicos, ou semip\u00fablicos.<\/p>\n\n\n\n<p>Os bens p\u00fablicos n\u00e3o podem ser oferecidos de forma compat\u00edvel com as necessidades da sociedade atrav\u00e9s do sistema de mercado, devido \u00e0s suas caracter\u00edsticas de n\u00e3o rivalidade e n\u00e3o exclusividade.<\/p>\n\n\n\n<p>A <strong>n\u00e3o rivalidade<\/strong> traz a ideia de que o uso de um bem por uma pessoa n\u00e3o impede o uso desse mesmo bem por outra pessoa.<\/p>\n\n\n\n<p>J\u00e1 a <strong>n\u00e3o exclusividade<\/strong> significa que n\u00e3o \u00e9 poss\u00edvel para um usu\u00e1rio excluir outros de se beneficiarem do bem.<\/p>\n\n\n\n<p>O fato de os benef\u00edcios gerados pelos bens p\u00fablicos estarem dispon\u00edveis a todos os consumidores, faz com que n\u00e3o haja pagamento volunt\u00e1rio aos fornecedores desses bens. Dessa forma, o governo se encarrega de determinar o tipo e a quantidade de bens p\u00fablicos a serem ofertados e a calcular o n\u00edvel de contribui\u00e7\u00e3o de cada consumidor.<\/p>\n\n\n\n<p>Portanto, <strong>a fun\u00e7\u00e3o alocativa do governo consiste em complementar a a\u00e7\u00e3o do mercado, quando ela falha<\/strong>, no que diz respeito \u00e0 maneira como os recursos s\u00e3o utilizados. Ou seja, refere-se \u00e0 <strong>aloca\u00e7\u00e3o dos recursos na economia de forma eficiente, quando o mercado n\u00e3o consegue alcan\u00e7ar esse resultado sozinho<\/strong>.<\/p>\n\n\n\n<p>A fun\u00e7\u00e3o alocativa busca essa efici\u00eancia do mercado atrav\u00e9s de tr\u00eas formas de atua\u00e7\u00e3o do governo: produ\u00e7\u00e3o, financiamento ou regula\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-estado-produtor-financiador-e-regulador\"><strong>Estado Produtor, Financiador e Regulador<\/strong><\/h3>\n\n\n\n<p>Para buscar a oferta de bens p\u00fablicos e corrigir as falhas de mercado, o Estado pode atuar produzindo diretamente bens e servi\u00e7os \u00e0 sociedade; fornecendo recursos financeiros, como empr\u00e9stimos ou subs\u00eddios, para que o mercado atue de forma mais eficiente; ou controlando as atividades econ\u00f4micas, por meio de normatiza\u00e7\u00e3o e fiscaliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>O Estado desempenha, na realidade, os pap\u00e9is de produtor, financiador e regulador ao mesmo tempo, por\u00e9m, a economia brasileira \u00e9 marcada por per\u00edodos nos quais prevaleceu uma ou outra forma de atua\u00e7\u00e3o.<\/p>\n\n\n\n<p>O <strong>Estado Produtor pode ser bem observado durante os anos p\u00f3s-guerra<\/strong>, contemplando os governos de Dutra, Vargas e JK, <strong>caracterizado pela forte presen\u00e7a de empresas de propriedade do Estado<\/strong>, como a Petrobr\u00e1s e a Vale do Rio Doce, not\u00e1veis exploradoras de atividade econ\u00f4mica que foram criadas nesse per\u00edodo.<\/p>\n\n\n\n<p>J\u00e1 o <strong>papel do Estado Financiador<\/strong> \u00e9 poss\u00edvel ser observado a partir de 1964, com <strong>amplia\u00e7\u00e3o do cr\u00e9dito ao setor privado<\/strong> promovida pelo Banco Nacional de Desenvolvimento Econ\u00f4mico (BNDE), Banco do Nordeste, Banco do Brasil, Caixa Econ\u00f4mica Federal e Banco Nacional de Habita\u00e7\u00e3o. At\u00e9 a d\u00e9cada de 1980, conhecida pela crise da d\u00edvida, esse papel foi bastante intenso, dada a dificuldade de obter financiamento privado, especialmente de longo prazo.<\/p>\n\n\n\n<p>O <strong>Estado Regulador<\/strong> \u00e9 o mais presente na realidade atual e se manifesta quando o <strong>Estado interv\u00e9m limitando as liberdades dos agentes econ\u00f4micos por meio de normas e fiscaliza\u00e7\u00e3o<\/strong> de seu cumprimento, com o objetivo de aumentar a efici\u00eancia econ\u00f4mica e o bem-estar da sociedade.<\/p>\n\n\n\n<p>Portanto, quando o Estado age como regulador, ele permanece como titular, mas o setor privado \u00e9 quem executa a atividade ou servi\u00e7o p\u00fablico, cumprindo as exig\u00eancias legais e regulamentares impostas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-funcao-distributiva\"><strong>Fun\u00e7\u00e3o Distributiva<\/strong><\/h2>\n\n\n\n<p>A <strong>fun\u00e7\u00e3o distributiva<\/strong> atende a certos preceitos ou crit\u00e9rios socialmente aceitos de distribui\u00e7\u00e3o de renda, estando diretamente relacionada \u00e0 <strong>redu\u00e7\u00e3o das diferen\u00e7as econ\u00f4micas e sociais da popula\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Essa fun\u00e7\u00e3o do Estado se refere \u00e0 <strong>redistribui\u00e7\u00e3o de rendas realizada atrav\u00e9s das transfer\u00eancias, dos impostos e dos subs\u00eddios governamentais<\/strong>. Podemos trazer como exemplo a destina\u00e7\u00e3o de parte dos recursos provenientes da tributa\u00e7\u00e3o para complementar a renda das fam\u00edlias que est\u00e3o em situa\u00e7\u00f5es de extrema pobreza.<\/p>\n\n\n\n<p>Portanto, \u00e9 por meio da combina\u00e7\u00e3o desses instrumentos que o governo pode distribuir a renda, <strong>tributando mais as classes de renda mais alta<\/strong>, e depois <strong>transferindo esses recursos diretamente para as camadas mais pobres<\/strong> da sociedade, ou <strong>subsidiado a popula\u00e7\u00e3o mais carente<\/strong>, ao pagar uma parte dos bens adquiridos por essa camada da sociedade.<\/p>\n\n\n\n<p>A ado\u00e7\u00e3o de <strong>pol\u00edticas de transfer\u00eancia de renda<\/strong> em favor de popula\u00e7\u00f5es mais carentes \u00e9 um instrumento que pode ser observado, por exemplo, nos recursos do Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios (FPM), do Fundo de Participa\u00e7\u00e3o dos Estados (FPE) e do Programa Bolsa Fam\u00edlia.<\/p>\n\n\n\n<p>A <strong>assist\u00eancia social<\/strong> tamb\u00e9m pode ser considerada uma clara manifesta\u00e7\u00e3o da <strong>fun\u00e7\u00e3o distributiva <\/strong>do Estado na economia, uma vez que trata de <strong>garantir condi\u00e7\u00f5es m\u00ednimas para aqueles incapazes de prover as necessidades mais b\u00e1sicas para si mesmos e suas fam\u00edlias.<\/strong><\/p>\n\n\n\n<p>Essa fun\u00e7\u00e3o \u00e9 de extrema import\u00e2ncia na economia do pa\u00eds, pois est\u00e1 diretamente relacionada \u00e0 corre\u00e7\u00e3o da desigualdade existente na distribui\u00e7\u00e3o da renda nacional, o que \u00e9 a causa de muitos problemas sociais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-funcao-estabilizadora\"><strong>Fun\u00e7\u00e3o Estabilizadora<\/strong><\/h2>\n\n\n\n<p>A<strong> fun\u00e7\u00e3o estabilizadora do Estado<\/strong> consiste, basicamente, em proporcionar \u00e0 economia <strong>crescimento, alto \u00edndice de emprego e pre\u00e7os est\u00e1veis.<\/strong><\/p>\n\n\n\n<p>A infla\u00e7\u00e3o, o desemprego, a balan\u00e7a comercial, a taxa de c\u00e2mbio, e v\u00e1rios outros indicadores econ\u00f4micos variam ao longo do tempo, e podem provocar grandes preju\u00edzos \u00e0 sociedade.<\/p>\n\n\n\n<p>Essa fun\u00e7\u00e3o ganhou for\u00e7a, principalmente, <strong>depois da Grande Depress\u00e3o, em 1929, <\/strong>quando foi percept\u00edvel que o <strong>mercado n\u00e3o era capaz, pelo menos no curto prazo, de evitar grandes distor\u00e7\u00f5es e desequil\u00edbrios.<\/strong><\/p>\n\n\n\n<p>Essa pol\u00edtica pode se manifestar diretamente, atrav\u00e9s da varia\u00e7\u00e3o dos gastos p\u00fablicos em consumo e investimento, ou indiretamente, pela redu\u00e7\u00e3o das al\u00edquotas de impostos, que eleva a renda dispon\u00edvel do setor privado.<\/p>\n\n\n\n<p>Ela <strong>concentra seus esfor\u00e7os na manuten\u00e7\u00e3o de um alto n\u00edvel de utiliza\u00e7\u00e3o de recursos e de um valor est\u00e1vel da moeda<\/strong>. Cabe, portanto, ao governo buscar atenuar os chamados ciclos econ\u00f4micos e suas oscila\u00e7\u00f5es, utilizando pol\u00edticas econ\u00f4micas (fiscal, monet\u00e1ria e cambial) para tanto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\"><strong>Considera\u00e7\u00f5es Finais<\/strong><\/h2>\n\n\n\n<p>Pudemos observar, portanto, que a forma de atua\u00e7\u00e3o do governo possui in\u00fameros reflexos na atividade econ\u00f4mica, e devido \u00e0 import\u00e2ncia dessas fun\u00e7\u00f5es do Estado na economia, seu entendimento \u00e9 essencial para o pr\u00f3ximo concurso da SEFAZ-MG.<\/p>\n\n\n\n<p>S\u00e3o tr\u00eas as fun\u00e7\u00f5es do Estado na economia que possuem reflexos sobre o or\u00e7amento p\u00fablico e que merecem destaque para prova da SEFAZ-MG: fun\u00e7\u00e3o alocativa, fun\u00e7\u00e3o distributiva e fun\u00e7\u00e3o estabilizadora.<\/p>\n\n\n\n<p>Na <strong>fun\u00e7\u00e3o alocativa<\/strong>, o <strong>Estado atua diretamente na produ\u00e7\u00e3o de bens<\/strong>. Essa fun\u00e7\u00e3o surge, principalmente, <strong>em raz\u00e3o das denominadas falhas de mercado<\/strong>, como a competi\u00e7\u00e3o imperfeita, a exist\u00eancia de bens p\u00fablicos, a presen\u00e7a de externalidades e de mercados incompletos, a informa\u00e7\u00e3o imperfeita, o desemprego e outros dist\u00farbios macroecon\u00f4micos.<\/p>\n\n\n\n<p>A <strong>fun\u00e7\u00e3o distributiva<\/strong> visa a promo\u00e7\u00e3o de pol\u00edticas de distribui\u00e7\u00e3o de recursos p\u00fablicos como forma de tentar resolver problemas sociais que surgem devido \u00e0s <strong>diferen\u00e7as econ\u00f4micas e sociais da popula\u00e7\u00e3o<\/strong>. \u00c9 uma fun\u00e7\u00e3o essencial para a sociedade como um todo, pois ela atua na <strong>redistribui\u00e7\u00e3o de rendas realizada atrav\u00e9s das transfer\u00eancias, dos impostos e dos subs\u00eddios governamentais<\/strong>.<\/p>\n\n\n\n<p>E atrav\u00e9s da <strong>fun\u00e7\u00e3o estabilizadora<\/strong>, o governo <strong>busca equilibrar a economia<\/strong>, controlando pre\u00e7os e utilizando os instrumentos macroecon\u00f4micos, como as <strong>pol\u00edticas p\u00fablicas fiscais e monet\u00e1rias. <\/strong>Essa fun\u00e7\u00e3o do governo tamb\u00e9m \u00e9 de extrema import\u00e2ncia, pois visa a um alto n\u00edvel de emprego, um grau razo\u00e1vel de estabilidade nos pre\u00e7os, equil\u00edbrio no balan\u00e7o de pagamentos e uma aceit\u00e1vel taxa de crescimento econ\u00f4mico.<\/p>\n\n\n\n<p>E hoje ficamos por aqui, pessoal! Uma boa semana e bons estudos!<\/p>\n\n\n\n<p>D\u00e9bora Vaz<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\">Concursos 2023<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal! Como voc\u00eas est\u00e3o? Hoje traremos mais uma parte importante da disciplina de economia para o pr\u00f3ximo concurso da SEFAZ-MG: as Fun\u00e7\u00f5es do Estado na Economia. O grande nome da vis\u00e3o cl\u00e1ssica das fun\u00e7\u00f5es do estado, o fil\u00f3sofo e economista, Adam Smith, acreditava que a interven\u00e7\u00e3o do Estado na economia deveria ser m\u00ednima. Essa [&hellip;]<\/p>\n","protected":false},"author":2407,"featured_media":962664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219974],"class_list":["post-1086505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-mg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG<\/title>\n<meta name=\"description\" content=\"Analisaremos as tr\u00eas fun\u00e7\u00f5es do Estado na economia (alocativa, distributiva e estabilizadora) para o pr\u00f3ximo concurso da SEFAZ-MG\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG\" \/>\n<meta property=\"og:description\" content=\"Analisaremos as tr\u00eas fun\u00e7\u00f5es do Estado na economia (alocativa, distributiva e estabilizadora) para o pr\u00f3ximo concurso da SEFAZ-MG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T11:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"D\u00e9bora Vaz Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"D\u00e9bora Vaz Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\"},\"author\":{\"name\":\"D\u00e9bora Vaz Ferreira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/3ac3a2171af8f7657d180d6ae5f2f484\"},\"headline\":\"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG\",\"datePublished\":\"2022-09-26T11:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\"},\"wordCount\":1775,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\",\"name\":\"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg\",\"datePublished\":\"2022-09-26T11:01:00+00:00\",\"description\":\"Analisaremos as tr\u00eas fun\u00e7\u00f5es do Estado na economia (alocativa, distributiva e estabilizadora) para o pr\u00f3ximo concurso da SEFAZ-MG\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg\",\"width\":2560,\"height\":2276,\"caption\":\"Tax icons isometric set with internal revenue service time calculation elements vector illustration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/3ac3a2171af8f7657d180d6ae5f2f484\",\"name\":\"D\u00e9bora Vaz Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/59ca904a5c31c9d452c94b546e93d8f4edc959802fcdcfd9cf11f8913663abfa?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59ca904a5c31c9d452c94b546e93d8f4edc959802fcdcfd9cf11f8913663abfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59ca904a5c31c9d452c94b546e93d8f4edc959802fcdcfd9cf11f8913663abfa?s=96&d=mm&r=g\",\"caption\":\"D\u00e9bora Vaz Ferreira\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/debora-vazfgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG","description":"Analisaremos as tr\u00eas fun\u00e7\u00f5es do Estado na economia (alocativa, distributiva e estabilizadora) para o pr\u00f3ximo concurso da SEFAZ-MG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/","og_locale":"pt_BR","og_type":"article","og_title":"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG","og_description":"Analisaremos as tr\u00eas fun\u00e7\u00f5es do Estado na economia (alocativa, distributiva e estabilizadora) para o pr\u00f3ximo concurso da SEFAZ-MG","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-09-26T11:01:00+00:00","og_image":[{"width":2560,"height":2276,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg","type":"image\/jpeg"}],"author":"D\u00e9bora Vaz Ferreira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"D\u00e9bora Vaz Ferreira","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/"},"author":{"name":"D\u00e9bora Vaz Ferreira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/3ac3a2171af8f7657d180d6ae5f2f484"},"headline":"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG","datePublished":"2022-09-26T11:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/"},"wordCount":1775,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/","name":"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg","datePublished":"2022-09-26T11:01:00+00:00","description":"Analisaremos as tr\u00eas fun\u00e7\u00f5es do Estado na economia (alocativa, distributiva e estabilizadora) para o pr\u00f3ximo concurso da SEFAZ-MG","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/02\/06172226\/funcoes-do-governo-na-economia-scaled.jpg","width":2560,"height":2276,"caption":"Tax icons isometric set with internal revenue service time calculation elements vector illustration"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/funcoes-estado-sefaz-mg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Fun\u00e7\u00f5es do Estado na Economia para SEFAZ-MG"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/3ac3a2171af8f7657d180d6ae5f2f484","name":"D\u00e9bora Vaz Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/59ca904a5c31c9d452c94b546e93d8f4edc959802fcdcfd9cf11f8913663abfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59ca904a5c31c9d452c94b546e93d8f4edc959802fcdcfd9cf11f8913663abfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59ca904a5c31c9d452c94b546e93d8f4edc959802fcdcfd9cf11f8913663abfa?s=96&d=mm&r=g","caption":"D\u00e9bora Vaz Ferreira"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/debora-vazfgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1086505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2407"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1086505"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1086505\/revisions"}],"predecessor-version":[{"id":1086512,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1086505\/revisions\/1086512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/962664"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1086505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1086505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1086505"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1086505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}