{"id":1046972,"date":"2023-06-05T14:22:00","date_gmt":"2023-06-05T17:22:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1046972"},"modified":"2023-06-05T14:23:52","modified_gmt":"2023-06-05T17:23:52","slug":"concurso-cro-ba","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/","title":{"rendered":"Concurso CRO BA: resultado final dispon\u00edvel; veja!"},"content":{"rendered":"\n<p>O resultado final do <strong>concurso CRO BA<\/strong> (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conselho Regional de Odontologia da Bahia<\/a>) foi divulgado! <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/06\/05142212\/1_cro-ba_concurso_publico_2022_resultado_final.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Veja aqui o nome dos aprovados! <\/a><\/p>\n\n\n\n<p>S\u00e3o 09 vagas imediatas mais cadastro reserva nos cargos de Agente de Fiscaliza\u00e7\u00e3o, T\u00e9cnico Administrativo, T\u00e9cnico de Inform\u00e1tica e Analista de Licita\u00e7\u00e3o e Contrato; que exigem n\u00edveis m\u00e9dio, t\u00e9cnico e superior.<\/p>\n\n\n\n<p>A remunera\u00e7\u00e3o ofertada varia de <strong>R$ 1.799,77<\/strong> a <strong>R$ 3.147,18<\/strong>. A taxa de inscri\u00e7\u00e3o varia de R$ 63,00 a R$ 70,00. As provas ser\u00e3o aplicadas no dia 18 de dezembro. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Concurso CRO BA<\/strong><\/li>\n\n\n\n<li><strong>Status:\u00a0<\/strong>resultado final<\/li>\n\n\n\n<li><strong>Banca:<\/strong>&nbsp;Instituto Quadrix<\/li>\n\n\n\n<li><strong>Vagas:<\/strong>&nbsp;09+CR<\/li>\n\n\n\n<li><strong>Sal\u00e1rio inicial:<\/strong>  de R$ 1.799,77 a R$ 3.147,18<\/li>\n\n\n\n<li><strong>Edital<\/strong>:&nbsp;<a href=\"http:\/\/www.quadrix.org.br\/web\/visualizar.html?file=http:\/\/www.quadrix.org.br\/Archives\/General\/26661\/27418\/27421\/281F231BEA58\/1_CRO-BA_concurso_publico_2022_edital_abertura.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">CRO BA <\/a><\/li>\n<\/ul>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds.<\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Estude conosco CRO BA<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a os cursos<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<p>Confira no \u00edndice abaixo os detalhes do concurso CRO BA:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#atual\">Situa\u00e7\u00e3o atual <\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#banca\">Principais datas <\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><a href=\"#cargos-e-vagas\">Cargos e vagas <\/a><\/li>\n\n\n\n<li><a href=\"#remuneracoes\">Remunera\u00e7\u00f5es <\/a><\/li>\n\n\n\n<li><a href=\"#requisitos-e-atribuicoes\">Requisitos e atribui\u00e7\u00f5es <\/a><\/li>\n\n\n\n<li><a href=\"#etapas\">Etapas<\/a><\/li>\n\n\n\n<li><a href=\"#ultimo\">\u00daltimo concurso <\/a>\n<ul class=\"wp-block-list\">\n<li><a href=\"#cargos\">Cargos e vagas<\/a><\/li>\n\n\n\n<li><a href=\"#requisitos\">Requisitos <\/a><\/li>\n\n\n\n<li><a href=\"#etapas\">Etapas<\/a> <\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#artigos\">Artigos<\/a><\/li>\n\n\n\n<li><a href=\"#cursos\">Cursos<\/a><\/li>\n\n\n\n<li><a href=\"#ficha\">Ficha t\u00e9cnica <\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-cro-ba-situacao-atual\">Concurso CRO BA: situa\u00e7\u00e3o atual <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Principais datas <\/h3>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>Inscri\u00e7\u00f5es<\/strong>: <s>de 27 de setembro a 03 de novembro<\/s><br \/><strong>Isen\u00e7\u00e3o da taxa<\/strong>: <s>27a 29 de setembro<\/s> <br \/><strong>\u00daltimo dia para pagamento<\/strong>: 04 de novembro <br \/><strong>Prova<\/strong>: 18 de dezembro<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Concurso CRO BA: cargos e vagas <\/h2>\n\n\n\n<p>De acordo com o edital, s\u00e3o ofertadas, ao todo, 09 vagas imediatas mais forma\u00e7\u00e3o de cadastro de reserva, sendo: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Agente de Fiscaliza\u00e7\u00e3o<\/strong>\n<ul class=\"wp-block-list\">\n<li>Vagas: 1 + CR<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>T\u00e9cnico Administrativo<\/strong>\n<ul class=\"wp-block-list\">\n<li>Vagas: 7 + CR<br \/><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>T\u00e9cnico de Inform\u00e1tica<\/strong>\n<ul class=\"wp-block-list\">\n<li>Vagas: 1 + CR<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Analista de Licita\u00e7\u00e3o e Contrato<\/strong>\n<ul class=\"wp-block-list\">\n<li>Vagas: CR<br \/><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Concurso CRO BA: remunera\u00e7\u00f5es <\/h2>\n\n\n\n<p>As remunera\u00e7\u00f5es variam entre R$ 1.799,77 e R$ 3.147,18:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Agente de Fiscaliza\u00e7\u00e3o: R$ 1.924,99 + benef\u00edcios;<\/li>\n\n\n\n<li>T\u00e9cnico Administrativo: R$ 1.828,72 + benef\u00edcios;<\/li>\n\n\n\n<li>T\u00e9cnico de Inform\u00e1tica: R$ 1.799,77 + benef\u00edcios; e<\/li>\n\n\n\n<li>Analista de Licita\u00e7\u00e3o e Contrato: R$ 3.147,18 + benef\u00edcios. <\/li>\n<\/ul>\n\n\n\n<p>O CRO-BA oferecer\u00e1 os seguintes benef\u00edcios:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vale Alimenta\u00e7\u00e3o no valor de R$ 31,36 por dia trabalhado;<\/li>\n\n\n\n<li>Plano de Sa\u00fade M\u00e9dico;<\/li>\n\n\n\n<li>Plano de Cargos e Sal\u00e1rios; e<\/li>\n\n\n\n<li>Vale transporte, conforme legisla\u00e7\u00e3o vigente.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Concurso CRO BA: requisitos e atribui\u00e7\u00f5es <\/h2>\n\n\n\n<p>Confira quais s\u00e3o as atribui\u00e7\u00f5es e os requisitos exigidos: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Agente de Fiscaliza\u00e7\u00e3o<\/strong>\n<ul class=\"wp-block-list\">\n<li>Requisitos: Certificado, devidamente registrado, de conclus\u00e3o de curso de n\u00edvel m\u00e9dio, expedido por institui\u00e7\u00e3o de ensino reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC). Carteira Nacional de Habilita\u00e7\u00e3o (CNH) no m\u00ednimo categoria \u201cB\u201d, conforme arts. 143 e 147 do C\u00f3digo Nacional de Tr\u00e2nsito e Resolu\u00e7\u00f5es 168\/2004e 285\/2008, do CONTRAN, com pontua\u00e7\u00e3o que permita, nos termos da legisla\u00e7\u00e3o de tr\u00e2nsito, o pleno exerc\u00edcio do direito de dirigir.<\/li>\n\n\n\n<li>Atribui\u00e7\u00f5es: Atender, diariamente, atrav\u00e9s dos meios de comunica\u00e7\u00e3o disponibilizados pelo Conselho, todos os profissionais de Odontologia e cidad\u00e3os, que buscam informa\u00e7\u00f5es, orienta\u00e7\u00f5es ou que desejam realizar algum tipo de den\u00fancia. Cadastrar, acompanhar e arquivar as fichas referentes as visitas realizadas no m\u00eas, como documento probat\u00f3rio, caso ocorra uma necessidade de auditoria futura. Realizar, mensalmente, as viagens de fiscaliza\u00e7\u00e3o para outras localidades, no intuito de identificar as irregularidades existentes nas localidades visitadas. Notificar em conformidade com a legisla\u00e7\u00e3o vigente, pessoas jur\u00eddicas ou profissionais que exer\u00e7am atividades privativas da Odontologia, sem estarem legalmente habilitados. Apresentar relat\u00f3rios semanais e mensais das atividades realizadas e apresentar novas estrat\u00e9gias de fiscaliza\u00e7\u00e3o com a finalidade de diminuir a irregularidade dos profissionais que n\u00e3o exercem de maneira correta sua profiss\u00e3o. Realizar presta\u00e7\u00e3o de contas, referente as di\u00e1rias recebidas, para realiza\u00e7\u00e3o de fiscaliza\u00e7\u00e3o em outras localidades, no intuito de comprovar o roteiro estabelecido. Solicitar \u00e0 autoridade policial o acesso \u00e0s depend\u00eancias de onde ocorrer impedimento ou obst\u00e1culo da a\u00e7\u00e3o de fiscaliza\u00e7\u00e3o, informando \u00e0 Supervis\u00e3o de Fiscaliza\u00e7\u00e3o.  Executar a\u00e7\u00f5es de car\u00e1ter preventivo, junto aos profissionais e empresas, de forma a orient\u00e1-los no cumprimento da Legisla\u00e7\u00e3o que regulamenta a profiss\u00e3o.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>T\u00e9cnico Administrativo<\/strong>\n<ul class=\"wp-block-list\">\n<li>Requisitos: Certificado, devidamente registrado, de conclus\u00e3o de curso de n\u00edvel m\u00e9dio, expedido por institui\u00e7\u00e3o de ensino reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC).<\/li>\n\n\n\n<li>Atribui\u00e7\u00f5es: Auxiliar o Agente de Contrata\u00e7\u00e3o\/Pregoeiro em todas as etapas da licita\u00e7\u00e3o, visando o bom andamento e efici\u00eancia do processo licitat\u00f3rio. Recepcionar os licitantes e\/ou seus representantes em uma sess\u00e3o de licita\u00e7\u00e3o presencial. Recepcionar documentos. Elaborar planilhas, atas, relat\u00f3rios e mapas necess\u00e1rios ao certame. Criar Licita\u00e7\u00e3o no sistema, promovendo altera\u00e7\u00f5es quando necess\u00e1rias e autorizadas pelo superior imediato. Publicar Avisos e Editais no DOU e no site do CRO-BA. Apoiar a \u00e1rea nos atendimentos \u00e0s auditorias internas e externas. Instruir processos de dispensa de licita\u00e7\u00e3o. Demais atividades que sejam solicitadas pelo superior imediato.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>T\u00e9cnico de Inform\u00e1tica<\/strong>\n<ul class=\"wp-block-list\">\n<li>Requisitos: Certificado, devidamente registrado, de conclus\u00e3o de conclus\u00e3o de curso de n\u00edvel m\u00e9dio profissionalizante em Tecnologia da Informa\u00e7\u00e3o ou de curso de n\u00edvel m\u00e9dio acrescido de curso na \u00e1rea de Tecnologia da Informa\u00e7\u00e3o ou curso de denomina\u00e7\u00e3o e conte\u00fado equivalentes, expedidos por institui\u00e7\u00e3o de ensino reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC). Ser\u00e3o aceitos tamb\u00e9m cursos de gradua\u00e7\u00e3o de n\u00edvel superior conclu\u00eddos na \u00e1rea de Tecnologia da Informa\u00e7\u00e3o.<\/li>\n\n\n\n<li>Atribui\u00e7\u00f5es: Manuten\u00e7\u00e3o preventiva\/corretiva de computadores e rede, executando instala\u00e7\u00f5es\/configura\u00e7\u00f5es de sistema operacional, realiza\u00e7\u00e3o de limpeza e conserva\u00e7\u00e3o dos equipamentos, servi\u00e7os de testes preventivos operacionais e de seguran\u00e7a nos equipamentos e demais perif\u00e9ricos, atendimentos de manuten\u00e7\u00e3o em postos interno\/externos, emiss\u00e3o de relat\u00f3rios t\u00e9cnicos de visitas e laudos de atendimento de manuten\u00e7\u00e3o. Suporte ao usu\u00e1rio (helpdesk) para garantir o funcionamento da opera\u00e7\u00e3o, de modo a prestar suporte de TI aos usu\u00e1rios nas diferentes plataformas de TI, como: uso de sistemas, e-mails, impressoras, aplicativos e sistemas operacionais, hardware, entre outros, de forma remota, por telefone, em eventos externos ou no local. Instala\u00e7\u00e3o e Configura\u00e7\u00e3o de softwares. Controle de acesso na seguran\u00e7a da informa\u00e7\u00e3o para garantir a Confidencialidade, a Integridade, a Disponibilidade e a Autenticidade, contribuindo para que a informa\u00e7\u00e3o seja acessada somente pelos respons\u00e1veis diretos, impedindo que seja divulgado para um usu\u00e1rio, entidade ou processo n\u00e3o autorizado. Abertura de chamados t\u00e9cnicos e acompanhamento junto aos prestadores de servi\u00e7os para solicita\u00e7\u00f5es ou resolu\u00e7\u00e3o de problemas detectados ou sob orienta\u00e7\u00e3o superior. Executar outras atividades correlatas e inerentes ao seu cargo e compat\u00edveis com as atribui\u00e7\u00f5es estabelecidas acima, conforme necessidade do servi\u00e7o e orienta\u00e7\u00e3o superior, quando solicitado.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Analista de Licita\u00e7\u00e3o e Contrato<\/strong>\n<ul class=\"wp-block-list\">\n<li>Requisitos: Diploma, devidamente registrado, de conclus\u00e3o de curso de gradua\u00e7\u00e3o de n\u00edvel superior em Administra\u00e7\u00e3o, Direito ou \u00e1rea afins, fornecido por institui\u00e7\u00e3o de ensino reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC). Registro ativo e adimplente no respectivo Conselho Regional da profiss\u00e3o.<\/li>\n\n\n\n<li>Atribui\u00e7\u00f5es: Realizar apresenta\u00e7\u00f5es e outras atividades de compartilhamento do conhecimento, dentro ou fora da organiza\u00e7\u00e3o, sobre assuntos restritos \u00e0 sua especialidade e aos processos de que participa. Analisar termos de refer\u00eancia, elaborar editais e relat\u00f3rios relacionados aos processos em que atua. Apoiar a \u00e1rea nos atendimentos \u00e0s auditorias internas e externas. Negociar com fornecedores diversos. Conduzir processos licitat\u00f3rios objetivando a contrata\u00e7\u00e3o de empresas especializadas para presta\u00e7\u00e3o de servi\u00e7os em gerais, servi\u00e7os terceirizados, obras de engenharia e para compras de materiais, equipamentos, entre outros, visando atender as demandas da Autarquia. Analisar problemas, identificar e implementar solu\u00e7\u00f5es t\u00e9cnicas dentro de sua \u00e1rea de atua\u00e7\u00e3o, seguindo a legisla\u00e7\u00e3o vigente. Realizar atividades de n\u00edvel superior a fim de proporcionar o adequado funcionamento e desenvolvimento organizacional; compreende o planejamento, desenvolvimento, execu\u00e7\u00e3o, acompanhamento e a avalia\u00e7\u00e3o de planos, projetos, inclusive de propostas e implementa\u00e7\u00e3o de moderniza\u00e7\u00e3o e qualidade voltados para o aprimoramento e produtividade das \u00e1reas de licita\u00e7\u00f5es, bem como o acompanhamento da legisla\u00e7\u00e3o, doutrina e jurisprud\u00eancia inerentes \u00e0s respectivas \u00e1reas. Proceder a pesquisas e o processamento de gest\u00e3o de informa\u00e7\u00f5es; executar trabalhos, tais como: elabora\u00e7\u00e3o de despachos, pareceres, informa\u00e7\u00f5es, relat\u00f3rios, of\u00edcios; realizar atividades que exijam conhecimentos b\u00e1sicos de inform\u00e1tica, dentre outras de mesma natureza e grau de complexidade que venham a ser determinadas pelo superior imediato.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Concurso CRO BA: etapas <\/h2>\n\n\n\n<p>A sele\u00e7\u00e3o dos candidatos inscritos no edital CRO BA se dar\u00e1 mediante aplica\u00e7\u00e3o das seguintes etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prova preambular (objetiva) \u2013 eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li>Prova escrita \u2013 eliminat\u00f3rio e classificat\u00f3rio; e <\/li>\n\n\n\n<li>Prova de t\u00edtulos \u2013 classificat\u00f3rio.<\/li>\n<\/ul>\n\n\n\n<p>As provas objetiva e discursiva tiveram a dura\u00e7\u00e3o de 4 horas.<\/p>\n\n\n\n<p>As fases do concurso p\u00fablico foram realizadas nas cidades de: Barreiras\/BA, Eun\u00e1polis\/BA, Feira de Santana\/BA, Ilh\u00e9us\/BA, Irec\u00ea\/BA, Juazeiro\/BA, Paulo Afonso\/BA, Salvador\/BA, Teixeira de Freitas\/BA e Vit\u00f3ria da Conquista\/BA.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"disciplinas\">Disciplinas<\/h4>\n\n\n\n<p><strong>Todos os cargos&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecimentos B\u00e1sicos: 40 quest\u00f5es<\/li>\n\n\n\n<li>Conhecimentos Complementares: 30 quest\u00f5es<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos: 50 quest\u00f5es<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"estrutura-prova\">Estrutura da prova<\/h3>\n\n\n\n<p>A prova objetiva, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, foi composta de 120 itens, valeu 120,00 pontos e avaliou as habilidades e os conhecimentos do candidato.<\/p>\n\n\n\n<p>Cada \u00e1rea de conhecimento foi constitu\u00edda por itens para julgamento, agrupados por comandos que dever\u00e3o ser respeitados. O julgamento de cada item ser\u00e1 CERTO ou ERRADO, de acordo com o(s) comando(s) a que se refere o item.<\/p>\n\n\n\n<p>Houve, na folha de respostas da prova objetiva, para cada item, dois campos de marca\u00e7\u00e3o: o campo designado com a letra C, que dever\u00e1 ser preenchido pelo candidato caso julgue o item CERTO, e o campo designado com a letra E, que dever\u00e1 ser preenchido pelo candidato caso julgue o item ERRADO.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"prova-discursiva\">Prova discursiva<\/h3>\n\n\n\n<p>A prova discursiva foi aplicada no mesmo dia e dentro dos prazos de dura\u00e7\u00e3o previstos para a realiza\u00e7\u00e3o da prova objetiva.<\/p>\n\n\n\n<p>A prova discursiva, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, valeu10,00 pontos e consistiu na elabora\u00e7\u00e3o de texto dissertativo, com extens\u00e3o m\u00ednima de 20 linhas e m\u00e1xima de 30 linhas, a respeito de tema relacionado aos conhecimentos b\u00e1sicos. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"avaliacao\">Avalia\u00e7\u00e3o de T\u00edtulos<\/h3>\n\n\n\n<p>Apenas para os cargos de n\u00edvel superior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ultimo-concurso\">\u00daltimo concurso <\/h2>\n\n\n\n<p>O&nbsp;Conselho Regional de Odontologia da Bahia&nbsp;realizou em 2017, o processo seletivo&nbsp;do <strong>concurso CRO BA<\/strong>. Foram 116 vagas, sendo 28 para provimento imediato e 88 reservadas para a forma\u00e7\u00e3o de cadastro reserva (CR). <\/p>\n\n\n\n<p>Na \u00e9poca, a banca organizadora foi o IDIB (Instituto de Desenvolvimento Institucional Brasileiro). As remunera\u00e7\u00f5es variavam entre R$ 2.125,40 e R$ 1.056,90. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"cargos-e-vagas\">Cargos e vagas<\/h3>\n\n\n\n<p>Veja as oportunidades indicadas na \u00e9poca:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Analista Administrativo (6 + CR 24)<\/li>\n\n\n\n<li>Agente de Fiscaliza\u00e7\u00e3o (4 + CR 16)<\/li>\n\n\n\n<li>T\u00e9cnico Administrativo (15 + 36 CR)<\/li>\n\n\n\n<li>T\u00e9cnico em Inform\u00e1tica (01 + CR 04)<\/li>\n\n\n\n<li>Auxiliar Administrativo (02 + CR 08)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"requisitos\">Requisitos<\/h3>\n\n\n\n<p>Veja as exig\u00eancias para ingresso nas ocupa\u00e7\u00f5es:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Analista Administrativo<\/strong>: Ensino Superior completo.<\/li>\n\n\n\n<li><strong>Agente de Fiscaliza\u00e7\u00e3o<\/strong>: Ensino M\u00e9dio Completo ou profissionalizante; Carteira nacional de habilita\u00e7\u00e3o categoria \u201cB\u201d; Disponibilidade para viagens.<\/li>\n\n\n\n<li><strong>T\u00e9cnico Administrativo<\/strong>: Ensino M\u00e9dio Completo.<\/li>\n\n\n\n<li><strong>T\u00e9cnico em Inform\u00e1tica<\/strong>: Ensino M\u00e9dio Completo com forma\u00e7\u00e3o t\u00e9cnica completa nas \u00e1reas de Telecomunica\u00e7\u00f5es; Processamento de Dados ou Inform\u00e1tica; Conhecimentos de inform\u00e1tica e dos aplicativos do Microsoft Office e software livre em n\u00edvel de suporte t\u00e9cnico; Diagrama\u00e7\u00e3o.<\/li>\n\n\n\n<li><strong>Auxiliar Administrativo<\/strong>: Ensino Fundamental Completo.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"etapas\">Etapas<\/h3>\n\n\n\n<p>Os candidatos inscritos foram avaliados por somente uma etapa, a prova objetiva. A avalia\u00e7\u00e3o de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio teve pontua\u00e7\u00e3o distintas de acordo com a escolaridade. <\/p>\n\n\n\n<p>Para ser considerado classificado, o candidato tinha que ter o m\u00ednimo de 50% de acerto no total da prova. A dura\u00e7\u00e3o das provas foi de 3h. <\/p>\n\n\n\n<p>Cada quest\u00e3o de m\u00faltipla escolha constar\u00e1 de 04 alternativas dentre as quais somente 01 estar\u00e1 correta. Veja abaixo as disciplinas e as pontua\u00e7\u00f5es:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"nivel-superior\">N\u00edvel superior<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecimentos b\u00e1sicos: L\u00edngua Portuguesa e Inform\u00e1tica<\/li>\n\n\n\n<li>Conhecimentos espec\u00edficos\n<ul class=\"wp-block-list\">\n<li>Total de quest\u00f5es: 80<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"nivel-medio\">N\u00edvel m\u00e9dio<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecimentos b\u00e1sicos: L\u00edngua Portuguesa e Inform\u00e1tica<\/li>\n\n\n\n<li>Conhecimentos espec\u00edficos\n<ul class=\"wp-block-list\">\n<li>Total de quest\u00f5es: 60<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"nivel-fundamental\">N\u00edvel fundamental<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conhecimentos b\u00e1sicos: L\u00edngua Portuguesa e Racioc\u00ednio L\u00f3gico<\/li>\n\n\n\n<li>Conhecimentos espec\u00edficos\n<ul class=\"wp-block-list\">\n<li>Total de quest\u00f5es: 40<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos\"><strong><em>Quer estudar para o Concurso CRO BA?<\/em><\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-center\"><em>Gostou desta oportunidade e deseja come\u00e7ar se preparar agora mesmo? Ent\u00e3o, confira os nossos cursos e comece a estudar:<\/em><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Cursos para concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Estude conosco CRO BA<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a os cursos<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 Ano ou 2 Anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100-1024x632.png\" alt=\"Ficha t\u00e9cnica do concurso CRO BA\" class=\"wp-image-708475\" width=\"193\" height=\"119\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100-1024x632.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100-300x185.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100-768x474.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100-1536x948.png 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100-610x377.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/06121705\/ficha-tecnica-100.png 1571w\" sizes=\"auto, (max-width: 193px) 100vw, 193px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"ficha-tecnica-concurso-tjdft\"><strong>\u2666Informa\u00e7\u00f5es do novo concurso CRO BA<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inscri\u00e7\u00f5es<\/strong>: <s>de 27 de setembro a 03 de novembro<\/s><\/li>\n\n\n\n<li><strong>Provas<\/strong>: 18 de dezembro<\/li>\n\n\n\n<li><strong>Vagas<\/strong>: 09 + CR<\/li>\n\n\n\n<li><strong>Cargos<\/strong>: Agente de Fiscaliza\u00e7\u00e3o, T\u00e9cnico Administrativo, T\u00e9cnico de Inform\u00e1tica e Analista de Licita\u00e7\u00e3o e Contrato<\/li>\n\n\n\n<li><strong>Banca<\/strong>: Quadrix <\/li>\n\n\n\n<li><strong>Escolaridade<\/strong>: m\u00e9dio, t\u00e9cnico e superior <\/li>\n\n\n\n<li><strong>Edital<\/strong>:&nbsp;<a href=\"http:\/\/www.quadrix.org.br\/web\/visualizar.html?file=http:\/\/www.quadrix.org.br\/Archives\/General\/26661\/27418\/27421\/281F231BEA58\/1_CRO-BA_concurso_publico_2022_edital_abertura.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">CRO BA <\/a><\/li>\n<\/ul>\n\n\n\n<p><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O resultado final do concurso CRO BA (Conselho Regional de Odontologia da Bahia) foi divulgado! Veja aqui o nome dos aprovados! S\u00e3o 09 vagas imediatas mais cadastro reserva nos cargos de Agente de Fiscaliza\u00e7\u00e3o, T\u00e9cnico Administrativo, T\u00e9cnico de Inform\u00e1tica e Analista de Licita\u00e7\u00e3o e Contrato; que exigem n\u00edveis m\u00e9dio, t\u00e9cnico e superior. A remunera\u00e7\u00e3o ofertada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1046973,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news_page","footnotes":""},"categories":[214992,220219],"tags":[],"tax_estado":[219968],"class_list":["post-1046972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","category-noticias","tax_estado-ba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso CRO BA: resultado final dispon\u00edvel; veja!<\/title>\n<meta name=\"description\" content=\"Concurso CRO BA: confira com o Estrat\u00e9gia Concursos os detalhes do certame do Conselho Regional de Odontologia da Bahia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso CRO BA: resultado final dispon\u00edvel; veja!\" \/>\n<meta property=\"og:description\" content=\"Concurso CRO BA: confira com o Estrat\u00e9gia Concursos os detalhes do certame do Conselho Regional de Odontologia da Bahia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T17:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T17:23:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso CRO BA: resultado final dispon\u00edvel; veja!\",\"datePublished\":\"2023-06-05T17:22:00+00:00\",\"dateModified\":\"2023-06-05T17:23:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\"},\"wordCount\":2171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png\",\"articleSection\":[\"Executivo (Administrativa)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\",\"name\":\"Concurso CRO BA: resultado final dispon\u00edvel; veja!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png\",\"datePublished\":\"2023-06-05T17:22:00+00:00\",\"dateModified\":\"2023-06-05T17:23:52+00:00\",\"description\":\"Concurso CRO BA: confira com o Estrat\u00e9gia Concursos os detalhes do certame do Conselho Regional de Odontologia da Bahia.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso CRO BA: resultado final dispon\u00edvel; veja!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso CRO BA: resultado final dispon\u00edvel; veja!","description":"Concurso CRO BA: confira com o Estrat\u00e9gia Concursos os detalhes do certame do Conselho Regional de Odontologia da Bahia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso CRO BA: resultado final dispon\u00edvel; veja!","og_description":"Concurso CRO BA: confira com o Estrat\u00e9gia Concursos os detalhes do certame do Conselho Regional de Odontologia da Bahia.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2023-06-05T17:22:00+00:00","article_modified_time":"2023-06-05T17:23:52+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png","type":"image\/png"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso CRO BA: resultado final dispon\u00edvel; veja!","datePublished":"2023-06-05T17:22:00+00:00","dateModified":"2023-06-05T17:23:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/"},"wordCount":2171,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png","articleSection":["Executivo (Administrativa)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/","name":"Concurso CRO BA: resultado final dispon\u00edvel; veja!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png","datePublished":"2023-06-05T17:22:00+00:00","dateModified":"2023-06-05T17:23:52+00:00","description":"Concurso CRO BA: confira com o Estrat\u00e9gia Concursos os detalhes do certame do Conselho Regional de Odontologia da Bahia.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/20065710\/concurso-cro-ba.png","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cro-ba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso CRO BA: resultado final dispon\u00edvel; veja!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1046972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1046972"}],"version-history":[{"count":11,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1046972\/revisions"}],"predecessor-version":[{"id":1227845,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1046972\/revisions\/1227845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1046973"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1046972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1046972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1046972"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1046972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}