{"id":104586,"date":"2018-01-30T19:46:14","date_gmt":"2018-01-30T22:46:14","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=104586"},"modified":"2018-01-31T13:23:33","modified_gmt":"2018-01-31T16:23:33","slug":"provacomentadaafocgmjp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/","title":{"rendered":"Prova comentada e recurso CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor &#8211; AFO"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Prova comentada CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor Municipal de Controle Interno (Cargos 1 a 3)<\/strong><\/p>\n<p style=\"text-align: justify\" align=\"left\"><b>\u00a0Administra\u00e7\u00e3o\u00a0 Financeira e Or\u00e7ament\u00e1ria<\/b><b><\/b><\/p>\n<p style=\"text-align: justify\" align=\"left\"><strong>Cabe Recurso na quest\u00e3o 39<\/strong><\/p>\n<p style=\"text-align: justify\">Ol\u00e1 amigos!<\/p>\n<p style=\"text-align: justify\">Foi realizada a prova da CGM\/Jo\u00e3o Pessoa para o cargo de Auditor Municipal de Controle Interno e, como era esperado, vieram muitas quest\u00f5es de AFO.<\/p>\n<p>&nbsp;<\/p>\n<p>A prova de T\u00e9cnico foi comentada em: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prova-comentada-cgm-joao-pessoa-tecnico-afo\/\" target=\"_blank\" rel=\"noopener\">Prova_AFO_T\u00e9cnico_CGM_Jo\u00e3o_Pessoa<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><strong>39\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) A lei or\u00e7ament\u00e1ria anual somente pode ser elaborada ap\u00f3s a aprova\u00e7\u00e3o da lei de diretrizes or\u00e7ament\u00e1rias.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Cabe recurso!<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">\u00c9 fato que a LDO \u00e9 refer\u00eancia para a LOA, bem como que os prazos para o envio da LOA s\u00e3o posteriores aos prazos de aprova\u00e7\u00e3o da LDO. Por\u00e9m, a <u>elabora\u00e7\u00e3o<\/u> da LOA <strong>n\u00e3o est\u00e1 condicionada<\/strong> \u00e0 aprova\u00e7\u00e3o da LDO.<\/p>\n<p style=\"text-align: justify\">Considerando que os prazos fossem sempre respeitados, a LDO seria aprovada pelo Congresso Nacional at\u00e9 17 de julho e a LOA deveria ser enviada pelo Poder Executivo at\u00e9 31 de agosto. Ou seja, se a quest\u00e3o estivesse correta, a LOA teria que ser elaborada em toda a sua complexidade em cerca de um m\u00eas e meio.<\/p>\n<p style=\"text-align: justify\">Gabarito preliminar: Certa<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Gabarito proposto: <strong>Errada<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>40\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) Para ser considerada princ\u00edpio or\u00e7ament\u00e1rio, a regra deve estar expressamente prevista na Constitui\u00e7\u00e3o Federal de 1988.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">H\u00e1 princ\u00edpios or\u00e7ament\u00e1rios previstos na CF\/1988, mas <strong>h\u00e1 princ\u00edpios previstos em lei e pela doutrina<\/strong>.<\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>41\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) Se o Estado receber determinado recurso na condi\u00e7\u00e3o de deposit\u00e1rio, sem que a correspondente restitui\u00e7\u00e3o se sujeite \u00e0 autoriza\u00e7\u00e3o legislativa, o ingresso n\u00e3o ser\u00e1 inclu\u00eddo na lei or\u00e7ament\u00e1ria anual.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">As receitas extraor\u00e7ament\u00e1rias <u>n\u00e3o integram o or\u00e7amento p\u00fablico<\/u> e constituem passivos exig\u00edveis do ente, de tal forma que o seu pagamento n\u00e3o est\u00e1 sujeito \u00e0 autoriza\u00e7\u00e3o legislativa. Isso ocorre porque possuem car\u00e1ter tempor\u00e1rio, n\u00e3o se incorporando ao patrim\u00f4nio p\u00fablico. S\u00e3o chamadas de ingressos extraor\u00e7ament\u00e1rios. Trata-se do caso em tela, em que o Estado \u00e9 deposit\u00e1rio, sem que a correspondente restitui\u00e7\u00e3o se sujeite \u00e0 autoriza\u00e7\u00e3o legislativa.<\/p>\n<p style=\"text-align: justify\">Resposta: Certa<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>42\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) \u00c9 vedada a utiliza\u00e7\u00e3o dos recursos provenientes de excesso de arrecada\u00e7\u00e3o como fonte para a abertura de cr\u00e9ditos suplementares ou especiais.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Uma das fontes para a abertura de cr\u00e9ditos adicionais <strong>\u00e9 o excesso de arrecada\u00e7\u00e3o<\/strong>, que corresponde ao saldo positivo das diferen\u00e7as acumuladas m\u00eas a m\u00eas entre a arrecada\u00e7\u00e3o prevista e a realizada, considerando-se, ainda, a tend\u00eancia do exerc\u00edcio.<\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>43 \u00a0\u00a0 \u00a0(CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) No \u00e2mbito do plano plurianual, as metas devem expressar as escolhas de pol\u00edticas p\u00fablicas para a transforma\u00e7\u00e3o de determinada realidade.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">As metas correspondem <strong>\u00e0 quantifica\u00e7\u00e3o dos objetivos<\/strong>. Os <strong>objetivos<\/strong> devem expressar as escolhas de pol\u00edticas p\u00fablicas para a transforma\u00e7\u00e3o de determinada realidade.<\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>44\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) O anexo de metas fiscais deve ser obrigatoriamente inclu\u00eddo na lei de diretrizes or\u00e7ament\u00e1rias, mas a inclus\u00e3o do anexo de riscos fiscais \u00e9 facultativa.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">O anexo de metas fiscais <strong>e o anexo de riscos fiscais integram a LDO.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Integrar\u00e1 o projeto de lei de diretrizes or\u00e7ament\u00e1rias Anexo de Metas Fiscais, em que ser\u00e3o estabelecidas metas anuais, em valores correntes e constantes, relativas a receitas, despesas, resultados nominal e prim\u00e1rio e montante da d\u00edvida p\u00fablica, para o exerc\u00edcio a que se referirem e para os dois seguintes (art. 4\u00ba, \u00a7 1\u00ba, da LRF). A <strong>LDO conter\u00e1 o anexo de riscos fiscais<\/strong> onde ser\u00e3o avaliados os passivos contingentes e outros riscos capazes de afetar as contas p\u00fablicas, informando as provid\u00eancias a serem tomadas, caso se concretizem (art. 4\u00ba, \u00a7 3\u00ba, da LRF).<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>45 \u00a0\u00a0 \u00a0(CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) O or\u00e7amento de investimento de determinada empresa somente deve ser inclu\u00eddo na lei or\u00e7ament\u00e1ria anual se a Uni\u00e3o detiver a maioria do capital social com direito a voto dessa empresa.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">A LOA compreende o or\u00e7amento fiscal, o or\u00e7amento da seguridade social e o or\u00e7amento de investimentos das empresas em que a Uni\u00e3o, direta ou indiretamente, detenha a maioria do capital social com direito a voto.<\/p>\n<p style=\"text-align: justify\">Resposta: Certa<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>46\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) O recurso legalmente vinculado \u00e0 finalidade espec\u00edfica que n\u00e3o for utilizado no objeto de sua vincula\u00e7\u00e3o at\u00e9 o final do exerc\u00edcio financeiro reverte ao Tesouro p\u00fablico e pode ser utilizado no exerc\u00edcio seguinte em outras finalidades.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Os recursos legalmente vinculados a finalidade espec\u00edfica <strong>ser\u00e3o utilizados exclusivamente para atender ao objeto de sua vincula\u00e7\u00e3o<\/strong>, <strong>ainda que em exerc\u00edcio diverso daquele em que ocorrer o ingresso<\/strong> (art. 8\u00ba, par\u00e1grafo \u00fanico, da LRF).<\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>47\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) A classifica\u00e7\u00e3o da receita p\u00fablica por esfera or\u00e7ament\u00e1ria deve ser utilizada para diferenciar os recursos que ser\u00e3o diretamente utilizados pelo ente arrecadador daqueles que devem ser transferidos para outros entes da Federa\u00e7\u00e3o.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">A classifica\u00e7\u00e3o por esfera \u00e9 uma classifica\u00e7\u00e3o que pode ser vista tanto na \u00f3tica da receita como na da despesa.<\/p>\n<p style=\"text-align: justify\">No que tange \u00e0 <u>receita<\/u>, tal classifica\u00e7\u00e3o tem por finalidade <strong>identificar se a receita pertence ao Or\u00e7amento Fiscal, da Seguridade Social ou de Investimento das Empresas Estatais<\/strong>, conforme distingue o \u00a7 5\u00ba do art. 165 da CF\/1988.<\/p>\n<p style=\"text-align: justify\">Da mesma forma, no que tange \u00e0 <u>despesa<\/u>, tal classifica\u00e7\u00e3o tem por finalidade identificar se a <u>despesa<\/u> pertence ao Or\u00e7amento Fiscal, da Seguridade Social ou de Investimento das Empresas Estatais, conforme distingue o \u00a7 5\u00ba do art. 165 da CF\/1988.<\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>48 \u00a0\u00a0 \u00a0(CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) As unidades or\u00e7ament\u00e1rias podem corresponder a v\u00e1rios \u00f3rg\u00e3os da estrutura administrativa ou apenas a uma parte de um \u00fanico \u00f3rg\u00e3o.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">As unidades or\u00e7ament\u00e1rias podem corresponder a v\u00e1rios \u00f3rg\u00e3os (reparti\u00e7\u00f5es) da estrutura administrativa ou apenas a uma parte de um \u00fanico \u00f3rg\u00e3o. Ainda, um \u00f3rg\u00e3o ou uma unidade or\u00e7ament\u00e1ria pode n\u00e3o corresponder sequer a uma estrutura administrativa.<\/p>\n<p style=\"text-align: justify\">Resposta: Certa<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>49 \u00a0\u00a0 \u00a0(CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) O \u00f3rg\u00e3o p\u00fablico que precisar descentralizar dota\u00e7\u00f5es do seu or\u00e7amento para unidades gestoras de outro \u00f3rg\u00e3o p\u00fablico dever\u00e1 realizar um destaque.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Quando a descentraliza\u00e7\u00e3o envolver unidades gestoras de um mesmo \u00f3rg\u00e3o, tem-se a descentraliza\u00e7\u00e3o interna, tamb\u00e9m chamada de provis\u00e3o. <u>Se, porventura, ocorrer entre unidades gestoras de \u00f3rg\u00e3os ou entidades de estrutura diferente, ter-se-\u00e1 uma descentraliza\u00e7\u00e3o externa, tamb\u00e9m denominada de destaque<\/u>.<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">Resposta: Certa<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>50\u00a0\u00a0\u00a0 (CESPE \u2013 Auditor Municipal de Controle Interno &#8211; CGM\/JP \u2013 2018) As transfer\u00eancias recebidas de outros entes n\u00e3o integram a receita corrente l\u00edquida.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\">A Receita Corrente L\u00edquida corresponde ao somat\u00f3rio das receitas tribut\u00e1rias, de contribui\u00e7\u00f5es, patrimoniais, industriais, agropecu\u00e1rias, de servi\u00e7os, <strong>transfer\u00eancias correntes <\/strong>e outras receitas tamb\u00e9m correntes, com as dedu\u00e7\u00f5es estabelecidas na pr\u00f3pria LRF.<\/p>\n<p style=\"text-align: justify\">Resposta: Errada<\/p>\n<p style=\"text-align: justify\">Quer aprender AFO e Direito Financeiro de verdade e &#8220;arrebentar em provas como essa&#8221;? Invista nos cursos espec\u00edficos para o seu concurso clicando em: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/sergio-mendes-3000\/\" target=\"_blank\" rel=\"noopener\">quero aprender AFO e LRF de verdade.<\/a><\/p>\n<p style=\"text-align: justify\">Se n\u00e3o h\u00e1 um curso espec\u00edfico para o concurso que voc\u00ea quer, sugiro para voc\u00ea o curso regular clicando em: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/administracao-financeira-e-orcamentaria-para-concursos-com-videoaulas-curso-regular-2018\/\" target=\"_blank\" rel=\"noopener\">quero aprender AFO para concursos.<\/a><\/p>\n<p style=\"text-align: justify\">Forte abra\u00e7o!<\/p>\n<p style=\"text-align: justify\">S\u00e9rgio Mendes<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.instagram.com\/sergiomendesafo\">www.instagram.com\/sergiomendesafo<\/a><\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.facebook.com\/sergiomendesafo\">www.facebook.com\/sergiomendesafo<\/a><\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.youtube.com\/sergiomendesafo\">www.youtube.com\/sergiomendesafo<\/a><\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.portaldoorcamento.com.br\/\">www.portaldoorcamento.com.br<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prova comentada CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor Municipal de Controle Interno (Cargos 1 a 3) \u00a0Administra\u00e7\u00e3o\u00a0 Financeira e Or\u00e7ament\u00e1ria Cabe Recurso na quest\u00e3o 39 Ol\u00e1 amigos! Foi realizada a prova da CGM\/Jo\u00e3o Pessoa para o cargo de Auditor Municipal de Controle Interno e, como era esperado, vieram muitas quest\u00f5es de AFO. &nbsp; A prova [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1984],"tags":[3448],"tax_estado":[],"class_list":["post-104586","post","type-post","status-publish","format-standard","hentry","category-tribunais","tag-porva-comentada-afo-cgm-jp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prova comentada e recurso CGM - Jo\u00e3o Pessoa - Auditor - AFO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prova comentada e recurso CGM - Jo\u00e3o Pessoa - Auditor - AFO\" \/>\n<meta property=\"og:description\" content=\"Prova comentada CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor Municipal de Controle Interno (Cargos 1 a 3) \u00a0Administra\u00e7\u00e3o\u00a0 Financeira e Or\u00e7ament\u00e1ria Cabe Recurso na quest\u00e3o 39 Ol\u00e1 amigos! Foi realizada a prova da CGM\/Jo\u00e3o Pessoa para o cargo de Auditor Municipal de Controle Interno e, como era esperado, vieram muitas quest\u00f5es de AFO. &nbsp; A prova [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profsergiomendes\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-30T22:46:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-31T16:23:33+00:00\" \/>\n<meta name=\"author\" content=\"S\u00e9rgio Mendes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9rgio Mendes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\"},\"author\":{\"name\":\"S\u00e9rgio Mendes\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4ddc4a162b4fdffa2ea9956dbf62f583\"},\"headline\":\"Prova comentada e recurso CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor &#8211; AFO\",\"datePublished\":\"2018-01-30T22:46:14+00:00\",\"dateModified\":\"2018-01-31T16:23:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\"},\"wordCount\":1324,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"porva comentada AFO CGM JP\"],\"articleSection\":[\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\",\"name\":\"Prova comentada e recurso CGM - Jo\u00e3o Pessoa - Auditor - AFO\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-01-30T22:46:14+00:00\",\"dateModified\":\"2018-01-31T16:23:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prova comentada e recurso CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor &#8211; AFO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4ddc4a162b4fdffa2ea9956dbf62f583\",\"name\":\"S\u00e9rgio Mendes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4eb4b562c33f40d6f7f76579da7e07350c69579df7db305d32a69ed32ecfd5ce?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4eb4b562c33f40d6f7f76579da7e07350c69579df7db305d32a69ed32ecfd5ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4eb4b562c33f40d6f7f76579da7e07350c69579df7db305d32a69ed32ecfd5ce?s=96&d=mm&r=g\",\"caption\":\"S\u00e9rgio Mendes\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profsergiomendes\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/sergiomendesestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prova comentada e recurso CGM - Jo\u00e3o Pessoa - Auditor - AFO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/","og_locale":"pt_BR","og_type":"article","og_title":"Prova comentada e recurso CGM - Jo\u00e3o Pessoa - Auditor - AFO","og_description":"Prova comentada CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor Municipal de Controle Interno (Cargos 1 a 3) \u00a0Administra\u00e7\u00e3o\u00a0 Financeira e Or\u00e7ament\u00e1ria Cabe Recurso na quest\u00e3o 39 Ol\u00e1 amigos! Foi realizada a prova da CGM\/Jo\u00e3o Pessoa para o cargo de Auditor Municipal de Controle Interno e, como era esperado, vieram muitas quest\u00f5es de AFO. &nbsp; A prova [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/profsergiomendes","article_published_time":"2018-01-30T22:46:14+00:00","article_modified_time":"2018-01-31T16:23:33+00:00","author":"S\u00e9rgio Mendes","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"S\u00e9rgio Mendes","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/"},"author":{"name":"S\u00e9rgio Mendes","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4ddc4a162b4fdffa2ea9956dbf62f583"},"headline":"Prova comentada e recurso CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor &#8211; AFO","datePublished":"2018-01-30T22:46:14+00:00","dateModified":"2018-01-31T16:23:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/"},"wordCount":1324,"commentCount":3,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["porva comentada AFO CGM JP"],"articleSection":["Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/","name":"Prova comentada e recurso CGM - Jo\u00e3o Pessoa - Auditor - AFO","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-01-30T22:46:14+00:00","dateModified":"2018-01-31T16:23:33+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/provacomentadaafocgmjp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Prova comentada e recurso CGM &#8211; Jo\u00e3o Pessoa &#8211; Auditor &#8211; AFO"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4ddc4a162b4fdffa2ea9956dbf62f583","name":"S\u00e9rgio Mendes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4eb4b562c33f40d6f7f76579da7e07350c69579df7db305d32a69ed32ecfd5ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4eb4b562c33f40d6f7f76579da7e07350c69579df7db305d32a69ed32ecfd5ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4eb4b562c33f40d6f7f76579da7e07350c69579df7db305d32a69ed32ecfd5ce?s=96&d=mm&r=g","caption":"S\u00e9rgio Mendes"},"sameAs":["https:\/\/www.facebook.com\/profsergiomendes"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/sergiomendesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/104586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=104586"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/104586\/revisions"}],"predecessor-version":[{"id":104704,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/104586\/revisions\/104704"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=104586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=104586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=104586"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=104586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}