{"id":1009058,"date":"2022-07-14T08:04:00","date_gmt":"2022-07-14T11:04:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1009058"},"modified":"2022-07-18T14:17:08","modified_gmt":"2022-07-18T17:17:08","slug":"propriedade-para-investimento-para-a-area-fiscal","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/","title":{"rendered":"Propriedade para Investimento para a \u00c1rea Fiscal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-1-introducao\">1. Introdu\u00e7\u00e3o<\/h2>\n\n\n\n<p>Aprenda aqui os principais pontos do CPC 28 (propriedade para investimento) (<a href=\"http:\/\/www.cpc.org.br\/CPC\/Documentos-Emitidos\/Pronunciamentos\">http:\/\/www.cpc.org.br\/CPC\/Documentos-Emitidos\/Pronunciamentos<\/a>) cobrados nos certames da \u00e1rea fiscal.<\/p>\n\n\n\n<p>Primeiramente, ressalta-se que o balan\u00e7o patrimonial \u00e9 composto de contas que visam apresentar de forma fidedigna a situa\u00e7\u00e3o cont\u00e1bil e financeira de uma empresa.<\/p>\n\n\n\n<p>Por sua vez, o ativo \u00e9 composto de bens e direitos controlados pela entidade. N\u00e3o \u00e9 necess\u00e1rio ser propriet\u00e1rio desse bem\/direito para contabiliz\u00e1-lo em seu ativo.<\/p>\n\n\n\n<p>Classificam-se as propriedades para investimento no grupo Investimentos do ativo circulante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-definicao-de-propriedade-para-investimento-para-a-area-fiscal\">2. Defini\u00e7\u00e3o de Propriedade para Investimento para a \u00c1rea Fiscal<\/h2>\n\n\n\n<p>O CPC 28 define propriedade para investimento como a propriedade mantida pelo propriet\u00e1rio ou pelo arrendat\u00e1rio em arrendamento financeiro para auferir aluguel e para a valoriza\u00e7\u00e3o do capital.<\/p>\n\n\n\n<p>Esta propriedade n\u00e3o pode ser usada na produ\u00e7\u00e3o ou fornecimento de bens ou servi\u00e7os ou para finalidades administrativas e tamb\u00e9m n\u00e3o pode ser vendida no curso ordin\u00e1rio do neg\u00f3cio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-exemplos-de-propriedades-para-investimento-para-a-area-fiscal\">2.1 Exemplos de Propriedades para Investimento para a \u00c1rea Fiscal<\/h3>\n\n\n\n<p>O pr\u00f3prio CPC 28 apresenta exemplos pr\u00e1ticos de propriedades para investimento:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>terrenos<\/strong> mantidos para a <strong>valoriza\u00e7\u00e3o de capital<\/strong> a longo prazo;<\/li><li><strong>terreno <\/strong>mantido para <strong>uso futuro indeterminado<\/strong>;<\/li><li><strong>edif\u00edcio <\/strong>desocupado, mas mantido para ser arrendado sob <strong>arrendamento operacional<\/strong>;<\/li><li>propriedade que esteja sendo <strong>constru\u00edda <\/strong>ou desenvolvida para <strong>futura utiliza\u00e7\u00e3o como propriedade para investimento<\/strong>;<\/li><\/ul>\n\n\n\n<p>Al\u00e9m disso, o CPC 28 apresenta exemplos de propriedades que n\u00e3o s\u00e3o propriedades para investimento:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>destinadas a venda no curso ordin\u00e1rio ou em constru\u00e7\u00e3o;<\/li><li>ocupadas pelo propriet\u00e1rio;<\/li><li>usadas por empregados, mesmo que o aluguel n\u00e3o seja pago a taxa de mercado;<\/li><li>ocupadas por propriet\u00e1rio no aguardo da aliena\u00e7\u00e3o;<\/li><li>arrendadas sob arrendamento financeiro;<\/li><\/ul>\n\n\n\n<p>Ressalta-se que o arrendamento financeiro \u00e9 aquele no qual o controle de uso de um determinado bem, assim como os seus riscos e benef\u00edcios, \u00e9 de responsabilidade do arrendat\u00e1rio. J\u00e1 no arrendamento operacional, o arrendador fica respons\u00e1vel pelos riscos e benef\u00edcios do ativo subjacente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-3-imoveis-para-aluguel\">2.3 Im\u00f3veis para Aluguel<\/h3>\n\n\n\n<p>Contabiliza-se um im\u00f3vel utilizado para aluguel como propriedade para investimento se os recursos dele provenientes n\u00e3o forem destinados \u00e0s atividades fins.<\/p>\n\n\n\n<p>Todavia, se esses recursos estiverem sendo utilizados para as atividades fins da entidade, o im\u00f3vel dever\u00e1 ser contabilizado como imobilizado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-reconhecimento-da-propriedade-para-investimento\">3. Reconhecimento da Propriedade para Investimento<\/h2>\n\n\n\n<p>O reconhecimento (contabiliza\u00e7\u00e3o) de uma propriedade para investimento deve ser feita conforme o CPC 28, e somente se estes dois requisitos forem cumpridos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>for prov\u00e1vel que os <strong>benef\u00edcios<\/strong> futuros <strong>fluir\u00e3o para a empresa<\/strong>;<\/li><li><strong>custo <\/strong>da propriedade para investimento possa ser <strong>mensurado confiavelmente<\/strong>;<\/li><\/ul>\n\n\n\n<p>Contudo, o que fazer se uma mesma propriedade tiver uma parte sendo usada para investimento e outra para a produ\u00e7\u00e3o\/ fornecimento de bens e servi\u00e7os?<\/p>\n\n\n\n<p>O CPC 28 determina que, caso cada parte possa ser vendida separadamente, ou arrendada separadamente por arrendamento financeiro, a entidade deve contabiliz\u00e1-las separadamente. Ou seja, a usada para investimento deve ser classificada como propriedade para investimento e a usada para atividades operacionais como imobilizado.<\/p>\n\n\n\n<p>Todavia, se as partes n\u00e3o puderem ser vendidas separadamente, a propriedade somente deve ser contabilizada como propriedade para investimento se uma parte <strong>insignificante <\/strong>dela for usada para a produ\u00e7\u00e3o\/ fornecimento de bens e servi\u00e7os.<\/p>\n\n\n\n<p>Al\u00e9m disso, o CPC 28 tamb\u00e9m determinou que:<\/p>\n\n\n\n<p><em>11. Em alguns casos, a entidade proporciona <strong>servi\u00e7os de apoio aos ocupantes da propriedade<\/strong> que ela mantenha. A entidade trata tal propriedade como propriedade para investimento se os<strong> servi\u00e7os forem insignificantes em rela\u00e7\u00e3o ao acordo<\/strong> como um todo. Portanto, um exemplo \u00e9 quando o propriet\u00e1rio de edif\u00edcio de escrit\u00f3rios proporciona servi\u00e7os de seguran\u00e7a e de manuten\u00e7\u00e3o aos arrendat\u00e1rios que ocupam o edif\u00edcio.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-mensuracao-da-propriedade-para-investimento-para-a-area-fiscal\">4. &nbsp;Mensura\u00e7\u00e3o da Propriedade para Investimento para a \u00c1rea Fiscal<\/h2>\n\n\n\n<p>A propriedade para investimento deve ser mensurada inicialmente pelo valor de custo (pre\u00e7o de compra e qualquer disp\u00eandio diretamente atribu\u00edvel).<\/p>\n\n\n\n<p>Em contrapartida, o pr\u00f3prio CPC 28 define o que este custo <strong>n\u00e3o<\/strong> deve compreender:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>custo inicial<\/strong> de atividades;<\/li><li><strong>perdas operacionais<\/strong> incorridas <strong>antes <\/strong>de a propriedade ter atingido o <strong>n\u00edvel de ocupa\u00e7\u00e3o<\/strong> prevista;<\/li><li>quantidade <strong>anormal <\/strong>de material, m\u00e3o de obra ou outros recursos;<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-mensuracao-da-propriedade-para-investimento-para-a-area-fiscal-apos-o-reconhecimento-inicial\">4.1 Mensura\u00e7\u00e3o da Propriedade para Investimento para a \u00c1rea Fiscal ap\u00f3s o Reconhecimento Inicial<\/h3>\n\n\n\n<p>Ap\u00f3s o reconhecimento inicial pelo valor de custo, a entidade pode classificar as suas propriedades para investimento pelo valor de custo ou pelo valor justo. Esta escolha da pr\u00e1tica cont\u00e1bil deve ser feita e aplicada a todos estes ativos de maneira id\u00eantica.<\/p>\n\n\n\n<p>Caso se adote o m\u00e9todo do valor de custo, o valor cont\u00e1bil \u00e9:<\/p>\n\n\n\n<p class=\"has-text-align-center\">Va<em>lor Cont\u00e1bil = Custo &#8211; Amortiza\u00e7\u00e3o\/ Deprecia\u00e7\u00e3o\/Exaust\u00e3o +- Impairment<\/em><\/p>\n\n\n\n<p>Por outro lado, se o valor justo for escolhido, o valor cont\u00e1bil ser\u00e1 o \u201cpre\u00e7o que seria recebido pela venda de um ativo ou que seria pago pela transfer\u00eancia de um passivo em uma <strong>transa\u00e7\u00e3o n\u00e3o for\u00e7ada<\/strong> entre <strong>participantes <\/strong>do mercado na data de mensura\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>Vale ressaltar que, mesmo se a entidade optar pela utiliza\u00e7\u00e3o da t\u00e9cnica de mensura\u00e7\u00e3o pelo custo, o valor justo deve ser mensurado para fins de mera divulga\u00e7\u00e3o. Percebe-se, portanto, que sempre se calcular\u00e1 o valor justo da propriedade para investimento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-mensuracao-da-propriedade-para-investimento-quando-da-alteracao-de-uso\">4.2 Mensura\u00e7\u00e3o da Propriedade para Investimento quando da Altera\u00e7\u00e3o de Uso<\/h3>\n\n\n\n<p>Como mensurar um ativo que estava contabilizado como imobilizado pelo custo, quando este passa a ser usado como uma propriedade para investimento? E se, por outro lado, uma propriedade para investimento come\u00e7asse a ser usada como imobilizado?<\/p>\n\n\n\n<p>Felizmente, o CPC 28 define as regras gerais de contabiliza\u00e7\u00e3o para as situa\u00e7\u00f5es citadas e tamb\u00e9m para outras que s\u00e3o comuns \u00e0 pr\u00e1tica cont\u00e1bil.<\/p>\n\n\n\n<p>Se a propriedade para investimento estiver avaliada pelo m\u00e9todo de custo e posteriormente for reclassificada como propriedade ocupada pelo propriet\u00e1rio ou estoque, o valor cont\u00e1bil dela n\u00e3o se altera e permanece sendo o custo.<\/p>\n\n\n\n<p>Todavia, se a propriedade para investimento for avaliada pelo valor justo, a sua transfer\u00eancia para uma propriedade ocupada pelo propriet\u00e1rio ou estoque deve ser feita considerando o seu valor justo na data da altera\u00e7\u00e3o como sendo o seu custo.<\/p>\n\n\n\n<p>Al\u00e9m disso, analisaremos o caminho inverso. Caso um ativo seja classificado como imobilizado e posteriormente passe a ser contabilizado como propriedade para investimentos ao valor justo, duas situa\u00e7\u00f5es podem acontecer.<\/p>\n\n\n\n<p>Se o valor de custo for maior que o valor justo, esse ajuste gera uma despesa. Todavia, se o valor de custo for menor que o valor justo, esse ajuste gera uma revers\u00e3o do impairment e um posterior ajuste de avalia\u00e7\u00e3o patrimonial.<\/p>\n\n\n\n<p>Por fim, tamb\u00e9m analisaremos como deve ser feita a contabilidade quando se transfere um estoque (imobilizado mantido para venda) para o subgrupo propriedade para investimento.<\/p>\n\n\n\n<p>Se o valor cont\u00e1bil do estoque for maior que o valor justo, esta transfer\u00eancia acarreta uma despesa. Por outro lado, se o valor cont\u00e1bil for menor que o valor justo, esta reclassifica\u00e7\u00e3o gera uma receita.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg\" alt=\"Propriedade para Investimento para a \u00c1rea Fiscal\" class=\"wp-image-1009708\" width=\"724\" height=\"290\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg 601w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento-300x120.jpg 300w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-divulgacao-da-propriedade-para-investimento-para-a-area-fiscal\">5. Divulga\u00e7\u00e3o da Propriedade para Investimento para a \u00c1rea Fiscal<\/h2>\n\n\n\n<p>O CPC 28 definiu alguns aspectos que a entidade precisa divulgar quando da contabiliza\u00e7\u00e3o do valor justo:<\/p>\n\n\n\n<p><em>75. A entidade deve <strong>divulgar<\/strong>:<\/em><\/p>\n\n\n\n<p><em>(a) se aplica o <strong>m\u00e9todo <\/strong>do valor justo ou o m\u00e9todo do custo;<\/em><\/p>\n\n\n\n<p><em>(c) quando a <strong>classifica\u00e7\u00e3o for dif\u00edcil, os crit\u00e9rios<\/strong> que usa para distinguir propriedades para investimento de propriedades ocupadas pelo propriet\u00e1rio e de propriedades mantidas para venda no curso ordin\u00e1rio dos neg\u00f3cios;<\/em><\/p>\n\n\n\n<p><em>(e) a extens\u00e3o at\u00e9 a qual o valor justo da propriedade para investimento (tal como mensurado ou divulgado nas demonstra\u00e7\u00f5es cont\u00e1beis) se baseia em <strong>avalia\u00e7\u00e3o de avaliador independente<\/strong> que possua qualifica\u00e7\u00e3o profissional reconhecida e relevante e que, portanto, tenha experi\u00eancia recente no local e na categoria da propriedade para investimento que est\u00e1 sendo avaliada<\/em>;<\/p>\n\n\n\n<p><em>(f) as quantias reconhecidas no resultado para:<\/em><\/p>\n\n\n\n<p><em>(i) <strong>lucros de rendas<\/strong> de propriedade para investimento;<\/em><\/p>\n\n\n\n<p><em>(ii)<strong> gastos operacionais diretos<\/strong> (incluindo reparos e manuten\u00e7\u00e3o) provenientes de propriedades para investimento que <strong>tenham <\/strong>gerado rendas durante o per\u00edodo;<\/em><\/p>\n\n\n\n<p><em>(iii) gastos operacionais diretos (incluindo reparos e manuten\u00e7\u00e3o) provenientes de propriedades para investimento que<strong> n\u00e3o tenham<\/strong>, portanto, gerado rendas durante o per\u00edodo; e<\/em><\/p>\n\n\n\n<p><em>(iv) a altera\u00e7\u00e3o cumulativa no valor justo reconhecido nos resultados com a venda de propriedade para investimento de um conjunto de ativos em que se usa o m\u00e9todo do custo para um conjunto em que se usa o m\u00e9todo do valor justo;<\/em><\/p>\n\n\n\n<p><em>(g) a exist\u00eancia e quantias de <strong>restri\u00e7\u00f5es sobre a capacidade de realiza\u00e7\u00e3o<\/strong> de propriedades para investimento ou a remessa de lucros e recebimentos de aliena\u00e7\u00e3o;<\/em><\/p>\n\n\n\n<p><em>(h) <strong>obriga\u00e7\u00f5es contratuais<\/strong> para <strong>comprar, construir ou desenvolver propriedades <\/strong>para investimento ou para reparos, manuten\u00e7\u00e3o ou aumentos.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-alienacao-da-propriedade-para-investimento\">6. Aliena\u00e7\u00e3o da Propriedade para Investimento<\/h2>\n\n\n\n<p>O CPC 28 determina que se baixe a propriedade para investimento quando da aliena\u00e7\u00e3o ou quando da sua retirada permanentemente de uso.<\/p>\n\n\n\n<p>Al\u00e9m disso, ressalta-se que referido CPC considera aliena\u00e7\u00e3o tanto a venda do bem quanto a celebra\u00e7\u00e3o de arrendamento financeiro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-conclusao\">7. Conclus\u00e3o<\/h2>\n\n\n\n<p>Utiliza-se bastante o subgrupo propriedade para investimento na pr\u00e1tica cont\u00e1bil, o que justifica, portanto, a sua cobran\u00e7a constante nos principais certames da \u00e1rea fiscal.<\/p>\n\n\n\n<p>Em suma, este artigo apresentou a defini\u00e7\u00e3o de propriedade para investimento, trouxe exemplos dados pelo pr\u00f3prio CPC 28 e divulgou as regras gerais de contabiliza\u00e7\u00e3o deste tipo de ativo. <\/p>\n\n\n\n<p>Por fim, para mais detalhes sobre Contabilidade, n\u00e3o deixe de conferir os cursos ofertados pelo ESTRAT\u00c9GIA Concursos, feitos pelos maiores especialistas do assunto.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><span class=\"has-inline-color has-white-color\">Concursos abertos<\/span><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-white-color\">Concursos 2022<\/span><\/a><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1. Introdu\u00e7\u00e3o Aprenda aqui os principais pontos do CPC 28 (propriedade para investimento) (http:\/\/www.cpc.org.br\/CPC\/Documentos-Emitidos\/Pronunciamentos) cobrados nos certames da \u00e1rea fiscal. Primeiramente, ressalta-se que o balan\u00e7o patrimonial \u00e9 composto de contas que visam apresentar de forma fidedigna a situa\u00e7\u00e3o cont\u00e1bil e financeira de uma empresa. Por sua vez, o ativo \u00e9 composto de bens e direitos [&hellip;]<\/p>\n","protected":false},"author":2380,"featured_media":1009708,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1009058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Propriedade para Investimento para a \u00c1rea Fiscal<\/title>\n<meta name=\"description\" content=\"Aprenda aqui os principais pontos do CPC 28 \u2013 Propriedade para Investimento cobrados nos principais certames da \u00e1rea fiscal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Propriedade para Investimento para a \u00c1rea Fiscal\" \/>\n<meta property=\"og:description\" content=\"Aprenda aqui os principais pontos do CPC 28 \u2013 Propriedade para Investimento cobrados nos principais certames da \u00e1rea fiscal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-14T11:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-18T17:17:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Baldasso Robbi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Baldasso Robbi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\"},\"author\":{\"name\":\"Daniel Baldasso Robbi\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4706c9277c329e71d61e70ab89087\"},\"headline\":\"Propriedade para Investimento para a \u00c1rea Fiscal\",\"datePublished\":\"2022-07-14T11:04:00+00:00\",\"dateModified\":\"2022-07-18T17:17:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\"},\"wordCount\":1664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\",\"name\":\"Propriedade para Investimento para a \u00c1rea Fiscal\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg\",\"datePublished\":\"2022-07-14T11:04:00+00:00\",\"dateModified\":\"2022-07-18T17:17:08+00:00\",\"description\":\"Aprenda aqui os principais pontos do CPC 28 \u2013 Propriedade para Investimento cobrados nos principais certames da \u00e1rea fiscal.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg\",\"width\":601,\"height\":241},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriedade para Investimento para a \u00c1rea Fiscal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4706c9277c329e71d61e70ab89087\",\"name\":\"Daniel Baldasso Robbi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7adccfa899d98d59b5ba109a9db74da163673c0afb22bf30f80dc3f8a6ffec72?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7adccfa899d98d59b5ba109a9db74da163673c0afb22bf30f80dc3f8a6ffec72?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7adccfa899d98d59b5ba109a9db74da163673c0afb22bf30f80dc3f8a6ffec72?s=96&d=mm&r=g\",\"caption\":\"Daniel Baldasso Robbi\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/danielrobbi1995gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Propriedade para Investimento para a \u00c1rea Fiscal","description":"Aprenda aqui os principais pontos do CPC 28 \u2013 Propriedade para Investimento cobrados nos principais certames da \u00e1rea fiscal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/","og_locale":"pt_BR","og_type":"article","og_title":"Propriedade para Investimento para a \u00c1rea Fiscal","og_description":"Aprenda aqui os principais pontos do CPC 28 \u2013 Propriedade para Investimento cobrados nos principais certames da \u00e1rea fiscal.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2022-07-14T11:04:00+00:00","article_modified_time":"2022-07-18T17:17:08+00:00","og_image":[{"width":601,"height":241,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg","type":"image\/jpeg"}],"author":"Daniel Baldasso Robbi","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Daniel Baldasso Robbi","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/"},"author":{"name":"Daniel Baldasso Robbi","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4706c9277c329e71d61e70ab89087"},"headline":"Propriedade para Investimento para a \u00c1rea Fiscal","datePublished":"2022-07-14T11:04:00+00:00","dateModified":"2022-07-18T17:17:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/"},"wordCount":1664,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/","name":"Propriedade para Investimento para a \u00c1rea Fiscal","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg","datePublished":"2022-07-14T11:04:00+00:00","dateModified":"2022-07-18T17:17:08+00:00","description":"Aprenda aqui os principais pontos do CPC 28 \u2013 Propriedade para Investimento cobrados nos principais certames da \u00e1rea fiscal.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/14155111\/propriedade-para-investimento.jpg","width":601,"height":241},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/propriedade-para-investimento-para-a-area-fiscal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Propriedade para Investimento para a \u00c1rea Fiscal"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/86e4706c9277c329e71d61e70ab89087","name":"Daniel Baldasso Robbi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7adccfa899d98d59b5ba109a9db74da163673c0afb22bf30f80dc3f8a6ffec72?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7adccfa899d98d59b5ba109a9db74da163673c0afb22bf30f80dc3f8a6ffec72?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7adccfa899d98d59b5ba109a9db74da163673c0afb22bf30f80dc3f8a6ffec72?s=96&d=mm&r=g","caption":"Daniel Baldasso Robbi"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/danielrobbi1995gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1009058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2380"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1009058"}],"version-history":[{"count":58,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1009058\/revisions"}],"predecessor-version":[{"id":1062863,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1009058\/revisions\/1062863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1009708"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1009058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1009058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1009058"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1009058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}