{"id":946063,"date":"2022-01-14T11:17:58","date_gmt":"2022-01-14T14:17:58","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=946063"},"modified":"2022-01-14T11:18:00","modified_gmt":"2022-01-14T14:18:00","slug":"entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/","title":{"rendered":"ENTREVISTA: Gustavo Rocha &#8211; Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/12190659\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg\" alt=\"\" class=\"wp-image-946080\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/12190659\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg 225w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/12190659\/whatsapp-image-2022-01-12-at-16-49-43-1-768x1024.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/12190659\/whatsapp-image-2022-01-12-at-16-49-43-1-610x813.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/12190659\/whatsapp-image-2022-01-12-at-16-49-43-1.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;A estrat\u00e9gia que adotei pra manter o foco nas disciplinas foi adotar metas semanais que eram feitas por mim todo domingo, ap\u00f3s o simulado, quando identificava os erros que precisava trabalhar. Foi assim que aos poucos fui melhorando as notas.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para  cargo de Agente Penitenci\u00e1rio:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam te conhecer melhor. Voc\u00ea \u00e9 formado em que \u00e1rea? Qual sua idade? De onde voc\u00ea \u00e9?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Gustavo Rocha: <\/strong>Estou concluindo o meu curso na \u00e1rea administrativa, processos ger\u00eancias, tenho 24 anos e sou de Arapiraca (AL).<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos? Por que a \u00e1rea Policial?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Um policial militar da Bahia que eu acabei conhecendo me perguntou por que eu n\u00e3o estudava para concurso para ser policial. Isso entrou na minha cabe\u00e7a e como ainda estava concluindo o ensino m\u00e9dio comecei aos poucos, mas efetivamente comecei em 2017, tr\u00eas meses ap\u00f3s a essa pergunta .<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Durante sua caminhada como concurseiro, voc\u00ea trabalhava e estudava ou se dedicava inteiramente aos estudos para concurso?\u00a0<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Sim, por n\u00e3o ser privilegiado socialmente e filho de uma empregada dom\u00e9stica e um motot\u00e1xi. Comecei a estudar ainda no tempo de escola durante o ensino m\u00e9dio, quando comecei nos concurso tive dificuldades por quest\u00e3o de hor\u00e1rio pra estudar. Trabalhei como porteiro, vigia noturno e vendi produtos de porta em porta com meu pai. Me lembro que em um dia eu patrulhava como vigia e carregava uma apostila do concurso da Policia Militar na parte interna da roupa, como n\u00e3o podia estudar abertamente eu entrava no banheiro para ler o material .<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quantos e em quais concursos j\u00e1 foi aprovado? Pretende seguir estudando ou \u201caposentou\u201d?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>N\u00e3o obtive muitos resultados satisfat\u00f3rios, fiz as provas do DEPEN acabei aprovado na objetiva, mas na discursiva reprovei por 1,1 pontos, ent\u00e3o efetivamente s\u00f3 fui aprovado no concurso da Policia Penal de Alagoas, mas pretendo continuar estudando para o cargo de Agente da Policia Federal.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? <\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Meu conv\u00edvio social n\u00e3o \u00e9 muito ativo, pois por n\u00e3o utilizar bebidas alco\u00f3licas e por n\u00e3o saber dan\u00e7ar, n\u00e3o tive muita op\u00e7\u00e3o. J\u00e1 as redes sociais eu uso, mas n\u00e3o de corriqueira. J\u00e1 passei 4 meses sem utilizar o Instagram e Facebook para poder focar nos estudos. Sou um rapaz de poucos amigos, posso contar nos dedos .<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia entendeu e apoiou sua caminhada como concurseiro? Se sim, de que forma? \u00a0<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Estou namorando e tenho uma filha. Moro com meus pais, minha fam\u00edlia n\u00e3o tem muito a cultura acad\u00eamica e por isso achavam que n\u00e3o iria dar em nada, por\u00e9m hoje estou contando minha hist\u00f3ria. J\u00e1 minha namorada \u00e9 o oposto, ela acreditava no meu potencial mais que eu mesmo e sempre me ajudou muito e minha filha que tem 3 anos \u00e9 uma importante motiva\u00e7\u00e3o, v\u00e1rias vezes enquanto eu estudava ela assistia desenho animado no celular.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao concurso que foi aprovado? Qual foi o segredo de manter a disciplina durante todo o per\u00edodo?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Para o concurso da Penal de Alagoas estudei 2 meses e alguns dias, pois comecei ap\u00f3s a prova da Policia Civil de Alagoas. A estrat\u00e9gia que adotei para manter o foco nas disciplinas foi adotar metas semanais que eram feitas por mim todo domingo, ap\u00f3s o simulado, quando identificava os erros que precisava trabalhar. Foi assim que aos poucos fui melhorando as notas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Que materiais voc\u00ea usou em sua prepara\u00e7\u00e3o para o concurso? Quais foram as principais vantagens e desvantagens de cada um?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Ap\u00f3s passar muito tempo procurando os mat\u00e9rias na internet e com dificuldades, eu adquirir uma assinatura b\u00e1sica do Estrat\u00e9gia Concursos que me ajudou bastante. Inicialmente, ainda distante da prova, eu utilizava o PDF simplificado que \u00e9 mais detalhado, j\u00e1 as v\u00eddeos aulas n\u00e3o utilizei muito, mas quando usava era em conte\u00fado que n\u00e3o tinha muita afinidade. E do meio para o final passei a reler diversas vezes os mapas mentais e resumos para ser mais efetivo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Conheci o Estrat\u00e9gia ainda no ano de 2018, por meio de aulas gratuitas no YouTube.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Antes de conhecer o Estrat\u00e9gia estudei por outro cursinho que algumas vezes n\u00e3o me satisfazia por quest\u00f5es de foco, conversas n\u00e3o relacionadas ao conte\u00fado, material com pouco informa\u00e7\u00e3o, did\u00e1tica que muitas vezes n\u00e3o funcionava e outras vezes falta de comprometimento com o aluno.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O concurseiro j\u00e1 se dedica tanto hoje para ser aprovado e investe bastante! Imagine chegar na prova e ver quest\u00f5es que abordam assuntos que o professor nem abordou nas videoaulas ou no material em PDF. Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Antes de ser aluno Estrat\u00e9gia\u00a0adquiri outros cursos e tive gastos desnecess\u00e1rios que n\u00e3o tiveram retorno, pois n\u00e3o consegui ser aprovado e tamb\u00e9m n\u00e3o tinha bons resultados. V\u00e1rias vezes fui reprovado por 1 ou 2 pontos e por perder quest\u00f5es as quais deveriam ter visto nos mat\u00e9rias que comprei.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? <\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Ap\u00f3s ter acesso a plataforma do Estrat\u00e9gia conheci ferramentas como o PDF dos aprovados, que exp\u00f5e a an\u00e1lise e as observa\u00e7\u00f5es de pessoas que j\u00e1 estiveram no meu lugar, quest\u00f5es in\u00e9ditas comentadas pelos professores e tudo isso me ajudou a elevar o n\u00edvel de estudo .<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos? Quantas horas l\u00edquidas estudava por dia?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Durante a prepara\u00e7\u00e3o n\u00e3o fazia uso de meios como cronometragem de horas de estudo, mas sim de metas semanais que acabavam me dando mais liberdade enquanto j\u00e1 estava com dever cumprido.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia revis\u00f5es? Costumava fazer resumos, simulados ou algo mais?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Minhas revis\u00f5es eram com leituras das partes que eu recortava das mat\u00e9rias que achava interessante e com chance de cair na prova. Tamb\u00e9m sempre guardei as quest\u00f5es que eu errava nos simulados para n\u00e3o repetir os erros e criava muitas quest\u00f5es das leis junto com amigos de um grupo espec\u00edficos o qual j\u00e1 teve muitos aprovados.<\/p>\n\n\n\n<p><strong> Estrat\u00e9gia: Voc\u00ea tinha mais dificuldades em alguma disciplina? Como voc\u00ea fez para superar estas dificuldades?\u00a0<\/strong> <\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Minhas dificuldades eram nas disciplinas de RLM , Direito Penal, \u00c9tica, mas ap\u00f3s come\u00e7ar a estud\u00e1-las corriqueiramente obtive mais facilidade chegando a gabaritar RLM, \u00c9tica na prova da Pol\u00edcia Penal.<\/p>\n\n\n\n<p><strong><\/strong><strong>Estrat\u00e9gia: A reta final \u00e9 sempre um per\u00edodo estressante. Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Um dia antes da prova resolvi meu ultimo simulado do ciclo.\u00a0Fiz algumas anota\u00e7\u00f5es e fui bem, 104 pontos uma semana antes passei a reler meu materiais de resumo e resolver quest\u00f5es que eu tinha feito para retomar o racioc\u00ednio.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como est\u00e1 sendo sua prepara\u00e7\u00e3o para o TAF e para as demais etapas?\u00a0<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>A prepara\u00e7\u00e3o para o TAF est\u00e1 sendo intensa com nata\u00e7\u00e3o, corrida sob o sol, tudo que tem direito.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Se voc\u00ea tivesse que apontar ERROS em sua prepara\u00e7\u00e3o, quais seriam? Diga-nos tamb\u00e9m quais foram os maiores ACERTOS?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Entre os maiores erros na minha prepara\u00e7\u00e3o foi achar que sabia muito quando na verdade ainda estava no in\u00edcio de uma jornada. Ter tomado decis\u00f5es como comprar materiais sem qualidade tamb\u00e9m foi um erro. Por outro lado, os acertos foram acreditar o m\u00e1ximo poss\u00edvel que o que eu queria era poss\u00edvel e fazer investimentos na minha educa\u00e7\u00e3o, como no curso Estrat\u00e9gia e em uma gradua\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Por incr\u00edvel\u00a0que pare\u00e7a a minha f\u00e9 na vit\u00f3ria sempre foi inabal\u00e1vel, eu passei por muitos momentos ruins, como desemprego, dificuldades sentimentais, mas sempre acreditei que em um dia eu iria achar o que eu sempre procurei. Parece fanatismo, mas \u00e9 verdade, conheci pessoas que desistiram, pessoas que querem desistir e fico triste por isso, pois \u00e9 muito gratificante ler seu nome no di\u00e1rio oficial e ver que realmente voc\u00ea estava l\u00facido quando come\u00e7ou e que o seu sonho n\u00e3o era apenas um del\u00edrio qualquer.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso. Deixe-nos sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Gustavo: <\/strong>Ap\u00f3s anos nessa jornada, o que poderia falar pra voc\u00ea que est\u00e1 iniciando ou j\u00e1 \u00e9 do meio dos concursos \u00e9: acredite em voc\u00ea, n\u00e3o importa o quanto \u00e9 ou ser\u00e1 \u00e1rdua a sua caminhada, apenas caminhe, seja humilde para reconhecer seus erros, pois assim os acertos sorrir\u00e3o para voc\u00ea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;A estrat\u00e9gia que adotei pra manter o foco nas disciplinas foi adotar metas semanais que eram feitas por mim todo domingo, ap\u00f3s o simulado, quando identificava os erros que precisava trabalhar. Foi assim que aos poucos fui melhorando as notas.&#8221; Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-946063","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Gustavo Rocha - Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para cargo de Agente Penitenci\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Gustavo Rocha - Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para cargo de Agente Penitenci\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-14T14:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/\",\"name\":\"ENTREVISTA: Gustavo Rocha - Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg\",\"datePublished\":\"2022-01-14T14:17:58+00:00\",\"dateModified\":\"2022-01-14T14:18:00+00:00\",\"description\":\"Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para cargo de Agente Penitenci\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#primaryimage\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg\",\"contentUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Gustavo Rocha &#8211; Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Gustavo Rocha - Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio","description":"Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para cargo de Agente Penitenci\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Gustavo Rocha - Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio","og_description":"Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para cargo de Agente Penitenci\u00e1rio.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2022-01-14T14:18:00+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/","name":"ENTREVISTA: Gustavo Rocha - Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg","datePublished":"2022-01-14T14:17:58+00:00","dateModified":"2022-01-14T14:18:00+00:00","description":"Confira nossa entrevista com Gustavo Rocha, aprovado em 2\u00b0 lugar no concurso PP AL para cargo de Agente Penitenci\u00e1rio.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#primaryimage","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg","contentUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/01\/whatsapp-image-2022-01-12-at-16-49-43-1-225x300.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-gustavo-rocha-aprovado-em-2-lugar-no-concurso-pp-al-para-o-cargo-de-agente-penitenciario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Gustavo Rocha &#8211; Aprovado em 2\u00b0 lugar no concurso PP AL para o cargo de Agente Penitenci\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/946063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/946063\/revisions"}],"predecessor-version":[{"id":947356,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/946063\/revisions\/947356"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=946063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}