{"id":928661,"date":"2021-12-16T09:56:44","date_gmt":"2021-12-16T12:56:44","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=928661"},"modified":"2023-01-03T15:30:18","modified_gmt":"2023-01-03T18:30:18","slug":"concurso-pm-ce-aprovada-maria-nogueira","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/","title":{"rendered":"ENTREVISTA: Maria Alexsandra Nogueira &#8211; Aprovada no concurso PM CE"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2-213x300.jpg\" alt=\"\" class=\"wp-image-928662\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2-213x300.jpg 213w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2-726x1024.jpg 726w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2-768x1083.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2-1089x1536.jpg 1089w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2-610x861.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2.jpg 1361w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>\u201cO h\u00e1bito \u00e9 mais importante que a motiva\u00e7\u00e3o, assista depoimentos dos aprovados no canal do Estrat\u00e9gia, resolva quest\u00f5es sempre antes, durante e depois da teoria, para ter um norte, aproveite qualquer brecha de tempo, de pouquinho em pouquinho o pouco se torna muito\u201d<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam te conhecer melhor. Voc\u00ea \u00e9 formada em que \u00e1rea? Qual sua idade? De onde voc\u00ea \u00e9?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra Nogueira: <\/strong>Meu nome \u00e9 Maria Alexsandra, 29 anos, sou de Fortaleza-CE. Sou m\u00e3e de dois meninos, um de 9 e o outro de 7 anos de idade, casada h\u00e1 11 anos. Rec\u00e9m-formada na gradua\u00e7\u00e3o de gest\u00e3o de Recursos Humanos.&nbsp;<\/p>\n\n\n\n<p>Estudo para concursos h\u00e1 4 anos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos? Por que a \u00e1rea Policial?<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Ver meu esposo concursado pela segunda vez, ambas na \u00e1rea de seguran\u00e7a p\u00fablica, me motivou a querer isso para minha vida. Eu n\u00e3o me vejo em outra \u00e1rea que n\u00e3o seja a da seguran\u00e7a p\u00fablica.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Durante sua caminhada como concurseira, voc\u00ea trabalhava e estudava (como conciliava trabalho e estudos?), ou se dedicava inteiramente aos estudos para concurso?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Por ter duas crian\u00e7as e pouqu\u00edssimo apoio familiar eu me dediquei \u00e0 vida dom\u00e9stica em tempo integral, o que tornou o per\u00edodo de estudo desafiador e estressante, pois \u00e9 dif\u00edcil para uma crian\u00e7a conter seus momentos de querer extravasar. Fora as obriga\u00e7\u00f5es dom\u00e9sticas que eu n\u00e3o tinha como me abster. Mas nenhum obst\u00e1culo ou desafio me fez desistir. <\/p>\n\n\n\n<p>Durante o dia eu aproveitava qualquer brecha de tempo para resolver quest\u00f5es ou revisar. O per\u00edodo de estudo mesmo valendo era \u00e0 tarde, enquanto meu filho mais velho estava no col\u00e9gio e o mais novo dormia ou assistia seus desenhos, e no restinho da madrugada entre 3 \u00e0s 6 da manh\u00e3. Sempre aproveitava os momentos que estava lavando a lou\u00e7a para assistir \u00e0s videoaulas, principalmente as aulas gratuitas do Estrat\u00e9gia no youtube.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quantos e em quais concursos j\u00e1 foi aprovada? Qual o \u00faltimo? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende seguir estudando ou \u201caposentou\u201d?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Essa foi a minha primeira aprova\u00e7\u00e3o, gra\u00e7as ao Estrat\u00e9gia e \u00e0 monitoria feita pelo professor Bruno Bezerra.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos, fam\u00edlia, etc? Ou adotou uma postura radical, abdicando do conv\u00edvio social?<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Criei uma rede social com perfil de concurseiro, s\u00f3 para acompanhar os professores. Evitava sair sim, pois eu sempre achei que minhas horas de estudo eram pouco tempo e de baixa qualidade, por causa de interfer\u00eancias e cansa\u00e7o. Ent\u00e3o preferia ficar em casa e aproveitar qualquer brecha de tempo para estudar. Meu esposo aproveitava as f\u00e9rias do trabalho para assumir os afazeres de casa e filhos para que eu tivesse mais tempo para estudar, por conta disso o lazer era coisa rara por aqui. Geralmente opt\u00e1vamos em ter lazer quando o n\u00edvel de estresse estava elevado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casada? Tem filhos? Namora? Mora com seus pais? Sua fam\u00edlia entendeu e apoiou sua caminhada como concurseira? Se sim, de que forma? &nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Casada, dois filhos (9 e 7 anos), um cachorro. Temos nosso cantinho, a peteca \u00e9 s\u00f3 entre eu e meu esposo, n\u00e3o temos apoio familiar , apesar de morarmos perto de nossas fam\u00edlias.&nbsp;Meu esposo sempre me apoiou a estudar para concurso. Minha fam\u00edlia a princ\u00edpio achou loucura, pois achava que eu n\u00e3o daria conta de estudar e cuidar de duas crian\u00e7as, mas com um tempo comecei a ganhar apoio e admira\u00e7\u00e3o deles, porque mesmo sendo dif\u00edcil eu estava indo \u00e0 luta em vez de arranjar desculpas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao concurso que foi aprovada? Qual foi o segredo de manter a disciplina durante todo o per\u00edodo?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Dois meses, por\u00e9m eu j\u00e1 vinha com uma bagagem de outros concursos anteriores (Guarda municipal do Eus\u00e9bio, DEPEN , PC CE , CFO CE \u2013 que ainda n\u00e3o teve). O segredo da minha disciplina foi querer vencer na vida e o h\u00e1bito, eu n\u00e3o aguentava mais a vida que eu estava levando de dona de casa e dependente financeiramente do marido. Eu queria vencer a qualquer custo, nem que isso me custasse noites sem dormir ou perder a paz implorando por sil\u00eancio para conseguir estudar, cheguei a chorar v\u00e1rias vezes para os meus filhos , implorando para que eles ficassem quietos para que eu conseguisse estudar.&nbsp;<\/p>\n\n\n\n<p>EU QUERIA ISSO A QUALQUER CUSTO, esse foi o meu segredo para manter a disciplina. NADA E NEM NINGU\u00c9M IRIA ME PARAR.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Que materiais voc\u00ea usou em sua prepara\u00e7\u00e3o para o concurso? Aulas presenciais, telepresenciais, livros, cursos em PDF, videoaulas? Quais foram as principais vantagens e desvantagens de cada um?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>PDF e V\u00eddeo aula do Estrat\u00e9gia e site de quest\u00f5es.<\/p>\n\n\n\n<p>Amei os pdfs do Estrat\u00e9gia, sentia que a mat\u00e9ria fixava melhor e era um estudo mais r\u00e1pido. As aulas em v\u00eddeo eu costumava assistir depois de ler o pdf e quando estava dirigindo ou arrumando a casa.&nbsp;<\/p>\n\n\n\n<p>A princ\u00edpio n\u00e3o vejo nenhuma desvantagem.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Nas aulas gratuitas do youtube, fui me fascinando pela did\u00e1tica dos professores at\u00e9 que comprei o curso.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Sim, uns 4 cursinhos , incomodava o fato de ter aulas reaproveitadas e antigas, alguns professores n\u00e3o tinha maturidade para lidar com certos assuntos e ficava perdendo muito tempo com piadas bestas em vez de ir direto ao assunto , brincar com o assunto para ajudar a memorizar \u00e9 uma coisa , ficar de piada que n\u00e3o agrega em nada \u00e9 perda de tempo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou em nosso material? (Pode citar uma ou mais ferramentas que mais te ajudaram na prepara\u00e7\u00e3o).<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>A diferen\u00e7a foi t\u00e3o relevante que fui aprovada, a mentoria do professor Bruno Bezerra foi uma ajuda que nem tenho palavras para agradecer. O material em PDF tamb\u00e9m foi uma excelente ferramenta.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos? Estudava v\u00e1rias mat\u00e9rias ao mesmo tempo? Quantas? Quantas horas l\u00edquidas estudava por dia?<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Plano de estudo sempre foi algo que eu tinha dificuldade de montar, e o Estrat\u00e9gia fez isso por mim e me ajudou significativamente. O pacote que adquiri foi o que tinha a trilha estrat\u00e9gica e monitoria, foi o que me salvou! Horas de estudo, eu nunca contabilizei para evitar frustra\u00e7\u00e3o, pois durante o dia eu era constantemente interrompida pelos filhos, e na madrugada \u00e0s vezes eu dormia por cima do material, ent\u00e3o nunca deu muito certo contabilizar .. rs.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia revis\u00f5es? Costumava fazer resumos, simulados ou algo mais?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Minhas revis\u00f5es eram feitas atrav\u00e9s de quest\u00f5es e grifos do pdf e os mapas mentais do Estrat\u00e9gia.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>A resolu\u00e7\u00e3o de exerc\u00edcios \u00e9 extremamente importante n\u00e3o s\u00f3 para revisar e massificar o conte\u00fado, como tamb\u00e9m conhecer a banca e suas pegadinhas. Para esse concurso no qual fui aprovada, creio que fiz no m\u00ednimo 5 mil quest\u00f5es, al\u00e9m do site de quest\u00f5es eu sempre imprimia as quest\u00f5es das aulas gratuitas do youtube para resolver, fora as quest\u00f5es dos PDFs.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea tinha mais dificuldades em alguma(s) disciplina(s)? Quais? Como voc\u00ea fez para superar estas dificuldades?&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Sim, portugu\u00eas e matem\u00e1tica. Portugu\u00eas comprei um curso da professora Adriana Figueiredo e estudei muito, matem\u00e1tica n\u00e3o consegui sanar minha dificuldade por falta de dedica\u00e7\u00e3o. <strong>&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: A reta final \u00e9 sempre um per\u00edodo estressante. Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Estudava o dia inteiro, n\u00e3o cuidava da casa e nem dos filhos, era cada um por si, s\u00f3 fazia a comida e colocava para eles comerem. Meu esposo ajudava com a casa sempre que dava, foi um caos ..kkk. No dia anterior \u00e0 prova eu descansei e apenas revisei os mapas mentais.&nbsp; Pr\u00e9-prova foi a sensa\u00e7\u00e3o de dever cumprido e consci\u00eancia tranquila por ter dado o meu melhor e o meu m\u00e1ximo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi (ou est\u00e1 sendo) sua prepara\u00e7\u00e3o para o TAF e para as demais etapas?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Comecei a me preparar para o TAF um m\u00eas antes da prova. A princ\u00edpio para aliviar a tens\u00e3o e o estresse, agora o treino est\u00e1 mais intenso.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Se voc\u00ea tivesse que apontar ERROS em sua prepara\u00e7\u00e3o (se \u00e9 que houve), quais seriam? Diga-nos tamb\u00e9m quais foram os maiores ACERTOS? <\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>O treino ajudou muito a aliviar a tens\u00e3o e o estresse, deveria ter come\u00e7ado h\u00e1 mais tempo. Meu maior acerto foi ter investido no curso do Estrat\u00e9gia. Outro erro foi n\u00e3o ter enfrentado meu medo da matem\u00e1tica.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>Quando meus filhos n\u00e3o colaboravam, me dava vontade de desistir, pois a sensa\u00e7\u00e3o \u00e9 de remar contra a mar\u00e9. Mas eu n\u00e3o tinha essa op\u00e7\u00e3o de desistir, eu n\u00e3o podia desistir, afinal eu tenho que dar exemplo para os meus filhos. E apesar de n\u00e3o terem ajudado muito, contendo a energia deles, eles sabiam o motivo de estudar tanto. Eles, mais do que eu, esperavam um resultado positivo, sempre que eu fazia uma prova meu filhos me indagavam se eu havia passado na prova. Eles perguntavam quando eu ia conseguir passar na prova e esperavam esse resultado ansiosamente. EU N\u00c3O PODIA DESISTIR!<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso. Deixe-nos sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Maria Alexsandra: <\/strong>O h\u00e1bito \u00e9 mais importante que a motiva\u00e7\u00e3o, assista depoimentos dos aprovados no canal do Estrat\u00e9gia, resolva quest\u00f5es sempre antes, durante e depois da teoria, para ter um norte, aproveite qualquer brecha de tempo, de pouquinho em pouquinho o pouco se torna muito. Os obst\u00e1culos v\u00eam para nos deixar mais fortes, para quem tem sua religi\u00e3o e cr\u00ea em DEUS, se apegue a ele e assim conseguir\u00e1 perseverar mesmo diante de dificuldades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO h\u00e1bito \u00e9 mais importante que a motiva\u00e7\u00e3o, assista depoimentos dos aprovados no canal do Estrat\u00e9gia, resolva quest\u00f5es sempre antes, durante e depois da teoria, para ter um norte, aproveite qualquer brecha de tempo, de pouquinho em pouquinho o pouco se torna muito\u201d Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-928661","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Maria Alexsandra Nogueira - Aprovada no concurso PM CE<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Maria Alexsandra Nogueira - Aprovada no concurso PM CE\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-03T18:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/12\/img_5402_2-213x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/\",\"name\":\"ENTREVISTA: Maria Alexsandra Nogueira - Aprovada no concurso PM CE\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/12\/img_5402_2-213x300.jpg\",\"datePublished\":\"2021-12-16T12:56:44+00:00\",\"dateModified\":\"2023-01-03T18:30:18+00:00\",\"description\":\"Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2.jpg\",\"width\":1361,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Maria Alexsandra Nogueira &#8211; Aprovada no concurso PM CE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Maria Alexsandra Nogueira - Aprovada no concurso PM CE","description":"Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Maria Alexsandra Nogueira - Aprovada no concurso PM CE","og_description":"Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-01-03T18:30:18+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/12\/img_5402_2-213x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/","name":"ENTREVISTA: Maria Alexsandra Nogueira - Aprovada no concurso PM CE","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2021\/12\/img_5402_2-213x300.jpg","datePublished":"2021-12-16T12:56:44+00:00","dateModified":"2023-01-03T18:30:18+00:00","description":"Confira nossa entrevista com Maria Alexsandra Nogueira, aprovada no concurso PM CE para o cargo de Soldado.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13200412\/img_5402_2.jpg","width":1361,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ce-aprovada-maria-nogueira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Maria Alexsandra Nogueira &#8211; Aprovada no concurso PM CE"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/928661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/928661\/revisions"}],"predecessor-version":[{"id":1146701,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/928661\/revisions\/1146701"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=928661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}