{"id":858435,"date":"2021-09-29T11:05:08","date_gmt":"2021-09-29T14:05:08","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=858435"},"modified":"2021-09-29T00:10:06","modified_gmt":"2021-09-29T03:10:06","slug":"entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/","title":{"rendered":"ENTREVISTA: Luis Fernando Acassio de Oliveira &#8211; Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: center;\"><strong>&#8220;O dif\u00edcil foi ter que abrir m\u00e3o de advogar durante esse per\u00edodo, mas n\u00e3o pensei em desistir em momento algum.&#8221;<\/strong><\/p>\n<\/blockquote>\n<p>Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial:<\/p>\n<p><strong>Estrat\u00e9gia Concursos:<\/strong> <strong>Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam te conhecer melhor. Voc\u00ea \u00e9 formado em que \u00e1rea?\u00a0Qual sua idade?\u00a0De onde voc\u00ea \u00e9?<\/strong><\/p>\n<p><strong>Luis Fernando de Oliveira:<\/strong> Sou formado em Direito; tenho 27 anos; sou natural de S\u00e3o Geraldo do Araguaia\/PA.<\/p>\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Oportunidade de seguir uma \u00f3tima carreira e ter estabilidade.<\/p>\n<p><strong>Estrat\u00e9gia: Por que a \u00e1rea Policial?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Admira\u00e7\u00e3o pela atua\u00e7\u00e3o, prerrogativas e deveres inerentes do cargo.<\/p>\n<p><strong>Estrat\u00e9gia: Durante sua caminhada como concurseiro, voc\u00ea trabalhava e estudava (como<\/strong> <strong>conciliava trabalho e estudos?), ou se dedicava inteiramente aos estudos para concurso?<\/strong><\/p>\n<p><strong>Luis Fernando:<\/strong>\u00a0Dediquei inteiramente por tr\u00eas meses, entre dezembro, janeiro e fevereiro.<\/p>\n<p><strong>Estrat\u00e9gia: Quantos e em quais concursos j\u00e1 foi aprovado? Qual o \u00faltimo? Em qual cargo e em que coloca\u00e7\u00e3o?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Este foi o primeiro.<\/p>\n<p><strong>Estrat\u00e9gia: Qual foi sua sensa\u00e7\u00e3o ao ver seu nome na lista dos aprovados\/classificados na primeira fase do certame?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Felicidade, gratid\u00e3o e a sensa\u00e7\u00e3o de dever cumprido.<\/p>\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos, fam\u00edlia, etc? Ou adotou uma postura radical, abdicando do conv\u00edvio social?\u00a0<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Eu conseguia conciliar bem, tinha um curto e suficiente tempo para amigos, namoro e lazer.<\/p>\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casado?\u00a0Tem filhos?\u00a0Namora?\u00a0Mora com seus pais?\u00a0Sua fam\u00edlia entendeu e apoiou sua caminhada como concurseiro?\u00a0Se sim, de que forma?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>N\u00e3o, mas namoro. Minha fam\u00edlia entendeu bastante, garantindo apoio moral e ajuda financeira.<\/p>\n<p><strong>Estrat\u00e9gia: Voc\u00ea acha que vale a pena fazer outros concursos, com foco diferente daquele concurso que \u00e9 realmente seu objetivo maior?\u00a0<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Sim, apesar de n\u00e3o ter feito outros eu acredito que vale sim. Eu me sinto bem realizado com essa aprova\u00e7\u00e3o. Por\u00e9m, as vezes sinto interesse em estudar para Auditor de Receitas Estaduais do Par\u00e1.<\/p>\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao concurso que foi aprovado?\u00a0<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Por tr\u00eas meses.<\/p>\n<p><strong>Estrat\u00e9gia: Chegou a estudar sem ter edital na pra\u00e7a? Durante esse tempo, como voc\u00ea fazia para manter a disciplina nos estudos?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Estudei p\u00f3s-edital, inclusive o mesmo fora lan\u00e7ado em novembro de 2021.<\/p>\n<p><strong>Estrat\u00e9gia: Que materiais voc\u00ea usou em sua prepara\u00e7\u00e3o para o concurso? Aulas presenciais, telepresenciais, livros, cursos em PDF, videoaulas? Quais foram as principais vantagens e desvantagens de cada um?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Cursos em PDF e Videoaulas. As mat\u00e9rias comuns os PDFs foram fundamentais e suficientes para o aprendizado. J\u00e1 as mat\u00e9rias espec\u00edficas as videoaulas complementaram bastante e suficiente para garantir um bom aprendizado.<\/p>\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Nas\u00a0redes sociais.<\/p>\n<p><strong>Estrat\u00e9gia: Uma das principais dificuldades de todo o concursando \u00e9 a quantidade de assuntos que devem ser memorizados. Como voc\u00ea fez para estudar todo o conte\u00fado do concurso?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Primeiramente eu montei um cronograma de todo o conte\u00fado program\u00e1tico do concurso e como eu tinha apenas 3 meses, decidi estudar duas mat\u00e9rias por dia, sempre fazendo de 30 a 50 quest\u00f5es diariamente, algumas na recente plataforma do Estrat\u00e9gia e algumas em uma outra plataforma. Eu apenas realizava a leitura e revis\u00e3o dos cursos. Nunca fui muito bom em fazer resumos, esquemas e anota\u00e7\u00f5es. Eu estudava de 03 a 05 horas por dia. \u00c0s vezes bem mais (risos).<\/p>\n<p><strong>Estrat\u00e9gia: Voc\u00ea tinha mais dificuldades em alguma(s) disciplina(s)? Quais? Como voc\u00ea fez para superar estas dificuldades?<\/strong><\/p>\n<p><strong>Luis Fernando:<\/strong> Em tr\u00eas, Direito Processual Penal Militar, Direito Penal Militar e Legisla\u00e7\u00e3o Institucional da PMPA; Para superar isso eu intensifiquei o estudo delas, que al\u00e9m de complicadas tinham peso 2 na prova objetiva.<\/p>\n<p>Lembro-me de ter feito a leitura di\u00e1ria da lei seca, sendo do C\u00f3digo de Processo Penal Militar e do C\u00f3digo Penal Militar al\u00e9m de toda legisla\u00e7\u00e3o pertinente \u00e0 legisla\u00e7\u00e3o da PMPA.<\/p>\n<p><strong>Estrat\u00e9gia: A reta final \u00e9 sempre um per\u00edodo estressante. Como foi sua rotina de estudos na semana que antecedeu a prova? E v\u00e9spera de prova: foi dia de descanso ou dia de estudo?<\/strong><\/p>\n<p><strong>Luis Fernando:<\/strong>\u00a0A semana foi de pura concentra\u00e7\u00e3o e dedica\u00e7\u00e3o aos estudos. J\u00e1 o dia anterior \u00e0 prova foi de pleno descanso.<\/p>\n<p><strong>Estrat\u00e9gia: No seu concurso, tivemos, al\u00e9m das provas objetivas, as provas discursivas. Como foi seu estudo para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n<p><strong>Luis Fernando:<\/strong>\u00a0Estudei pelo curso em PDF do Estrat\u00e9gia e tive ajuda de um amigo professor para fazer as corre\u00e7\u00f5es. Sobre o conselho, eu sugiro escrever bastante, tipo umas 3 vezes por semana, sempre procurar temas relevantes que tenham liga\u00e7\u00e3o com o cargo almejado.<\/p>\n<p><strong>Estrat\u00e9gia: Como est\u00e1 sendo sua prepara\u00e7\u00e3o para o TAF e para as demais etapas?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Est\u00e1 sendo tranquila. Est\u00e1 tudo conforme o planejado at\u00e9 o momento.<\/p>\n<p><strong>Estrat\u00e9gia: Se voc\u00ea tivesse que apontar ERROS em sua prepara\u00e7\u00e3o (se \u00e9 que houve), quais seriam? Diga-nos tamb\u00e9m quais foram os maiores ACERTOS?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>O maior erro foi n\u00e3o ter come\u00e7ado a estudar bem antes, foi dif\u00edcil lidar com a sobrecarga de conte\u00fado. Nunca mais pretendo estudar assim, acredito que a longo prazo \u00e9 bem melhor. O acerto foi n\u00e3o ter desistido.<\/p>\n<p><strong>Estrat\u00e9gia: O que foi mais dif\u00edcil nessa caminhada rumo \u00e0 aprova\u00e7\u00e3o? Chegou a pensar, por algum momento, em desistir? Se sim, como fez para seguir em frente?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>O dif\u00edcil foi ter que abrir m\u00e3o de advogar durante esse per\u00edodo, mas n\u00e3o pensei em desistir em momento algum.<\/p>\n<p><strong>Estrat\u00e9gia: Qual foi sua principal motiva\u00e7\u00e3o?<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>A busca por estabilidade profissional e financeira.<\/p>\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso. Deixe-nos sua mensagem para todos aqueles que um dia almejam chegar onde voc\u00ea chegou!<\/strong><\/p>\n<p><strong>Luis Fernando: <\/strong>Aconselho a come\u00e7arem o quanto antes e jamais desistir sob nenhum pretexto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O dif\u00edcil foi ter que abrir m\u00e3o de advogar durante esse per\u00edodo, mas n\u00e3o pensei em desistir em momento algum.&#8221; Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam te conhecer [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-858435","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Luis Fernando Acassio de Oliveira - Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso da Pol\u00edcia Militar do Estado do Par\u00e1 para o cargo de Oficial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Luis Fernando Acassio de Oliveira - Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso da Pol\u00edcia Militar do Estado do Par\u00e1 para o cargo de Oficial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/\",\"name\":\"ENTREVISTA: Luis Fernando Acassio de Oliveira - Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2021-09-29T14:05:08+00:00\",\"description\":\"Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso da Pol\u00edcia Militar do Estado do Par\u00e1 para o cargo de Oficial.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Luis Fernando Acassio de Oliveira &#8211; Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Luis Fernando Acassio de Oliveira - Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial","description":"Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso da Pol\u00edcia Militar do Estado do Par\u00e1 para o cargo de Oficial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Luis Fernando Acassio de Oliveira - Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial","og_description":"Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso da Pol\u00edcia Militar do Estado do Par\u00e1 para o cargo de Oficial.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/","og_site_name":"Estrat\u00e9gia Concursos","twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/","name":"ENTREVISTA: Luis Fernando Acassio de Oliveira - Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2021-09-29T14:05:08+00:00","description":"Confira nossa entrevista com Luis Fernando Acassio de Oliveira, aprovado em 45\u00ba lugar no concurso da Pol\u00edcia Militar do Estado do Par\u00e1 para o cargo de Oficial.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-luis-fernando-acassio-de-oliveira-aprovado-em-45o-lugar-no-concurso-pm-pa-para-o-cargo-de-oficial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Luis Fernando Acassio de Oliveira &#8211; Aprovado em 45\u00ba lugar no concurso PM-PA para o cargo de Oficial"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/858435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/858435\/revisions"}],"predecessor-version":[{"id":872924,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/858435\/revisions\/872924"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=858435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}