{"id":1689684,"date":"2025-12-26T14:20:44","date_gmt":"2025-12-26T17:20:44","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1689684"},"modified":"2025-12-26T14:20:46","modified_gmt":"2025-12-26T17:20:46","slug":"aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/","title":{"rendered":"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-225x300.jpg\" alt=\"\" class=\"wp-image-1689881\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-225x300.jpg 225w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-768x1024.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-1152x1536.jpg 1152w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-1536x2048.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-640x853.jpg 640w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-150x200.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption class=\"wp-element-caption\">Georg Augustus Lima<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;Estude. Supere os seus desafios. Fa\u00e7a o que d\u00e1 pra voc\u00ea fazer e seja honesto consigo mesmo (quando der pra fazer mais, fa\u00e7a). N\u00e3o se compare com algu\u00e9m. Passar em concurso \u00e9 voc\u00ea, contra voc\u00ea. N\u00e3o se subestime, voc\u00ea pode muito, todos n\u00f3s podemos. Acredite em voc\u00ea.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira a nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua idade, forma\u00e7\u00e3o e cidade natal?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus Lima:<\/strong> Eu sou tecn\u00f3logo em Seguran\u00e7a P\u00fablica e licenciado em Educa\u00e7\u00e3o f\u00edsica. Tenho 36 anos e sou de Natal-RN.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Conte o in\u00edcio da sua trajet\u00f3ria, o que te levou a iniciar os estudos para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Eu trabalhava embarcado pelo regime de CLT e depois de alguns anos, eu resolvi procurar um emprego que me desse maior estabilidade e que n\u00e3o precisasse viajar muito. Ent\u00e3o, eu resolvi sair do emprego e focar nos concursos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como voc\u00ea conheceu o Estrat\u00e9gia Concursos e porque tomou a decis\u00e3o de se tornar nosso aluno?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Eu iniciei a minha prepara\u00e7\u00e3o para concursos, visando sair da vida embarcado atrav\u00e9s de curso presencial e de apostilas f\u00edsicas. Depois, algumas pessoas me indicaram cursos on-line e sempre me falavam da qualidade do curso do Estrat\u00e9gia. Sendo assim, fui atr\u00e1s do material.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua rotina e plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Eu estudava de 3 a 4 horas l\u00edquidas e praticamente todos os dias eu via as mat\u00e9rias principais daquele edital dando \u00eanfase as mat\u00e9rias que teriam mais quest\u00f5es, mas n\u00e3o esquecendo das que eu n\u00e3o poderia zerar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Nos primeiros concursos que fiz, estudei um pouco ainda trabalhando. Estudava nas horas vagas durante o per\u00edodo no navio e quando estava em casa. Ap\u00f3s alguns meses, pedi para sair do emprego e fiquei apenas estudando. Depois de passar no primeiro e assumir, continuei estudando nos dias de folga, pois comecei a trabalhar por escala.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais ferramentas do Estrat\u00e9gia voc\u00ea mais utilizou em sua prepara\u00e7\u00e3o e quais eram os diferenciais de cada?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Videoaulas, PDF e quest\u00f5es. Muitas quest\u00f5es. Videoulas \u00e9 bom, pois voc\u00ea pode parar, voltar, escrever da forma que entendeu e acompanhar pelo PDF. As quest\u00f5es s\u00e3o \u00f3timas, pois \u00e9 a pr\u00e1tica e quanto mais praticar, melhor voc\u00ea fica.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>No final do ano de 2023, eu decidi focar nos concursos da educa\u00e7\u00e3o e comecei a estudar e fazer os editais que apareciam. Apareceram diversos no ano de 2024 e eu fui fazendo e aprendendo com conte\u00fados diferentes e de diversas bancas. Para o concurso de Mossor\u00f3, foram 4 meses, por\u00e9m, eu j\u00e1 tinha uma \u201cbagagem\u201d boa de outros e isso me ajudou bastante, pois sempre revisava os conte\u00fados. Eu criei uma rotina de estudos e isso fez com que eu j\u00e1 ficasse no \u201cautom\u00e1tico\u201d para ir ao quarto e come\u00e7ar os meus estudos. Gostava de fazer as minhas obriga\u00e7\u00f5es di\u00e1rias relacionados ao estudo logo pela manh\u00e3 para n\u00e3o me distrair depois. Quando a gente come\u00e7a a ver a evolu\u00e7\u00e3o, isso nos anima e nos d\u00e1 for\u00e7a a continuar e esperar com ansiedade a data daquela prova marcada. Esse objetivo em curto e m\u00e9dio prazo de editais que abriram, me ajudaram a estudar e, no geral, a aprender diversas coisas que foram me ajudando nas provas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Talvez Portugu\u00eas tenha sido o mais desafiador, pois pode mudar muito de uma banca para outra. Por\u00e9m, eu iniciava de forma tranquila quando tinha essa mudan\u00e7a repentina (quando fazia um concurso e o pr\u00f3ximo era totalmente diferente), ia estudar focado na banca, procurava entender o seu m\u00e9todo e seu estilo e, assim, eu conseguia evoluir.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual sua estrat\u00e9gia de reta final?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Muitas quest\u00f5es e revis\u00e3o das minhas anota\u00e7\u00f5es, por\u00e9m, no dia anterior eu fui surfar. Estava muito ansioso. Kkkk<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi a sua rotina de estudos para esta importante fase do certame?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>No concurso de Mossor\u00f3, a prova discursiva era sobre um tema espec\u00edfico. Sendo assim, na minha prepara\u00e7\u00e3o das quest\u00f5es espec\u00edficas, eu estudava um pouco mais detalhado atento ao que poderia cair na reda\u00e7\u00e3o. E foi ela que me deixou em primeiro lugar. Fiz algumas reda\u00e7\u00f5es sobre diversos temas antes da prova. Aconselho a n\u00e3o deixar para a \u00faltima hora o estudo de reda\u00e7\u00e3o. \u00c9 bom praticar antes, pegar exemplos do que pode cair. Treinar isso, colocar os seus pensamentos de forma ordenada na folha de reda\u00e7\u00e3o e em tempo h\u00e1bil.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casado? Tem filhos? De que forma sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>N\u00e3o sou casado e nem tenho Filhos. Os meus familiares e amigos me apoiavam. Sempre respeitaram esse momento em que eu queria ficar estudando. Isso foi muito bom.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a sensa\u00e7\u00e3o de ter sido convidado para o Baile dos Primeiros do Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Fiquei muito feliz e fui logo contar para a minha irm\u00e3, cunhado e namorada. Quando chegou o e-mail, fazia poucos dias que eu tinha recebido alta do hospital, onde eu tive que fazer uma cirurgia na clav\u00edcula, por causa de um acidente de moto. Passei 7 dias no hospital aguardando essa cirurgia e receber um convite como esse, pouco depois dessa fase, me deu mais \u00e2nimo, fiquei mais alegre, mudou o meu dia para melhor. Recebi o convite como um chamado para celebrar a vida e minhas conquistas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Durante sua prepara\u00e7\u00e3o, ouviu falar sobre o Baile dos Primeiros? Imaginou que um dia estaria nesta confraterniza\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>Sim, ja tinha ouvido falar sobre o baile, mas nunca imaginei ser convidado. Foi, realmente, uma surpresa muito boa e que vai ficar para sempre na minha mem\u00f3ria, pois n\u00e3o \u00e9 todo dia que o maior curso de prepara\u00e7\u00e3o para concursos entra em contato e te chama para comemorar uma aprova\u00e7\u00e3o. Al\u00e9m disso, estar presente nesse baile, acompanhado de v\u00e1rios aprovados em diversos concursos, mostra a qualidade do material e nos dar a certeza que acreditar na prepara\u00e7\u00e3o para uma prova com os conte\u00fados do Estrat\u00e9gia foi a escolha certa.\u00a0<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>De acerto, foi seguir para as quest\u00f5es desde o in\u00edcio. Sobre erro, foi n\u00e3o ter entrado em mais detalhes em alguns assuntos, sempre \u00e9 bom estudar e ver os detalhes, \u00e0s vezes, n\u00e3o fazemos isso pela quest\u00e3o de tempo, mas pode fazer a diferen\u00e7a l\u00e1 na frente.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? O que voc\u00ea diria para a sua vers\u00e3o de 5 anos atr\u00e1s?<\/strong><\/p>\n\n\n\n<p><strong>Georg Augustus: <\/strong>N\u00e3o. Estava focado. Estava com vontade de ser, tamb\u00e9m, professor de Educa\u00e7\u00e3o F\u00edsica. Eu diria para a minha vers\u00e3o de 5 anos atr\u00e1s que poderia ter dado mais import\u00e2ncia ao estudo, que sempre vai valer a pena o sacrif\u00edcio.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, deixe sua mensagem para todos aqueles que est\u00e3o come\u00e7ando e almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><br \/><strong>Georg Augustus: <\/strong>Estude. Supere os seus desafios. Fa\u00e7a o que d\u00e1 pra voc\u00ea fazer e seja honesto consigo mesmo (quando der pra fazer mais, fa\u00e7a). N\u00e3o se compare com algu\u00e9m. Passar em concurso \u00e9 voc\u00ea, contra voc\u00ea. N\u00e3o se subestime, voc\u00ea pode muito, todos n\u00f3s podemos. Acredite em voc\u00ea!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Estude. Supere os seus desafios. Fa\u00e7a o que d\u00e1 pra voc\u00ea fazer e seja honesto consigo mesmo (quando der pra fazer mais, fa\u00e7a). N\u00e3o se compare com algu\u00e9m. Passar em concurso \u00e9 voc\u00ea, contra voc\u00ea. N\u00e3o se subestime, voc\u00ea pode muito, todos n\u00f3s podemos. Acredite em voc\u00ea.&#8221; Confira a nossa entrevista com Georg Augustus Lima, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1689684","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-26T17:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/12\/georg-augustus-225x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/\",\"name\":\"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/12\/georg-augustus-225x300.jpg\",\"datePublished\":\"2025-12-26T17:20:44+00:00\",\"dateModified\":\"2025-12-26T17:20:46+00:00\",\"description\":\"Confira nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima","description":"Confira nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/","og_locale":"pt_BR","og_type":"article","og_title":"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima","og_description":"Confira nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2025-12-26T17:20:46+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/12\/georg-augustus-225x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/","name":"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/12\/georg-augustus-225x300.jpg","datePublished":"2025-12-26T17:20:44+00:00","dateModified":"2025-12-26T17:20:46+00:00","description":"Confira nossa entrevista com Georg Augustus Lima, aprovado em 1\u00ba lugar na SME Mossor\u00f3 para o cargo de Professor de Educa\u00e7\u00e3o F\u00edsica:","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/12\/23101709\/georg-augustus-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovado-em-1o-lugar-no-sme-mossoro-georg-augustus-lima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprovado em 1\u00ba lugar no SME Mossor\u00f3: Georg Augustus Lima"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1689684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1689684\/revisions"}],"predecessor-version":[{"id":1690621,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1689684\/revisions\/1690621"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1689684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}