{"id":1622346,"date":"2025-08-13T11:05:41","date_gmt":"2025-08-13T14:05:41","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1622346"},"modified":"2025-08-13T11:05:43","modified_gmt":"2025-08-13T14:05:43","slug":"aprovada-na-sme-muriae-mg-percilia-rocha","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/","title":{"rendered":"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha-240x300.jpg\" alt=\"\" class=\"wp-image-1622378\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha-240x300.jpg 240w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha-819x1024.jpg 819w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha-768x960.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha-150x188.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha.jpg 1080w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><figcaption class=\"wp-element-caption\">Perc\u00edlia Rocha<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;[&#8230;] Eu n\u00e3o precisei ser a melhor ou a mais inteligente para ser aprovada, eu s\u00f3 precisei dar o melhor de mim! D\u00ea o seu melhor, ainda que ache que isso n\u00e3o seja suficiente!&#8221;<\/strong>.<\/p>\n\n\n\n<p>Confira a nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-la. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia Rocha: <\/strong>Eu tenho forma\u00e7\u00e3o em Direito e Pedagogia. Tenho 37 anos. Minha cidade natal \u00e9 Divino\/MG<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Quando resolvi me aprofundar na \u00e1rea de Educa\u00e7\u00e3o, percebi que as maiores oportunidades vinham atrav\u00e9s de concurso p\u00fablico, por essa raz\u00e3o decidi investir em concurso p\u00fablico.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Sempre conciliei trabalho com estudo. Inicialmente, estudava \u00e0 noite e aos finais de semana. Ap\u00f3s a aprova\u00e7\u00e3o no concurso de Supervisora Pedag\u00f3gica, passei a trabalhar somente meio per\u00edodo e com isso estudava todas manh\u00e3s, das 5:30 \u00e0s 11h e aos finais de semana.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovada? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>J\u00e1 fui aprovada no concurso da Pol\u00edcia Civil de Minas Gerais, no cargo de Analista (pedagogia) ficando em 4\u00ba lugar. J\u00e1 passei em 2\u00ba lugar no cargo de Supervisora Pedag\u00f3gica no Munic\u00edpio de Muria\u00e9\/MG.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Costumava sair aos s\u00e1bados \u00e0 noite e me dedicava \u00e0 fam\u00edlia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseira? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Tive o apoio da fam\u00edlia, Eles sempre me incentivaram.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>J\u00e1 vinha estudando h\u00e1 tr\u00eas anos para concursos. A minha disciplina vinha atrav\u00e9s da minha responsabilidade com a minha vida, em n\u00e3o depender de algu\u00e9m. Procurei sobreviver sozinha para justamente ganhar mais for\u00e7a ao meu prop\u00f3sito.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Estudei com lei seca e material do Estrat\u00e9gia Concursos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Sou cliente h\u00e1 muitos anos do Estrat\u00e9gia Concursos. Comecei quando ainda fazia faculdade de Direito. Comecei fazendo cursos preparat\u00f3rios de concursos de Tribunais.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Cheguei usar de outros cursos, mas n\u00e3o gostava do material escrito.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Sim, mas n\u00e3o fui aprovada.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Na minha prepara\u00e7\u00e3o, o maior diferencial do curso Estrat\u00e9gia \u00e9 o material escrito. As apostilas s\u00e3o muito bem elaboradas, s\u00e3o esquematizadas. O desenrolar da apostila faz com que pare\u00e7a uma aula oral. Ter esse material contribuiu para entender melhor o direcionamento de videoaulas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Quando comecei, estudava duas horas por dia. Depois, comecei fazer quatro ciclos de 40 minutos, com dez minutos de descanso. Aos finais de semana, eu fazia seis ciclos de 40 minutos aos s\u00e1bados e quatro ciclos de 40 minutos aos domingos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Fazia resumos e depois, eu fazia quest\u00f5es. Com a resolu\u00e7\u00e3o das quest\u00f5es, eu fazia anota\u00e7\u00f5es extras no resumo.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Resolu\u00e7\u00e3o de exerc\u00edcios \u00e9 prioridade. Cheguei a uma m\u00e9dia de quinze a trinta quest\u00f5es por dia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Tinha muita dificuldade em Portugu\u00eas. Comecei a estudar do zero, montei um caderno de Portugu\u00eas. Superei o desafio ap\u00f3s completar todo o curso de Portugu\u00eas da professora Adriana Figueiredo, ela transformou a minha vida. Gra\u00e7as a ela, fechei a prova de portugu\u00eas do concurso que fui aprovada.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Na semana da prova, fiz quest\u00f5es e li a legisla\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>O maior erro, foi n\u00e3o acreditar que seria poss\u00edvel e n\u00e3o acreditar em mim mesma. Entre outros erros, ficar muito presa a livros, doutrinas e n\u00e3o fazer quest\u00f5es. O maior acerto, foi acreditar. Entre outros acertos, dar prioridade ao estudo de Portugu\u00eas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Sim, v\u00e1rias vezes. N\u00e3o sei dizer qual foi a minha maior motiva\u00e7\u00e3o, mas aprendi a ser disciplinada. A disciplina me trouxe onde estou.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Perc\u00edlia: <\/strong>Ningu\u00e9m vai seguir o seu caminho a n\u00e3o ser voc\u00ea mesmo! Ningu\u00e9m vai andar com os seus p\u00e9s! Se tem algo que aprendi, \u00e9 que ningu\u00e9m precisa acreditar que seja poss\u00edvel, a n\u00e3o ser voc\u00ea mesmo! Eu precisava que somente \u201cEu\u201d acreditasse e isso foi suficiente! Eu n\u00e3o precisei ser a melhor ou a mais inteligente para ser aprovada, eu s\u00f3 precisei dar o melhor de mim! D\u00ea o seu melhor, ainda que ache que isso n\u00e3o seja suficiente!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;[&#8230;] Eu n\u00e3o precisei ser a melhor ou a mais inteligente para ser aprovada, eu s\u00f3 precisei dar o melhor de mim! D\u00ea o seu melhor, ainda que ache que isso n\u00e3o seja suficiente!&#8221;. Confira a nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar: Estrat\u00e9gia Concursos: Conte-nos um pouco [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1622346","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T14:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/aprovada-sme-muriae-mg-percilia-rocha-240x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/\",\"name\":\"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/aprovada-sme-muriae-mg-percilia-rocha-240x300.jpg\",\"datePublished\":\"2025-08-13T14:05:41+00:00\",\"dateModified\":\"2025-08-13T14:05:43+00:00\",\"description\":\"Confira nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha","description":"Confira nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/","og_locale":"pt_BR","og_type":"article","og_title":"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha","og_description":"Confira nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2025-08-13T14:05:43+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/aprovada-sme-muriae-mg-percilia-rocha-240x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/","name":"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/08\/aprovada-sme-muriae-mg-percilia-rocha-240x300.jpg","datePublished":"2025-08-13T14:05:41+00:00","dateModified":"2025-08-13T14:05:43+00:00","description":"Confira nossa entrevista com Perc\u00edlia Rocha, aprovada em\u00a01\u00b0 lugar\u00a0no concurso\u00a0SME Muria\u00e9\/MG\u00a0para o cargo de\u00a0Inspetor Escolar:","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/08\/12163529\/aprovada-sme-muriae-mg-percilia-rocha.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-sme-muriae-mg-percilia-rocha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprovada na SME Muria\u00e9\/MG: Perc\u00edlia Rocha"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1622346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1622346\/revisions"}],"predecessor-version":[{"id":1622716,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1622346\/revisions\/1622716"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1622346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}