{"id":1609779,"date":"2025-08-31T09:01:22","date_gmt":"2025-08-31T12:01:22","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1609779"},"modified":"2025-08-31T09:01:23","modified_gmt":"2025-08-31T12:01:23","slug":"aprovada-na-dpe-ro-maria-euzilene-carneiro","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/","title":{"rendered":"Aprovada na DPE-RO: Maria Euzilene Carneiro"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro-222x300.jpg\" alt=\"\" class=\"wp-image-1609814\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro-222x300.jpg 222w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro-759x1024.jpg 759w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro-768x1036.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro-1139x1536.jpg 1139w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro-150x202.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro.jpg 1287w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><figcaption class=\"wp-element-caption\">Maria Euzilene Carneiro<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;[&#8230;] ao olhar a lista de aprovados e ver seu nome nela, a sensa\u00e7\u00e3o \u00e9 indescrit\u00edvel, \u00e9 a prova de que cada ren\u00fancia valeu a pena e que, para alcan\u00e7ar esse resultado, tudo dependeu de voc\u00ea, do seu esfor\u00e7o e da sua dedica\u00e7\u00e3o.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)&nbsp;no concurso&nbsp;DPE\/RO&nbsp;para o cargo de&nbsp;T\u00e9cnico Administrativo (Regi\u00e3o VI):<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-la. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene Carneiro: <\/strong>Me chamo Maria Euzilene, tenho 28 anos, sou formada em Ci\u00eancias Cont\u00e1beis pela Faculdade de Rolim de Moura &#8211; FAROL e sou natural de Jaguaretama\/CE. No entanto, quando eu tinha 3 anos, meus pais decidiram se mudar para Rond\u00f4nia. Inicialmente, moramos em Seringueiras\/RO e, aos 19 anos, mudei-me para Rolim de Moura\/RO com o objetivo de cursar a faculdade, onde resido at\u00e9 hoje.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Eu sempre trabalhei no mercado privado (CLT) e as experi\u00eancias nesse setor me trouxeram muitos aprendizados, mas tamb\u00e9m me mostraram, como \u00e9 esse ambiente profissional: inst\u00e1vel, com press\u00e3o constante, metas desafiadoras, poucas garantias de estabilidade e, muitas vezes, pouca valoriza\u00e7\u00e3o, mesmo quando nos dedicamos muito e entregamos bons resultados.<\/p>\n\n\n\n<p><br \/>Desse modo, comecei a perceber que queria algo diferente para a minha vida. Eu desejava estabilidade, seguran\u00e7a financeira e tranquilidade para construir meus planos sem o receio de ser demitida de forma inesperada.<\/p>\n\n\n\n<p><br \/>Foi ent\u00e3o que vi no servi\u00e7o p\u00fablico a oportunidade de ter toda a seguran\u00e7a que eu almejava. Eu n\u00e3o precisaria entregar curr\u00edculos, fazer v\u00e1rias entrevistas, nem lidar com a frustra\u00e7\u00e3o de n\u00e3o ser selecionada para uma vaga. Al\u00e9m disso, no setor privado eu sempre dependeria das decis\u00f5es de outras pessoas para ser contratada, enquanto no servi\u00e7o p\u00fablico eu sabia que, para conquistar um bom emprego, com um bom sal\u00e1rio, dependeria apenas de mim: estudar, me dedicar e alcan\u00e7ar meu objetivo de ser aprovada em um concurso.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>No primeiro per\u00edodo dos meus estudos, final de 2022 at\u00e9 2024, eu conciliava estudo, atividades dom\u00e9sticas e trabalho durante a semana e algumas vezes aos s\u00e1bados. Por\u00e9m, durante 2022 e 2023, eu n\u00e3o estudava com const\u00e2ncia nem tinha foco.&nbsp;<\/p>\n\n\n\n<p>J\u00e1 em 2024, devido a insatisfa\u00e7\u00e3o com o trabalho, decidi me dedicar aos estudos de forma constante e foquei no concurso do TSE unificado. Nesse per\u00edodo, eu estudava antes de ir para o trabalho, pois minha rotina durante o dia era exaustiva e eu sabia que n\u00e3o conseguiria render muito ap\u00f3s o expediente. Eu acordava \u00e0s 3h30 da madrugada para estudar e conseguia fazer cerca de 1h30 a 2h l\u00edquidas, com pequenos intervalos entre os blocos de estudo. Busquei me dedicar ainda mais nos finais de semana, s\u00e1bado e domingo, pois tinha mais tempo para estudar, tentando alcan\u00e7ar cerca de cinco horas l\u00edquidas. Ao final do dia, durante a semana, fazia atividade f\u00edsica (muscula\u00e7\u00e3o) e cuidava das tarefas dom\u00e9sticas. Cabe ressaltar que sempre contei com o suporte do meu esposo, principalmente com as tarefas de casa, o que fez toda a diferen\u00e7a, pois me dava tranquilidade para estudar sem me sobrecarregar com outras demandas.<\/p>\n\n\n\n<p>Contudo, essa rotina foi se tornando muito cansativa e, somada \u00e0 insatisfa\u00e7\u00e3o com o emprego, decidi pedir demiss\u00e3o. Juntamente com meu esposo, passamos a nos organizar financeiramente para que eu pudesse focar nos estudos sem preocupa\u00e7\u00f5es e, em dezembro de 2024, pedi o desligamento da empresa em que trabalhava. Desde ent\u00e3o, tenho me dedicado exclusivamente aos estudos.<\/p>\n\n\n\n<p>No segundo per\u00edodo do meu estudo, em 2025, comecei a estudar em tempo integral, pois j\u00e1 n\u00e3o trabalhava mais, e, logo depois, em fevereiro, saiu o edital da DPE-RO. Durante essa fase, dediquei-me totalmente aos estudos: estudava de segunda a segunda, conseguindo cumprir de 5 a 6 horas l\u00edquidas por dia, conciliando a rotina de estudos com as tarefas dom\u00e9sticas e, ao final do dia, mantinha minha pr\u00e1tica de atividade f\u00edsica.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovada? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Consegui classifica\u00e7\u00e3o nos seguintes concursos:<\/p>\n\n\n\n<p>No ano de 2024:<\/p>\n\n\n\n<p>Prefeitura de S\u00e3o Felipe D\u2019Oeste \u2013 RO<\/p>\n\n\n\n<p>Pregoeiro\/Agente de contrata\u00e7\u00e3o: 121\u00b0 ampla concorr\u00eancia&nbsp;<\/p>\n\n\n\n<p>Controlador Interno: 60\u00b0 ampla concorr\u00eancia&nbsp;<\/p>\n\n\n\n<p>Prefeitura de Cacoal \u2013 RO<\/p>\n\n\n\n<p>Agente Administrativo: 35\u00b0 PCD<\/p>\n\n\n\n<p>Agente de tr\u00e2nsito: 7\u00b0 PCD<\/p>\n\n\n\n<p>TSE Unificado<\/p>\n\n\n\n<p>TJAA: 461\u00b0 &#8211; Ampla concorr\u00eancia&nbsp;<\/p>\n\n\n\n<p>J\u00e1 em 2025, foram os seguintes:&nbsp;<\/p>\n\n\n\n<p>C\u00e2mara Municipal de Rolim de Moura \u2013 RO&nbsp;<\/p>\n\n\n\n<p>Agente Administrativo: 1\u00b0 PCD<\/p>\n\n\n\n<p>Art\u00edfice de Copas: 1\u00b0 PCD<\/p>\n\n\n\n<p>Defensoria Publica de Rond\u00f4nia&nbsp;<\/p>\n\n\n\n<p>T\u00e9cnico administrativo: 1\u00b0 PCD e 3\u00b0 Ampla concorr\u00eancia&nbsp;<\/p>\n\n\n\n<p>Pretendo continuar estudando para um cargo de n\u00edvel superior.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Durante a minha prepara\u00e7\u00e3o busquei manter um equil\u00edbrio entre os estudos e a vida social, com fam\u00edlia e amigos, pois entendia que esses momentos me ajudavam a relaxar e ter um rendimento ainda melhor. Sempre que poss\u00edvel, sa\u00eda com amigos, mas sem exageros: preferia lugares tranquilos e voltava para casa cedo. Eu costumava dormir at\u00e9 as 21h, ent\u00e3o, perto desse hor\u00e1rio, j\u00e1 estava caindo de sono (risos).<\/p>\n\n\n\n<p>No entanto, pr\u00f3ximo \u00e0s provas, especialmente a da DPE, eu procurava ao m\u00e1ximo n\u00e3o sair e aproveitava todo o meu tempo para estudar. A \u00fanica coisa de que realmente \u201cn\u00e3o abri m\u00e3o\u201d durante toda minha prepara\u00e7\u00e3o foi a atividade f\u00edsica, mas abdiquei de muitos momentos com a fam\u00edlia e os amigos. Ainda assim, eu sabia que seria tempor\u00e1rio e que, l\u00e1 na frente, valeria a pena.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseira? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Sempre tive o apoio dos meus familiares e amigos durante toda a minha jornada de estudos. Meu esposo sempre me ajudou com as atividades dom\u00e9sticas e estava disposto a ajudar com o que fosse preciso para que eu n\u00e3o me preocupasse e n\u00e3o perdesse o foco nos estudos. Al\u00e9m disso, quando eu estudava de madrugada, ele sempre acordava comigo para fazer o caf\u00e9.\u00a0<\/p>\n\n\n\n<p><br \/>Meus amigos sempre me deram apoio emocional e acreditavam em mim, muitas vezes, at\u00e9 mais do que eu mesma. Meus sogros e meus pais tamb\u00e9m sempre estiveram ao meu lado, inclusive, em muitas vezes, ajudando a pagar cursinhos e at\u00e9 comprando um computador melhor para que eu pudesse estudar com mais qualidade.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, meu primeiro concurso, em 2015, quando eu tinha apenas 17 anos, foi meu pai quem me inscreveu, e foi justamente o primeiro concurso para servidores da DPE-RO. Infelizmente, naquela \u00e9poca eu n\u00e3o passei, mas em 2025, dez anos depois, eu tive uma segunda chance, e dessa vez eu consegui a t\u00e3o sonhada aprova\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Acredito que todo esse apoio foi fundamental para que eu n\u00e3o pensasse em desistir e sempre me lembrasse de que existem pessoas torcendo por mim e acreditando no meu potencial, ainda mais nessa jornada de concurseiro, que \u00e9 t\u00e3o solit\u00e1ria, eu tive a grande sorte de contar com pessoas maravilhosas ao meu lado, me incentivando e acreditando que eu seria capaz.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Eu comecei a estudar para a DPE-RO em fevereiro de 2025 e a prova foi realizada no dia 1\u00ba de junho de 2025. Portanto, foram cerca de quatro meses me dedicando exclusivamente a esse concurso. Para manter a disciplina durante esse per\u00edodo, busquei pensar de forma positiva: acreditava que iria passar e, caso n\u00e3o passasse, outros concursos viriam e eu s\u00f3 pararia de estudar quando fosse nomeada e tomasse posse.<\/p>\n\n\n\n<p>Por isso, eu tinha um planejamento dos concursos que pretendia fazer e, na segunda-feira seguinte \u00e0 prova, j\u00e1 estava estudando para outro edital. Acredito que pensar assim, e sempre ter outro objetivo \u201cengatilhado\u201d ap\u00f3s cada prova, faz toda a diferen\u00e7a e ajuda a controlar a ansiedade.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, ter o apoio da minha fam\u00edlia e cuidar da minha sa\u00fade f\u00edsica e mental foram fundamentais para manter o foco.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Optei por estudar por PDFs porque achei que renderia mais e me permitiria estudar de forma mais acelerada. Sempre utilizei os PDFs simplificados para a teoria, e para as revis\u00f5es gostava de usar os resumos, as quest\u00f5es e tamb\u00e9m o Passo Estrat\u00e9gico.<\/p>\n\n\n\n<p>Uma das principais vantagens do Passo Estrat\u00e9gico \u00e9 que ele \u00e9 direto ao ponto, al\u00e9m de possuir uma tabela que indica os assuntos mais cobrados pela banca. Isso fez com que eu estudasse exatamente o que iria cair na prova, sem perder tempo com temas irrelevantes. Outra vantagem s\u00e3o as quest\u00f5es ao final de cada PDF, que trazem a tranquilidade de saber que estamos praticando exerc\u00edcios selecionados criteriosamente pelo professor para ajudar a fixar o conte\u00fado estudado.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0s desvantagens dos materiais, n\u00e3o vejo nenhuma, pois considero o Estrat\u00e9gia um curso bastante completo, com diversas ferramentas para ajudar na aprendizagem e reten\u00e7\u00e3o do conte\u00fado.<\/p>\n\n\n\n<p>Nunca participei de curso presencial e n\u00e3o acho vantajoso, pois ficamos restritos ao conte\u00fado, j\u00e1 que, muitas vezes, o material \u00e9 disponibilizado somente na hora ou ap\u00f3s a aula. Com o Estrat\u00e9gia, consigo organizar meus estudos e estudar de acordo com a minha realidade.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Ao iniciar os estudos, a primeira coisa que devemos fazer \u00e9 pesquisar bons materiais para o nosso estudo. Desse modo, ao pesquisar sobre cursinhos preparat\u00f3rios encontrei o Estrat\u00e9gia Concursos. Vi diversos depoimentos positivos de alunos e resolvi realizar a assinatura. Desde ent\u00e3o, o Estrat\u00e9gia tem sido meu principal meio de estudo, principalmente por oferecer materiais atualizados, focados no edital e com ferramentas que facilitam o aprendizado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Sempre estudei com o Estrat\u00e9gia&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Devido sempre ter estudado pelo Estrat\u00e9gia, sentia que estava evoluindo constantemente. Al\u00e9m disso, no in\u00edcio da minha prepara\u00e7\u00e3o, adquiri a assinatura Platinum e contei com o acompanhamento de dois coaches: Arthur Conde e Gilzan Lessa. Eles foram fundamentais para o meu desempenho futuro, pois me orientaram sobre como dividir as mat\u00e9rias em blocos de estudo, identificar os assuntos mais relevantes cobrados pelas bancas examinadoras e utilizar da melhor forma as ferramentas do Estrat\u00e9gia. Al\u00e9m disso, eles faziam lives para nos orientar sobre como manter o equil\u00edbrio f\u00edsico-mental, mostrando como cuidar da sa\u00fade mental faz toda a diferen\u00e7a na prepara\u00e7\u00e3o e na performance no dia da prova<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Para o concurso da DPE-RO, montei meu plano de estudo em uma planilha no Excel, onde inclu\u00ed todas as disciplinas do edital e as aulas do curso. Dividi os estudos em ciclos, com quatro mat\u00e9rias por dia. Conforme ia concluindo as aulas ou disciplinas, eu marcava na planilha para controlar a evolu\u00e7\u00e3o do meu estudo.<\/p>\n\n\n\n<p>Quanto \u00e0s horas de estudo, eu estudava todos os dias, destinava cerca de 1h30 para cada mat\u00e9ria, totalizando aproximadamente 5 horas l\u00edquidas por dia, dividindo esse tempo entre teoria, revis\u00e3o e quest\u00f5es.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>No in\u00edcio, eu tentei fazer resumos manuscritos para revisar, mas percebi que isso me tomava muito tempo e acabava tornando o estudo passivo. Depois, optei por revisar atrav\u00e9s de quest\u00f5es, o que funcionou melhor para mim. Eu preferia resolver as quest\u00f5es apenas depois de finalizar determinado assunto ou aula, dividindo-as em partes iguais ao longo dos dias. Por exemplo, se o tema \u201ccrase\u201d em Portugu\u00eas tivesse 45 quest\u00f5es, eu dividia em tr\u00eas blocos de 15 quest\u00f5es cada, e resolvia de forma espa\u00e7ada: 7, 15 e 30 dias.<\/p>\n\n\n\n<p>Al\u00e9m disso, sempre marcava as quest\u00f5es em que errava ou ficava na d\u00favida, para revis\u00e1-las quando esgotasse as quest\u00f5es daquele assunto e tamb\u00e9m pr\u00f3ximo \u00e0 data da prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>A resolu\u00e7\u00e3o de exerc\u00edcios foi essencial para minha aprova\u00e7\u00e3o. Considero que fazer quest\u00f5es \u00e9 uma das partes mais importantes da prepara\u00e7\u00e3o, porque \u00e9 por meio delas que identificamos nossos pontos fracos, fixamos o conte\u00fado e, principalmente, entendemos o perfil da banca e o que ela costuma cobrar. Al\u00e9m disso, resolver muitas quest\u00f5es me ajudava a ganhar mais seguran\u00e7a para a prova porque, a cada acerto, eu percebia que estava realmente aprendendo e evoluindo. Isso fortalecia minha confian\u00e7a e mostrava que meu esfor\u00e7o estava dando resultado.<\/p>\n\n\n\n<p>Desde o in\u00edcio do meu estudo para o TSE em 2024, que foi onde passei a estudar com mais foco e organiza\u00e7\u00e3o, at\u00e9 o concurso da DPE em maio de 2025, tenho feito 18.599 quest\u00f5es. J\u00e1 exclusivamente para a DPE entre fevereiro a maio de 2025, fiz 6.421 quest\u00f5es.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Minha maior dificuldade foi Portugu\u00eas, principalmente porque a banca do meu concurso era a FGV, que tem um hist\u00f3rico de cobran\u00e7a diferenciada nessa disciplina. Para melhorar meu desempenho, eu assisti v\u00eddeo aulas para aprender a teoria e, posteriormente, fiz muitas quest\u00f5es espec\u00edficas da banca e resolvi provas anteriores aplicadas pela FGV. Acredito que isso foi o grande diferencial para conseguir acertar as quest\u00f5es no dia da prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Na semana anterior \u00e0 prova da DPE-RO, revisei os conte\u00fados em que ainda sentia mais dificuldade e intensifiquei a resolu\u00e7\u00e3o de quest\u00f5es. Aproveitei tamb\u00e9m para revisar resumos, anota\u00e7\u00f5es importantes e refazer quest\u00f5es que havia errado anteriormente, garantindo que n\u00e3o repetiria os mesmos erros.<\/p>\n\n\n\n<p>No dia anterior \u00e0 prova, assisti \u00e0 Revis\u00e3o de V\u00e9spera do Estrat\u00e9gia, que foi fundamental para mim, pois me ajudou a refrescar pontos importantes de cada mat\u00e9ria e, inclusive, v\u00e1rios conte\u00fados da revis\u00e3o de v\u00e9spera ca\u00edram na prova, o que fez toda a diferen\u00e7a para que eu acertasse algumas quest\u00f5es.<\/p>\n\n\n\n<p>Al\u00e9m disso, o estudo mais intenso nesses \u00faltimos dias ajudou a me sentir mais segura e tranquila, sabendo que fiz tudo o que estava ao meu alcance.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Acredito que meu principal erro, no in\u00edcio dos estudos, foi querer resumir toda a teoria logo ao ler o PDF e negligenciar a resolu\u00e7\u00e3o de quest\u00f5es. Eu pensava que precisava cobrir todo o edital, que era essencial finalizar toda a teoria para estar competitiva. Por\u00e9m, percebi que as quest\u00f5es s\u00e3o a nossa b\u00fassola, s\u00e3o elas que mostram se estamos realmente preparados ou n\u00e3o. N\u00e3o adianta apenas ler toda a teoria e deixar de fazer quest\u00f5es.<\/p>\n\n\n\n<p>Depois que entendi isso, comecei a fazer mais exerc\u00edcios, utilizando os resumos disponibilizados pelos professores e o passo estrat\u00e9gico e conforme fazia as quest\u00f5es, complementava esses materiais com o que julgava necess\u00e1rio.<\/p>\n\n\n\n<p>Outro erro que posso citar foi querer estudar para todos os concursos que surgiam, conciliando editais de \u00e1reas diferentes, ou seja, estudando para dois concursos ao mesmo tempo. Quando percebi que essa abordagem n\u00e3o me fazia evoluir, decidi focar em uma \u00e1rea, especificamente a de tribunais, o que melhorou meu desempenho, e, logo os resultados come\u00e7aram a aparecer.<\/p>\n\n\n\n<p>No entanto, n\u00e3o deixei de prestar concursos cujas provas eram pr\u00f3ximas da minha cidade e, em alguns, consegui aprova\u00e7\u00e3o apenas com a bagagem dos estudos para o concurso no qual estava focada. Al\u00e9m disso, essas provas funcionaram como simulados reais, e me ajudaram a me preparar melhor para o dia da prova principal.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Eu acredito que tem momentos em que pensamos em desistir sim, mas penso que isso acontece porque o caminho \u00e9 \u00e1rduo e n\u00e3o temos certeza se vamos conseguir, nem quando alcan\u00e7aremos a t\u00e3o sonhada aprova\u00e7\u00e3o. Vejo esse pensamento, de \u201cdesistir\u201d, mais como uma rea\u00e7\u00e3o emocional do nosso c\u00e9rebro para nos proteger daquela situa\u00e7\u00e3o dif\u00edcil, do que como uma vontade verdadeira.&nbsp;<\/p>\n\n\n\n<p>Portanto, sim, j\u00e1 pensei em desistir, mas foi algo mais emocional do que racional, pois sei que esse \u00e9 o caminho que quero para minha vida. N\u00e3o me vejo mais trabalhando 44 horas por semana, dedicando dias e dias da minha vida sem ter perspectiva de crescimento profissional. Acredito que foi essa clareza de prop\u00f3sito que me fez continuar firme nessa caminhada, sempre lembrando que meu maior objetivo \u00e9 ter estabilidade e seguran\u00e7a financeira para realizar meus sonhos pessoais: ter filhos, poder trocar de carro, viajar e proporcionar mais qualidade de vida para meus pais quando estiverem na fase idosa. Sei que todo esfor\u00e7o vale a pena quando penso no futuro que quero construir.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Maria Euzilene: <\/strong>Meu conselho para quem est\u00e1 come\u00e7ando agora \u00e9: tenha paci\u00eancia e mantenha a disciplina. Estude com foco, mas tamb\u00e9m cuide da sua sa\u00fade f\u00edsica e mental, e n\u00e3o tenha medo de errar, pois \u00e9 assim que se aprende. Mesmo quando parecer que n\u00e3o est\u00e1 avan\u00e7ando, continue firme e acredite no seu potencial e nunca perca de vista o motivo que te levou a iniciar essa jornada.<\/p>\n\n\n\n<p>O caminho pode parecer longo e dif\u00edcil, mas ao olhar a lista de aprovados e ver seu nome nela, a sensa\u00e7\u00e3o \u00e9 indescrit\u00edvel, \u00e9 a prova de que cada ren\u00fancia valeu a pena e que, para alcan\u00e7ar esse resultado, tudo dependeu de voc\u00ea, do seu esfor\u00e7o e da sua dedica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por fim, agrade\u00e7o a todos que dedicaram um tempo para ler minha entrevista. Lembre-se: voc\u00ea \u00e9 capaz de chegar onde quiser. N\u00e3o pare at\u00e9 conseguir, pois voc\u00ea merece colher os frutos do seu esfor\u00e7o.<\/p>\n\n\n\n<p>\u00c0 equipe do Estrat\u00e9gia Concursos, muito obrigada pelo convite. \u00c9 uma honra compartilhar minha caminhada at\u00e9 a aprova\u00e7\u00e3o com voc\u00eas.<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;[&#8230;] ao olhar a lista de aprovados e ver seu nome nela, a sensa\u00e7\u00e3o \u00e9 indescrit\u00edvel, \u00e9 a prova de que cada ren\u00fancia valeu a pena e que, para alcan\u00e7ar esse resultado, tudo dependeu de voc\u00ea, do seu esfor\u00e7o e da sua dedica\u00e7\u00e3o.&#8221; Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)&nbsp;no [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1609779","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aprovada na DPE-RO: Maria Euzilene Carneiro<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)\u00a0no concurso\u00a0DPE\/RO\u00a0para T\u00e9cnico Administrativo (Regi\u00e3o VI):\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprovada na DPE-RO: Maria Euzilene Carneiro\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)\u00a0no concurso\u00a0DPE\/RO\u00a0para T\u00e9cnico Administrativo (Regi\u00e3o VI):\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-31T12:01:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/07\/aprovada-dpe-ro-maria-euzilene-carneiro-222x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/\",\"name\":\"Aprovada na DPE-RO: Maria Euzilene Carneiro\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/07\/aprovada-dpe-ro-maria-euzilene-carneiro-222x300.jpg\",\"datePublished\":\"2025-08-31T12:01:22+00:00\",\"dateModified\":\"2025-08-31T12:01:23+00:00\",\"description\":\"Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)\u00a0no concurso\u00a0DPE\/RO\u00a0para T\u00e9cnico Administrativo (Regi\u00e3o VI):\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro.jpg\",\"width\":1287,\"height\":1736},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprovada na DPE-RO: Maria Euzilene Carneiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aprovada na DPE-RO: Maria Euzilene Carneiro","description":"Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)\u00a0no concurso\u00a0DPE\/RO\u00a0para T\u00e9cnico Administrativo (Regi\u00e3o VI):","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/","og_locale":"pt_BR","og_type":"article","og_title":"Aprovada na DPE-RO: Maria Euzilene Carneiro","og_description":"Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)\u00a0no concurso\u00a0DPE\/RO\u00a0para T\u00e9cnico Administrativo (Regi\u00e3o VI):","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2025-08-31T12:01:23+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/07\/aprovada-dpe-ro-maria-euzilene-carneiro-222x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/","name":"Aprovada na DPE-RO: Maria Euzilene Carneiro","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/07\/aprovada-dpe-ro-maria-euzilene-carneiro-222x300.jpg","datePublished":"2025-08-31T12:01:22+00:00","dateModified":"2025-08-31T12:01:23+00:00","description":"Confira nossa entrevista com Maria Euzilene Carneiro, aprovada em 1\u00b0 lugar (PCD)\u00a0no concurso\u00a0DPE\/RO\u00a0para T\u00e9cnico Administrativo (Regi\u00e3o VI):","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/07\/18183249\/aprovada-dpe-ro-maria-euzilene-carneiro.jpg","width":1287,"height":1736},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/aprovada-na-dpe-ro-maria-euzilene-carneiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprovada na DPE-RO: Maria Euzilene Carneiro"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1609779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1609779\/revisions"}],"predecessor-version":[{"id":1631298,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1609779\/revisions\/1631298"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1609779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}