{"id":1462391,"date":"2024-09-25T14:12:23","date_gmt":"2024-09-25T17:12:23","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1462391"},"modified":"2024-09-25T14:12:24","modified_gmt":"2024-09-25T17:12:24","slug":"concurso-caixa-aprovada-ingrid-caroline-rosa-lopes","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/","title":{"rendered":"ENTREVISTA: Ingrid Caroline Rosa Lopes &#8211; Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo &#8211; Macropolo: MG &#8211; Polo: Varginha"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>&#8220;O estudo para concurso \u00e9 um trabalho silencioso em que n\u00e3o conseguimos ver o resultado concreto no dia a dia, o que pode desanimar. Por isso, acredito que o melhor caminho \u00e9 focar no objetivo final [&#8230;]&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Ingrid Caroline Rosa Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo &#8211; Macropolo: MG &#8211; Polo: Varginha:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-la. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid Caroline Rosa Lopes: <\/strong>Meu nome \u00e9 Ingrid Lopes, sou natural de Borda da Mata \u2013 MG. Tenho vinte e oito anos e sou formada em Direito h\u00e1 cinco anos, exer\u00e7o a advocacia desde ent\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Apesar de gostar do Direito, havia um tempo em que pensava sobre mudar de \u00e1rea, at\u00e9 que decidi fazer a transi\u00e7\u00e3o para carreira banc\u00e1ria. Ent\u00e3o, quando tive not\u00edcia sobre o concurso Caixa, comecei a estudar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava? <\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Sim, trabalho como associada em um escrit\u00f3rio de advocacia. Organizei minha rotina para conciliar com o estudo. Normalmente estudava \u00e0 noite e aos fins de semana.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovada? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Fui aprovada no concurso Caixa para T\u00e9cnico Banc\u00e1rio Novo, ficando em 11\u00ba na coloca\u00e7\u00e3o de ampla concorr\u00eancia. Como meu objetivo \u00e9 realizar a transi\u00e7\u00e3o de carreira para a \u00e1rea banc\u00e1ria, a princ\u00edpio n\u00e3o tenho outro concurso em vista para o curto prazo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>A partir da publica\u00e7\u00e3o do edital tive que organizar minha rotina para conciliar o trabalho e os estudos. Tamb\u00e9m precisei aproveitar o tempo do fim de semana para estudar, ent\u00e3o o lazer e encontros com amigos e familiares ficou um pouco mais restrito, mas ainda acontecia pontualmente. <\/p>\n\n\n\n<p>Assim como a pr\u00e1tica de atividade f\u00edsica, encontros sociais pontuais s\u00e3o importantes para manter a sa\u00fade mental nessa fase.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseira? De que forma?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Sim, todos ao meu redor me apoiaram bastante nessa fase, principalmente entendendo que eu estaria temporariamente mais ausente por conta do cronograma.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Iniciei o estudo um m\u00eas antes da publica\u00e7\u00e3o do edital, no total foram quase quatro meses de estudo. Para manter a disciplina, organizei minha rotina, deixando estipulado os hor\u00e1rios de estudo e n\u00e3o abri m\u00e3o de alguns momentos de lazer. Acredito que separar alguns momentos para descansar e descontrair s\u00e3o important\u00edssimos para manter a ades\u00e3o \u00e0 rotina e a sa\u00fade mental nesse per\u00edodo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Usei principalmente os PDFs disponibilizados pelo Estrat\u00e9gia. Como o conte\u00fado era muito extenso, estudar pelos materiais escritos e resumos era mais \u00e1gil. Por outro lado, as mat\u00e9rias com as quais eu tinha mais dificuldade, estudava com as videoaulas, que eram muito esclarecedoras.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Por ser da \u00e1rea do Direito e ter amigos concurseiros, j\u00e1 conhecia o Estrat\u00e9gia por indica\u00e7\u00f5es e coment\u00e1rios.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Sim, em 2023 fiz o concurso para o Banco do Brasil e estudei com materiais de outro curso preparat\u00f3rio. A principal diferen\u00e7a que notei entre os cursinhos foi a qualidade dos PDFs disponibilizados pelo Estrat\u00e9gia. Eles s\u00e3o extremamente completos e proporcionam \u00f3tima din\u00e2mica nos estudos, a depender da mat\u00e9ria e do conhecimento do estudante.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovada?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Sim, fiz o concurso do Banco do Brasil em 2023. Tive uma boa coloca\u00e7\u00e3o, mas fora das vagas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Sim, comprei o curso normal, mais a Trilha Estrat\u00e9gica. Achei os conte\u00fados mais completos e as Trilhas facilitavam muito o estudo em mat\u00e9rias em que eu j\u00e1 tinha maior familiaridade.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Apesar das recomenda\u00e7\u00f5es de estudar mais de uma mat\u00e9ria, sempre gostei de estudar uma mat\u00e9ria por dia. Estudava aproximadamente tr\u00eas horas l\u00edquidas em dia de semana, e seis aos fins de semana. Nos dias de semana estudava uma mat\u00e9ria e realizava algumas quest\u00f5es, e aos fins de semana dividia em dois blocos de tr\u00eas horas, nesse caso alternando as mat\u00e9rias entre os blocos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Semanalmente eu revisava os pontos estudados e, normalmente aos domingos, realizava um simulado e ap\u00f3s, sua corre\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>N\u00e3o consigo me recordar da m\u00e9dia de quest\u00f5es, mas fiz muitas. Os materiais disponibilizavam muitas quest\u00f5es e simulados. Tentei fazer o m\u00e1ximo que pude.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Probabilidade e estat\u00edstica foi a mat\u00e9ria de maior dificuldade, ent\u00e3o assisti todas as videoaulas e resolu\u00e7\u00e3o de quest\u00f5es, at\u00e9 conseguir assimilar o conte\u00fado e acertar as quest\u00f5es trazidas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Na semana pr\u00e9 prova eu me dividi entre revis\u00f5es e simulados. No dia que antecedeu a prova, assisti a live do Estrat\u00e9gia transmitida no Youtube.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>Acredito que os maiores erros foram cometidos no estudo do concurso do ano anterior, o que me permitiu corrigi-los. Mas no geral, os maiores erros foram fazer poucos simulados e focar em videoaulas, que apesar de muito boas, as vezes tomam um tempo excessivo, principalmente em conte\u00fados que o concurseiro assimila mais r\u00e1pido. <\/p>\n\n\n\n<p>Por outro lado, os acertos foram: realizar simulados com frequ\u00eancia, entender qual conte\u00fado demanda estudo mais lento e qual conte\u00fado pode ter ritmo acelerado, e por fim manter uma rotina saud\u00e1vel, sem excesso de priva\u00e7\u00e3o, para conseguir manter a const\u00e2ncia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>N\u00e3o. Como meu per\u00edodo de estudos n\u00e3o foi longo, aproximadamente quatro meses, me apeguei a disciplina e const\u00e2ncia para tentar alcan\u00e7ar o objetivo final.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Ingrid: <\/strong>O estudo para concurso \u00e9 um trabalho silencioso em que n\u00e3o conseguimos ver o resultado concreto no dia a dia, o que pode desanimar. Por isso, acredito que o melhor caminho \u00e9 focar no objetivo final e organiza\u00e7\u00e3o da rotina para ser constante, j\u00e1 que a motiva\u00e7\u00e3o vai oscilar muito durante o processo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O estudo para concurso \u00e9 um trabalho silencioso em que n\u00e3o conseguimos ver o resultado concreto no dia a dia, o que pode desanimar. Por isso, acredito que o melhor caminho \u00e9 focar no objetivo final [&#8230;]&#8221; Confira nossa entrevista com Ingrid Caroline Rosa Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1462391","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Ingrid Caroline Rosa Lopes - Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo - Macropolo: MG - Polo: Varginha<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Ingrid Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio - Polo: Varginha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Ingrid Caroline Rosa Lopes - Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo - Macropolo: MG - Polo: Varginha\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Ingrid Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio - Polo: Varginha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T17:12:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/\",\"name\":\"ENTREVISTA: Ingrid Caroline Rosa Lopes - Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo - Macropolo: MG - Polo: Varginha\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2024-09-25T17:12:23+00:00\",\"dateModified\":\"2024-09-25T17:12:24+00:00\",\"description\":\"Confira nossa entrevista com Ingrid Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio - Polo: Varginha\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Ingrid Caroline Rosa Lopes &#8211; Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo &#8211; Macropolo: MG &#8211; Polo: Varginha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Ingrid Caroline Rosa Lopes - Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo - Macropolo: MG - Polo: Varginha","description":"Confira nossa entrevista com Ingrid Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio - Polo: Varginha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Ingrid Caroline Rosa Lopes - Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo - Macropolo: MG - Polo: Varginha","og_description":"Confira nossa entrevista com Ingrid Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio - Polo: Varginha","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2024-09-25T17:12:24+00:00","twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/","name":"ENTREVISTA: Ingrid Caroline Rosa Lopes - Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo - Macropolo: MG - Polo: Varginha","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2024-09-25T17:12:23+00:00","dateModified":"2024-09-25T17:12:24+00:00","description":"Confira nossa entrevista com Ingrid Lopes, aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio - Polo: Varginha","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-caixa-aprovada-ingrid-caroline-rosa-lopes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Ingrid Caroline Rosa Lopes &#8211; Aprovada em 2\u00b0 lugar no concurso\u00a0CAIXA\u00a0para\u00a0o cargo de\u00a0T\u00e9cnico Banc\u00e1rio Novo &#8211; Macropolo: MG &#8211; Polo: Varginha"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1462391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1462391\/revisions"}],"predecessor-version":[{"id":1466948,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1462391\/revisions\/1466948"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1462391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}