{"id":1455217,"date":"2024-09-03T10:57:07","date_gmt":"2024-09-03T13:57:07","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1455217"},"modified":"2024-09-03T10:57:08","modified_gmt":"2024-09-03T13:57:08","slug":"entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/","title":{"rendered":"ENTREVISTA: Carlos Roberto Pereira Bitencourt &#8211; Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"314\" height=\"270\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1.jpeg\" alt=\"\" class=\"wp-image-1455220\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1.jpeg 314w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1-300x258.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1-150x129.jpeg 150w\" sizes=\"auto, (max-width: 314px) 100vw, 314px\" \/><figcaption class=\"wp-element-caption\">Carlos Roberto Pereira Bitencourt<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;Meu principal acerto foi manter a motiva\u00e7\u00e3o intr\u00ednseca ao estudar. Eu tenho a caracter\u00edstica de me apaixonar pelas atividades que desempenho, e isso ocorreu com as mat\u00e9rias do concurso. [&#8230;]&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso&nbsp;MP-PR&nbsp;para&nbsp;o cargo de&nbsp;Promotor:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. H\u00e1 quanto tempo se formou em Direito? Qual sua idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto Pereira Bitencourt: <\/strong>Eu me chamo Carlos Roberto Pereira Bitencourt. Tenho trinta e um anos de idade. Nasci numa pequena cidade do interior de S\u00e3o Paulo, chamada Cruzeiro, no Vale do Para\u00edba, onde morei at\u00e9 os 18 anos. Fiz a minha gradua\u00e7\u00e3o na Faculdade de Direito da USP, no Largo de S\u00e3o Francisco, onde me formei em 2015. Tamb\u00e9m fiz uma especializa\u00e7\u00e3o em Direito Penal na Escola Paulista da Magistratura, em 2018.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos? Escolheu o seu curso superior j\u00e1 pensando em fazer concurso ou chegou a advogar?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Quando eu escolhi fazer a faculdade de direito, meu \u00fanico interesse era o estudo das mat\u00e9rias que constavam da grade curricular \u2013 que eu acessava pela plataforma Jupiter Web, pela internet. Eu achava incr\u00edvel estudar uma gama t\u00e3o ampla de assuntos como Direito Romano, Economia Pol\u00edtica e Direito Penal Internacional. Quando eu ingressei na faculdade, tive uma professora excelente, chamada Juliana Krueger Pela, que me despertou interesse por direito societ\u00e1rio, \u00e1rea na qual estagiei por cerca de um ano, com muito entusiasmo. No final do segundo ano da faculdade, fui aprovado no concurso para Escrevente T\u00e9cnico Judici\u00e1rio do Tribunal de Justi\u00e7a de S\u00e3o Paulo, institui\u00e7\u00e3o na qual trabalho at\u00e9 hoje. O sonho de prestar concursos p\u00fablicos, contudo, consolidou-se apenas posteriormente, no ano de 2016, quando comecei a trabalhar como Assistente Jur\u00eddico do Desembargador Vito Guglielmi, na 6\u00aa C\u00e2mara de Direito Privado do TJSP. No gabinete, percebi que era apaixonado pelo trabalho, que impactava diretamente a vida das pessoas.\u00a0<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sempre fez concursos para carreira jur\u00eddica?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Sim.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Sim, eu sempre conciliei o trabalho e os estudos, mesmo antes de ingressar na faculdade. Especificamente para concursos p\u00fablicos, o trabalho na Subse\u00e7\u00e3o de Direito Privado I do TJSP me ajudou muito nos estudos, e vice-versa, pois as mat\u00e9rias com as quais eu trabalhava tinham grande incid\u00eancia nas provas. Quanto aos hor\u00e1rios, eu sempre gostei de estudar nas primeiras horas da manh\u00e3, pois n\u00e3o rendo \u00e0 noite. Nos \u00faltimos meses, nos dias mais produtivos, acordava bem cedo \u2013 antes das 5h00 -, e estudava at\u00e9 \u00e0s 10h00. Trabalhava das 11h00 \u00e0s 19h00. \u00c0 noite, estudava at\u00e9 por volta das 21h00, mat\u00e9rias mais leves. Se estivesse muito cansado, descansava nesse per\u00edodo.&nbsp; Sempre estudei, igualmente, aos finais de semana, feriados e recesso forense. Apesar disso, entendo que \u00e9 importante estabelecer um equil\u00edbrio com os momentos de lazer e vida social, aspecto no qual sempre tive dificuldade.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Eu fui aprovado nos concursos de Escrevente T\u00e9cnico Judici\u00e1rio do TJSP, em 2013; e no concurso de T\u00e9cnico Judici\u00e1rio do Tribunal Regional do Trabalho de 2014. Este ano \u2013 2024 -, fui finalmente aprovado para Promotor de Justi\u00e7a no Minist\u00e9rio P\u00fablico do Estado do Paran\u00e1. Fiquei com a quarta maior nota na prova discursiva, e com a oitava maior m\u00e9dia ap\u00f3s a contabiliza\u00e7\u00e3o da prova oral. Ainda n\u00e3o sei a minha classifica\u00e7\u00e3o final ap\u00f3s a contagem dos t\u00edtulos, pois n\u00e3o tenho muitos. Estou muito feliz por haver passado!\u00a0<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Eu fiz um estudo de reta final de cerca de tr\u00eas meses para enfrentar a prova objetiva, entretanto estudo para concursos p\u00fablicos desde 2016.&nbsp;<\/p>\n\n\n\n<p>Para manter a disciplina, no \u00faltimo ano, eu e alguns amigos criamos um grupo de estudos no Whatsapp, bem como um servidor no \u201cDiscord\u201d, ferramenta que vem sendo utilizada com enorme proveito por muitos estudantes. A ideia foi de uma amiga. Nesse dispositivo, n\u00f3s nos conect\u00e1vamos, lig\u00e1vamos (ou n\u00e3o) a c\u00e2mera e cronometr\u00e1vamos pomodoros de 50 minutos, com 10 minutos de descanso para um caf\u00e9 ou pequena conversa. Assim, um estimulava o outro durante o hor\u00e1rio estabelecido para as sess\u00f5es coletivas de estudo, que eram feitas silenciosamente, cada um em sua casa. Faz\u00edamos os pomodoros \u00e0 noite, igualmente. Toda semana, estudava informativos de jurisprud\u00eancia com algumas amigas, por meio de perguntas e respostas que nos formul\u00e1vamos reciprocamente pelo mesmo aplicativo. Na segunda fase, me recordo de lembrar as respostas das perguntas rememorando cenas desses encontros \u2013 \u201cJ\u00e1 conversei sobre esse precedente com a Ha\u00edssa, com a Dinah!\u201d. Quando fui para a fase oral, contei igualmente com o apoio e o treino ao lado dos amigos, numa rede de est\u00edmulo e suporte muito bonita. Fiz grandes amigos durante a minha prepara\u00e7\u00e3o, amizades que levarei para minha vida.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Nos tr\u00eas primeiros anos de prepara\u00e7\u00e3o, eu n\u00e3o realizei cursos preparat\u00f3rios, o que me prejudicou imensamente. Eu sempre senti prazer ao estudar os livros de doutrina, mas evitava a lei seca e os informativos de jurisprud\u00eancia. Enorme erro! Considero importante ler boas doutrinas, mas o estudo por rodadas de PDF\u2019s, legisla\u00e7\u00f5es destacadas, cursos preparat\u00f3rios e trilhas estrat\u00e9gicas \u2013 como aquelas fornecidas pelo Estrat\u00e9gia \u2013 aumenta consideravelmente o seu desempenho, sobretudo na prova objetiva. Tamb\u00e9m criei o h\u00e1bito de ouvir podcasts, discutir a mat\u00e9ria com os colegas e estudar por flashcards e mapas mentais. Em todas as fases, por fim, os grupos de Whatsapp em que troc\u00e1vamos dicas, ementas de precedentes importantes e at\u00e9 \u201cenquetes\u201d \u2013 para os membros votarem se determinada assertiva seria verdadeira ou falsa &#8211; em mat\u00e9rias espec\u00edficas me ajudaram de modo inacredit\u00e1vel.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Pela internet, buscando boas indica\u00e7\u00f5es de cursos preparat\u00f3rios.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Certamente. Gostava muito das quest\u00f5es, resolvidas no corpo do pr\u00f3prio roteiro de estudos, com coment\u00e1rios dos professores. Tamb\u00e9m adorava as trilhas estrat\u00e9gicas, os mapas mentais e os slides, sobretudo os fornecidos pelo Professor Herbert Almeida, de Direito Administrativo.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Eu sempre gostei de estudar uma mat\u00e9ria por dia. \u00c0s vezes, \u00e0 noite, trocava para uma mat\u00e9ria mais leve, com as quais tinha mais familiaridade. Deixava as horas nobres da manh\u00e3 para as mat\u00e9rias mais \u00e1rduas. Durante a semana, creio que estudava cerca de cinco horas l\u00edquidas di\u00e1rias. Aos finais de semana, estudava o m\u00e1ximo que conseguia: creio que sete ou oito horas.&nbsp; Para esse ritmo pesado de estudos, a compreens\u00e3o e o apoio dos familiares, sobretudo dos c\u00f4njuges, fazem toda a diferen\u00e7a.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Eu considero que o estudo s\u00e9rio dos informativos de jurisprud\u00eancia, bem como a resolu\u00e7\u00e3o de quest\u00f5es e provas antigas \u00e9 uma forma org\u00e2nica de revisar os temas mais relevantes de todas as mat\u00e9rias. Tamb\u00e9m gostava de revisar por flashcards, mapas mentais. Nos \u00faltimos meses, desenvolvi o h\u00e1bito de enviar \u00e1udios de \u201cWhatsapp\u201d para mim mesmo com pequenos resumos de algumas mat\u00e9rias. Ali\u00e1s, para a fase oral do Minist\u00e9rio P\u00fablico do Paran\u00e1, combinei com um grande amigo, Alexandre, que diariamente eu criaria e lhe enviaria perguntas de Direito Penal, para que ele me enviasse respostas na forma de \u00e1udios. Ele, por sua vez, faria o mesmo para eu responder. Eu acredito de verdade que a criatividade e a colabora\u00e7\u00e3o com os amigos s\u00e3o excelentes maneiras de revisar e de aprender.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Resolver quest\u00f5es objetivas e dissertativas, al\u00e9m de treinar as argui\u00e7\u00f5es antes da prova oral, \u00e9 essencial. N\u00e3o sei o n\u00famero ao certo de quest\u00f5es que resolvi, mas foram literalmente milhares.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Eu sou o tipo que estuda at\u00e9 o \u00faltimo minuto antes de entrar na sala. Fiz isso a minha vida inteira. Na semana da prova oral, contudo, notei que eu havia chegado a um grau de exaust\u00e3o mental extremo e resolvi pegar mais leve. Estudei na v\u00e9spera, mas tive uma boa noite de sono; sa\u00ed para tomar caf\u00e9 com minhas amigas, Let\u00edcia e Bruna; ouvi m\u00fasica. Minha amiga Camile fez uma ora\u00e7\u00e3o comigo antes de eu sair para a prova oral.&nbsp; Levei o livro de Salmos para a sala de confinamento da prova, onde fiquei aguardando a minha vez de ser arguido. Eu entendo que a espiritualidade nos ajuda muito a superar os desafios.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Concursos para carreira jur\u00eddica s\u00e3o compostos por v\u00e1rias fases. Como foi sua prepara\u00e7\u00e3o para a prova discursiva? E para a prova oral?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Para todas as fases do concurso, considero imprescind\u00edvel \u2013 verdadeiramente essencial \u2013 estudar no detalhe as provas antigas, e nesse aspecto as an\u00e1lises estat\u00edsticas e a curadoria de quest\u00f5es do Estrat\u00e9gia se destacam. Fazer quest\u00f5es anteriores, compreender quais s\u00e3o os temas mais cobrados, e de que forma. Para a prova dissertativa, fiz simulados de quest\u00f5es discursivas e de pe\u00e7as pr\u00e1ticas. Para a prova oral, treinei todos os dias com os demais candidatos. Muitos deles viraram grandes amigos.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Meu principal acerto foi manter a motiva\u00e7\u00e3o intr\u00ednseca ao estudar. Eu tenho a caracter\u00edstica de me apaixonar pelas atividades que desempenho, e isso ocorreu com as mat\u00e9rias do concurso. Estudar se tornou uma atividade prazerosa e at\u00e9 mesmo greg\u00e1ria, dado que estudei ao lado dos amigos.<\/p>\n\n\n\n<p>Meu principal erro foi negligenciar, por vezes, o descanso, a alimenta\u00e7\u00e3o saud\u00e1vel, o exerc\u00edcio f\u00edsico, o sono. Estudar para concursos \u00e9 desgastante, e nos sentimos ansiosos em diversos momentos.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Carlos Roberto: <\/strong>Gostaria de deixar um poema da Professora Ada Pellegrini Grinover, do seu livro \u201cCantos\u201d. Chama-se \u201cSemente\u201d.&nbsp;<\/p>\n\n\n\n<p><em>SEMENTE<\/em><\/p>\n\n\n\n<p><em>Olhe bem para a semente<\/em><\/p>\n\n\n\n<p><em>E acredite que vingar\u00e1.<\/em><\/p>\n\n\n\n<p><em>Por mais \u00e1rida que seja a terra<\/em><\/p>\n\n\n\n<p><em>Por mais \u00e1spero que seja o clima<\/em><\/p>\n\n\n\n<p><em>Por mais hostil que seja o ambiente<\/em><\/p>\n\n\n\n<p><em>Lance a sua semente.<\/em><\/p>\n\n\n\n<p><em>E, se morrer, lance outra e mais outra<\/em><\/p>\n\n\n\n<p><em>At\u00e9 que um dia<\/em><\/p>\n\n\n\n<p><em>Vir\u00e1 uma chuva leve e benfazeja<\/em><\/p>\n\n\n\n<p><em>Os ventos amainar\u00e3o<\/em><\/p>\n\n\n\n<p><em>Os p\u00e1ssaros agressores<\/em><\/p>\n\n\n\n<p><em>Ir\u00e3o em busca de outra sementeira.<\/em><\/p>\n\n\n\n<p><em>E sua semente germinar\u00e1.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Meu principal acerto foi manter a motiva\u00e7\u00e3o intr\u00ednseca ao estudar. Eu tenho a caracter\u00edstica de me apaixonar pelas atividades que desempenho, e isso ocorreu com as mat\u00e9rias do concurso. [&#8230;]&#8221; Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso&nbsp;MP-PR&nbsp;para&nbsp;o cargo de&nbsp;Promotor: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1455217","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Carlos Roberto Pereira Bitencourt - Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Carlos Roberto Pereira Bitencourt - Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T13:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/09\/foto-entrevista-1.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/\",\"name\":\"ENTREVISTA: Carlos Roberto Pereira Bitencourt - Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/09\/foto-entrevista-1.jpeg\",\"datePublished\":\"2024-09-03T13:57:07+00:00\",\"dateModified\":\"2024-09-03T13:57:08+00:00\",\"description\":\"Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1.jpeg\",\"width\":314,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Carlos Roberto Pereira Bitencourt &#8211; Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Carlos Roberto Pereira Bitencourt - Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor","description":"Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Carlos Roberto Pereira Bitencourt - Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor","og_description":"Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2024-09-03T13:57:08+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/09\/foto-entrevista-1.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/","name":"ENTREVISTA: Carlos Roberto Pereira Bitencourt - Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/09\/foto-entrevista-1.jpeg","datePublished":"2024-09-03T13:57:07+00:00","dateModified":"2024-09-03T13:57:08+00:00","description":"Confira nossa entrevista com Carlos Roberto Pereira Bitencourt, aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/02183505\/foto-entrevista-1.jpeg","width":314,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-roberto-pereira-bitencourt-aprovado-no-concurso-mp-pr-para-o-cargo-de-promotor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Carlos Roberto Pereira Bitencourt &#8211; Aprovado no concurso\u00a0MP-PR\u00a0para\u00a0o cargo de\u00a0Promotor"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1455217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1455217\/revisions"}],"predecessor-version":[{"id":1455590,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1455217\/revisions\/1455590"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1455217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}