{"id":1368339,"date":"2024-04-04T16:06:04","date_gmt":"2024-04-04T19:06:04","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1368339"},"modified":"2024-04-04T16:10:11","modified_gmt":"2024-04-04T19:10:11","slug":"entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/","title":{"rendered":"ENTREVISTA: Anselmo Bomfim dos Reis &#8211; Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"162\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373-300x162.png\" alt=\"\" class=\"wp-image-1369180\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373-300x162.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373-1024x554.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373-768x415.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373-610x330.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373-150x81.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373.png 1098w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Anselmo Bomfim dos Reis<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;Seu dia, sua hora, sua vez, pode ser na pr\u00f3xima prova. N\u00e3o desaponte seu sonho, ele est\u00e1 logo \u00e0 frente.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;SEJUS-ES&nbsp;para o cargo de&nbsp;Inspetor Penitenci\u00e1rio:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo Bomfim dos Reis: <\/strong>Meu Nome \u00e9 Anselmo Bomfim dos Reis, sou formado em An\u00e1lise e Desenvolvimento de Sistema pela IESB, tenho 41 anos, nasci em Bras\u00edlia-DF.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Quando mais novo, eu cheguei a estudar para alguns concursos de diversas \u00e1reas (sa\u00fade, policial, administrativo). Contudo, nunca foi algo bem feito, n\u00e3o tinha a dedica\u00e7\u00e3o que deveria ter. No in\u00edcio de 2019, minha esposa e eu trabalh\u00e1vamos com transporte escolar, que era nossa \u00fanica renda. Logo ap\u00f3s o in\u00edcio da pandemia, paramos de trabalhar devido ao fechamento das escolas, o que nos deixou sem renda. Foi um tempo muito dif\u00edcil para n\u00f3s. As contas n\u00e3o paravam de chegar e n\u00e3o t\u00ednhamos como pag\u00e1-las. No meio de tudo isso, minha esposa conseguiu emprego de representante comercial e eu fui trabalhar de motorista em uma empresa de tecnologia, imaginando um dia voltar a atuar na \u00e1rea de inform\u00e1tica por essa empresa.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Sim, trabalhava das 9h at\u00e9 \u00e0s 19h. Tive que fazer o que a maioria dos concurseiros faz: sacrificar o sono. Minha filha mais nova tinha 2 anos. Quando eu chegava em casa, por volta das 20h30, ficava com elas at\u00e9 elas pegarem no sono, isso acontecia por volta das 22h. Era essa hora que eu iniciava os estudos e continuava at\u00e9 \u00e0s 2h da manh\u00e3.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Minha primeira aprova\u00e7\u00e3o foi no processo seletivo simplificado na SEJUSP\u2013MG, no ano de 2022 para o cargo de Agente de Seguran\u00e7a Penitenci\u00e1ria. Eles ofereceram 930 vagas para a cidade de Contagem \u2013 MG, passei na posi\u00e7\u00e3o 169. O segundo foi na SERJUS-ES, na coloca\u00e7\u00e3o 343 para o caro de Inspetor Penitenci\u00e1rio, agora transformado Policial Penal.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>No in\u00edcio, eu estava t\u00e3o focado no que queria e no que deveria fazer para conseguir o que desejava, que quase n\u00e3o sa\u00eda muito. Todo tempo extra eu usava para estudar. Por\u00e9m, ap\u00f3s come\u00e7ar a ganhar mais conhecimento dos assuntos, eu tamb\u00e9m coloquei o lazer com a fam\u00edlia no meio da rotina de estudos e isso fez muito bem para mim. Aconselho colocar o lazer no cronograma de estudos rsrs.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Eu sempre digo que n\u00f3s n\u00e3o fomos feitos para fazer nada sozinhos. Minha esposa foi pe\u00e7a fundamental nessa jornada, ela sempre me deu muita for\u00e7a, sempre procurou, dentro do poss\u00edvel, me deixar o mais confort\u00e1vel poss\u00edvel para estudar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Na verdade, eu continuo estudando desde a aprova\u00e7\u00e3o no primeiro concurso. Mas para o concurso da pol\u00edcia Penal ES, eu passei a estudar direcionado a ele com 3 meses antes de sair o edital, usando o \u00faltimo edital como refer\u00eancia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Nas mat\u00e9rias em que eu tinha mais conhecimento, eu usei os PDFs do Estrat\u00e9gia Concursos por serem os mais \u201cenxutos\u201d e objetivos. Isso nos d\u00e1 celeridade na prepara\u00e7\u00e3o.<\/p>\n\n\n\n<p>Nas mat\u00e9rias em que eu tinha mais dificuldade, eu optava pelas videoaulas para buscar a informa\u00e7\u00e3o direto do professor.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Eu conheci o Estrat\u00e9gia no meio dos concursos mesmo. A maioria dos f\u00f3runs, grupos de estudos, todos sempre foram un\u00e2nimes em dizer da alta qualidade dos conte\u00fados entregues pelo Estrat\u00e9gia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Usei sim. O que mais incomodava, com toda certeza, era que nos disponibilizavam muito material para estudar, mas sem orienta\u00e7\u00e3o alguma.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>A diferen\u00e7a \u00e9 enorme, principalmente em rela\u00e7\u00e3o a produ\u00e7\u00e3o dos PDFs. Parece que era algo premeditado. Na hora da prova eu lembrava do assunto por j\u00e1 ter visto no material do Estrat\u00e9gia. Tinha momento que lembrava at\u00e9 de algum coment\u00e1rio do professor alertando sobre a grande possibilidade de o assunto ser cobrado na prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>No come\u00e7o dos estudos, iniciei estudando uma, duas horas no m\u00e1ximo por dia, at\u00e9 mesmo que ainda estava incluindo essa rotina no meu dia e tinha a tal da desaten\u00e7\u00e3o. Ap\u00f3s um per\u00edodo, j\u00e1 com a rotina estabelecida, passei a estudar de tr\u00eas a quatro horas por dia. Desligava celular e tudo que poderia me tirar a aten\u00e7\u00e3o. Em per\u00edodo p\u00f3s-edital, j\u00e1 uso muito bem meus dias de folga (trabalho na escala de 24\/72), estudando praticamente o dia todo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Minhas revis\u00f5es eu gosto muito de fazer pelos meus pr\u00f3prios resumos. Tenho um caderno de resumo para cada mat\u00e9ria. Somado a isso, eu tenho uma meta de 100 quest\u00f5es por dia do assunto estudado, onde fraciono elas no decorrer do dia. Fazia muito simulados para me adequar ao tempo de prova e poder ter no\u00e7\u00e3o quando tempo eu teria para fazer as quest\u00f5es, a reda\u00e7\u00e3o, se fosse o caso, e preencher o gabarito.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>A resolu\u00e7\u00e3o de exerc\u00edcios \u00e9 uma das tarefas principais para qualquer concurso, especialmente as quest\u00f5es da banca que aplicar\u00e1 o concurso. A quantidade de quest\u00f5es chegou a oito mil, mais ou menos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Meu carma sempre foi RLM e Portugu\u00eas. Para essas mat\u00e9rias, eu fazia as quest\u00f5es que a banca tinha aplicado em provas recentes e procurava verificar quais eram os assuntos mais cobrados para tentar melhorar minha pontua\u00e7\u00e3o nessas mat\u00e9rias.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Eu deixei de viver, rsrsr. Parei com todas as outras atividades do dia a dia, como academia, corrida, assistir futebol, essas coisas. Sabia que faltava pouco para o dia em que eu iria conseguir o meu objetivo e que tudo aquilo valeria a pena. Na v\u00e9spera da prova, eu apenas revisei pontos que julgava importantes e procurei me tranquilizar para a prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Essa fase foi de igual import\u00e2ncia, pois ela valia os mesmos 100 pontos da prova objetiva. Ap\u00f3s a publica\u00e7\u00e3o do edital, procurei um especialista em elabora\u00e7\u00e3o de reda\u00e7\u00e3o com temas da \u00e1rea policial. Passei a fazer tr\u00eas reda\u00e7\u00f5es por semana, observando os ensinamentos do professor e usando, at\u00e9 mesmo, a pr\u00f3pria folha de reda\u00e7\u00e3o das bancas para treinar todos os pontos cobrados.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Meu principal erro foi iniciar sem uma orienta\u00e7\u00e3o profissional. Depois que passei a estudar direcionadamente e seguindo as instru\u00e7\u00f5es dos professores do Estrat\u00e9gia, eu obtive um resultado de aprendizagem muito mais r\u00e1pido do que quando estudava por conta pr\u00f3pria. Em rela\u00e7\u00e3o aos acertos, posso dizer que me dedicar, ter compromisso com meu sonho e n\u00e3o ter desistido na primeira reprova\u00e7\u00e3o foram os determinantes para minha aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Eu reprovei 9 vezes antes de conseguir a primeira aprova\u00e7\u00e3o. Em certo momentos, principalmente ap\u00f3s a divulga\u00e7\u00e3o dos gabaritos, onde voc\u00ea via que n\u00e3o tinha ido bem na prova, eu repensava se aquilo era pra mim mesmo, gasto com toda a log\u00edstica de ir fazer prova em outro Estado, tudo isso passava pela minha cabe\u00e7a, mas meu sonho sempre foi ser policial. Eu lembrava o porqu\u00ea eu comecei a estudar, minhas filhas, minha esposa. Com isso, eu sacudia a poeira e voltava para a \u201carena\u201d.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Anselmo: <\/strong>Eu diria: sua aprova\u00e7\u00e3o est\u00e1 a mais um assunto visto, a mais uma quest\u00e3o resolvida, h\u00e1 mais um dia sem \u00e2nimo para estudar superado. N\u00e3o desista do seu sonho por conta de uma, duas, tr\u00eas  reprova\u00e7\u00f5es. Seu dia, sua hora, sua vez, pode ser na pr\u00f3xima prova. N\u00e3o desaponte seu sonho, ele est\u00e1 logo \u00e0 frente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Seu dia, sua hora, sua vez, pode ser na pr\u00f3xima prova. N\u00e3o desaponte seu sonho, ele est\u00e1 logo \u00e0 frente.&#8221; Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;SEJUS-ES&nbsp;para o cargo de&nbsp;Inspetor Penitenci\u00e1rio: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1368339","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Anselmo Bomfim dos Reis - Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Anselmo Bomfim dos Reis - Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T19:10:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/03\/image-373-300x162.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/\",\"name\":\"ENTREVISTA: Anselmo Bomfim dos Reis - Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/03\/image-373-300x162.png\",\"datePublished\":\"2024-04-04T19:06:04+00:00\",\"dateModified\":\"2024-04-04T19:10:11+00:00\",\"description\":\"Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio:\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373.png\",\"width\":1098,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Anselmo Bomfim dos Reis &#8211; Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Anselmo Bomfim dos Reis - Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio","description":"Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Anselmo Bomfim dos Reis - Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio","og_description":"Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio:","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2024-04-04T19:10:11+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/03\/image-373-300x162.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/","name":"ENTREVISTA: Anselmo Bomfim dos Reis - Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/03\/image-373-300x162.png","datePublished":"2024-04-04T19:06:04+00:00","dateModified":"2024-04-04T19:10:11+00:00","description":"Confira nossa entrevista com Anselmo Bomfim dos Reis, aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio:","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/15100522\/image-373.png","width":1098,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-anselmo-bomfim-dos-reis-aprovado-em-343-lugar-no-concurso-sejus-es-para-o-cargo-de-inspetor-penitenciario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Anselmo Bomfim dos Reis &#8211; Aprovado em 343\u00b0\u00a0lugar\u00a0no concurso\u00a0SEJUS-ES\u00a0para o cargo de\u00a0Inspetor Penitenci\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1368339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1368339\/revisions"}],"predecessor-version":[{"id":1379218,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1368339\/revisions\/1379218"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1368339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}