{"id":1354256,"date":"2024-02-19T16:13:28","date_gmt":"2024-02-19T19:13:28","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1354256"},"modified":"2024-02-19T16:13:30","modified_gmt":"2024-02-19T19:13:30","slug":"entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/","title":{"rendered":"ENTREVISTA: Leonardo dos Santos &#8211; Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal &#8211; Masculino"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422-169x300.png\" alt=\"\" class=\"wp-image-1354257\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422-169x300.png 169w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422-150x267.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422.png 519w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><figcaption class=\"wp-element-caption\">Leonardo dos Santos<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;Organize sua vida e sua rotina. Honre seus familiares e seu emprego atual. Fa\u00e7a um plano de estudos realista, simples e o siga. V\u00e1 aperfei\u00e7oando com o passar dos dias [&#8230;]&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar&nbsp;no concurso&nbsp;SEJUSP-MG&nbsp;para o cargo de&nbsp;Policial Penal &#8211; Masculino:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo dos Santos: <\/strong>Me chamo Leonardo dos Santos, 28 anos, Bacharel em Direito e Tecn\u00f3logo em Gest\u00e3o P\u00fablica, natural de Mafra-SC.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos? Por que a \u00e1rea policial?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>O concurso \u00e9 o meio necess\u00e1rio pelo qual busco exercer o que acredito ser a minha voca\u00e7\u00e3o, o meu chamado.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Sim! Durante o per\u00edodo de prepara\u00e7\u00e3o fui militar do Ex\u00e9rcito. Um quartel pequeno e muito demandado. Ainda que houvesse muito incentivo por parte dos comandantes que tive, n\u00e3o conseguia ter muita rotina de estudos, devido a oscila\u00e7\u00e3o de hor\u00e1rios das atividades castrenses. Quando estudava, procurava ser o mais eficiente poss\u00edvel.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Este \u00e9 o primeiro concurso que eu sou aprovado. Tenho outros objetivos, mas que ainda precisam ser amadurecidos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>N\u00e3o tinha muita vida social, devido ao fato de ter pouco tempo dispon\u00edvel para estudo. Mas, considero o descanso e uma vida social moderada, uma estrat\u00e9gia fundamental para maior rendimento no estudo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Sou casado. Minha esposa me apoiou em todas as etapas, nos dias bons e ruins, sendo a minha principal aliada. N\u00e3o conquistei essa aprova\u00e7\u00e3o sozinho, houve diversas pessoas que somaram para a realiza\u00e7\u00e3o desse prop\u00f3sito.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Estudei p\u00f3s-edital. Diria que a palavra mais apropriada para o momento foi perseveran\u00e7a. Por muitos dias n\u00e3o consegui estudar. \u00c0s vezes, porque estava envolvido em atividades militares, outras, porque me sentia exausto. Mas n\u00e3o desistia de retomar os estudos t\u00e3o logo conseguisse.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Para as mat\u00e9rias jur\u00eddicas: lei seca, quest\u00f5es comentadas dos PDFs e de plataforma de quest\u00f5es. As vantagens foram: a simplicidade na execu\u00e7\u00e3o do planejamento, o estudo da lei seca com as mais diversas formas de cobran\u00e7a em provas e a celeridade no progresso do edital. A desvantagem \u00e9 sempre o risco de aparecer quest\u00f5es in\u00e9ditas com temas pouco cobrados anteriormente e, portanto, pouco aprofundado nos coment\u00e1rios das quest\u00f5es.<\/p>\n\n\n\n<p>Para portugu\u00eas, inform\u00e1tica e RLM: utilizei algumas aulas em PDF, mas logo passei para a realiza\u00e7\u00e3o de quest\u00f5es exclusivamente da banca. A vantagem foi compreender o padr\u00e3o espec\u00edfico de cobran\u00e7a. A desvantagem foi que n\u00e3o havia muitas quest\u00f5es da banca organizadora e, por causa da estrat\u00e9gia que utilizei, meu estudo ficou limitado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Quando decidi estudar, fiz uma pesquisa buscando os melhores cursos preparat\u00f3rios. Acertei na escolha e n\u00e3o me arrependo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Estudava, em m\u00e9dia, duas mat\u00e9rias por dia. No edital desse concurso, algumas mat\u00e9rias representavam grande percentual da prova e com maior peso. Ent\u00e3o, priorizei um pouco mais essas mat\u00e9rias. Fiz um estudo seguindo cada t\u00f3pico do edital. Nas mat\u00e9rias jur\u00eddicas, lia a lei pertinente ao assunto e, em seguida, respondia quest\u00f5es comentadas sobre o t\u00f3pico. Aquilo que eu achava pertinente eu inclu\u00eda como coment\u00e1rio na lei. Depois que terminasse, partia para o pr\u00f3ximo t\u00f3pico do edital. Em portugu\u00eas, inform\u00e1tica e RLM, respondia quest\u00f5es e anotava em um caderno tudo o que era poss\u00edvel aprender com cada quest\u00e3o. Meu hor\u00e1rio de estudo era muito relativo, ent\u00e3o n\u00e3o contabilizava a quantidade de horas l\u00edquidas\/di\u00e1rias.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Infelizmente n\u00e3o consegui fazer revis\u00f5es regulares.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Considero que a resolu\u00e7\u00e3o de exerc\u00edcios foi um grande diferencial no meu processo de aprendizagem e na celeridade da aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Portugu\u00eas e inform\u00e1tica. Resolu\u00e7\u00e3o de exerc\u00edcios.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Estudo intenso tanto na semana como no dia que antecedeu a prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Li as aulas de reda\u00e7\u00e3o em PDF e estudei alguns temas pelo padr\u00e3o de resposta fornecido pelo professor, tamb\u00e9m em PDF. Indico reservar um tempo para leitura durante a semana, mas ao inv\u00e9s de somente ler, buscar identificar as t\u00e9cnicas utilizadas pelo escritor. Al\u00e9m disso, embora eu n\u00e3o tenha feito, jugo importante escrever uma reda\u00e7\u00e3o por semana.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua prepara\u00e7\u00e3o para o TAF e para as demais etapas?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Procurei ser diligente em todas as etapas. Cada fase do concurso trouxe seus pr\u00f3prios desafios. Alguns que, particularmente, julgo terem sido maiores que a fase objetiva\/reda\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Acertos: Estudar a lei seca e realiza\u00e7\u00e3o de muitas quest\u00f5es comentadas. Realiza\u00e7\u00e3o de quest\u00f5es da banca. N\u00e3o ter desistido, ainda que pelas circunst\u00e2ncias, essa aprova\u00e7\u00e3o parecesse improv\u00e1vel.&nbsp;<\/p>\n\n\n\n<p>Erros: Estabelecer metas irreais de acordo com a rotina de atribui\u00e7\u00f5es que eu tinha. Isso mais me frustrava do que me impulsionava. N\u00e3o aproveitei alguns momentos livres por um pensamento err\u00f4neo de que o pouco e o nada eram sin\u00f4nimos. N\u00e3o ter estudado bem os fundamentos do RLM quase custou a minha aprova\u00e7\u00e3o. N\u00e3o ter realizado revis\u00f5es regulares. N\u00e3o ter estudado todas as leis me custou algumas quest\u00f5es. Ter perdido tempo planejando e trocando de planejamento durante o estudo, sendo que j\u00e1 se tratava de reta final.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Sim, algumas. Primeiramente Jesus Cristo, se n\u00e3o fosse Ele, nada disso teria sido poss\u00edvel. Quando surgiram as in\u00fameras adversidades e elas surgem, o que me sustentou foi saber quem havia me confiado essa miss\u00e3o. Al\u00e9m do Senhor, minha amada esposa, que tem suportado todo o processo ao meu lado. Acreditou em mim nos dias bons e nos dias de ang\u00fastia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Leonardo: <\/strong>Organize sua vida e sua rotina. Honre seus familiares e seu emprego atual. Fa\u00e7a um plano de estudo realista, simples e o siga. V\u00e1 aperfei\u00e7oando com o passar dos dias. O imediatismo, muitas vezes, destr\u00f3i prop\u00f3sitos de vida. N\u00e3o negligencie a atividade f\u00edsica e o descanso, eles s\u00e3o aliados \u00e0 sua aprova\u00e7\u00e3o. Assim como o fogo serve para refinar o ouro, os dias dif\u00edceis surgem para provar a nossa paci\u00eancia e perseveran\u00e7a. Cuide da sua vida espiritual. Se cr\u00ea em Deus, consagre a Ele o seu sonho e os seus planos ser\u00e3o bem-sucedidos. Fa\u00e7a isso de todo o seu cora\u00e7\u00e3o, como para o Cristo, o Senhor, porque Dele vir\u00e1 a recompensa!\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Organize sua vida e sua rotina. Honre seus familiares e seu emprego atual. Fa\u00e7a um plano de estudos realista, simples e o siga. V\u00e1 aperfei\u00e7oando com o passar dos dias [&#8230;]&#8221; Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar&nbsp;no concurso&nbsp;SEJUSP-MG&nbsp;para o cargo de&nbsp;Policial Penal &#8211; Masculino: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1354256","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Leonardo dos Santos - Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Leonardo dos Santos - Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T19:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/02\/image-422-169x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/\",\"name\":\"ENTREVISTA: Leonardo dos Santos - Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/02\/image-422-169x300.png\",\"datePublished\":\"2024-02-19T19:13:28+00:00\",\"dateModified\":\"2024-02-19T19:13:30+00:00\",\"description\":\"Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422.png\",\"width\":519,\"height\":923},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Leonardo dos Santos &#8211; Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal &#8211; Masculino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Leonardo dos Santos - Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino","description":"Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Leonardo dos Santos - Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino","og_description":"Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2024-02-19T19:13:30+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/02\/image-422-169x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/","name":"ENTREVISTA: Leonardo dos Santos - Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/02\/image-422-169x300.png","datePublished":"2024-02-19T19:13:28+00:00","dateModified":"2024-02-19T19:13:30+00:00","description":"Confira nossa entrevista com Leonardo dos Santos, aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal - Masculino","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/02\/19142437\/image-422.png","width":519,"height":923},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-leonardo-dos-santos-aprovado-em-413-lugar-no-concurso-sejusp-mg-para-o-cargo-de-policial-penal-masculino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Leonardo dos Santos &#8211; Aprovado em 413\u00b0 lugar\u00a0no concurso\u00a0SEJUSP-MG\u00a0para o cargo de\u00a0Policial Penal &#8211; Masculino"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1354256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1354256\/revisions"}],"predecessor-version":[{"id":1354463,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1354256\/revisions\/1354463"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1354256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}