{"id":1318054,"date":"2023-12-08T12:22:24","date_gmt":"2023-12-08T15:22:24","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1318054"},"modified":"2023-12-11T11:02:34","modified_gmt":"2023-12-11T14:02:34","slug":"concurso-tce-to-aprovada-juliana-tomaz-sganzerla","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/","title":{"rendered":"ENTREVISTA: Juliana Tomaz Sganzerla &#8211; Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica &#8211; Odontologia"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-169x300.png\" alt=\"\" class=\"wp-image-1319228\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-169x300.png 169w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-576x1024.png 576w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-768x1365.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-864x1536.png 864w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-1152x2048.png 1152w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-610x1084.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143-150x267.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143.png 1290w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><figcaption class=\"wp-element-caption\">Juliana Tomaz Sganzerla <\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;O caminho precisa ser percorrido, o que precisamos \u00e9 encontrar meios que nos fa\u00e7am passar por ele com mais velocidade. Foi assim que o Estrat\u00e9gia me ajudou!&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico &#8211; Medicina:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-la. Qual a sua idade, forma\u00e7\u00e3o e cidade natal?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Juliana Tomaz Sganzerla: <\/strong>Sou ga\u00facha, natural de Bento Gon\u00e7alves. Atualmente tenho 35 anos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Conte o in\u00edcio da sua trajet\u00f3ria, o que te levou a iniciar os estudos para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Iniciei os estudos para o concurso quando eu estava no \u00faltimo ano da gradua\u00e7\u00e3o, em 2016. Prestei meu primeiro concurso e obtive a 17\u00aa coloca\u00e7\u00e3o. Era apenas uma vaga e n\u00e3o fui aprovada, por\u00e9m, me senti feliz, pois eram mais de 100 candidatos e eu n\u00e3o havia nem terminado a gradua\u00e7\u00e3o ainda e tamb\u00e9m n\u00e3o havia me preparado de forma intensiva para o concurso. Isso foi a motiva\u00e7\u00e3o para ir em busca de outros concursos e focar na prepara\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como voc\u00ea conheceu o Estrat\u00e9gia Concursos e porque tomou a decis\u00e3o de se tornar nosso aluno?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Conheci o Estrat\u00e9gia pela internet, fazendo buscas de preparat\u00f3rios. Ao entrar no site, verifiquei a grande quantidade de material dispon\u00edvel para estudo e como o material era organizado de forma espec\u00edfica para cada concurso. Considerei isso um fator muito importante, pois eu n\u00e3o precisaria perder tempo juntando material, bastaria focar nos estudos.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua rotina e plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Durante minha prepara\u00e7\u00e3o, n\u00e3o deixei de trabalhar, ent\u00e3o utilizei o tempo que eu tinha dispon\u00edvel (f\u00e9rias, noites e finais de semana). Durante as f\u00e9rias, eram em torno de 8h por dia e eu focava em uma ou duas mat\u00e9rias por dia. Ap\u00f3s o t\u00e9rmino das f\u00e9rias, foquei em estudar a noite (em torno de 2h por dia) e as disciplinas que eu sabia que tinha um &#8220;<em>gap<\/em>&#8221; maior de conhecimento e que tamb\u00e9m seriam as mais dif\u00edceis para os meus concorrentes. No caso da Odontologia, as \u00e1reas de direito e portugu\u00eas sempre s\u00e3o um desafio, ent\u00e3o foquei nelas. Pois, como sou professora de gradua\u00e7\u00e3o, meu conhecimento espec\u00edfico j\u00e1 estava mais consolidado.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Conforme descrevi acima, estudava \u00e0 noite 2h por noite e aos finais de semana, em torno de 6h por dia. Focando nas disciplinas que eu sabia ter maior dificuldade.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais ferramentas do Estrat\u00e9gia voc\u00ea mais utilizou em sua prepara\u00e7\u00e3o e quais eram os diferenciais de cada?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>O preparat\u00f3rio que adquiri n\u00e3o tinha a Trilha, eu a considero uma ferramenta superinteressante, mas utilizei muito as videoaulas e o estudo baseado em quest\u00f5es.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Foram 3 meses de prepara\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Portugu\u00eas e Direito foram as que eu apresentei maior dificuldade. Como eu j\u00e1 vinha me preparando h\u00e1 algum tempo para outros concursos, consegui me destacar no portugu\u00eas e fiz uma excelente prova (acertei 80% da prova da FGV). J\u00e1 o direito n\u00e3o consegui um desempenho t\u00e3o bom mas os acertos da \u00e1rea espec\u00edfica e do portugu\u00eas acabaram compensando.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual sua estrat\u00e9gia de reta final?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Na reta final foquei no estudo por quest\u00f5es e na revis\u00e3o de v\u00e9spera. Foi um grande diferencial, pois consegui garantir pelo menos umas 8 quest\u00f5es.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi a sua rotina de estudos para esta importante fase do certame?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>A discursiva foi o que me colocou em primeiro lugar no concurso. Eu havia ficado na 5\u00aa coloca\u00e7\u00e3o nas objetivas, por\u00e9m quase fechei as discursivas e ganhei uma pontua\u00e7\u00e3o excelente, me jogando para a primeira coloca\u00e7\u00e3o. A prepara\u00e7\u00e3o para a discursiva, na minha opini\u00e3o, necessita um tempo maior e uma bagagem de conhecimento mais elevada. Isso foi constru\u00eddo durante minha trajet\u00f3ria acad\u00eamica e de p\u00f3s-gradua\u00e7\u00e3o. Sempre tive o costume de escrever e estudar os conte\u00fados de forma mais integralizada, fazendo conex\u00f5es entre as diversas \u00e1reas da odontologia. Isso, certamente, foi o meu diferencial para conseguir compreender o que estava sendo perguntado e elaborar respostas com conte\u00fado relevante e de forma clara e objetiva. Recomendo aos candidatos que treinem a escrita de forma cont\u00ednua para conseguirem um bom desempenho. Al\u00e9m disso, muitos concorrentes deixaram a discursiva em branco. Eu observei enquanto aguardava o tempo para sair da prova com o caderno de quest\u00f5es. No edital do concurso estava claro que quem n\u00e3o atingisse 50% de acerto na discursiva estaria eliminado. Ou seja, ler o edital antes de se submeter a um concurso \u00e9 essencial, pois de nada adiantou muitos dos meus concorrentes terem dedicado tempo \u00e0s objetivas e entregado a prova sem responder as discursivas, pois j\u00e1 estavam eliminados.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casada? Tem filhos? De que forma sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Na \u00e9poca do concurso eu estava em um relacionamento, hoje j\u00e1 n\u00e3o estou mais, sou solteira e n\u00e3o tenho filhos. Mas meu namorado na \u00e9poca era super compreensivo e me apoiava nos estudos. Isso foi bem importante!<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a sensa\u00e7\u00e3o de ter sido convidada para o Baile dos Primeiros do Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Estar no baile \u00e9 a coroa\u00e7\u00e3o de toda essa caminhada. \u00c9 sentir que voc\u00ea chegou no topo da montanha. \u00c9 olhar para tr\u00e1s, para toda a sua caminhada (que n\u00e3o foi apenas a prepara\u00e7\u00e3o do concurso, mas o caminho que escolhi percorrer desde o dia que inicie a gradua\u00e7\u00e3o) e ver que valeu a pena!<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Durante sua prepara\u00e7\u00e3o, ouviu falar sobre o Baile dos Primeiros? Imaginou que um dia estaria nesta confraterniza\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Eu n\u00e3o conhecia o Baile dos Primeiros e tamb\u00e9m n\u00e3o sabia que o Estrat\u00e9gia chamava para essas entrevistas, mas quando fui convidada me senti lisonjeada, muito feliz e emocionada.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Se eu tivesse que refazer o caminho, focaria um pouco mais na \u00e1rea do direito, pois acredito que mesmo tendo estudado, n\u00e3o foi o suficiente. Sabia, desde o in\u00edcio, que seriam quest\u00f5es que poderiam me diferenciar dos demais concorrentes. Apostaria mais nelas.&nbsp;<\/p>\n\n\n\n<p>Os grandes acertos foram em construir um conhecimento s\u00f3lido, sem buscar atalhos. Preparar-se demanda tempo, agregar conhecimento demanda tempo. E essa parte do processo precisa ser entendida para que n\u00e3o fiquemos frustrados diante das reprova\u00e7\u00f5es. Afinal todos passamos por elas at\u00e9 chegarmos ao t\u00e3o sonhado primeiro lugar.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? O que voc\u00ea diria para a sua vers\u00e3o de 5 anos atr\u00e1s?<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Sim, estudar para concurso \u00e9 um caminho incerto. Temos a expectativa, por\u00e9m, nenhuma certeza. Por muitas vezes achei que n\u00e3o teria capacidade, mas hoje olho para tr\u00e1s e me orgulho. Se pudesse ter um papo comigo mesma diria que a const\u00e2ncia \u00e9 mais importante do que a intensidade dos estudos. Al\u00e9m disso, diria que a paci\u00eancia nos faz chegar mais longe.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, deixe sua mensagem para todos aqueles que est\u00e3o come\u00e7ando e almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Juliana: <\/strong>Gosto de uma frase de uma m\u00fasica que diz o seguinte <em>\u201cN\u00e3o deixe que os problemas acabem com o seu sono, mas deixe o sono vir quando for para voc\u00ea sonhar\u201d<\/em>. Ou seja, n\u00e3o perca tempo olhando para o tamanho da montanha, para a lista de concorrentes, para a imensid\u00e3o do edital, mas se permita sonhar e utilize esse sonho como o combust\u00edvel para ir vencendo um dia por vez. Nem sempre conseguiremos vencer todo o edital, seja estrat\u00e9gico. Estude o que voc\u00ea tem mais dificuldade e o que voc\u00ea sabe que ir\u00e1 lhe diferenciar dos demais. Seja diferente dos iguais e tenha paci\u00eancia, n\u00e3o desista! Aprova\u00e7\u00e3o em concurso \u00e9 igual uma fila. A sua hora vai chegar, por\u00e9m, muitas vezes \u00e9 necess\u00e1rio aguardar algumas pessoas que est\u00e3o \u00e0 sua frente chegarem primeiro. Estrat\u00e9gia de estudo nos ajuda a ganhar velocidade, por\u00e9m, n\u00e3o pode ser usada para encurtar o caminho. O caminho precisa ser percorrido, o que precisamos \u00e9 encontrar meios que nos fa\u00e7a passar por ele com mais velocidade. Foi assim que o Estrat\u00e9gia me ajudou!&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O caminho precisa ser percorrido, o que precisamos \u00e9 encontrar meios que nos fa\u00e7am passar por ele com mais velocidade. Foi assim que o Estrat\u00e9gia me ajudou!&#8221; Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico &#8211; Medicina: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1318054","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Juliana Tomaz Sganzerla - Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica - Odontologia<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico - Medicina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Juliana Tomaz Sganzerla - Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica - Odontologia\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico - Medicina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-11T14:02:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/12\/image-143-169x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/\",\"name\":\"ENTREVISTA: Juliana Tomaz Sganzerla - Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica - Odontologia\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/12\/image-143-169x300.png\",\"datePublished\":\"2023-12-08T15:22:24+00:00\",\"dateModified\":\"2023-12-11T14:02:34+00:00\",\"description\":\"Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico - Medicina.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143.png\",\"width\":1290,\"height\":2293},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Juliana Tomaz Sganzerla &#8211; Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica &#8211; Odontologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Juliana Tomaz Sganzerla - Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica - Odontologia","description":"Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico - Medicina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Juliana Tomaz Sganzerla - Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica - Odontologia","og_description":"Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico - Medicina.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-12-11T14:02:34+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/12\/image-143-169x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/","name":"ENTREVISTA: Juliana Tomaz Sganzerla - Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica - Odontologia","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/12\/image-143-169x300.png","datePublished":"2023-12-08T15:22:24+00:00","dateModified":"2023-12-11T14:02:34+00:00","description":"Confira nossa entrevista com Juliana Tomaz Sganzerla, aprovada em 2\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnico - Medicina.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11104029\/image-143.png","width":1290,"height":2293},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tce-to-aprovada-juliana-tomaz-sganzerla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Juliana Tomaz Sganzerla &#8211; Aprovada em 1\u00ba lugar no concurso TCE-TO para o cargo de Analista T\u00e9cnica &#8211; Odontologia"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1318054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":13,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1318054\/revisions"}],"predecessor-version":[{"id":1319279,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1318054\/revisions\/1319279"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1318054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}