{"id":1271232,"date":"2023-09-02T09:19:43","date_gmt":"2023-09-02T12:19:43","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?post_type=depoimento&#038;p=1271232"},"modified":"2023-09-04T09:19:48","modified_gmt":"2023-09-04T12:19:48","slug":"concurso-gcm-fortaleza-aprovada-milena-machado-costa","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/","title":{"rendered":"ENTREVISTA: Milena Machado Costa &#8211; Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">.<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" class=\"wp-image-1273240\" style=\"width: 200px;\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg\" alt=\"\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg 655w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1-300x300.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1-150x150.jpeg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1-610x610.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1-96x96.jpeg 96w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>&#8220;Meu conselho \u00e9 escolher uma \u00e1rea para se dedicar, n\u00e3o desviar o foco dela e a cada reprova\u00e7\u00e3o avaliar onde precisamos ajustar e quais mat\u00e9rias devemos dar uma maior aten\u00e7\u00e3o [&#8230;]&#8221;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira nossa entrevista com Milena Machado Costa, aprovada no concurso&nbsp;da&nbsp;Guarda Municipal de Fortaleza:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-la. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena Machado Costa: <\/strong>Me chamo Milena Machado e sou engenheira civil por forma\u00e7\u00e3o. Tenho 25 anos e nasci em Fortaleza, no Cear\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Os exemplos que eu tenho na fam\u00edlia, pois a maioria dos meus tios s\u00e3o concursados e dentro de casa tenho como exemplo o meu pai, ex-concurseiro, que tamb\u00e9m j\u00e1 conseguiu algumas aprova\u00e7\u00f5es. Juntamente com a crise na constru\u00e7\u00e3o civil e a consequente desvaloriza\u00e7\u00e3o dos engenheiros atuantes na \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Nos primeiros concursos que fiz ainda trabalhava, fazia faculdade e era muito inexperiente, n\u00e3o conseguindo lograr \u00eaxito nesses certames. No final de 2021 fiquei desempregada e me vi em uma situa\u00e7\u00e3o complicada, pois a constru\u00e7\u00e3o civil na regi\u00e3o onde eu estava morando estava muito parada e a \u00fanica forma de voltar a trabalhar logo seria passando em um concurso. Foi a\u00ed que me organizei, arregacei as mangas e enfrentei um ano e meio de estudos integrais at\u00e9 uma aprova\u00e7\u00e3o dentro das vagas imediatas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovada? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Consegui algumas aprova\u00e7\u00f5es, fora das vagas, no concurso da Assistente\/secret\u00e1rio escolar SEMED-Macei\u00f3 (2017) \u2013 3196\u00b0, Assistente em administra\u00e7\u00e3o UFRJ (2022) \u2013 42\u00b0, Fiscal de obras \u2013 Prefeitura de Aperib\u00e9 (2022) \u2013 12\u00b0. E aprovada dentro das vagas no concurso da Guarda Municipal de Fortaleza (2023) \u2013 260\u00b0. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pretendo continuar estudando, mas agora para concursos no \u00e2mbito federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Minha vida social mudou drasticamente, pois fiquei desempregada e onde eu estava morando n\u00e3o conseguia um emprego na minha \u00e1rea de forma\u00e7\u00e3o, ent\u00e3o aproveitei que estava morando com meus pais e enquanto procurava emprego, estudava para concursos. Como estava morando em uma nova cidade e distante dos meus amigos, foquei 100% nos estudos e diminu\u00ed muito minhas horas de lazer, porque de alguma forma eu queria encurtar o caminho at\u00e9 a aprova\u00e7\u00e3o. \u00c9 doloroso, solit\u00e1rio, mas vale a pena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseira? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Meus pais foram essenciais para que essa aprova\u00e7\u00e3o fosse conquistada, sempre me apoiaram e seguraram as pontas quando fiquei desempregada e virei concurseira em tempo integral. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alguns amigos meus entenderam sim, outros n\u00e3o, pois queriam me ver atuando na \u00e1rea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Eu j\u00e1 vinha estudando para \u00e1rea policial h\u00e1 um ano e meio, fiz algumas provas onde n\u00e3o consegui aprova\u00e7\u00e3o. No final de 2022 fiquei sabendo dos boatos que haveria o concurso da GMF na minha cidade natal, ent\u00e3o, quando saiu o edital, foquei nas mat\u00e9rias espec\u00edficas que ainda n\u00e3o tinha visto e revisei o que j\u00e1 vinha estudando. O que me fez manter a disciplina foi ter uma rotina de estudos, e ver minha evolu\u00e7\u00e3o nos simulados me animava muito.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Sempre preferi escrever, fazer meus resumos, ent\u00e3o assistia as videoaulas e ia preparando meu pr\u00f3prio material.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Atrav\u00e9s do meu pai, que j\u00e1 foi concurseiro. Ele tamb\u00e9m conseguiu aprova\u00e7\u00e3o atrav\u00e9s de materiais do Estrat\u00e9gia h\u00e1 alguns anos atr\u00e1s.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Sim, usei materiais de outro cursinho. O que mais me incomodava era a demora para as aulas serem postadas e o material que, em algumas disciplinas, era superficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>N\u00e3o fiz prova durante esse per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Senti uma grande diferen\u00e7a sim. Os materiais do Estrat\u00e9gia s\u00e3o muito completos e bastante aprofundados, o que acho essencial para formar uma boa base, independente da \u00e1rea pra qual voc\u00ea estuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como montou seu plano de estudos?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Eu n\u00e3o tinha um plano de estudos certinho. De acordo com o edital que eu estava focando eu reorganizei meu hor\u00e1rio, mas sempre estudava um assunto de tr\u00eas mat\u00e9rias diferentes por dia, resolvendo quest\u00f5es no fim do dia. E revezava com um dia de videoaula e \u201cconfec\u00e7\u00e3o\u201d dos meus resumos, at\u00e9 fechar o edital e ficar somente revisando os tr\u00eas assuntos de tr\u00eas mat\u00e9rias diferentes todo dia. E no fim de semana resolvia simulados e quest\u00f5e<strong>s.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Revisava lendo meus resumos, resolvendo quest\u00f5es e simulados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Resolver quest\u00f5es ajuda a fixar os assuntos e conhecer o estilo de cobran\u00e7a da banca. Fiz mais 8 mil quest\u00f5es durante esse um ano e meio de estudos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>No in\u00edcio dos meus estudos eu n\u00e3o tinha nenhuma no\u00e7\u00e3o em direito e, sem d\u00favidas, eram as mat\u00e9rias que eu mais tinha dificuldade. Assisti todas as videoaulas dessas mat\u00e9rias, montei meus resumos e resolvi muitas quest\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Resolvendo muitas quest\u00f5es, simulados e revisando o assunto que eu ainda estava errando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Meu principal erro foi n\u00e3o focar em apenas uma \u00e1rea de estudos e sair fazendo v\u00e1rias provas com assuntos bastante distintos, no in\u00edcio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meu principal acerto foi investir em um curso direcionado, como o Estrat\u00e9gia, e uma plataforma de quest\u00f5es com um bom banco de quest\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>A inseguran\u00e7a do mundo dos concursos nos acompanha diariamente, o que nos faz duvidar da nossa capacidade de conseguir aprova\u00e7\u00e3o. Pensei em desistir v\u00e1rias vezes, mas o fato de a cada reprova\u00e7\u00e3o eu ver que eu estava mais pr\u00f3ximo de conseguir a t\u00e3o sonhada aprova\u00e7\u00e3o dentro das vagas imediatas, me fez continuar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milena: <\/strong>Meu conselho \u00e9 escolher uma \u00e1rea para se dedicar, n\u00e3o desviar o foco dela e a cada reprova\u00e7\u00e3o avaliar onde precisamos ajustar e quais mat\u00e9rias devemos dar uma maior aten\u00e7\u00e3o. A mensagem que deixo \u00e9 um pouco clich\u00ea, mas s\u00f3 n\u00e3o passa quem desiste, ent\u00e3o precisamos ter f\u00e9 e paci\u00eancia que uma hora d\u00e1 certo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>. &#8220;Meu conselho \u00e9 escolher uma \u00e1rea para se dedicar, n\u00e3o desviar o foco dela e a cada reprova\u00e7\u00e3o avaliar onde precisamos ajustar e quais mat\u00e9rias devemos dar uma maior aten\u00e7\u00e3o [&#8230;]&#8221; Confira nossa entrevista com Milena Machado Costa, aprovada no concurso&nbsp;da&nbsp;Guarda Municipal de Fortaleza: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1271232","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Milena Machado Costa - Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista na \u00edntegra com Milena Machado Costa, aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Milena Machado Costa - Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista na \u00edntegra com Milena Machado Costa, aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T12:19:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/\",\"name\":\"ENTREVISTA: Milena Machado Costa - Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/08\\\/02091913\\\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg\",\"datePublished\":\"2023-09-02T12:19:43+00:00\",\"dateModified\":\"2023-09-04T12:19:48+00:00\",\"description\":\"Confira nossa entrevista na \u00edntegra com Milena Machado Costa, aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/08\\\/02091913\\\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/08\\\/02091913\\\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Milena Machado Costa &#8211; Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Milena Machado Costa - Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0","description":"Confira nossa entrevista na \u00edntegra com Milena Machado Costa, aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Milena Machado Costa - Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0","og_description":"Confira nossa entrevista na \u00edntegra com Milena Machado Costa, aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-09-04T12:19:48+00:00","og_image":[{"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/","name":"ENTREVISTA: Milena Machado Costa - Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg","datePublished":"2023-09-02T12:19:43+00:00","dateModified":"2023-09-04T12:19:48+00:00","description":"Confira nossa entrevista na \u00edntegra com Milena Machado Costa, aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/02091913\/whatsapp-image-2023-08-30-at-15-52-15-1.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-gcm-fortaleza-aprovada-milena-machado-costa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Milena Machado Costa &#8211; Aprovada no concurso\u00a0da\u00a0Guarda Municipal de Fortaleza\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1271232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1271232\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1271232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}