{"id":1267051,"date":"2023-09-01T11:15:42","date_gmt":"2023-09-01T14:15:42","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1267051"},"modified":"2023-09-01T11:52:29","modified_gmt":"2023-09-01T14:52:29","slug":"concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/","title":{"rendered":"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves &#8211; Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220-300x221.png\" alt=\"\" class=\"wp-image-1267054\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220-300x221.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220-1024x754.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220-768x565.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220-610x449.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220-150x110.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220.png 1170w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">V\u00edtor Jorge Santos Vieira Alves<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;Sobre todos que foram aprovados: nenhum deles iniciou sabendo tudo.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado em 99\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;da&nbsp;Receita Federal do Brasil&nbsp;para o cargo de&nbsp;Analista-Tribut\u00e1rio:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor Jorge Santos Vieira Alves: <\/strong>Sou nascido e criado em Niter\u00f3i, no Rio de Janeiro, e me formei em Direito, em 2022.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Eu estava bem perdido quando me formei, n\u00e3o tinha certeza se iria querer o servi\u00e7o p\u00fablico. Decidi estudar enquanto esperava a carteira da OAB ser expedida, para ver como seria. Minha fam\u00edlia tamb\u00e9m me incentivou.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Sim, eu era advogado. Trabalhava de forma aut\u00f4noma, ent\u00e3o quando vi que iria seguir o caminho dos concursos eu pude diminuir o tempo destinado ao trabalho.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Fui aprovado fora das vagas imediatas em outros concursos, o PGM Niter\u00f3i e a PGE Rio de Janeiro, para Analista Processual, e o da Agenarsa, para Analista t\u00e9cnico. <\/p>\n\n\n\n<p>Analista da Receita Federal foi o primeiro em que passei dentro das vagas. <\/p>\n\n\n\n<p>Sobre continuar estudando, sim! Estou me preparando pra Fiscal de Rendas do munic\u00edpio do Rio de Janeiro, quase n\u00e3o parei depois da prova da Receita. Continuo porque Fiscal de Rendas (ou Auditor Fiscal) \u00e9 o cargo que quero realmente. Tentei para Analista na Receita Federal porque j\u00e1 estava de olho nos fiscos e sabia que ter\u00edamos os do Rio em breve, municipal e estadual, e tamb\u00e9m queria mais tempo para estudar para Auditor Fiscal, eu me achava muito iniciante para o cargo na \u00e9poca.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Era bem limitada, principalmente depois que saiu o edital. Eu sa\u00eda bem pouco com amigos, evitava sair tarde para manter o sono regrado. Tamb\u00e9m mal visitava os familiares, mas eles entendiam o motivo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Minha fam\u00edlia me apoiou bastante, foi por causa deles que eu pude manter os estudos em primeiro plano, sem tanta preocupa\u00e7\u00e3o no trabalho. Meus amigos tamb\u00e9m, eles entendiam que minha vida social estava limitada na \u00e9poca.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Estudei uns 10 meses com foco no concurso da Receita.<\/p>\n\n\n\n<p>Sobre a disciplina, a virada de chave pra mim foi \u2014 e eu comecei a fazer isso em meados de janeiro \u2014 ir estabelecendo um cronograma para os estudos. Baixei um daqueles apps de afazeres e comecei a, toda semana, preencher os dias com o que ia estudar, as mat\u00e9rias, os assuntos, se era leitura de mat\u00e9ria nova ou revis\u00e3o, colocava tudo ali e o app me avisava. Ter esse cronograma e essas metas di\u00e1rias me ajudava a manter a disciplina.<\/p>\n\n\n\n<p>Outra coisa que me ajudou foi ter o concurso da Receita como prioridade, mas me empenhando para fazer outros ao longo do caminho. Isso porque foi bom para mim ter esses outros concursos que iam saindo \u2014 o PGE Rio de Janeiro, o do Senado \u2014 como minhas metas de curto prazo, ao inv\u00e9s de ficar focado s\u00f3 no da Receita, que na \u00e9poca que eu comecei a estudar n\u00e3o tinha nem sido autorizado, e \u00e9 mais dif\u00edcil manter a disciplina para algo assim de longo prazo. Ent\u00e3o eu fui me disciplinando a cada concurso, me acostumando a manter a disciplina. E isso, \u00e9 claro, me ajudava tamb\u00e9m pela experi\u00eancia de fazer as provas e notar minhas fraquezas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Quando eu comecei, eu n\u00e3o tinha assinatura, ent\u00e3o estudava principalmente por provas recentes (CGU e TCU, na \u00e9poca). Quando assinei o Estrat\u00e9gia eu comecei preferindo as videoaulas, porque era como eu tinha aulas na faculdade, ent\u00e3o achei que seria melhor por eu j\u00e1 estar acostumado. O problema \u00e9 que as videoaulas demoram bastante, e eu notei isso quando passei a priorizar os pdf\u2019s, percebia que era bem mais eficiente.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>J\u00e1 havia ouvido falar, fui conhecer mesmo quando estudava para a OAB, porque lia os artigos sobre o exame, sobre estrat\u00e9gia de prova e os temas mais cobrados, e via os v\u00eddeos do Youtube comentando as provas passadas, principalmente sobre as discursivas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Antes do Estrat\u00e9gia eu estudava por minha conta, com quest\u00f5es de provas atuais e o que tinha de conte\u00fado gratuito na internet. Eu aprendi algumas coisas, mas era bem ineficiente. Assim que foi autorizado o concurso da Receita eu assinei o Estrat\u00e9gia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Fui aprovado na PGE Rio de Janeiro, fora das vagas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Gostei bastante do material, o material escrito \u00e9 bem completo, e o fato de ter quest\u00f5es logo ali no pdf facilitava muito a revis\u00e3o. Depois que eu comecei a estudar por pdf\u2019s, n\u00e3o abandonei as videoaulas: v\u00e1rias eram boas para revis\u00e3o, pelo fato dos professores pegarem quest\u00f5es bem recentes e entrarem em detalhes sobre os pontos mais complexos. Das videoaulas, acho que as da Nelma Fontana e Adriana Figueiredo foram as que mais assisti.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Em janeiro que eu comecei com um plano de estudos organizado, e eu estudava umas cinco, seis mat\u00e9rias novas por semana, deixando outras para revis\u00e3o. Escolhia as mat\u00e9rias com base no peso e na complexidade, e tamb\u00e9m controlava de semana a semana \u2014 se eu passasse uma semana sem estudar ou revisar uma mat\u00e9ria, na seguinte eu j\u00e1 fixava ela na grade. Sobre o tempo, eu estudava todos os dias, por cerca de cinco horas l\u00edquidas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>No come\u00e7o eu fazia resumindo as mat\u00e9rias e lendo os resumos. \u201cFuncionou at\u00e9 aqui, mudar pra qu\u00ea?\u201d, eu pensava, mas isso era super ineficiente! N\u00e3o sei se passaria se continuasse assim. O que passei a fazer \u2014 e o que fa\u00e7o atualmente \u2014 \u00e9 resolver muitas quest\u00f5es, s\u00f3 \u201cresumindo&#8221; aqueles pontos que eu via que: a) ca\u00edam bastante; e b) eu tinha dificuldade. <\/p>\n\n\n\n<p>Fiz simulados tamb\u00e9m, para me preparar para as nove horas de prova e para a quest\u00e3o discursiva.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>O Sistema de Quest\u00f5es de voc\u00eas me disse que fiz 3.595 at\u00e9 a data da prova. Isso, somado \u00e0s listas, simulados, provas anteriores etc. deve dar quase o dobro, e com certeza foi o que mais me ajudou a me preparar. Saber o que e como \u00e9 cobrado e saber suas fraquezas foi essencial.<\/p>\n\n\n\n<p>Antes de estudar para concursos eu n\u00e3o sabia que jurisprud\u00eancia era t\u00e3o cobrada, por exemplo, e em mat\u00e9rias muito amplas, com muitos detalhes \u2014 Contabilidade, os ramos do Direito, Portugu\u00eas \u2014 \u00e9 essencial saber em que se deve focar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Tecnologia da Informa\u00e7\u00e3o, apelidada Flu\u00eancia em Dados, sem d\u00favida foi o maior desafio, v\u00e1rias coisas ali eu n\u00e3o assimilava. Nesta minha prepara\u00e7\u00e3o foi bem deficiente, deixei de lado alguns pontos do edital e foquei nos que achei mais vi\u00e1veis. Tinha coisa ali que eu sabia que, com o tempo, eu pegaria, mas me tomaria muito tempo, ent\u00e3o guardei essa energia para outras mat\u00e9rias que tamb\u00e9m valiam muitos pontos e nas quais meu aproveitamento era melhor. <\/p>\n\n\n\n<p>Tenho que mencionar tamb\u00e9m a Contabilidade, que acho que foi a que mais demorei a assimilar. Para ela, precisei reservar bastante tempo, e toda semana ver um assunto novo e revisar os passados, s\u00f3 assim para eu come\u00e7ar a me familiarizar com a mat\u00e9ria.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Na semana anterior, algo que me ajudou muito foi ir ajustando meu fuso hor\u00e1rio. Para ir fazer a prova eu acordei \u00e0s 5h20, bem mais cedo que eu normalmente acordava, ent\u00e3o fui adiantado aos poucos o despertador durante essa semana. Isso me ajudou bastante a me mantar descansado e alerta para a prova inteira. <\/p>\n\n\n\n<p>Sobre os estudos, praticamente s\u00f3 fiz quest\u00f5es e revi meus erros de provas passadas. Deixei para revisar nessa \u00faltima semana os t\u00f3picos mais importantes de cada mat\u00e9ria, para tirar proveito da mem\u00f3ria de curto prazo. Tinha v\u00e1rios pontos do edital que eu n\u00e3o tinha tido tempo de estudar, o que me deixava apreensivo, mas deixei assim mesmo e priorizei essas revis\u00f5es. Fui num ritmo bem intenso at\u00e9 a quinta-feira, depois priorizei o descanso para chegar bem para fazer a prova.<\/p>\n\n\n\n<p>No s\u00e1bado nem toquei no material. Talvez eu tenha perdido alguma quest\u00e3o por n\u00e3o ter revisado algum ponto no \u00faltimo minuto, mas n\u00e3o me arrependo. Ganhei bem mais por estar relaxado e descansado para fazer as provas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Eu fiz quest\u00f5es de provas anteriores, de simulados, mas tamb\u00e9m escolhia alguns temas e discorria sobre eles num certo tempo, detalhando o m\u00e1ximo que podia. Acho que isso \u00e9 bem \u00fatil, porque te faz notar se voc\u00ea de fato sabe o tema: se, fora do conforto de uma objetiva, voc\u00ea consegue lembrar de todos os detalhes por si s\u00f3. Tamb\u00e9m priorizei o que era mais condizente com o cargo: Direito Tribut\u00e1rio, Legisla\u00e7\u00e3o Tribut\u00e1ria Federal e Legisla\u00e7\u00e3o Aduaneira.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Os maiores erros foram n\u00e3o ter mantido desde o in\u00edcio \u2014 por in\u00edcio, leia-se a autoriza\u00e7\u00e3o do concurso \u2014 um plano de estudos bem estruturado, e n\u00e3o ter logo come\u00e7ado no combo pdf\u2019s + quest\u00f5es. Perdi bastante tempo com os resumos e notei que l\u00ea-los nem foi uma revis\u00e3o efetiva. <\/p>\n\n\n\n<p>Quanto aos acertos, manter um cronograma di\u00e1rio constante, com hora para acordar e para dormir, e ajustar meu hor\u00e1rio de acordar na semana da prova. Tamb\u00e9m me ajudou bastante fazer uma prova \u2014a de Analista da Agenarsa \u2014 logo antes dessa da Receita, para eu recapitular a din\u00e2mica de ir fazer prova e ver o que a banca estava cobrando na \u00e9poca. S\u00f3 acertei uma quest\u00e3o de portugu\u00eas na Receita porque tinha visto o mesmo estilo de enunciado nessa outra prova. Tamb\u00e9m acho que tirar os dias anteriores para descansar me ajudou muito, vi muito mais aproveitamento nas quest\u00f5es em que tive d\u00favida do que em outros momentos, quando estava naquele ritmo incessante.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Ambi\u00e7\u00e3o, muita vontade de conseguir o que eu queria e confian\u00e7a de que eu era capaz de consegui-lo, foi isso que me manteve ali firme. <\/p>\n\n\n\n<p>Sobre desistir, assim que comecei a estudar para concursos e comecei o ver o n\u00edvel que era exigido, principalmente pela FGV, pensei que n\u00e3o conseguiria, que aquilo ali n\u00e3o era pra mim. Mas, com apoio dos familiares, segui nesse caminho, e a cada tema que aprendia me tornava mais confiante.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>V\u00edtor: <\/strong>Aconselharia a n\u00e3o se desanimar ao olhar a quantidade de mat\u00e9rias que ainda precisam aprender. Sobre todos que foram aprovados: nenhum deles iniciou sabendo tudo. Quando a gente olha, l\u00e1 no come\u00e7o, parece inalcan\u00e7\u00e1vel, mas com o tempo, se dedicando chegamos l\u00e1. Al\u00e9m disso, n\u00e3o desanimar com os momentos em que seu desempenho n\u00e3o foi t\u00e3o bom: o percurso n\u00e3o \u00e9 progresso constante, vai ter os altos e baixos, os detalhes esquecidos, tudo isso faz parte da prepara\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Sobre todos que foram aprovados: nenhum deles iniciou sabendo tudo.&#8221; Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado em 99\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;da&nbsp;Receita Federal do Brasil&nbsp;para o cargo de&nbsp;Analista-Tribut\u00e1rio: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal? V\u00edtor Jorge Santos Vieira Alves: [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1267051","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves - Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para\u00a0Analista-Tribut\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves - Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para\u00a0Analista-Tribut\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T14:52:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/image-220-300x221.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/\",\"name\":\"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves - Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/image-220-300x221.png\",\"datePublished\":\"2023-09-01T14:15:42+00:00\",\"dateModified\":\"2023-09-01T14:52:29+00:00\",\"description\":\"Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para\u00a0Analista-Tribut\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220.png\",\"width\":1170,\"height\":861},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves &#8211; Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves - Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio","description":"Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para\u00a0Analista-Tribut\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves - Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio","og_description":"Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para\u00a0Analista-Tribut\u00e1rio.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-09-01T14:52:29+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/image-220-300x221.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/","name":"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves - Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/image-220-300x221.png","datePublished":"2023-09-01T14:15:42+00:00","dateModified":"2023-09-01T14:52:29+00:00","description":"Confira nossa entrevista com V\u00edtor Jorge Santos Vieira Alves, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para\u00a0Analista-Tribut\u00e1rio.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/21194708\/image-220.png","width":1170,"height":861},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-vitor-jorge-santos-vieira-alves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: V\u00edtor Jorge Santos Vieira Alves &#8211; Aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1267051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1267051\/revisions"}],"predecessor-version":[{"id":1272616,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1267051\/revisions\/1272616"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1267051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}