{"id":1264468,"date":"2023-08-17T11:37:35","date_gmt":"2023-08-17T14:37:35","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1264468"},"modified":"2023-08-17T11:53:09","modified_gmt":"2023-08-17T14:53:09","slug":"concurso-rfb-aprovado-henrique-sella-kerst","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/","title":{"rendered":"ENTREVISTA: Henrique Sella Kerst &#8211; Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020-169x300.jpg\" alt=\"\" class=\"wp-image-1264469\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020-169x300.jpg 169w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020-576x1024.jpg 576w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020-610x1084.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020-150x267.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020.jpg 729w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><figcaption class=\"wp-element-caption\">Henrique Sella Kerst<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;N\u00e3o h\u00e1 nada melhor do que ser aprovado! N\u00e3o desista.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Henrique Sella Kerst, aprovado em 260\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;da&nbsp;Receita Federal do Brasil&nbsp;para o cargo de&nbsp;Analista-Tribut\u00e1rio:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Henrique Sella Kerst: <\/strong>Sou de Londrina, Paran\u00e1. Tenho 29 anos e sou formado em engenharia civil pela Universidade Estadual de Londrina.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>N\u00e3o me encontrei na profiss\u00e3o de engenharia. Avaliei minhas op\u00e7\u00f5es e vi meu perfil como funcion\u00e1rio p\u00fablico. Foi quando iniciei minha jornada em 2018, fazendo meu primeiro concurso: Agente da Pol\u00edcia Federal.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Trabalhava como engenheiro civil, mas fui parando conforme meus resultados melhoravam.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Quando comecei a estudar, coloquei como meta ser Auditor Fiscal da Receita Federal. Como eu n\u00e3o conseguia estudar fora de editais e n\u00e3o sabia quando sairia o certame, fui fazendo concursos de mat\u00e9rias relacionadas, gra\u00e7as a assinatura ilimitada do Estrat\u00e9gia. Nessa jornada fui aprovado nos seguintes concursos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>AUXILIAR ADM CRP PR 2019 &#8211; 1\u00ba lugar CR, nunca fui chamado;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>COORDENADOR CENSIT\u00c1RIO IBGE LONDRINA 2020 &#8211; 5\u00ba lugar, onde trabalhei de fevereiro de 2021 a outubro de 2022. Durante esse per\u00edodo saiu o edital INSS e n\u00e3o consegui estudar. Como era tempor\u00e1rio, tomei a decis\u00e3o de pedir exonera\u00e7\u00e3o no final de outubro para estudar direito previdenci\u00e1rio. Felizmente deu certo;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ESCRIV\u00c3O PF 2021 &#8211; 54\u00ba lugar, reprovei na fase de exames m\u00e9dicos, esqueci de dois exames irrelevantes, e fui considerado inapto por isso;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>BOMBEIRO MILITAR PR 2021 &#8211; 9\u00ba lugar, fui at\u00e9 a fase de exames m\u00e9dicos, onde desisti da sele\u00e7\u00e3o;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>TEC. DO SEG. SOCIAL INSS GEX LONDRINA 2022 &#8211; 2\u00ba lugar, onde trabalho atualmente;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ANALISTA TRIBUT\u00c1RIO RFB 2023 &#8211; 260\u00ba lugar, onde pretendo trabalhar;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>AUDITOR FISCAL DA RECEITA FEDERAL DO BRASIL &#8211; onde pretendo chegar;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ah sim, e fui reprovado em muuuitos outros: PF18, TRF3 e 4, PCPR, ICMS SC, ISS Curitiba, CGU\u2026 Se pretendo continuar estudando? Pretendo\u2026? Assinei recentemente a vital\u00edcia com esse intuito, de estar l\u00e1 quando eu precisar. Mas a verdade \u00e9 que sempre tive dificuldade em conciliar trabalho e estudo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Sim, sa\u00eda com ambos os grupos. Mas confesso que \u00e9 dif\u00edcil estar 100% mentalmente presente. Sempre tem aquela prova se aproximando que tira seu sono.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Com exce\u00e7\u00e3o de alguns poucos, nunca recebi muito apoio dos meus familiares, nem de amigos. A iniciativa privada discrimina muito o servi\u00e7o p\u00fablico e quem trabalha para o Estado.<strong> <\/strong>Concursos intermedi\u00e1rios tamb\u00e9m s\u00e3o discriminados e chamados insuficientes. N\u00e3o tem o glamour dos grandes cargos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Como mencionado anteriormente, sempre tive dificuldade de estudar fora de editais\u2026 nem mesmo not\u00edcias de autoriza\u00e7\u00f5es me motivaram. S\u00f3 se tornava real quando sa\u00eda o edital. S\u00f3 ent\u00e3o eu estudava. Como foi com a RFB.&nbsp;<\/p>\n\n\n\n<p>Com tantas mat\u00e9rias exclusivas do concurso, n\u00e3o conseguiria vencer o edital para Auditor, ent\u00e3o escolhi Analista. Outro fator que n\u00e3o me ajudou foi o concurso do INSS e o curso de forma\u00e7\u00e3o que coincidiu com as provas. Tive que focar apenas na legisla\u00e7\u00e3o espec\u00edfica e levar a bagagem anterior comigo.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Usei apenas o material do Estrat\u00e9gia. PDFs e Trilhas Estrat\u00e9gicas, em sua grande maioria. V\u00eddeos foram somente os de cursos b\u00f4nus e nas revis\u00f5es de v\u00e9spera.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>J\u00e1 tinha visto alguns pre\u00e7os de cursos em diversos cursinhos. Mas s\u00f3 escolhi o Estrat\u00e9gia pois ele foi pioneiro em assinatura ilimitada, que ficaria muito mais em conta observada minha estrat\u00e9gia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Fiz concursos no in\u00edcio, sem usar nenhum material especializado. Fui eliminado, como esperado.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Sim. O direcionamento e a organiza\u00e7\u00e3o do material s\u00e3o completamente diferentes. \u00c9 fundamental ter uma dire\u00e7\u00e3o quando voc\u00ea est\u00e1 come\u00e7ando.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>J\u00e1 usei de tudo, sempre dependendo do concurso:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nos primeiros concursos, caderno e resumo;&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>J\u00e1 para a Policia Federal, usei Trilhas e planilhas de controle de horas l\u00edquidas e quest\u00f5es resolvidas. Foi um per\u00edodo at\u00edpico, que eu tinha mais tempo para estudar por causa da pandemia;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para o INSS, como j\u00e1 possu\u00eda a bagagem necess\u00e1ria, a Trilha n\u00e3o rendia, ent\u00e3o estudei pela legisla\u00e7\u00e3o previdenci\u00e1ria seca e PDFs em ordem corrida, sem planejamento;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Simulados! Conseguem abarcar uma grande por\u00e7\u00e3o do conte\u00fado e apontar as falhas do estudo. Ent\u00e3o era s\u00f3 voltar e revisar.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Muito importante. N\u00e3o s\u00f3 para praticar e encontrar suas fraquezas, mas tamb\u00e9m para se acostumar com a banca. Acelera seu tempo de resolu\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Auditoria e Administra\u00e7\u00e3o. Por mais que eu estudasse, n\u00e3o conseguia melhorar meu desempenho. Principalmente se tratando de FGV. E foi assim at\u00e9 o fim\u2026 Decidi por Analista por n\u00e3o cair Auditoria, e decidi sacrificar o conte\u00fado absurdamente grande e rico em detalhes de Administra\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Eu sacrifiquei tudo. Curso de forma\u00e7\u00e3o do INSS. Praias de Florian\u00f3polis (local do curso). Horas de sono (acordava mais cedo, dormia mais tarde). Cheguei a fazer 15 horas l\u00edquidas de revis\u00e3o de v\u00e9spera e li sobre MapReduce (Flu\u00eancia em Dados) literalmente na porta da prova (que me rendeu uma quest\u00e3o e fez toda a diferen\u00e7a).<\/p>\n\n\n\n<p>Uma vez um professor de direito administrativo do Estrat\u00e9gia falou sobre a import\u00e2ncia da v\u00e9spera e do quanto podemos crescer nela (meses) e eu concordo plenamente. Sempre me dediquei MUITO nas semanas de v\u00e9spera e sempre me trouxe bons resultados.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Eu daria a mesma recomenda\u00e7\u00e3o que daria sobre estudar portugu\u00eas para a prova da FGV: N\u00c3O ESTUDE.&nbsp;<\/p>\n\n\n\n<p>O percentual necess\u00e1rio na prova objetiva para sequer corrigirem sua prova discursiva \u00e9 alt\u00edssimo, ainda mais para vagas universais. Nunca estudei, sempre fui muito mal, mas nunca me desqualificou. Quando me dediquei \u00e0 discursiva (CGU), fui eliminado na objetiva (faltou tempo).&nbsp;<\/p>\n\n\n\n<p>Confesso que derrubou minha coloca\u00e7\u00e3o em mais de 100 vagas neste \u00faltimo, mas n\u00e3o por n\u00e3o saber redigir uma reda\u00e7\u00e3o, mas por inverter um conceito que me fez errar dois quesitos (-10 pontos).&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Erros:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ter medo de fazer concursos longe de casa. Concurso \u00e9 treino. Fa\u00e7a o m\u00e1ximo poss\u00edvel antes do edital dos seus sonhos. Fazer concurso perto apenas te limita \u00e0 espera;<\/li>\n<\/ul>\n\n\n\n<p>Acertos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>N\u00e3o ter desistido.<\/li>\n<\/ul>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>J\u00e1 pensei. Ser concurseiro \u00e9 terr\u00edvel. \u00c9 ler not\u00edcia que os concursos v\u00e3o acabar. Que aconteceram fraudes. Que v\u00e3o ter menos vagas universais a cada dia que passa. Que muita gente como voc\u00ea est\u00e1 pegando carona em pol\u00edtica p\u00fablica de reserva de vaga. Que muita gente como voc\u00ea est\u00e1 tomando rem\u00e9dio para estudar mais, para dormir melhor. \u00c9 cobran\u00e7a no relacionamento, cobran\u00e7a da fam\u00edlia, cobran\u00e7a de si mesmo.<\/p>\n\n\n\n<p>No meio de tudo isso, minha principal motiva\u00e7\u00e3o foi sempre pensar que parar naquele momento me obrigaria a recome\u00e7ar de alguma forma, e tudo at\u00e9 ali teria sido em v\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Henrique: <\/strong>Eu diria que n\u00e3o h\u00e1 nada melhor do que ser aprovado! N\u00e3o desista.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;N\u00e3o h\u00e1 nada melhor do que ser aprovado! N\u00e3o desista.&#8221; Confira nossa entrevista com Henrique Sella Kerst, aprovado em 260\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;da&nbsp;Receita Federal do Brasil&nbsp;para o cargo de&nbsp;Analista-Tribut\u00e1rio: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal? Henrique Sella Kerst: Sou de Londrina, Paran\u00e1. [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1264468","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Henrique Sella Kerst - Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Henrique Sella Kerst, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista Tribut\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Henrique Sella Kerst - Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Henrique Sella Kerst, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista Tribut\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-17T14:53:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/img-20230405-wa0020-169x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/\",\"name\":\"ENTREVISTA: Henrique Sella Kerst - Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/img-20230405-wa0020-169x300.jpg\",\"datePublished\":\"2023-08-17T14:37:35+00:00\",\"dateModified\":\"2023-08-17T14:53:09+00:00\",\"description\":\"Confira nossa entrevista com Henrique Sella Kerst, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista Tribut\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020.jpg\",\"width\":729,\"height\":1296},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Henrique Sella Kerst &#8211; Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Henrique Sella Kerst - Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio","description":"Confira nossa entrevista com Henrique Sella Kerst, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista Tribut\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Henrique Sella Kerst - Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio","og_description":"Confira nossa entrevista com Henrique Sella Kerst, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista Tribut\u00e1rio.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-08-17T14:53:09+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/img-20230405-wa0020-169x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/","name":"ENTREVISTA: Henrique Sella Kerst - Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/08\/img-20230405-wa0020-169x300.jpg","datePublished":"2023-08-17T14:37:35+00:00","dateModified":"2023-08-17T14:53:09+00:00","description":"Confira nossa entrevista com Henrique Sella Kerst, aprovado no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista Tribut\u00e1rio.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/08\/14130315\/img-20230405-wa0020.jpg","width":729,"height":1296},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-rfb-aprovado-henrique-sella-kerst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Henrique Sella Kerst &#8211; Aprovado em no concurso\u00a0da\u00a0Receita Federal do Brasil\u00a0para o cargo de\u00a0Analista-Tribut\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1264468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1264468\/revisions"}],"predecessor-version":[{"id":1265818,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1264468\/revisions\/1265818"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1264468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}