{"id":1223447,"date":"2023-06-06T13:57:37","date_gmt":"2023-06-06T16:57:37","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1223447"},"modified":"2023-06-06T14:17:35","modified_gmt":"2023-06-06T17:17:35","slug":"concurso-pm-ba-ezequiel-de-oliveira-santos","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/","title":{"rendered":"ENTREVISTA: Ezequiel de Oliveira Santos &#8211; Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM &#8211; Barreiras"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-807x1024.jpg\" alt=\"\" class=\"wp-image-1223457\" width=\"198\" height=\"251\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-807x1024.jpg 807w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-236x300.jpg 236w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-768x975.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-1210x1536.jpg 1210w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-610x774.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3-150x190.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3.jpg 1557w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><figcaption class=\"wp-element-caption\">Ezequiel de Oliveira Santos<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>&#8220;A aprova\u00e7\u00e3o \u00e9 persist\u00eancia. Muitas reprova\u00e7\u00f5es vir\u00e3o, \u00e0s vezes devido a erros bobos e falta de aten\u00e7\u00e3o. Isso \u00e9 inevit\u00e1vel. Por\u00e9m, a aprova\u00e7\u00e3o vir\u00e1, mesmo que demore um pouco&#8221;<\/em><\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;PM BA&nbsp;para Soldado&nbsp;PM &#8211; Barreiras:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel de Oliveira Santos: <\/strong>Me chamo Ezequiel de Oliveira Santos, tenho 22 anos, e nasci e cresci na zona rural de Bom Jesus da Lapa-BA. Moro em Barreiras-BA desde 2019. Atualmente fa\u00e7o faculdade de direito na UFOB, nesta cidade.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> \u00c9 muito dif\u00edcil pensar, principalmente para quem vem de fam\u00edlia pobre, em grandes oportunidades que n\u00e3o sejam o servi\u00e7o p\u00fablico. \u00c9 uma das poucas op\u00e7\u00f5es alcan\u00e7\u00e1veis. O servi\u00e7o p\u00fablico consegue proporcionar o acesso a altos sal\u00e1rios. Conquist\u00e1-los n\u00e3o \u00e9 f\u00e1cil, mas o concurso \u00e9 um meio bastante democr\u00e1tico no qual quem estuda ser\u00e1 aprovado. Ainda, \u00e9 fundamental a estabilidade. Uma das coisas que mais tenho receio na vida \u00e9 chegar no fim da carreira e n\u00e3o ter mais acesso ao mercado de trabalho simplesmente por \u201cser velho\u201d.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu trabalho desde 2019&nbsp;na prefeitura de Barreiras, jornada de 40h (contrato tempor\u00e1rio) e ainda fa\u00e7o faculdade que deveria ser tarde e noite. Devido a pandemia minha faculdade atrasou bastante, por isso coloquei passar em um concurso como meta para 2022. Como peguei poucas disciplinas na UFOB, reservei o pouco tempo que restava para isso. Estudava em torno de 18 horas por semana, principalmente aos s\u00e1bados e domingos. Eu n\u00e3o tinha tempo livre, ent\u00e3o tive que abdicar de tudo, inclusive dos momentos de lazer, para isso. Entendo que foi um sacrif\u00edcio necess\u00e1rio.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Minhas primeiras tentativas foram o TJTO e Fiscal de tributos do munic\u00edpio, mas devido a alguns vacilos fiquei apenas no cadastro reserva. A meta s\u00f3 foi batida em dezembro, quando passei no concurso do INSS (4\u00b0 colocado PPP, ger\u00eancia executiva de Barreiras). No concurso da PM BA, j\u00e1 aliviado, tive mais tranquilidade e consegui ser o primeiro colocado da minha regi\u00e3o. Acredito que se continuar irei passar em outros. Por isso, pretendo me dedicar mais a faculdade nos pr\u00f3ximos 2 anos, e seguir carreira no mundo dos concursos, especificamente na \u00e1rea jur\u00eddica, onde desejo desempenhar a minha forma\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu j\u00e1 sou uma pessoa pouco soci\u00e1vel. Durante a prepara\u00e7\u00e3o (e agora) eu tive que abrir m\u00e3o de praticamente tudo. N\u00e3o vou a festas, nem saio com os amigos. Estou vivendo para estudar, seja para concursos ou faculdade. \u00c9 muito exaustivo, mas entendo que esses sacr\u00edficos s\u00e3o necess\u00e1rios, principalmente para quem possui pouco tempo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu sou de poucos amigos, e os raros tamb\u00e9m est\u00e3o na correria dos estudos. Quanto a minha fam\u00edlia, estudar sempre foi uma meta para todos. Desde crian\u00e7a, meus pais, que quase n\u00e3o tiveram oportunidades, me for\u00e7avam a estudar. Isso foi importante para desenvolver o gosto pelos estudos. Ainda, \u00e9 un\u00e2nime entre n\u00f3s que essa \u00e9 uma das poucas formas de termos progresso na vida. Ningu\u00e9m resistiu em rela\u00e7\u00e3o a minhas escolhas nesse sentido, muito pelo contr\u00e1rio, todos compreenderam.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu estudo de fato para concursos desde janeiro de 2022. Nesse per\u00edodo procurei me dedicar as mat\u00e9rias gerais para quando sair o edital me dedicar ao conte\u00fado espec\u00edfico. Para o concurso do INSS, eu s\u00f3 me dediquei com o edital aberto e apenas com o conte\u00fado de previdenci\u00e1rio. O restante foi apenas revis\u00e3o e quest\u00f5es. <\/p>\n\n\n\n<p>J\u00e1 em rela\u00e7\u00e3o ao meu \u00faltimo concurso, o da PM BA, eu n\u00e3o estudei especialmente para ele, mas a base criada anteriormente foi suficiente para fazer uma excelente prova. \u00c9 um caminho exaustivo, mas ter sempre em mente o nosso objetivo nos mant\u00e9m na caminhada.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu aprendi a usar PDFs, e meu estudo \u00e9 quase todo por meio deles. \u00c9 interessante porque o candidato consegue estudar mais conte\u00fado e de forma mais espec\u00edfica, em compara\u00e7\u00e3o com as videoaulas, por exemplo. Muitas pessoas encontram dificuldade em estudar assim, apenas lendo, eu tamb\u00e9m tive inicialmente, principalmente quando n\u00e3o h\u00e1 um dom\u00ednio b\u00e1sico da mat\u00e9ria. Ainda, atualmente procuro ter um conhecimento mais aprofundado, por isso tamb\u00e9m inseri livros na minha rotina de estudos.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Quando comecei a estudar, em 2019, eu assistia bastante videoaula, foi quando encontrei as aulas do Thallius, Jana\u00edna e Fauth. Eram meus professores preferidos. Com a chegada deles ao Estrat\u00e9gia eu tive que chegar tamb\u00e9m. At\u00e9 conhecia a plataforma antes, mas s\u00f3 passei a utilizar de fato com a vinda deles.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> N\u00e3o tenho muitas cr\u00edticas em rela\u00e7\u00e3o a concorr\u00eancia. Minha op\u00e7\u00e3o pelo Estrat\u00e9gia foi tamb\u00e9m uma quest\u00e3o de metodologia. Eu sa\u00ed das videoaulas para estudar por PDFs, que s\u00e3o mais produtivos e espec\u00edficos, e ainda pretendia desenvolver o gosto pela leitura. O Estrat\u00e9gia possui materiais muito bons nesse quesito, por isso optei mudar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Na \u00e9poca eu utilizei apenas para conseguir um cargo tempor\u00e1rio, ent\u00e3o foi suficiente naquele momento.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu particularmente gosto bastante do material do Estrat\u00e9gia por consider\u00e1-lo completo. Tenho muito receio de estudar por algo e ao fazer a prova descobrir que o material n\u00e3o foi suficiente. Indico os PDFs, que \u00e9 meu m\u00e9todo de estudo, mas cada candidato tem suas peculiaridades. Apesar de n\u00e3o utilizar videoaulas, conhe\u00e7o muitos professores que s\u00e3o muito bons, inclusive, conheci a plataforma por eles. O importante \u00e9 estudar, e que seja por meio de uma plataforma que te d\u00ea diversas possibilidades para fazer isso atrav\u00e9s de um bom material.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Eu n\u00e3o tinha um plano de estudos r\u00edgido. Procurava estudar por assunto, intercalando disciplinas sempre que terminava um. Tentava estudar as disciplinas gerais, como Portugu\u00eas, Direito Adm e Constitucional, e deixava para especificar quando sa\u00edsse o edital. Como tinha pouco tempo, normalmente meus estudos se concentravam no final de semana, chegando a cerca de 18h semanais.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> (In)felizmente eu s\u00f3 aprendo escrevendo. Ent\u00e3o eu estudava por materiais extensos com um bom n\u00edvel de aprofundamento e com base neles eu fazia resumos. Quando fosse necess\u00e1rio acessar novamente o conte\u00fado, eu consultava apenas os resumos. Tentava deixar tudo pronto algumas semanas antes da prova para poder apenas revis\u00e1-los nesse per\u00edodo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Os exerc\u00edcios, al\u00e9m de servirem como revis\u00e3o, ir\u00e3o apontar os pontos que normalmente costumam ser mais cobrados. Al\u00e9m disso, \u00e9 important\u00edssimo conhecer a metodologia da banca, pois cada uma possui suas particularidades, inclusive de escrita. Eu considero que se n\u00e3o tivesse realizado simulados, teria ficado longe da classifica\u00e7\u00e3o no INSS, pois a Cespe, por exemplo, possui uma forma de cobran\u00e7a muito particular. Eu tentava fazer um simulado toda semana e nos dias anteriores \u00e0s provas eram dezenas todos os dias.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Sempre tive muita dificuldade com inform\u00e1tica e no\u00e7\u00f5es de administra\u00e7\u00e3o p\u00fablica. Essas disciplinas j\u00e1 me custaram a aprova\u00e7\u00e3o, inclusive. Ainda n\u00e3o consigo domin\u00e1-las, mas procuro deixar um tempo maior para elas e compensar tamb\u00e9m atrav\u00e9s de videoaulas, pois estas facilitam a compreens\u00e3o da l\u00f3gica da disciplina.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Na semana da prova n\u00e3o tem mais o que estudar de novo. O que tinha que estudar em espec\u00edfico, j\u00e1 deve ter sido feito antes desse per\u00edodo, restando apenas revisar o conte\u00fado. Assim, eu deixava esse per\u00edodo para revisar meus resumos e resolver quest\u00f5es. <\/p>\n\n\n\n<p>No dia anterior a prova era dia apenas das revis\u00f5es de v\u00e9spera. Durante muito tempo ignorei essas revis\u00f5es, mas hoje vejo que elas fazem milagres. Muito conte\u00fado realmente cai.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> No concurso da PM BA houve prova discursiva, mas como eu j\u00e1 possu\u00eda um dom\u00ednio para escrita da reda\u00e7\u00e3o, resolvi n\u00e3o estud\u00e1-la. Reda\u00e7\u00e3o \u00e9 principalmente treino. Apesar de suas particularidades, eu aprendi durante o Enem, escrevendo uma a cada 3 dias. Inicialmente, eu espelhava em outras reda\u00e7\u00f5es nota m\u00e1xima&nbsp;e aos poucos ia adaptando a estrutura dos textos conforme a minha escrita. Com isso aprendi a estrutura da disserta\u00e7\u00e3o e assim sai dos 440 do primeiro Enem para 960 nos posteriores.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Um grande problema que muitos cometem, e eu tamb\u00e9m, \u00e9 estudar por disciplinas e n\u00e3o seguir efetivamente o conte\u00fado do edital. No TJTO, por exemplo, a banca se limitou a cobrar tribunal do j\u00fari, e eu perdia tempo estudando pontos pouco relevantes para a prova. Al\u00e9m disso, os concursos p\u00fablicos est\u00e3o em um n\u00edvel alt\u00edssimo, n\u00e3o se pode mais ignorar uma disciplina. Hoje, para ser aprovado precisa ter conhecimento em todas. Ainda, costumava fazer resumos a m\u00e3o, o que \u00e9 muito improdutivo e de dif\u00edcil organiza\u00e7\u00e3o. <\/p>\n\n\n\n<p>Por outro lado, um dos grandes acertos foi me preparar com quest\u00f5es. Para o concurso do INSS quase que todas as disciplinas b\u00e1sicas eu estudei apenas assim. Se o candidato j\u00e1 tem um dom\u00ednio de um tema, vejo ser mais produtivo estudar como a banca cobra esses temas. Se a plataforma possuir quest\u00f5es comentadas, elas j\u00e1 servir\u00e3o para revisar ou pegar pontos que ainda n\u00e3o foram dominados.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> N\u00e3o. Vejo nos estudos a \u00fanica oportunidade de dar grandes saltos na vida. Eu acredito bastante em mim e vejo que, para a minha realidade, esse \u00e9 um caminho necess\u00e1rio e inevit\u00e1vel. Quando os inevit\u00e1veis momentos de des\u00e2nimo chegavam, eu descansava, dormia e retornava \u00e0 rotina no dia seguinte.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Ezequiel:<\/strong> Inicialmente, n\u00e3o existe aprova\u00e7\u00e3o sem estudo. \u00c9 preciso \u201csentar a bunda na cadeira e estudar\u201d. Acho interessante come\u00e7ar com conte\u00fados comuns das \u00e1reas que deseja atuar, para j\u00e1 sair na frente, e posteriormente se dedicar ao conte\u00fado espec\u00edfico com o edital aberto. Ainda, \u00e9 preciso resolver muitas quest\u00f5es para aprender na pr\u00e1tica e conhecer as particularidades da banca. Na semana anterior \u00e0 prova n\u00e3o pode ignorar os aul\u00f5es de v\u00e9spera, pois abordam muita coisa que de fato ser\u00e1 cobrado.<\/p>\n\n\n\n<p>Por fim, a aprova\u00e7\u00e3o \u00e9 persist\u00eancia. Muitas reprova\u00e7\u00f5es vir\u00e3o, \u00e0s vezes devido a erros bobos e falta de aten\u00e7\u00e3o. Isso \u00e9 inevit\u00e1vel. Por\u00e9m, a aprova\u00e7\u00e3o vir\u00e1, mesmo que demore um pouco. Enquanto uns precisam de poucos meses, outros ter\u00e3o que se dedicar por anos. \u00c9 preciso reconhecer e respeitar que cada um tem o seu tempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;A aprova\u00e7\u00e3o \u00e9 persist\u00eancia. Muitas reprova\u00e7\u00f5es vir\u00e3o, \u00e0s vezes devido a erros bobos e falta de aten\u00e7\u00e3o. Isso \u00e9 inevit\u00e1vel. Por\u00e9m, a aprova\u00e7\u00e3o vir\u00e1, mesmo que demore um pouco&#8221; Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;PM BA&nbsp;para Soldado&nbsp;PM &#8211; Barreiras: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1223447","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Ezequiel de Oliveira Santos - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Ezequiel de Oliveira Santos - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T17:17:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/img_20230208_113627727_hdr3-807x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/\",\"name\":\"ENTREVISTA: Ezequiel de Oliveira Santos - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/img_20230208_113627727_hdr3-807x1024.jpg\",\"datePublished\":\"2023-06-06T16:57:37+00:00\",\"dateModified\":\"2023-06-06T17:17:35+00:00\",\"description\":\"Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3.jpg\",\"width\":1557,\"height\":1976},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Ezequiel de Oliveira Santos &#8211; Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM &#8211; Barreiras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Ezequiel de Oliveira Santos - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras","description":"Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Ezequiel de Oliveira Santos - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras","og_description":"Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-06-06T17:17:35+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/img_20230208_113627727_hdr3-807x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/","name":"ENTREVISTA: Ezequiel de Oliveira Santos - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/img_20230208_113627727_hdr3-807x1024.jpg","datePublished":"2023-06-06T16:57:37+00:00","dateModified":"2023-06-06T17:17:35+00:00","description":"Confira nossa entrevista com Ezequiel de Oliveira Santos, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM - Barreiras.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/29105500\/img_20230208_113627727_hdr3.jpg","width":1557,"height":1976},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-pm-ba-ezequiel-de-oliveira-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Ezequiel de Oliveira Santos &#8211; Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0PM BA\u00a0para Soldado\u00a0PM &#8211; Barreiras"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1223447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":9,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1223447\/revisions"}],"predecessor-version":[{"id":1228432,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1223447\/revisions\/1228432"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1223447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}