{"id":1212163,"date":"2023-05-08T11:32:48","date_gmt":"2023-05-08T14:32:48","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1212163"},"modified":"2023-05-08T14:19:05","modified_gmt":"2023-05-08T17:19:05","slug":"concurso-cge-sc-aprovado-yves-nogueira-sousa","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/","title":{"rendered":"ENTREVISTA: Yves Nogueira Sousa &#8211; Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves.jpg\" alt=\"\" class=\"wp-image-1212165\" width=\"231\" height=\"303\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves.jpg 231w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves-229x300.jpg 229w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves-150x197.jpg 150w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><figcaption class=\"wp-element-caption\">Yves Nogueira Sousa<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&nbsp;&#8220;Paci\u00eancia, serenidade e vis\u00e3o de longo prazo. Passei por 4 reprova\u00e7\u00f5es antes de come\u00e7ar a ser aprovado.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;CGE SC&nbsp;para o cargo de&nbsp;Auditor do Estado &#8211; Ci\u00eancia da Computa\u00e7\u00e3o:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Yves Nogueira Sousa: <\/strong>Sou formado em Sistemas de Informa\u00e7\u00e3o, tenho 33 anos de idade e sou de Fortaleza.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Alguns fatores:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gosto da impessoalidade do setor p\u00fablico;<\/li>\n\n\n\n<li>As remunera\u00e7\u00f5es s\u00e3o muito competitivas com as do setor privado, com alguns direitos diferenciados, considerando o regime estatut\u00e1rio;<\/li>\n\n\n\n<li>A maior parte das mat\u00e9rias estudadas tamb\u00e9m traz benef\u00edcios em termos de conhecimento a ser aplicado no mercado;<\/li>\n\n\n\n<li>Gosto de estudar.<\/li>\n<\/ul>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Apenas estudava.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Yves:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Controladoria Geral do Estado de Santa Catarina<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2023<\/p>\n\n\n\n<p>Cargo: Auditor do Estado<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 1\u00ba lugar<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per\u00edcia Forense do Estado do Cear\u00e1&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2021&nbsp;<\/p>\n\n\n\n<p>Cargo: Perito Criminal \u2013 Computa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 1\u00ba&nbsp;lugar<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Cear\u00e1&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2021&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista de Tecnologia da Informa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 1\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Assembleia Legislativa do Estado do Cear\u00e1&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2020&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista Legislativo \u2013 Inform\u00e1tica&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 3\u00ba<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Secretaria da Fazenda do Estado do Cear\u00e1&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2021&nbsp;<\/p>\n\n\n\n<p>Cargo: Auditor Fiscal de Tecnologia da Informa\u00e7\u00e3o da Receita Estadual&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 12\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conselho Regional de Medicina do Estado do Cear\u00e1&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2021&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista de Sistema&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 5\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Petrobr\u00e1s&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2022&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista de Sistemas \u2013 Engenharia de Software&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o 33\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>C\u00e2mara de Teresina&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2020&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista \u2013 Inform\u00e1tica&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 5\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Minist\u00e9rio P\u00fablico do Estado do Cear\u00e1&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2019&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista Ministerial \u2013 Ci\u00eancias da Computa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 4\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Banco do Nordeste&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2019&nbsp;<\/p>\n\n\n\n<p>Cargo: Especialista T\u00e9cnico \u2013 Analista de Sistemas&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 4\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tribunal Regional do Trabalho da 7\u00aa Regi\u00e3o&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2017<\/p>\n\n\n\n<p>Cargo: Analista Judici\u00e1rio \u2013 Tecnologia da Informa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 27\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tribunal Regional do Trabalho da 8\u00aa Regi\u00e3o&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2015&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista Judici\u00e1rio \u2013 Tecnologia da Informa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 21\u00ba&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Minist\u00e9rio do Planejamento&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ano: 2015&nbsp;<\/p>\n\n\n\n<p>Cargo: Analista em Tecnologia da Informa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p>Coloca\u00e7\u00e3o: 58\u00ba<\/p>\n\n\n\n<p>Pretendo continuar estudando.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Sem vida social, basicamente.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Tive grande apoio de minha fam\u00edlia mais imediatamente pr\u00f3xima nos per\u00edodos sem remunera\u00e7\u00e3o, bem como tive grande apoio de um c\u00edrculo pr\u00f3ximo de amigos no come\u00e7o dos estudos, quando compartilhamos ideias e resumos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Algo em torno de 6 meses. No meu caso, uma rotina estruturada de estudos com certas metas di\u00e1rias e outras de mais longo prazo ajudaram a manter o foco.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Utilizo de tudo um pouco, guiando-me por quest\u00f5es de concursos comentadas e pelo que consta em edital. A principal vantagem \u00e9 ter uma cobertura ampla da mat\u00e9ria com abordagens variadas, todavia \u00e9 algo que exige mais disciplina e organiza\u00e7\u00e3o por conta do desvio de foco em um s\u00f3 material.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Por meio de amigos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia? <\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Os materiais em PDF s\u00e3o muito bons para acelerar o rendimento at\u00e9 a faixa de 70% a 80% de acerto, a depender da mat\u00e9ria e da banca. Ganha-se muito tempo ao n\u00e3o ser necess\u00e1rio pesquisar todo o edital para montar um material pr\u00f3prio.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Adotei minha maneira atual de estudar de maneira gradual e org\u00e2nica, observando o que funciona melhor para mim. Costumo estudar uma mat\u00e9ria de cada vez at\u00e9 finaliz\u00e1-la. Quando estou focando em um concurso, estudo basicamente o dia inteiro, n\u00e3o costumo contabilizar horas l\u00edquidas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Costumo revisar por meio de resumos pr\u00f3prios direcionados especificamente para o que consta em edital.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Quest\u00f5es comentadas s\u00e3o especialmente importantes para identificar o perfil de cobran\u00e7a da banca e para n\u00e3o perder tempo pesquisando a mat\u00e9ria cobrada nas quest\u00f5es. Parei de contar minhas quest\u00f5es resolvidas mais ou menos 6 anos atr\u00e1s, quando estava com um n\u00famero em torno de 36.000.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Considerando todos os concursos que j\u00e1 fiz, diria que, para mim, a mat\u00e9ria mais trabalhosa de se adquirir bom rendimento foi contabilidade. S\u00e3o muitos detalhes e as bancas costumam cobrar a maior parte deles. N\u00e3o h\u00e1 grandes atalhos, \u00e9 uma mat\u00e9ria que exige paci\u00eancia e dedica\u00e7\u00e3o de longo prazo. Mas essa pode ser uma percep\u00e7\u00e3o de quem n\u00e3o \u00e9 da \u00e1rea.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Dediquei um tempo adicional para treinar mais a discursiva, bem como para ler mais vezes meus resumos. De resto, minha rotina permaneceu a mesma.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Como a prova foi dissertativa-argumentativa, foquei em aprender a estrutura de tal g\u00eanero, que \u00e9 no m\u00ednimo t\u00e3o importante quanto o conte\u00fado. De resto, basta repetidamente treinar a escrita e a formula\u00e7\u00e3o do plano de resposta.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>N\u00e3o consigo identificar nenhum grande erro, mas talvez erros menores como aprofundar demasiadamente em uma mat\u00e9ria quando o n\u00edvel da prova n\u00e3o demandava e resolver quest\u00f5es em alguns momentos sem a devida aten\u00e7\u00e3o para realmente parar e absorver o conte\u00fado envolvido.<\/p>\n\n\n\n<p>Em termos de acertos, diria que tive uma boa capacidade para autocr\u00edtica a fim de adaptar e refinar minha maneira de estudar para meu perfil espec\u00edfico.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Pensei bastante antes de come\u00e7ar a estudar para concursos. Quando decidi come\u00e7ar, j\u00e1 estava resoluto em estudar at\u00e9 passar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Yves: <\/strong>Aconselharia paci\u00eancia, serenidade e vis\u00e3o de longo prazo. Passei por 4 reprova\u00e7\u00f5es antes de come\u00e7ar a ser aprovado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&#8220;Paci\u00eancia, serenidade e vis\u00e3o de longo prazo. Passei por 4 reprova\u00e7\u00f5es antes de come\u00e7ar a ser aprovado.&#8221; Confira nossa entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0&nbsp;lugar&nbsp;no concurso&nbsp;CGE SC&nbsp;para o cargo de&nbsp;Auditor do Estado &#8211; Ci\u00eancia da Computa\u00e7\u00e3o: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1212163","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Yves Nogueira Sousa - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado<\/title>\n<meta name=\"description\" content=\"Confira a entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Yves Nogueira Sousa - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado\" \/>\n<meta property=\"og:description\" content=\"Confira a entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T17:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/yves.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/\",\"name\":\"ENTREVISTA: Yves Nogueira Sousa - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/yves.jpg\",\"datePublished\":\"2023-05-08T14:32:48+00:00\",\"dateModified\":\"2023-05-08T17:19:05+00:00\",\"description\":\"Confira a entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves.jpg\",\"width\":231,\"height\":303},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Yves Nogueira Sousa &#8211; Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Yves Nogueira Sousa - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado","description":"Confira a entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Yves Nogueira Sousa - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado","og_description":"Confira a entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-05-08T17:19:05+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/yves.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/","name":"ENTREVISTA: Yves Nogueira Sousa - Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/05\/yves.jpg","datePublished":"2023-05-08T14:32:48+00:00","dateModified":"2023-05-08T17:19:05+00:00","description":"Confira a entrevista com Yves Nogueira Sousa, aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/08102206\/yves.jpg","width":231,"height":303},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cge-sc-aprovado-yves-nogueira-sousa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Yves Nogueira Sousa &#8211; Aprovado em 1\u00b0\u00a0lugar\u00a0no concurso\u00a0CGE SC\u00a0para o cargo de\u00a0Auditor do Estado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1212163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1212163\/revisions"}],"predecessor-version":[{"id":1212400,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1212163\/revisions\/1212400"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1212163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}