{"id":1169084,"date":"2023-02-15T11:33:00","date_gmt":"2023-02-15T14:33:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1169084"},"modified":"2023-02-15T13:24:56","modified_gmt":"2023-02-15T16:24:56","slug":"concurso-sefaz-pe-aprovada-gabriela-cabral","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/","title":{"rendered":"ENTREVISTA: Gabriela de Ara\u00fajo Cabral &#8211; Aprovada\u00a0no concurso\u00a0SEFAZ-PE"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-1024x951.jpg\" alt=\"\" class=\"wp-image-1169086\" width=\"512\" height=\"476\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-1024x951.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-300x279.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-768x713.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-1536x1427.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-2048x1902.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-610x567.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-150x139.jpg 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption class=\"wp-element-caption\">Gabriela de Ara\u00fajo Cabral<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;N\u00e3o existe um jeito certo e universal de estudar para passar em um concurso. \u00c9 preciso descobrir o que funciona para voc\u00ea. Acho que essa \u00e9 uma das tarefas mais dif\u00edceis e tamb\u00e9m a mais importante para um concurseiro [&#8230;]&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar&nbsp;no concurso&nbsp;SEFAZ-PE&nbsp;para&nbsp;Auditor Fiscal do Tesouro Estadual &#8211; Afte:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-la. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela de Ara\u00fajo Cabral:<\/strong> Sou formada em Direito, tenho 25 anos e sou de Recife\/PE.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Escolhi a faculdade de Direito visando os concursos p\u00fablicos, a princ\u00edpio na \u00e1rea jur\u00eddica, mas sem saber ao certo qual carreira escolheria. A qualidade de vida e a estabilidade financeira sempre foram grandes atrativos. Depois de 6 meses estudando para concursos, inicialmente para a \u00e1rea policial e depois para a jur\u00eddica, que eu decidi mudar meu foco para a \u00e1rea fiscal.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> N\u00e3o. Me formei em meados de 2021 e, desde ent\u00e3o, me dedico exclusivamente aos estudos para concursos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovada? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Ao iniciar meus estudos, os concursos da \u00e1rea policial estavam, e ainda est\u00e3o, em alta. Como sempre tive interesse pelo Direito Penal durante minha faculdade, foi a escolha \u00f3bvia para iniciar minha trajet\u00f3ria no mundo dos concursos.<\/p>\n\n\n\n<p>No primeiro concurso que fiz, fui aprovada na primeira fase para Escriv\u00e3 da Pol\u00edcia Civil do Estado de Alagoas (PC\/AL), mas desisti da carreira antes de realizar o teste de aptid\u00e3o f\u00edsica. Em busca de uma maior qualidade de vida, mudei meu foco para a \u00e1rea jur\u00eddica, mas fiz apenas o concurso para Escrevente Judici\u00e1rio do Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo, conseguindo ficar no cadastro de reserva.<\/p>\n\n\n\n<p>O concurso da Sefaz\/PE foi meu primeiro na \u00e1rea fiscal para o cargo de Auditor Fiscal e minha primeira aprova\u00e7\u00e3o dentro das vagas. Era o cargo e \u00f3rg\u00e3o que eu almejava quando decidi que focaria nessa \u00e1rea.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Como me dedicava exclusivamente aos estudos, eu os via como um trabalho: tinha meus hor\u00e1rios estabelecidos e minhas metas definidas, de forma que n\u00e3o atrapalhassem tanto minha vida social. J\u00e1 nos estudos p\u00f3s-edital, foi preciso abdicar de algumas coisas. N\u00e3o me isolei completamente, ainda frequentei anivers\u00e1rios e casamentos, por exemplo, mas tive que fazer escolhas para conseguir alcan\u00e7ar a aprova\u00e7\u00e3o que tanto desejava, principalmente no m\u00eas que antecedeu a prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseira? De que forma?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> O apoio da minha fam\u00edlia e amigos foi essencial nessa jornada. Desde o suporte financeiro at\u00e9 o apoio psicol\u00f3gico e mental, eles sempre estiveram do meu lado e acreditaram em mim e nesse sonho, mais do que eu mesma acreditava muitas vezes. Eu tenho certeza que n\u00e3o teria conseguido alcan\u00e7ar esse objetivo se n\u00e3o tivesse eles do meu lado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Iniciei os estudos para a \u00e1rea fiscal no in\u00edcio do ano passado. Na metade do ano, saiu o edital para Auditor Fiscal do Estado de Minas Gerais. Como o per\u00edodo entre o edital e a prova era consider\u00e1vel, decidi focar nesse concurso e fortalecer minha base atrav\u00e9s dele.<\/p>\n\n\n\n<p>Quando come\u00e7aram os rumores de que o edital do concurso da Sefaz\/PE estava para sair a qualquer momento, deixei de lado os estudos da legisla\u00e7\u00e3o espec\u00edfica de Minas Gerais, mas continuei estudando as demais mat\u00e9rias, j\u00e1 que a grande maioria era caracter\u00edstica da \u00e1rea fiscal.<\/p>\n\n\n\n<p>Finalmente, quando saiu o edital em outubro, me dediquei exclusivamente a esse concurso at\u00e9 a data da prova, que ocorreu em dezembro. Era o cargo que eu desejava e que permitiria que eu continuasse no meu Estado e retribu\u00edsse toda a ajuda que eu recebi durante esse percurso. Era isso que eu visualizava e repetia para mim mesma nos dias mais dif\u00edceis.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Os materiais que eu utilizava dependiam muito da mat\u00e9ria. Por exemplo, contabilidade e estat\u00edstica foram mat\u00e9rias que eu aprendi majoritariamente por videoaulas. Apesar de tomarem mais tempo que a leitura dos PDF\u2019s, as videoaulas foram essenciais nessas disciplinas em que sentia a necessidade de um maior aprofundamento nas explica\u00e7\u00f5es. J\u00e1 quanto \u00e0s demais, estudava pelos PDF\u2019s e, em algumas disciplinas de menor peso, at\u00e9 pelo PDF simplificado, o que otimizava bastante meu tempo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Meu primeiro contato com o Estrat\u00e9gia foi atrav\u00e9s do Prof. S\u00edlvio Sande e seu curso \u201cContabilidade de A a Z\u201d. Acompanhei o curso, inicialmente, pelo <em>Youtube<\/em> e, ap\u00f3s pesquisar sobre o Estrat\u00e9gia Concursos, decidi fazer a assinatura <em>premium<\/em>, que foi a minha melhor escolha.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> No in\u00edcio da minha trajet\u00f3ria, que ainda n\u00e3o era focada na \u00e1rea fiscal, eu fiz outros cursos, para a \u00e1rea policial e um espec\u00edfico para o concurso de Escrevente Judici\u00e1rio do TJSP. Quando meu foco mudou, me matriculei em um curso para carreiras fiscais, para que pudesse montar uma base s\u00f3lida.<\/p>\n\n\n\n<p>No entanto, o curso n\u00e3o atendeu \u00e0s minhas expectativas. A proposta era majoritariamente videoaulas e, adicionalmente, apostilas de mat\u00e9rias espec\u00edficas (que demoravam a ser liberadas). Dessa forma, ficava limitada \u00e0 libera\u00e7\u00e3o durante a semana das poucas videoaulas determinadas pelo curso, bem como limitada em rela\u00e7\u00e3o \u00e0s poucas disciplinas ofertadas, o que n\u00e3o condizia com meu hor\u00e1rio de estudo integral.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Fiz alguns concursos, mas nenhuma nomea\u00e7\u00e3o at\u00e9 o momento.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Senti uma diferen\u00e7a enorme quando me tornei aluna do Estrat\u00e9gia. Fiz a assinatura <em>premium<\/em>, o que permitiu que eu me matriculasse simultaneamente em at\u00e9 tr\u00eas cursos do meu interesse. Uma vez matriculada, a grande maioria dos materiais j\u00e1 estavam dispon\u00edveis e podiam ser acessados a qualquer momento, o que foi uma grande melhoria em rela\u00e7\u00e3o ao curso que fiz anteriormente.<\/p>\n\n\n\n<p>Al\u00e9m disso, tive acesso \u00e0s Trilhas Estrat\u00e9gicas, que com certeza foi o diferencial para a minha aprova\u00e7\u00e3o. O direcionamento que as Trilhas proporcionam \u00e9 um facilitador imensur\u00e1vel na nossa prepara\u00e7\u00e3o. N\u00e3o precisar dedicar tempo dos meus estudos para planejar quais mat\u00e9rias estudar, em que momento estud\u00e1-las, quais t\u00f3picos focar e quais quest\u00f5es responder foi o que possibilitou meu crescimento em relativamente pouco tempo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Eu seguia as Trilhas Estrat\u00e9gicas espec\u00edficas. Utilizei a Trilha Estrat\u00e9gica da Sefaz\/MG como direcionador dos meus estudos para construir uma base na carreira fiscal. Estudava em torno de quatro mat\u00e9rias por dia, variando de 7h a 8h l\u00edquidas di\u00e1rias, alguns dias mais, alguns dias menos. Depois que saiu o edital de Pernambuco, mudei para a Trilha Estrat\u00e9gica espec\u00edfica da Sefaz\/PE e, nos dias que conseguia, aumentava minha carga hor\u00e1ria de estudos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Minhas revis\u00f5es consistiam na resolu\u00e7\u00e3o de quest\u00f5es e na realiza\u00e7\u00e3o de simulados, esse \u00faltimo apenas no p\u00f3s-edital. Se continuasse com alguma d\u00favida em algum ponto da mat\u00e9ria, recorria ao PDF ou, em \u00faltimo caso, \u00e0 videoaula.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> N\u00e3o sei ao certo quantas quest\u00f5es resolvi ao longo da minha trajet\u00f3ria, foram in\u00fameras. Tanto as quest\u00f5es ao fim dos PDF\u2019s quanto as diversas quest\u00f5es do Sistema de Quest\u00f5es do Estrat\u00e9gia foram essenciais para visualizar a forma de cobran\u00e7a, descobrir o entendimento de cada banca sobre os assuntos e saber quais os t\u00f3picos de maior incid\u00eancia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Estat\u00edstica e contabilidade foram mat\u00e9rias com as quais eu s\u00f3 tive contato no ano passado. Assim, as videoaulas foram essenciais para o melhor entendimento dessas disciplinas. Assistia as videoaulas de estat\u00edstica na velocidade 2.5 (outro ponto extremamente positivo da plataforma do Estrat\u00e9gia) e logo depois partia para a resolu\u00e7\u00e3o de quest\u00f5es para consolidar o que havia aprendido. J\u00e1 em contabilidade, as aulas do Prof. S\u00edlvio Sande foram o meu guia desde a contabilidade geral at\u00e9 a avan\u00e7ada.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Na semana que antecedeu a prova, eu foquei em algumas videoaulas da prepara\u00e7\u00e3o turbo do curso espec\u00edfico para auditor fiscal da Sefaz\/PE, principalmente as das mat\u00e9rias de maior peso, como legisla\u00e7\u00e3o tribut\u00e1ria. Como j\u00e1 havia resolvido muitas quest\u00f5es durante minha prepara\u00e7\u00e3o, dei prefer\u00eancia \u00e0 videoaula, que, para mim, \u00e9 a melhor ferramenta para a constru\u00e7\u00e3o da mem\u00f3ria de curto prazo. No dia pr\u00e9-prova n\u00e3o poderia ser diferente. Assisti \u00e0 Revis\u00e3o de V\u00e9spera do Estrat\u00e9gia transmitido no <em>Youtube<\/em>, que foi essencial para relembrar alguns pontos chaves de todas as mat\u00e9rias.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Acredito que meu principal erro tenha sido no in\u00edcio da minha trajet\u00f3ria e que \u00e9 um erro que muitos cometem: n\u00e3o definir uma \u00e1rea espec\u00edfica. Aquela sensa\u00e7\u00e3o de querer \u201cabra\u00e7ar o mundo\u201d e encarar todo e qualquer concurso que aparecer pela frente. Consequentemente, meu maior acerto foi ter definido a \u00e1rea fiscal como meta. Depois que direcionei meus estudos para essa carreira, pude desenvolver e fortalecer uma base que otimizasse a realiza\u00e7\u00e3o dos futuros concursos.<\/p>\n\n\n\n<p>Assim, no in\u00edcio dos meus estudos para carreira fiscal, n\u00e3o me inscrevi em concursos como Sefaz Bahia e Sefaz Amazonas por ainda n\u00e3o estar preparada para encar\u00e1-los. J\u00e1 o concurso da Sefaz\/MG, por haver um grande lapso entre a data da publica\u00e7\u00e3o do edital e a data da prova (mais de cinco meses) e um edital caracter\u00edstico da \u00e1rea fiscal, encarei-o como uma forma de me motivar e direcionar meus estudos, que com certeza serviriam para outros concursos (que foi o que de fato aconteceu).<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> Creio que n\u00e3o cheguei a pensar em desistir do mundo dos concursos, mas cheguei a pensar que talvez o cargo de Auditor Fiscal n\u00e3o estivesse no meu alcance. Em alguns momentos, pensei que deveria sonhar \u201cmais baixo\u201d e focar em cargos menores e menos disputados. Mas minhas maiores motiva\u00e7\u00f5es foram a qualidade de vida que aquele cargo poderia me proporcionar e meus pais, que em nenhum momento duvidaram da minha capacidade e que fizerem de tudo para que eu pudesse me dedicar exclusivamente aos estudos e alcan\u00e7ar esse t\u00e3o sonhado cargo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Gabriela:<\/strong> N\u00e3o existe um jeito certo e universal de estudar para passar em um concurso. \u00c9 preciso descobrir o que funciona para voc\u00ea. Acho que essa \u00e9 uma das tarefas mais dif\u00edceis e tamb\u00e9m a mais importante para um concurseiro. N\u00e3o adianta voc\u00ea ler o PDF porque foi orientado a estudar por ele para otimizar seu tempo se voc\u00ea n\u00e3o consegue absorver aquela mat\u00e9ria por esse m\u00e9todo. N\u00e3o se sinta culpado por isso, nem ache que est\u00e1 perdendo tempo. O que voc\u00ea precisa fazer \u00e9 otimizar a ferramenta que funciona para voc\u00ea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;N\u00e3o existe um jeito certo e universal de estudar para passar em um concurso. \u00c9 preciso descobrir o que funciona para voc\u00ea. Acho que essa \u00e9 uma das tarefas mais dif\u00edceis e tamb\u00e9m a mais importante para um concurseiro [&#8230;]&#8221; Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar&nbsp;no concurso&nbsp;SEFAZ-PE&nbsp;para&nbsp;Auditor Fiscal do [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1169084","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Gabriela de Ara\u00fajo Cabral - Aprovada\u00a0no concurso\u00a0SEFAZ-PE<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar\u00a0no concurso\u00a0SEFAZ-PE\u00a0para\u00a0Auditor Fiscal do Tesouro Estadual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Gabriela de Ara\u00fajo Cabral - Aprovada\u00a0no concurso\u00a0SEFAZ-PE\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar\u00a0no concurso\u00a0SEFAZ-PE\u00a0para\u00a0Auditor Fiscal do Tesouro Estadual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-15T16:24:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/02\/img_6232-3-1024x951.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/\",\"name\":\"ENTREVISTA: Gabriela de Ara\u00fajo Cabral - Aprovada\u00a0no concurso\u00a0SEFAZ-PE\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/02\/img_6232-3-1024x951.jpg\",\"datePublished\":\"2023-02-15T14:33:00+00:00\",\"dateModified\":\"2023-02-15T16:24:56+00:00\",\"description\":\"Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar\u00a0no concurso\u00a0SEFAZ-PE\u00a0para\u00a0Auditor Fiscal do Tesouro Estadual.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-scaled.jpg\",\"width\":2560,\"height\":2378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Gabriela de Ara\u00fajo Cabral &#8211; Aprovada\u00a0no concurso\u00a0SEFAZ-PE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Gabriela de Ara\u00fajo Cabral - Aprovada\u00a0no concurso\u00a0SEFAZ-PE","description":"Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar\u00a0no concurso\u00a0SEFAZ-PE\u00a0para\u00a0Auditor Fiscal do Tesouro Estadual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Gabriela de Ara\u00fajo Cabral - Aprovada\u00a0no concurso\u00a0SEFAZ-PE","og_description":"Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar\u00a0no concurso\u00a0SEFAZ-PE\u00a0para\u00a0Auditor Fiscal do Tesouro Estadual.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-02-15T16:24:56+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/02\/img_6232-3-1024x951.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/","name":"ENTREVISTA: Gabriela de Ara\u00fajo Cabral - Aprovada\u00a0no concurso\u00a0SEFAZ-PE","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/02\/img_6232-3-1024x951.jpg","datePublished":"2023-02-15T14:33:00+00:00","dateModified":"2023-02-15T16:24:56+00:00","description":"Confira nossa entrevista com Gabriela de Ara\u00fajo Cabral, aprovada em 18\u00b0 lugar\u00a0no concurso\u00a0SEFAZ-PE\u00a0para\u00a0Auditor Fiscal do Tesouro Estadual.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/10102026\/img_6232-3-scaled.jpg","width":2560,"height":2378},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-sefaz-pe-aprovada-gabriela-cabral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Gabriela de Ara\u00fajo Cabral &#8211; Aprovada\u00a0no concurso\u00a0SEFAZ-PE"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1169084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1169084\/revisions"}],"predecessor-version":[{"id":1172154,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1169084\/revisions\/1172154"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1169084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}