{"id":1094066,"date":"2022-09-13T17:30:03","date_gmt":"2022-09-13T20:30:03","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?post_type=depoimento&#038;p=1094066"},"modified":"2022-09-13T17:30:07","modified_gmt":"2022-09-13T20:30:07","slug":"concurso-tjms-aprovado-joao-paulo-moreira","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/","title":{"rendered":"ENTREVISTA: Jo\u00e3o Paulo Moreira &#8211; Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><em>&#8220;Lembre-se: a aprova\u00e7\u00e3o n\u00e3o depende muito de m\u00e9todos de estudos revolucion\u00e1rios ou grau de intelig\u00eancia elevado, mas de const\u00e2ncia, perseveran\u00e7a e confian\u00e7a no estudo. Isso far\u00e1 o resultado acontecer&#8221;<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">.<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"363\" class=\"wp-image-1094072\" style=\"width: 250px;\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg\" alt=\"\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg 419w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo-207x300.jpeg 207w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo-150x218.jpeg 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio &#8211; \u00c1rea Fim (Campo Grande): <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo Moreira:<\/strong> Sou de Juiz de Fora &#8211; MG, tenho 29 anos, formado em Gest\u00e3o Ambiental e Direito. Al\u00e9m disso, atualmente, sou servidor da Universidade Federal de Juiz de Fora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu entrei no servi\u00e7o p\u00fablico no ano de 2014. Em regra, a carreira p\u00fablica oferece grandes atrativos como: estabilidade, remunera\u00e7\u00e3o acima da iniciativa privada, boas condi\u00e7\u00f5es de trabalho e a possibilidade de exercer uma fun\u00e7\u00e3o em prol da sociedade. Devido eu querer uma mudan\u00e7a em minha vida, em 2018 resolvi me matricular na faculdade de Direito em busca de melhoria profissional. Acabei gostando muito do curso e foquei durante a gradua\u00e7\u00e3o em concursos da \u00e1rea de analista de tribunais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu sempre conciliei trabalho e estudo. Sinceramente, acho que eu n\u00e3o conseguiria ficar s\u00f3 estudando. O estudo para concursos \u00e9 repleto de incertezas (mudan\u00e7as de datas e locais de provas, incertezas de quantos candidatos ser\u00e3o nomeados, etc.) e o trabalho ajuda um pouco a contornar a ansiedade pela aprova\u00e7\u00e3o e nomea\u00e7\u00e3o. Al\u00e9m de estudar e trabalhar, eu ainda estava cursando a faculdade de Direito que terminei em agosto de 2022, ent\u00e3o foi necess\u00e1rio um pouco mais de disciplina e estudar nas horas dispon\u00edveis, como em feriados e em finais de semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sem edital na pra\u00e7a, eu era mais relaxado, estudava o m\u00e1ximo que dava durante a semana e pelo menos um turno no s\u00e1bado e\/ou domingo. Quando surgiram editais interessantes, tirei f\u00e9rias no trabalho para estudar mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu fui aprovado em Analista Judici\u00e1rio de Execu\u00e7\u00e3o de Mandados no TJRJ (20\u00ba lugar &#8211; 2\u00b0 regi\u00e3o), Analista Judici\u00e1rio no TJDFT (ainda n\u00e3o saiu o resultado oficial, mas estou entre os 100 primeiros com os resultados das discursivas) e Analista Judici\u00e1rio no TJMS (10\u00ba lugar). Pretendo continuar estudando para alguma carreira jur\u00eddica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu abdiquei um pouco de minha vida social, por trabalhar e estudar tive que fazer alguns sacrif\u00edcios. Quando n\u00e3o tinha edital, eu sa\u00eda normalmente com a fam\u00edlia e amigos, mas sem exageros com bebidas alco\u00f3licas. Quando surgiram editais interessantes, eu abdiquei de lazer com amigos, ia apenas em eventos de familiares mais pr\u00f3ximos. Infelizmente, com concursos cada vez mais dif\u00edceis e concorridos, \u00e9 necess\u00e1rio fazer algumas escolhas em busca de algo maior, que \u00e9 a aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casado? Tem filhos? Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> N\u00e3o sou casado. Minha fam\u00edlia e meus amigos compreenderam, pois sabiam que estava buscando algo melhor para minha vida. Alguns amigos tive que me afastar, devido a rotina de estudos e a incompatibilidade de hor\u00e1rios. Al\u00e9m disso, eu busquei uma cabine de estudos para poder fazer novas amizades com concurseiros. Isso foi importante, pois o estudo para concursos \u00e9 repleto de d\u00favidas, a intera\u00e7\u00e3o com pessoas que est\u00e3o trilhando o mesmo caminhando ajudou a minimizar essas incertezas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Direcionando para os \u00faltimos concursos foram 6 meses. O que fez manter a disciplina foi a expectativa que seria uma grande chance. O TJMS e o TJDFT s\u00e3o tribunais que tem o hist\u00f3rico de nomearem v\u00e1rios analistas no decorrer da validade do concurso. Al\u00e9m disso, eram editais com conte\u00fado program\u00e1ticos semelhantes e com datas de provas pr\u00f3ximas. Por isso, me mantive disciplinado e focado, pois eram 2 excelentes chances que eu n\u00e3o poderia deixar passar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o? (Aulas presenciais, livros, cursos em PDF, videoaulas? Quais foram as principais vantagens e desvantagens?)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu lia a lei e s\u00famulas, fazia quest\u00f5es e acompanhava a jurisprud\u00eancia dos tribunais superiores. Usei os materiais do Estrat\u00e9gia para ver os pontos mais importantes de cada tema, os cursos em PDF deram um direcionamento naquilo que \u00e9 importante, principalmente por conter esquemas e grifos que me ajudaram na memoriza\u00e7\u00e3o. Al\u00e9m disso, eu utilizei videoaulas em temas que tive dificuldades, como por exemplo, no portugu\u00eas da FGV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acho como vantagem dos cursos em PDF: a possibilidade de ir mais r\u00e1pido no acesso \u00e0 informa\u00e7\u00e3o desejada. A videoaula apresenta como vantagem ser mais agrad\u00e1vel de estudar e como desvantagem o tempo gasto com elas. Por isso, acho que cada pessoa tem que se conhecer e ver, dentro de sua realidade, o que funciona melhor para si.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Conheci na internet com o depoimento de outras pessoas aprovadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> A diferen\u00e7a que senti foi a organiza\u00e7\u00e3o dos PDFs, com os esquemas gr\u00e1ficos, acho isso um diferencial dos materiais do Estrat\u00e9gia. Outra diferen\u00e7a relevante, foi a possibilidade de assistir \u00e0s aulas de um tema especifico que tinha dificuldade. Al\u00e9m disso, utilizei as an\u00e1lises estat\u00edsticas dos temas mais cobrados pela banca e simulados de reta final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como montou seu plano de estudos? (Estudava v\u00e1rias mat\u00e9rias ao mesmo tempo? Quantas? Quantas horas l\u00edquidas estudava por dia?)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu fazia ciclos de estudos, pegava todas as mat\u00e9rias e dividia em blocos de 2 horas. Ia revezando esses blocos com todas as mat\u00e9rias do edital. N\u00e3o focava em metas de horas liquidas, eu estudava a quantidade de horas que conseguia no dia. Tinha dia que consegui chegar a 8 horas e outros n\u00e3o estudava. N\u00e3o me apeguei em horas liquidas, pois a vida \u00e9 repleta de imprevistos e caso n\u00e3o conseguisse bater essas horas, isso causaria uma desmotiva\u00e7\u00e3o no estudo. Por isso, foquei em tentar estudar o m\u00e1ximo dentro de minha realidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es? (Costumava fazer resumos, simulados ou algo mais?)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> N\u00e3o tive um m\u00e9todo espec\u00edfico de revis\u00e3o. Surgia uma quest\u00e3o com algum assunto que n\u00e3o me lembrava, voltava no material para rever. Fiz resumos de temas espec\u00edficos, mas foram poucos. Fiz v\u00e1rios simulados de reta final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> A resolu\u00e7\u00e3o de exerc\u00edcios permite conhecer como a banca organizadora ir\u00e1 cobrar o assunto no dia da prova. Por exemplo, algumas cobram diretamente a literalidade do artigo da lei, outras, como a FGV, cobram o artigo da lei aplicado no caso concreto. Fazer quest\u00f5es permite pegar essas diferen\u00e7as de cobran\u00e7as e direciona os estudos naquilo que \u00e9 mais importante. Acho que fiz umas 10 mil quest\u00f5es mais os simulados de reta final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Senti mais dificuldade no Portugu\u00eas da FGV. Ela tem um perfil diferente de cobran\u00e7a. Eu fiz v\u00e1rias quest\u00f5es anteriores e assisti \u00e0s aulas de resolu\u00e7\u00e3o de exerc\u00edcios para compreender o perfil de cobran\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Na semana que antecedeu a prova, eu n\u00e3o consegui estudar muito bem. Eu achava que n\u00e3o iria conseguir, pois, no m\u00eas anterior a prova, n\u00e3o estudei do jeito que gostaria devido ao falecimento de meu pai. Pensei em at\u00e9 n\u00e3o ir realizar as provas, pois sabia que a concorr\u00eancia estava em alto n\u00edvel. No entanto, por j\u00e1 ter pago voo e a hospedagem, resolvi ir. No s\u00e1bado anterior a prova, eu foquei em revisar o regimento interno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> A prova de analista do TJDFT teve prova discursiva. Eu me preparei treinando com quest\u00f5es 1 vez por semana. No entanto, eu n\u00e3o me atentei que saber fazer a prova \u00e9 muito importante. Eu, por exemplo, no momento da execu\u00e7\u00e3o da prova, gastei muito tempo na parte objetiva e tive que fazer a prova discursiva correndo. Devido a essa falta de gest\u00e3o de tempo, n\u00e3o percebi os detalhes que a quest\u00e3o queria e perdi pontos preciosos que fizeram cair muitas posi\u00e7\u00f5es. Por isso, eu aconselho dar uma especial aten\u00e7\u00e3o as discursivas. Acho interessante fazer provas anteriores para conhecer o estilo de cobran\u00e7a e de avalia\u00e7\u00e3o da banca examinadora. A FGV, a t\u00edtulo de exemplo, tem muitas quest\u00f5es discursivas do exame da OAB para treino. E nos simulados, treinar o tempo de execu\u00e7\u00e3o da prova incluindo a prova discursiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Considero com acerto nos meus estudos: a disciplina e a confian\u00e7a que um dia seria aprovado. Entre os erros: acreditar que para ser aprovado precisa saber todas as leis, temas doutrin\u00e1rios mirabolantes e todas jurisprud\u00eancias dos tribunais superiores. N\u00e3o precisamos saber tudo, pois, \u00e0s vezes, apenas dominar o b\u00e1sico de cada tema \u00e9 suficiente para aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Eu pensei algumas vezes em desistir, principalmente com a quantidade de coisas que temos que estudar, as notas dos concorrentes cada dia mais altas, reforma administrativa e etc. Isso me assustou um pouco. Contudo, eu n\u00e3o tinha plano B, era passar ou passar. Com isso, a principal motiva\u00e7\u00e3o era ter a confian\u00e7a que meu esfor\u00e7o iria dar resultado, s\u00f3 n\u00e3o sabia onde e quando. Por isso resolvi continuar. O resultando veio e hoje percebo que sofri atoa por essas conjecturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jo\u00e3o Paulo:<\/strong> Tenha confian\u00e7a que o resultado chegar\u00e1 com seu esfor\u00e7o. Veja a melhor forma de estudo que funcione para voc\u00ea dentro de sua realidade, pois cada pessoa tem uma hist\u00f3ria de vida e obst\u00e1culos di\u00e1rios diferentes. Por fim, lembre-se: a aprova\u00e7\u00e3o n\u00e3o depende muito de m\u00e9todos de estudos revolucion\u00e1rios ou grau de intelig\u00eancia elevado, mas de const\u00e2ncia, perseveran\u00e7a e confian\u00e7a no estudo. Isso far\u00e1 o resultado acontecer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Lembre-se: a aprova\u00e7\u00e3o n\u00e3o depende muito de m\u00e9todos de estudos revolucion\u00e1rios ou grau de intelig\u00eancia elevado, mas de const\u00e2ncia, perseveran\u00e7a e confian\u00e7a no estudo. Isso far\u00e1 o resultado acontecer&#8221; . Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio &#8211; \u00c1rea Fim (Campo Grande): Estrat\u00e9gia Concursos: Conte-nos um [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1094066","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Jo\u00e3o Paulo Moreira - Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio - \u00c1rea Fim (Campo Grande)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Jo\u00e3o Paulo Moreira - Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio - \u00c1rea Fim (Campo Grande)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-13T20:30:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/\",\"name\":\"ENTREVISTA: Jo\u00e3o Paulo Moreira - Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/09\\\/13172849\\\/joao-paulo.jpeg\",\"datePublished\":\"2022-09-13T20:30:03+00:00\",\"dateModified\":\"2022-09-13T20:30:07+00:00\",\"description\":\"Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio - \u00c1rea Fim (Campo Grande)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/09\\\/13172849\\\/joao-paulo.jpeg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2022\\\/09\\\/13172849\\\/joao-paulo.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/depoimento\\\/concurso-tjms-aprovado-joao-paulo-moreira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Jo\u00e3o Paulo Moreira &#8211; Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Jo\u00e3o Paulo Moreira - Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio","description":"Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio - \u00c1rea Fim (Campo Grande)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Jo\u00e3o Paulo Moreira - Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio","og_description":"Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio - \u00c1rea Fim (Campo Grande)","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2022-09-13T20:30:07+00:00","og_image":[{"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/","name":"ENTREVISTA: Jo\u00e3o Paulo Moreira - Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg","datePublished":"2022-09-13T20:30:03+00:00","dateModified":"2022-09-13T20:30:07+00:00","description":"Confira nossa entrevista com Jo\u00e3o Paulo Moreira, aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio - \u00c1rea Fim (Campo Grande)","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/13172849\/joao-paulo.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-tjms-aprovado-joao-paulo-moreira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Jo\u00e3o Paulo Moreira &#8211; Aprovado em 10\u00ba lugar no concurso TJMS para\u00a0Analista Judici\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1094066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1094066\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1094066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}