{"id":1076685,"date":"2022-08-16T13:30:32","date_gmt":"2022-08-16T16:30:32","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1076685"},"modified":"2022-08-16T13:32:22","modified_gmt":"2022-08-16T16:32:22","slug":"concurso-cafar-aprovado-wallace-alves-de-lima","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/","title":{"rendered":"ENTREVISTA: Wallace Alves De Lima &#8211; Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg\" alt=\"\" class=\"wp-image-1076700\" width=\"256\" height=\"144\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-300x169.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-768x432.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-1536x865.jpeg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-610x344.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37-150x84.jpeg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/08\/12095954\/whatsapp-image-2022-08-12-at-09-42-37.jpeg 1600w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><figcaption>Wallace Alves De Lima<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>\u201cSe n\u00e3o for a sua vez, aguarde, continue estudando que a sua hora vai chegar, assim como a minha chegou tamb\u00e9m. Bons estudos a todos!\u201d<\/strong><\/p>\n\n\n\n<p>Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no Curso de Adapta\u00e7\u00e3o de Farmac\u00eauticos da Aeron\u00e1utica (CAFAR) para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Wallace Alves De Lima:<\/strong> Sou farmac\u00eautico formado pela UNISUAM e p\u00f3s-graduado pela UFRJ. Tenho 34 anos e sou natural do Rio de Janeiro.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> A estabilidade financeira e admira\u00e7\u00e3o pela a carreira militar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Geralmente eu trabalhava de dia e estudava a tarde. Mas, quando eu podia, ficava 12 horas estudando, acordava 2h antes de ir trabalhar para fazer revis\u00e3o. Quanto mais tempo investirmos nos estudos, mais pr\u00f3ximos estaremos do sucesso.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado(a)? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> J\u00e1 fui aprovado na Funda\u00e7\u00e3o de Assist\u00eancia M\u00e9dica Hospitalar da Eletronuclear, em primeiro lugar. Na Funda\u00e7\u00e3o Sa\u00fade do Estado do Rio de Janeiro, em quarto lugar. No CAFAR aprovado algumas vezes, mas, at\u00e9 ent\u00e3o, n\u00e3o classificado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Eu tinha pouca vida social, sa\u00eda pouco, ficava mais estudando mesmo. Encontrava os amigas quando era anivers\u00e1rio, e a fam\u00edlia em datas comemorativas. At\u00e9 meu anivers\u00e1rio eu j\u00e1 passei estudando (rsrs).<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casado? Tem filhos? Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Sim, tenho uma filha linda. Minha fam\u00edlia sempre me apoiou e me incentivou nos estudos. Mas, ao mesmo tempo, cobravam minha presen\u00e7a nas reuni\u00f5es de fam\u00edlias ou naqueles simples passeio em fam\u00edlia.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Eu estudo h\u00e1 uns 10 anos para esse concurso e sempre ficava perto das vagas oferecidas, mas continuei tentando at\u00e9 chegar a minha vez. Um famoso escritor disse uma vez: &#8220;voc\u00ea n\u00e3o tem que estudar para passar, tem que estudar at\u00e9 passar&#8221;. E foi isso que eu fiz, minha vez chegou.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o? (Aulas presenciais, livros, cursos em PDF, videoaulas? Quais foram as principais vantagens e desvantagens?)<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Usei muito material f\u00edsico, gosto de ler e marcar para fazer minha revis\u00e3o. As videoaulas eu assistia quando estava cansado de ler, dessa forma eu descansava da leitura e continuava estudando. A vantagem da leitura \u00e9 que voc\u00ea consegue destacar os detalhes que as bancas pedem, a desvantagem \u00e9\u00a0 que esse tipo de estudo demanda muito tempo. Para quem n\u00e3o possui muito tempo, as videoaulas s\u00e3o uma excelente ferramenta.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Conheci o Estrat\u00e9gia pesquisando editais abertos. Para qualquer edital o Estrat\u00e9gia tem um curso preparado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos? Se sim, o que mais incomodava quando voc\u00ea estudava por esse concorrente?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Sim, usei alguns cursos. Alguns n\u00e3o possuem muito foco na banca que realiza o CAFAR, mas n\u00e3o deixam de serem bons cursos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Sim, fui aprovado, mas n\u00e3o classificado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Utilizei o.material do Estrat\u00e9gia para fazer o concurso de Bioqu\u00edmico da Pol\u00edcia Militar do Rio Grande do Norte. As apostilas resumidas e os exerc\u00edcio ajudaram bastante.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos? (Estudava v\u00e1rias mat\u00e9rias ao mesmo tempo? Quantas? Quantas horas l\u00edquidas estudava por dia?)<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Geralmente eu estudava uma mat\u00e9ria espec\u00edfica e portugu\u00eas, ou no m\u00e1ximo duas mat\u00e9rias espec\u00edficas e portugu\u00eas. Eu estudava de 4 a 6 horas por dia. Aos s\u00e1bados e domingos estudava mais horas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es? (Costumava fazer resumos, simulados ou algo mais?)<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Eu lia, fazia resumos e depois exerc\u00edcios.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> A resolu\u00e7\u00e3o de quest\u00f5es \u00e9\u00a0fundamental. Vale destacar que \u00e9\u00a0importante dar mais \u00eanfase \u00e0s quest\u00f5es caracter\u00edsticas da banca,\u00a0 pois o candidato vai se familiarizando com a forma que o assunto \u00e9 cobrado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Microbiologia e biologia molecular. Assistindo videoaulas, al\u00e9m das leituras.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> S\u00f3 leitura dos resumo e exerc\u00edcios.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Fiz cursos e simulados desta disciplina. Aconselho que fa\u00e7am o mesmo e que estejam bem atentos aos temas militares, \u00e0s atualidades e na forma que a banca corrige a reda\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Wallace:<\/strong> Principal erro foi n\u00e3o destinar mais tempo para a prepara\u00e7\u00e3o da reda\u00e7\u00e3o. J\u00e1 o principal acerto foi destinar bastante tempo para a parte espec\u00edfica, cujo peso \u00e9 maior.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Wallace: <\/strong>Sim, pois sempre chegava perto e nunca entrava nas vagas. A minha principal motiva\u00e7\u00e3o foi que este era meu \u00faltimo ano e eu sabia que poderia fazer uma boa prova com os conhecimentos que adquiri ao longo do tempo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Wallace: <\/strong>Bem, eu aconselho que se dediquem ao m\u00e1ximo e que no dia da prova estejam tranquilos, sem se cobrar tanto. Se cobrem na prepara\u00e7\u00e3o e no dia da prova brilhem. Se n\u00e3o for a sua vez, aguarde, continue estudando que a sua hora vai chegar, assim como a minha chegou tamb\u00e9m. Bons estudos a todos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSe n\u00e3o for a sua vez, aguarde, continue estudando que a sua hora vai chegar, assim como a minha chegou tamb\u00e9m. Bons estudos a todos!\u201d Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no Curso de Adapta\u00e7\u00e3o de Farmac\u00eauticos da Aeron\u00e1utica (CAFAR) para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas: Estrat\u00e9gia Concursos: Conte-nos um [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1076685","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Wallace Alves De Lima - Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas<\/title>\n<meta name=\"description\" content=\"Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no concurso CAFAR para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Wallace Alves De Lima - Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas\" \/>\n<meta property=\"og:description\" content=\"Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no concurso CAFAR para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T16:32:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/\",\"name\":\"ENTREVISTA: Wallace Alves De Lima - Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg\",\"datePublished\":\"2022-08-16T16:30:32+00:00\",\"dateModified\":\"2022-08-16T16:32:22+00:00\",\"description\":\"Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no concurso CAFAR para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#primaryimage\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg\",\"contentUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Wallace Alves De Lima &#8211; Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Wallace Alves De Lima - Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas","description":"Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no concurso CAFAR para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Wallace Alves De Lima - Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas","og_description":"Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no concurso CAFAR para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2022-08-16T16:32:22+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/","name":"ENTREVISTA: Wallace Alves De Lima - Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg","datePublished":"2022-08-16T16:30:32+00:00","dateModified":"2022-08-16T16:32:22+00:00","description":"Confira a nossa entrevista com Wallace Alves De Lima, aprovado em 3\u00b0 lugar no concurso CAFAR para Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#primaryimage","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg","contentUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/08\/whatsapp-image-2022-08-12-at-09-42-37-1024x577.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cafar-aprovado-wallace-alves-de-lima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Wallace Alves De Lima &#8211; Aprovado em 3\u00b0 lugar no concurso CAFAR para o cargo Farm\u00e1cia Bioqu\u00edmica\/An\u00e1lises Qu\u00edmicas"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1076685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1076685\/revisions"}],"predecessor-version":[{"id":1435430,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1076685\/revisions\/1435430"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1076685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}