{"id":1055508,"date":"2022-07-05T10:46:14","date_gmt":"2022-07-05T13:46:14","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1055508"},"modified":"2022-07-05T12:59:33","modified_gmt":"2022-07-05T15:59:33","slug":"concurso-cgu-aprovado-carlos-franca","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/","title":{"rendered":"ENTREVISTA: Carlos Fran\u00e7a &#8211; Aprovado  no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle &#8211; Auditoria e Fiscaliza\u00e7\u00e3o (DF)"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><em>&#8220;Assim como 2+2=4, voc\u00ea passar\u00e1 no seu concurso se continuar estudando com qualidade. S\u00f3 n\u00e3o passa quem desiste! O oposto do sucesso n\u00e3o \u00e9 o fracasso, mas sim a desist\u00eancia! Fracasso faz parte da evolu\u00e7\u00e3o&#8221;<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05125701\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg\" alt=\"\" class=\"wp-image-1055600\" width=\"181\" height=\"241\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05125701\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05125701\/whatsapp-image-2022-07-05-at-11-58-37-225x300.jpeg 225w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05125701\/whatsapp-image-2022-07-05-at-11-58-37-1152x1536.jpeg 1152w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05125701\/whatsapp-image-2022-07-05-at-11-58-37-610x813.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05125701\/whatsapp-image-2022-07-05-at-11-58-37.jpeg 1200w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><\/figure><\/div>\n\n\n\n<p>Confira nossa entrevista com Carlos Fran\u00e7a, aprovado  no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle &#8211; Auditoria e Fiscaliza\u00e7\u00e3o (DF):<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Carlos Fran\u00e7a: <\/strong>Sou Engenheiro Qu\u00edmico, tenho 27 anos e sou de Recife.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Al\u00e9m do mercado de trabalho estar escasso para engenheiros, nas poucas sele\u00e7\u00f5es das quais participei, percebi que n\u00e3o tinha perfil para trabalhar ou pesquisar na \u00e1rea. Eu precisava ajudar minha m\u00e3e e me encontrar profissionalmente. Decidi olhar com mais carinho o servi\u00e7o p\u00fablico e percebi que me enxergava como servidor.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Eu sou servidor da UFPE (assistente administrativo) e trabalho 40 horas semanais. Para estudar, tracei a meta de 3 horas l\u00edquidas nos dias de semana e 6 horas nos finais de semana. Sempre preferi estudar com a \u201cmente limpa\u201d, portanto acordava \u00e0s 4:15 e buscava estudar at\u00e9 6:30. Ap\u00f3s o expediente, ao chegar em casa, tentava estudar pelo menos mais uma hora.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Com muito esfor\u00e7o e disciplina, consegui as seguintes aprova\u00e7\u00f5es: IBGE (Analista Censit\u00e1rio \u2013 4\u00ba lugar); UFRPE, UFPE e UFRN (Assistente Administrativo \u2013 7\u00ba, 4\u00ba e 2\u00ba lugar, respectivamente), IBAMA (Analista Administrativo do DF \u2013 36\u00ba lugar) e agora na CGU (Auditor Federal de Finan\u00e7as e Controle do DF \u2013 56\u00ba lugar). Ap\u00f3s a aprova\u00e7\u00e3o na CGU, resolvi \u201caposentar as canetas\u201d. AL\u00d4, THAIS MENDES, CONSEGUI!<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Eu sempre fui muito \u201ccaseiro\u201d. Ap\u00f3s come\u00e7ar a estudar para a \u00e1rea de controle, diminu\u00ed ainda mais a frequ\u00eancia de encontros sociais com fam\u00edlia e amigos. Ainda assim, eu possuo uma banda (@gelobaiano no Insta! rsrs) e costumava ensaiar a cada duas semanas, assim como visitava minha namorada nas outras duas semanas do m\u00eas.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casado? Tem filhos? Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Eu namoro e n\u00e3o possuo filhos. Minha fam\u00edlia sempre me apoiou bastante com energias positivas e com muita compreens\u00e3o acerca do meu \u201csumi\u00e7o\u201d social. Minha m\u00e3e fez absolutamente tudo que estava ao seu alcance para que eu me preocupasse apenas com o trabalho e estudos. Meus amigos tamb\u00e9m sempre torceram por mim e me animavam para que eu me sentisse confiante e motivado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Sempre achei essa pergunta dif\u00edcil de ser respondida, afinal n\u00e3o comecei \u201cdo zero\u201d para a CGU. Eu estudo desde 2018 e constru\u00ed uma boa base ao longo dos anos, sendo, indiretamente, um certo \u201cdirecionamento\u201d para a CGU (mesmo que na \u00e9poca eu n\u00e3o soubesse). Mas sendo mais pr\u00e1tico, posso responder que estudei para a \u00e1rea de controle (foco no TCU) desde 2020, e para a CGU, em espec\u00edfico, por 7 meses.<strong><\/strong><\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o? (Aulas presenciais, livros, cursos em PDF, videoaulas? Quais foram as principais vantagens e desvantagens?)<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Usei principalmente o PDF. Videoaulas s\u00f3 quando estava cansado e tentava absorver algo. Usei bastante um aplicativo de flashcards para memoriza\u00e7\u00e3o de lei seca e prepara\u00e7\u00e3o para as discursivas.<\/p>\n\n\n\n<p>PDFs e flashcards t\u00eam a grande vantagem do estudo ativo, muito mais enriquecedor e r\u00e1pido. A desvantagem dos flashcards \u00e9 o tempo que leva para construir as cartas.<\/p>\n\n\n\n<p>Videoaulas s\u00e3o mais c\u00f4modas, guiam um estudo passivo e s\u00e3o mais recomendadas para quem tem dificuldade em determinado assunto, por ser mais f\u00e1cil de ser compreendida. A desvantagem \u00e9 o tempo para ser \u201cconsumido\u201d o conte\u00fado.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Vai parecer at\u00e9 propaganda, mas foi exatamente assim: resolvi procurar na internet: \u201cqual o melhor curso preparat\u00f3rio online para concursos?\u201d. A maioria dos blogs e posts apontavam o Estrat\u00e9gia como o melhor. Resolvi assistir os v\u00eddeos no canal do curso e percebi a qualidade.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Ao me tornar aluno, percebi que na prova eu tinha conhecimento de tudo que estava sendo cobrado l\u00e1, mesmo que um conhecimento m\u00ednimo. Isso demonstra a abrang\u00eancia do conte\u00fado abordado pelo Estrat\u00e9gia. Al\u00e9m disso, a quantidade e qualidade das quest\u00f5es selecionadas para os PDFs ajudam o aluno a ter uma prepara\u00e7\u00e3o de alto n\u00edvel, o famoso \u201ctreinamento dif\u00edcil, combate f\u00e1cil\u201d. N\u00e3o \u00e9 \u00e0 toa que o Estrat\u00e9gia tem os n\u00fameros de aprovados t\u00e3o altos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos? (Estudava v\u00e1rias mat\u00e9rias ao mesmo tempo? Quantas? Quantas horas l\u00edquidas estudava por dia?)<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Para a CGU, me adaptei melhor ao m\u00e9todo 4.2. Consiste em separar 4 dias para teoria e 2 dias para revis\u00e3o, separando as mat\u00e9rias em 2 grupos: A e B. No meu caso, adaptei o m\u00e9todo e criei uma planilha para organizar tudo, estudando 9 disciplinas por ciclo, divididas em 3 grupos: A, B e C. Ou seja, 3 disciplinas por dia, com 1 hora para cada uma, totalizando 3 horas l\u00edquidas nos dias de semana. No s\u00e1bado, a ideia era realizar \u201cdois dias em um\u201d, totalizando 6 horas l\u00edquidas. No domingo, a regra era treino de discursivas e simulados.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es? (Costumava fazer resumos, simulados ou algo mais?)<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Revisava por leitura de grifos nos PDFs, flashcards, quest\u00f5es e alguns resumos \u00e0 m\u00e3o (esporadicamente, em assuntos puramente \u201cdecorebas\u201d)<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Resolver exerc\u00edcios \u00e9 fundamental para uma boa prepara\u00e7\u00e3o, pois nossa tarefa final \u00e9 encarar uma prova com v\u00e1rias quest\u00f5es! Na reta final foquei bastante em resolu\u00e7\u00f5es de quest\u00f5es abertas e fechadas, mas infelizmente n\u00e3o contabilizava a quantidade total.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Para a CGU, tive dificuldades em Administra\u00e7\u00e3o P\u00fablica e t\u00f3picos de Contabilidade P\u00fablica. Acabei comprando cursos extras (feitos por professores do Estrat\u00e9gia) dessas disciplinas, assisti algumas videoaulas e dei uma carga maior na revis\u00e3o da teoria.<strong><\/strong><\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Faltando um m\u00eas para a prova, tirei f\u00e9rias do trabalho e paguei uma sala de estudos, para estudar diariamente com uma alta carga l\u00edquida. Assim foi at\u00e9 a sexta-feira. No s\u00e1bado (v\u00e9spera de prova), assisti a transmiss\u00e3o do aul\u00e3o de v\u00e9spera do Estrat\u00e9gia e em seguida fui relaxar o resto do dia, fazendo coisas que gosto.<strong><\/strong><\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>A discursiva muda vidas. Muitas pessoas temem a discursiva, e \u00e9 a\u00ed que o candidato preparado deve tirar vantagem contra a concorr\u00eancia. Eu fiquei na nota de corte, e gra\u00e7as \u00e0 discursiva, subi 119 posi\u00e7\u00f5es, para chegar na 56\u00aa posi\u00e7\u00e3o (de 60 vagas).<\/p>\n\n\n\n<p>Busquei fazer ao menos uma discursiva de 60 ou 90 linhas por semana. Comprei a mentoria do professor Possati, bem como um pacote de corre\u00e7\u00f5es de discursivas. Ia recebendo os feedbacks e me aprimorando cada vez mais na parte estrutural. Quanto \u00e0 parte te\u00f3rica, mudei tamb\u00e9m a abordagem de estudo, usando especialmente flashcards para responder perguntas mais complexas e abertas.<\/p>\n\n\n\n<p>Aconselho o concurseiro a perder o medo da discursiva, come\u00e7ando aos poucos, consultando o material durante os primeiros treinos de reda\u00e7\u00e3o. Ganhe confian\u00e7a, agilidade e conhecimento. A partir da\u00ed, fa\u00e7a discursivas sem consultar nada, e escreva ao menos uma por semana (no p\u00f3s edital, duas por semana).<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>ACERTOS: Me preparar bem para discursivas, utilizar bastante flashcards, manter a disciplina e const\u00e2ncia nos estudos, mesmo que o dia n\u00e3o fosse produtivo, e, acima de tudo, buscar o equil\u00edbrio emocional durante os estudos\/simulados\/provas (no meu caso, atrav\u00e9s de terapia com psic\u00f3loga).<\/p>\n\n\n\n<p>ERROS: Estudar pouco jurisprud\u00eancia e fazer poucas quest\u00f5es de l\u00edngua portuguesa.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Nunca pensei em desistir. Eu queria muito passar na CGU, e todo dia tentava provar isso a mim mesmo. Minhas principais motiva\u00e7\u00f5es foram dar uma vida digna \u00e0 minha m\u00e3e e construir minha vida independente.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Carlos: <\/strong>Estude. Acredite (e muito). Deseje (e muito). Pense no seu cargo p\u00fablico \u201cideal\u201d&#8230; O quanto voc\u00ea deseja passar nele? Prove a si mesmo o quanto voc\u00ea quer! Prove todo dia. Fa\u00e7a acontecer. Mas n\u00e3o se desespere, existem dias bons e dias ruins de estudos. Apenas continue. Equilibre as emo\u00e7\u00f5es, pense sempre positivo e foque nos seus erros. Aprimore seus estudos, seus conhecimentos.<\/p>\n\n\n\n<p>Assim como 2+2=4, voc\u00ea passar\u00e1 no seu concurso se continuar estudando com qualidade. S\u00f3 n\u00e3o passa quem desiste! O oposto do sucesso n\u00e3o \u00e9 o fracasso, mas sim a desist\u00eancia! Fracasso faz parte da evolu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por \u00faltimo, gostaria aqui de resgatar um trecho da minha entrevista por escrito em 2020:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"836\" height=\"473\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05104434\/foto-1-cralos-franca.jpg\" alt=\"\" class=\"wp-image-1055515\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05104434\/foto-1-cralos-franca.jpg 836w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05104434\/foto-1-cralos-franca-300x170.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05104434\/foto-1-cralos-franca-768x435.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/05104434\/foto-1-cralos-franca-610x345.jpg 610w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><\/figure>\n\n\n\n<p>Eu tenho orgulho de dizer a mim mesmo que consegui. Cheguei l\u00e1. At\u00e9 jaj\u00e1, Thais! : )<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Assim como 2+2=4, voc\u00ea passar\u00e1 no seu concurso se continuar estudando com qualidade. S\u00f3 n\u00e3o passa quem desiste! O oposto do sucesso n\u00e3o \u00e9 o fracasso, mas sim a desist\u00eancia! Fracasso faz parte da evolu\u00e7\u00e3o&#8221; Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1055508","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Carlos Fran\u00e7a - Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Carlos Fran\u00e7a - Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-05T15:59:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/\",\"name\":\"ENTREVISTA: Carlos Fran\u00e7a - Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg\",\"datePublished\":\"2022-07-05T13:46:14+00:00\",\"dateModified\":\"2022-07-05T15:59:33+00:00\",\"description\":\"Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#primaryimage\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg\",\"contentUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Carlos Fran\u00e7a &#8211; Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle &#8211; Auditoria e Fiscaliza\u00e7\u00e3o (DF)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Carlos Fran\u00e7a - Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)","description":"Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Carlos Fran\u00e7a - Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)","og_description":"Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2022-07-05T15:59:33+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/","name":"ENTREVISTA: Carlos Fran\u00e7a - Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg","datePublished":"2022-07-05T13:46:14+00:00","dateModified":"2022-07-05T15:59:33+00:00","description":"Confira nossa entrevista com Carlos Fran\u00e7a, aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o (DF)","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#primaryimage","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg","contentUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/07\/whatsapp-image-2022-07-05-at-11-58-37-768x1024.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-carlos-franca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Carlos Fran\u00e7a &#8211; Aprovado no concurso CGU para o cargo de Auditor Federal de Finan\u00e7as e Controle &#8211; Auditoria e Fiscaliza\u00e7\u00e3o (DF)"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1055508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1055508\/revisions"}],"predecessor-version":[{"id":1055602,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1055508\/revisions\/1055602"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1055508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}