{"id":1049290,"date":"2022-06-29T14:58:25","date_gmt":"2022-06-29T17:58:25","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1049290"},"modified":"2022-06-29T14:58:27","modified_gmt":"2022-06-29T17:58:27","slug":"entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/","title":{"rendered":"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"196\" height=\"300\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1-196x300.jpeg\" alt=\"\" class=\"wp-image-1049306\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1-196x300.jpeg 196w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1-670x1024.jpeg 670w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1-768x1174.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1-1005x1536.jpeg 1005w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1-610x932.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23163446\/foto-1.jpeg 1047w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><figcaption>Zulmiro Martins Luz Junnior<\/figcaption><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>&#8220;Acredito que quanto antes voc\u00ea entender que passar em concurso n\u00e3o \u00e9 um dom e sim resultado de muito trabalho duro, melhor ser\u00e1 a sua disposi\u00e7\u00e3o para manter-se firme.&#8221;<\/strong><\/p><cite>&#8211; Zulmiro Junnior<\/cite><\/blockquote>\n\n\n\n<p>Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle &#8211; Auditoria e Fiscaliza\u00e7\u00e3o &#8211; Rond\u00f4nia<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro Martin Luz Junnior: <\/strong>Me chamo Zulmiro J\u00fannior, sou graduado em Ci\u00eancias Cont\u00e1beis e tenho 28 anos. Sou natural de Presidente M\u00e9dici, interior do estado de Rond\u00f4nia, contudo resido a pouco mais de 2 anos na cidade de Porto Velho\/RO.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro: <\/strong>Desde a \u00e9poca da faculdade que escuto muito as pessoas comentando sobre o cargo de Auditor. Quando descobri o portal da transpar\u00eancia e consultei o sal\u00e1rio de um Auditor tive a certeza de que um dia gostaria de desempenhar essa atividade, rs. <\/p>\n\n\n\n<p>No meu \u00faltimo ano de faculdade (2015) resolvi que assim que terminasse o curso iniciaria os estudos para Auditor, por\u00e9m algumas portas foram se abrindo para mim no setor privado. Assim que me formei tive a oportunidade de come\u00e7ar a assinar como contador respons\u00e1vel t\u00e9cnico na empresa em que eu trabalhava, pouco tempo depois surgiu a oportunidade de come\u00e7ar a lecionar na faculdade em que eu havia me formado. <\/p>\n\n\n\n<p>Como o sal\u00e1rio deu uma boa melhorada (rs) e devido ao fato de eu estar trabalhando durante tr\u00eas turnos (manh\u00e3, tarde e noite), resolvi deixar o estudo para concurso para um outro momento e aproveitar as oportunidades que eu estava recebendo. Ao final do ano de 2017 percebi que estava infeliz e exausto com a vida que estava levando, afinal eu trabalhava praticamente todos os dias durante tr\u00eas turnos. Eu via alguns conhecidos que eram servidores p\u00fablicos recebendo bons sal\u00e1rios e trabalhando muito menos do que eu, ent\u00e3o o somat\u00f3rio disso tudo foi o que me fez pedir demiss\u00e3o de um dos meus empregos e come\u00e7ar a estudar para concursos.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Hoje eu j\u00e1 sou servidor p\u00fablico, trabalho em torno de 34 horas semanais, ent\u00e3o precisei conciliar o trabalho com os estudos para esse concurso. Para aproveitar melhor o meu tempo eu acordava em torno de 4 horas da manh\u00e3, dessa forma quando iniciava o meu hor\u00e1rio de expediente eu j\u00e1 tinha feito uma boa carga hor\u00e1ria de estudos. Como trabalho no Poder Legislativo, aproveitei o per\u00edodo de recesso parlamentar para dedicar 100% do meu tempo dispon\u00edvel aos estudos e tirei um per\u00edodo de 10 dias de f\u00e9rias. Fui beneficiado tamb\u00e9m com o feriado prolongado do carnaval.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? Em qual cargo e em que coloca\u00e7\u00e3o? Pretende continuar estudando?<\/strong><\/p>\n\n\n\n<p><strong><\/strong><strong>Zulmiro:<\/strong> Desde quando eu resolvi que realmente iria estudar para concurso fiz apenas duas provas. A primeira foi no ano de 2018, 3 meses ap\u00f3s iniciar os estudos para concurso, para o cargo de Analista Legislativo \u2013 Contabilidade da Assembleia Legislativa do Estado de Rond\u00f4nia, onde fui aprovado na 2\u00aa coloca\u00e7\u00e3o para o cargo que ocupo hoje. <\/p>\n\n\n\n<p>A segunda prova que fiz foi essa para Auditor da CGU, sendo aprovado na 3\u00aa coloca\u00e7\u00e3o. Como meu sonho no servi\u00e7o p\u00fablico sempre foi seguir uma carreira na \u00e1rea de auditoria, acredito que agora eu tenha pendurado as chuteiras, provavelmente n\u00e3o estudarei mais para concursos.\u00a0<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? Voc\u00ea sa\u00eda com amigos e fam\u00edlia?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Eu sou uma pessoa extremamente caseira, meu passatempo preferido \u00e9 ficar em casa com a minha esposa, ent\u00e3o n\u00e3o tive dificuldades nessa \u00e1rea.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea \u00e9 casado? Tem filhos? Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Sou muito bem casado! Devo as minhas aprova\u00e7\u00f5es ao apoio incondicional da minha esposa. N\u00e3o teria conseguido pedir demiss\u00e3o de um dos meus empregos sem o seu encorajamento, consequentemente n\u00e3o teria sido aprovado no concurso da Assembleia Legislativa. Tamb\u00e9m n\u00e3o teria sido aprovado neste concurso da CGU, pois eu estava parado nos estudos, minha ideia era retornar estudando para a \u00e1rea fiscal, quando abriu o edital da CGU ela me encorajou a voltar aos estudos j\u00e1 com foco nessa prova. Gra\u00e7as a Deus eu a escutei e no final deu tudo certo!<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Eu estava parado nos estudos, por\u00e9m j\u00e1 tinha uma base em algumas mat\u00e9rias. Comecei a estudar para esse concurso exatamente no dia 29\/12\/2021, ent\u00e3o tive pouco menos que 3 meses de prepara\u00e7\u00e3o para esse certame. Eu n\u00e3o acredito em f\u00f3rmulas m\u00e1gicas, e nem em motiva\u00e7\u00e3o da forma como muitos pregam. Eu mantive a disciplina nos estudos simplesmente porque eu queria fazer parte de uma carreira de auditoria e ser muito bem remunerado. Se isso n\u00e3o for o suficiente para qualquer pessoa manter a disciplina nos estudos ent\u00e3o nada ser\u00e1.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o? (Aulas presenciais, livros, cursos em PDF, videoaulas? Quais foram as principais vantagens e desvantagens?)<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Minha base foram os PDFs simplificados. Como eu tive que correr atr\u00e1s de muitas mat\u00e9rias n\u00e3o seria vi\u00e1vel ler os PDFs completos, dessa forma eu praticamente fechei o edital nesse curto per\u00edodo de prepara\u00e7\u00e3o. Para algumas aulas eu usei apenas o Passo Estrat\u00e9gico, que \u00e9 um \u00f3timo material para quem j\u00e1 estudou a aula e precisa relembrar\/revisar o conte\u00fado. Eu particularmente n\u00e3o gosto muito de v\u00eddeo aula, pois n\u00e3o tenho muito paci\u00eancia em assistir, mesmo acelerando em 2x, contudo na semana da prova eu estava t\u00e3o nervoso que n\u00e3o conseguia mais ler nada, foi a\u00ed que comecei a assistir aos v\u00eddeos de revis\u00e3o dos professores, com as dicas e apostas.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Conheci o Estrat\u00e9gia na \u00e9poca da faculdade, quando eu pesquisava na internet sobre cursinhos para concurso. Na ocasi\u00e3o eu adquiri um curso avulso de Contabilidade de Custos e gostei da metodologia utilizada no PDF. Depois disso passei a adquirir outros materiais do Estrat\u00e9gia sempre que precisava.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Para mim o diferencial \u00e9 a quantidade de materiais dispon\u00edveis para facilitar a vida do aluno. Seria muito dif\u00edcil de eu conseguir a aprova\u00e7\u00e3o nesse concurso sem os PDFs simplificados. Posso citar tamb\u00e9m o Passo Estrat\u00e9gico e os Bizus, que enriqueceram muito as minhas revis\u00f5es. Embora eu n\u00e3o tenha utilizado neste concurso, gosto bastante tamb\u00e9m da proposta da Trilha Estrat\u00e9gica.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como montou seu plano de estudos? (Estudava v\u00e1rias mat\u00e9rias ao mesmo tempo? Quantas? Quantas horas l\u00edquidas estudava por dia?)<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Eu dividia a carga hor\u00e1ria de acordo com o tamanho e relev\u00e2ncia da mat\u00e9ria. O meu objetivo era n\u00e3o estudar uma mat\u00e9ria por mais do que uma hora seguida (embora as vezes extrapolasse um pouco esse tempo), pois saber que eu veria v\u00e1rias mat\u00e9rias no dia me deixava mais animado. Outra coisa que eu tentava fazer era n\u00e3o estudar duas mat\u00e9rias parecidas de forma seguida, por exemplo, se eu estava estudando AFO a pr\u00f3xima mat\u00e9ria n\u00e3o poderia ser Contabilidade P\u00fablica. Minha meta era fazer entre 7 e 9 horas l\u00edquidas. Para que isso fosse poss\u00edvel eu acordava \u00e0s 4 da manh\u00e3, pois precisei conciliar os estudos com o trabalho.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es? (Costumava fazer resumos, simulados ou algo mais?)<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Eu mapeei as mat\u00e9rias em que eu j\u00e1 tinha uma base e acabei tratando as revis\u00f5es de forma individualizada por mat\u00e9ria. Algumas mat\u00e9rias eu revisei apenas pelas minhas marca\u00e7\u00f5es nos PDFs, Passo Estrat\u00e9gico, Resumos e Mapas Mentais dispon\u00edveis nas aulas, outras eu revisei apenas por meio de quest\u00f5es do sistema do Estrat\u00e9gia, e em algumas como Auditoria e Administra\u00e7\u00e3o P\u00fablica eu confeccionei flashcards para as aulas que ainda n\u00e3o tinha sido objeto de prova em concursos anteriores. Utilizei tamb\u00e9m os Bizus na reta final. Como minha prepara\u00e7\u00e3o foi muito corrida, acabei conseguindo fazer apenas 2 dos v\u00e1rios simulados que o Estrat\u00e9gia disponibilizou.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> A resolu\u00e7\u00e3o de quest\u00f5es \u00e9 muito importante para a fixa\u00e7\u00e3o do conte\u00fado, contudo as bancas cada vez mais vem inovando nas formas de cobran\u00e7a, ent\u00e3o ter um bom desempenho na resolu\u00e7\u00e3o de quest\u00f5es anteriores n\u00e3o necessariamente garante um bom desempenho na prova. Penso que a resolu\u00e7\u00e3o de quest\u00f5es \u00e9 um meio para se chegar ao objetivo final, que \u00e9 aprender a mat\u00e9ria. Fiz uma boa quantidade de quest\u00f5es, por\u00e9m tive o entendimento de n\u00e3o me iludir com a quantidade de acertos ou de quest\u00f5es resolvidas, uma vez que muitas quest\u00f5es se repetem, mesmo que apenas em sua ess\u00eancia. Acabei focando muito apenas nas quest\u00f5es que errava, dessa forma refiz muitas quest\u00f5es, ent\u00e3o acredito que esse tenha sido o diferencial.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Eu tive um pouco de dificuldade em Auditoria Governamental, pois tinha alguns t\u00f3picos que nunca foram cobrados em concursos, dessa forma n\u00e3o havia quest\u00f5es no banco de dados do sistema, e eu ODEIO Portugu\u00eas, principalmente a forma como a FGV trabalha a mat\u00e9ria. <\/p>\n\n\n\n<p>Para Auditoria eu foquei muito nos resumos apresentados pelos professores e confeccionei alguns flashcards, sendo que eu lia esses materiais todos os dias. J\u00e1 em portugu\u00eas n\u00e3o tive muito o que fazer, foi a mat\u00e9ria que eu deixei para o final, estudei apenas no \u00faltimo m\u00eas pelos v\u00eddeos de revis\u00e3o da professora Adriana Figueiredo, tive um desempenho p\u00edfio.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Na semana da prova eu estava t\u00e3o nervoso que n\u00e3o conseguia mais ler nada, foi a\u00ed que comecei a assistir aos v\u00eddeos de revis\u00e3o dos professores com as dicas e apostas. Tamb\u00e9m assisti a revis\u00e3o de v\u00e9spera (tudo acelerado em 2x rs). Essas revis\u00f5es fornecidas pelo Estrat\u00e9gia me ajudaram muito, principalmente as aulas de jurisprud\u00eancia de Direito Administrativo (Herbert Almeida) e Constitucional (Nelma Fontana). Essa foi a minha \u00fanica fonte de estudo na semana da prova.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? O que voc\u00ea aconselha?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Eu comecei a estudar para a prova discursiva exatamente 1 m\u00eas antes da sua aplica\u00e7\u00e3o. Treinei muito, pois minha letra \u00e9 horr\u00edvel e tinha que tentar melhor\u00e1-la. Eu dedicava em torno de 2 horas di\u00e1rias s\u00f3 para o estudo da discursiva. Aconselho fazer esquemas e mapas mentais para os t\u00f3picos complexos e tentar replic\u00e1-los sem olhar, essa t\u00e9cnica me fez memorizar muitos t\u00f3picos extensos e de alto grau de dificuldade.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Meu maior erro foi n\u00e3o ter controlado a ansiedade, se eu tivesse conseguido me controlar poderia ter feito uma prova muito melhor, em certo momento pensei que tinha muitas chances de enfartar, minhas m\u00e3os ficaram tremendo durante praticamente toda a prova.<\/p>\n\n\n\n<p>Eu tive dois grandes acertos: 1\u00ba Me inscrevi para fazer o concurso da Sefaz AM e estava pensando em conciliar esse concurso com o da CGU, minha esposa me aconselhou a focar 100% dos meus esfor\u00e7os na CGU, fiz isso e acabei desistindo da Sefaz AM; 2\u00ba Por ser um concurso da \u00e1rea de controle e devido ao fato de o edital ter trazido apenas 5 quest\u00f5es de AFO, decidi apostar que a discursiva de maior peso seria sobre algum tema relacionado a essa mat\u00e9ria. Essa aposta deu muito certo, pois a discursiva de 90 linhas tinha v\u00e1rios t\u00f3picos de AFO, o que foi um diferencial para mim, fazendo com que eu pulasse da 7\u00aa para a 3\u00aa coloca\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Em muitos momentos eu pensei em n\u00e3o estudar mais para concurso, em seguir na minha carreira de Analista. O que me fez seguir foi o sonho de participar de uma carreira de auditoria, com uma \u00f3tima remunera\u00e7\u00e3o e com possibilidades de crescimento sem depender de indica\u00e7\u00e3o pol\u00edtica, e quando vi que o edital da CGU contemplava vagas para a minha cidade atual (Porto Velho\/RO) n\u00e3o tive d\u00favidas de que teria que dar tudo de mim para n\u00e3o deixar essa oportunidade passar.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><\/p>\n\n\n\n<p><strong>Zulmiro:<\/strong> Estudar para concursos \u00e9 muito ruim. Eu nunca gostei de estudar e n\u00e3o sou um g\u00eanio, diferentemente do que alguns pensam. Acredito que quanto antes voc\u00ea entender que passar em concurso n\u00e3o \u00e9 um dom e sim resultado de muito trabalho duro, melhor ser\u00e1 a sua disposi\u00e7\u00e3o para manter-se firme. Ent\u00e3o n\u00e3o tente romantizar o estudo, n\u00e3o estude apenas quando estiver motivado, crie uma rotina e, independentemente de como estiver o seu humor, estude, mesmo que voc\u00ea esteja triste ou desanimado continue estudando. Como consequ\u00eancia do h\u00e1bito um dia o resultado vir\u00e1!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Acredito que quanto antes voc\u00ea entender que passar em concurso n\u00e3o \u00e9 um dom e sim resultado de muito trabalho duro, melhor ser\u00e1 a sua disposi\u00e7\u00e3o para manter-se firme.&#8221; &#8211; Zulmiro Junnior Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1049290","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o - Rond\u00f4nia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o - Rond\u00f4nia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-29T17:58:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/\",\"name\":\"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg\",\"datePublished\":\"2022-06-29T17:58:25+00:00\",\"dateModified\":\"2022-06-29T17:58:27+00:00\",\"description\":\"Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o - Rond\u00f4nia\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#primaryimage\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg\",\"contentUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle","description":"Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o - Rond\u00f4nia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle","og_description":"Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o - Rond\u00f4nia","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2022-06-29T17:58:27+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/","name":"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg","datePublished":"2022-06-29T17:58:25+00:00","dateModified":"2022-06-29T17:58:27+00:00","description":"Confira nossa entrevista com Zulmiro Martin Luz Junnior, aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle - Auditoria e Fiscaliza\u00e7\u00e3o - Rond\u00f4nia","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#primaryimage","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg","contentUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/foto-1-196x300.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-zulmiro-martins-luz-junnior-aprovado-em-3o-lugar-no-concurso-cgu-para-o-cargo-de-auditor-federal-de-financas-e-controle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Zulmiro Martins Luz Junnior, Aprovado em 3\u00ba lugar no concurso CGU, para o cargo de Auditor Federal de Finan\u00e7as e Controle"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1049290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1049290\/revisions"}],"predecessor-version":[{"id":1052518,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1049290\/revisions\/1052518"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1049290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}