{"id":1048975,"date":"2022-06-23T12:06:46","date_gmt":"2022-06-23T15:06:46","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?post_type=depoimento&#038;p=1048975"},"modified":"2023-05-22T15:43:22","modified_gmt":"2023-05-22T18:43:22","slug":"concurso-cgu-aprovado-thiago-barbosa-de-lima","status":"publish","type":"depoimento","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/","title":{"rendered":"ENTREVISTA: Thiago Lima &#8211; Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-1024x814.jpg\" alt=\"\" class=\"wp-image-1048991\" width=\"256\" height=\"204\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-1024x814.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-300x238.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-768x610.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-1536x1220.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-2048x1627.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-610x485.jpg 610w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><figcaption class=\"wp-element-caption\">Thiago Barbosa de Lima<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>&#8220;Mesmo com todas as ferramentas e conte\u00fado dispon\u00edveis \u00e9 necess\u00e1rio um combust\u00edvel interno, n\u00e3o estude s\u00f3 para satisfazer as expectativas dos outros.&#8221;<\/strong><\/p>\n\n\n\n<p>Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para&nbsp;Auditor Federal De Finan\u00e7as e Controle na CGU:<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam conhec\u00ea-lo. Qual a sua forma\u00e7\u00e3o, idade e cidade natal? <\/strong><br \/><strong>Thiago Barbosa de Lima: <\/strong>Tenho 36 anos, sou formado em ci\u00eancias cont\u00e1beis e minha cidade natal \u00e9 o Rio de Janeiro.<br \/><br \/><strong>Estrat\u00e9gia: O que te levou a tomar a decis\u00e3o de come\u00e7ar a estudar para concursos?<\/strong><br \/><strong>Thiago: <\/strong>Desde 16 anos estudei para a carreira militar, aos 20 anos fui aprovado na Escola de Especialista da Aeron\u00e1utica &#8211; EEAR, sendo designado para cidade de Bras\u00edlia ap\u00f3s a forma\u00e7\u00e3o. Minha inten\u00e7\u00e3o era seguir a carreira, contudo em Bras\u00edlia descobri um novo horizonte, conhecendo pessoas aprovadas em diversos concursos com excelentes carreiras, o que me fez iniciar os estudos para concurso em janeiro de 2013.<br \/><br \/><strong>Estrat\u00e9gia: Voc\u00ea trabalhava e estudava? Se sim, como conciliava? <\/strong><br \/><strong>Thiago: <\/strong>Sim trabalhava, as horas de estudos eram conciliadas acordando mais cedo \u00e0s 05:00 da manh\u00e3, estudava at\u00e9 o in\u00edcio do trabalho e retornava ap\u00f3s. Tinha no m\u00ednimo 6 horas l\u00edquidas de estudo. Em janeiro de 2021 a log\u00edstica ficou um pouco mais complicada com o nascimento do primog\u00eanito, reduzi um pouco as horas de estudo para 4 horas e fui aumento aos poucos durante o ano.<br \/><br \/><strong>Estrat\u00e9gia: Em quais concursos j\u00e1 foi aprovado? <\/strong><br \/><strong>Thiago: <\/strong>Em 2006 fui aprovado em quarto lugar para o concurso da Escola de Especialista da Aeron\u00e1utica &#8211; COMAR VI. Em 2013 fui aprovado para t\u00e9cnico administrativo do Minist\u00e9rio Publicou da Uni\u00e3o, minha posi\u00e7\u00e3o foi 1060<em>, <\/em>sendo nomeado no fim da validade do certame, em que pedi desist\u00eancia. No meio de 2013, fui aprovado no concurso do Banco Central do Brasil, \u00c1rea II &#8211; Bras\u00edlia. Ficando em d\u00e9cimo segundo ap\u00f3s o curso de Forma\u00e7\u00e3o, em que tamb\u00e9m pedi desist\u00eancia. No fim de 2013, fui aprovado no concurso do Supremo Tribunal Federal, para t\u00e9cnico Judici\u00e1rio, \u00e1rea administrativa, na posi\u00e7\u00e3o 39, cargo em que ocupo hoje. Por fim, em 2022, fui aprovado no concurso Auditor Federal de Finan\u00e7as e Controle &#8211; AFFC, especializa\u00e7\u00e3o Auditoria e Fiscaliza\u00e7\u00e3o Bras\u00edlia, ficando na posi\u00e7\u00e3o 66* cadastro geral e quinto na quota para negros. N\u00e3o pretendo mais continuar estudando para concurso.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Como era sua vida social durante a prepara\u00e7\u00e3o para concursos? <\/strong><br \/><strong>Thiago: <\/strong>Durante a prepara\u00e7\u00e3o em per\u00edodos sem edital conseguia esporadicamente sair com a esposa aos domingos no fim do dia para algum restaurante.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Sua fam\u00edlia e amigos entenderam e apoiaram sua caminhada como concurseiro? De que forma?<\/strong><br \/><strong>Thiago: <\/strong>Sou casado com a Priscilla, temos um filho, Thomas de 1 ano e 5 meses. Minha fam\u00edlia sempre me apoio em meus objetivos, minha esposa \u00e9 uma pessoa especial, um dos grandes motivos para o alcance de meus objetivos sendo uma verdadeira base, sem ela n\u00e3o conseguiria. Quanto aos amigos sempre obtive apoio e ora\u00e7\u00f5es para minha luta, confiavam mais em mim do que eu.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Voc\u00ea estudou por quanto tempo direcionado ao \u00faltimo concurso? O que fez para manter a disciplina?<\/strong><br \/><strong>Thiago: <\/strong>Em novembro de 2018 retornei aos estudos com aux\u00edlio do coach F\u00e1bio Telles do Estrat\u00e9gia, meu foco inicial era o concurso da Receita Federal, em janeiro de 2020 mudei o foco para \u00e1rea de controle incentivados por amigos aprovados na \u00e1rea. Com o in\u00edcio da pandemia os concursos ficaram dif\u00edceis, contudo o apoio do F\u00e1bio foi essencial em manter a disciplina e o foco, al\u00e9m de um bom planejamento de estudos. Como j\u00e1 disse ao pr\u00f3prio F\u00e1bio, nos tornamos amigos durante essa jornada, sem seu incentivo e orienta\u00e7\u00e3o o caminho seria mais \u00e1rduo.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Quais materiais e ferramentas voc\u00ea usou em sua prepara\u00e7\u00e3o?<\/strong><br \/><strong>Thiago: <\/strong>As ferramentas utilizadas foram os PDFs do Estrat\u00e9gia, mapas mentais, algumas v\u00eddeos aulas de mat\u00e9ria espec\u00edficas como Contabilidade P\u00fablica, os \u00e1udios do aplicativo do estrat\u00e9gia, muito exerc\u00edcios. Al\u00e9m disso, fiz os simulados para CGU todos os domingos. Na reta final de prepara\u00e7\u00e3o assisti muitas aulas de revis\u00f5es do estrat\u00e9gia no YouTube, o foi important\u00edssimo principalmente nas jurisprud\u00eancias de Direito Constitucional e Administrativo. <br \/><br \/><strong>Estrat\u00e9gia: Como conheceu o Estrat\u00e9gia Concursos?<\/strong><br \/><strong>Thiago: <\/strong>Por meio de sites na internet e indica\u00e7\u00e3o de amigos.<br \/><br \/><strong>Estrat\u00e9gia: Antes de conhecer o Estrat\u00e9gia, voc\u00ea chegou a usar materiais de outros cursos?<\/strong><br \/><strong>Thiago: <\/strong>Nos concursos de 2013 utilizei ponto dos concursos.<br \/><br \/><strong>Estrat\u00e9gia: Voc\u00ea chegou a fazer algum concurso enquanto ainda se preparava com esse outro material? Foi aprovado? <\/strong><br \/><strong>Thiago: <\/strong>Sim, fui aprovado no MPU.<br \/><br \/><strong>Estrat\u00e9gia: Depois que voc\u00ea se tornou aluno do Estrat\u00e9gia, voc\u00ea sentiu uma diferen\u00e7a relevante na sua prepara\u00e7\u00e3o? Que diferencial encontrou nos materiais do Estrat\u00e9gia? <\/strong><br \/><strong>Thiago: <\/strong>Acredito que os conte\u00fados est\u00e3o muito mais detalhados, acho interessante os mapas mentais pois torna as revis\u00f5es mais r\u00e1pidas. Al\u00e9m disso as revis\u00f5es no YouTube s\u00e3o um diferencial.<br \/><br \/><strong>Estrat\u00e9gia: Como montou seu plano de estudos? <\/strong><br \/><strong>Thiago: <\/strong>Meu plano foi montado pelo coach Fabio Telles, com as mat\u00e9rias previstas no edital, com no m\u00ednimo 6 horas l\u00edquidas por dia.<br \/><br \/><strong>Estrat\u00e9gia: Como fazia suas revis\u00f5es? <\/strong><br \/><strong>Thiago: <\/strong>As revis\u00f5es eram programadas no come\u00e7o com 24h, 72h, uma semana e um m\u00eas. Pr\u00f3ximos ao concurso foram feitas as de 72h.<\/p>\n\n\n\n<p><strong>Estrat\u00e9gia: Qual a import\u00e2ncia da resolu\u00e7\u00e3o de exerc\u00edcios? Lembra quantas quest\u00f5es fez na sua trajet\u00f3ria?<\/strong><br \/><strong>Thiago: <\/strong>A resolu\u00e7\u00e3o de exerc\u00edcios \u00e9 um m\u00e9todo mais eficaz nos estudos, \u00e9 o que faz a mudan\u00e7a de n\u00edvel de aprendizado. Fiz tantos que n\u00e3o tenho ideia.<br \/><br \/><strong>Estrat\u00e9gia: Quais as disciplinas voc\u00ea tinha mais dificuldade? Como fez para superar?<\/strong><br \/><strong>Thiago: <\/strong>No \u00faltimo concurso tive dificuldade em ingl\u00eas e Avalia\u00e7\u00e3o de Pol\u00edticas P\u00fablicas. Em outros concursos na mat\u00e9ria TI. Para superar em ingl\u00eas foquei em vocabul\u00e1rio, em Avalia\u00e7\u00e3o de Pol\u00edticas P\u00fablicas pratiquei mais exerc\u00edcios.<br \/><br \/><strong>Estrat\u00e9gia: Como foi sua rotina de estudos na semana que antecedeu a prova e no dia pr\u00e9-prova?<\/strong><br \/><strong>Thiago: <\/strong>Tentei revisar o m\u00e1ximo que pude, assisti as revis\u00f5es do estrat\u00e9gia no YouTube. No dia anterior a prova fui na revis\u00e3o de v\u00e9spera do estrat\u00e9gia presencialmente e preparei uma estrat\u00e9gia de prova com o F\u00e1bio.<br \/><br \/><strong>Estrat\u00e9gia: No seu concurso, al\u00e9m da prova objetiva, teve a discursiva. Como foi sua prepara\u00e7\u00e3o para esta importante parte do certame? <\/strong><br \/><strong>Thiago: <\/strong>Sim, me preparei pelo curso <em>voc\u00eaconcursado<\/em> fazendo uma reda\u00e7\u00e3o por domingo. N\u00e3o se pode abrir m\u00e3o de um bom preparado para reda\u00e7\u00e3o, nos \u00faltimos concursos, define quem estar\u00e1 nas vagas.<br \/><br \/><strong>Estrat\u00e9gia: Quais foram seus principais ERROS e ACERTOS nesta trajet\u00f3ria?<\/strong><br \/><strong>Thiago: <\/strong>Acredito que o principal acerto foi contar com apoio do coach F\u00e1bio Telles, acredito que n\u00e3o teria mantido os estudos por esse tempo sem ele. Erro n\u00e3o identifico agora.<br \/><br \/><strong>Estrat\u00e9gia: Chegou a pensar, por algum momento, em desistir? Se sim, qual foi sua principal motiva\u00e7\u00e3o para seguir?<\/strong><br \/><strong>Thiago: <\/strong>Sim, principalmente quando o filho nasceu, para dar maior aten\u00e7\u00e3o a ele. Quanto a principal motiva\u00e7\u00e3o, pensar que quanto mais r\u00e1pido eu conseguisse meu objetivo, eu poderia dar toda a aten\u00e7\u00e3o para ele, focando em sua educa\u00e7\u00e3o.<br \/><br \/><strong>Estrat\u00e9gia: Por fim, o que voc\u00ea aconselharia a algu\u00e9m que est\u00e1 iniciando seus estudos para concurso? Deixe sua mensagem para todos aqueles que um dia almejam chegar aonde voc\u00ea chegou!<\/strong><br \/><strong>Thiago: <\/strong>Mesmo com todas as ferramentas e conte\u00fado dispon\u00edveis \u00e9 necess\u00e1rio um \u201ccombust\u00edvel interno\u201d, n\u00e3o estude s\u00f3 para satisfazer as expectativas dos outros. Meus pais me ensinaram que o estudo est\u00e1 acess\u00edvel a todos, independente da dificuldade, \u00e9 uma forma honesta e justa de melhorar de vida, em que voc\u00ea s\u00f3 depende de si. Por fim, tenha f\u00e9, fa\u00e7a sua parte que Deus o ajudar\u00e1.<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Mesmo com todas as ferramentas e conte\u00fado dispon\u00edveis \u00e9 necess\u00e1rio um combust\u00edvel interno, n\u00e3o estude s\u00f3 para satisfazer as expectativas dos outros.&#8221; Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para&nbsp;Auditor Federal De Finan\u00e7as e Controle na CGU: Estrat\u00e9gia Concursos: Conte-nos um pouco sobre voc\u00ea, para que nossos leitores possam [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-1048975","depoimento","type-depoimento","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ENTREVISTA: Thiago Lima - Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU<\/title>\n<meta name=\"description\" content=\"Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTREVISTA: Thiago Lima - Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU\" \/>\n<meta property=\"og:description\" content=\"Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T18:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/image_50394625-1024x814.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/\",\"name\":\"ENTREVISTA: Thiago Lima - Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/image_50394625-1024x814.jpg\",\"datePublished\":\"2022-06-23T15:06:46+00:00\",\"dateModified\":\"2023-05-22T18:43:22+00:00\",\"description\":\"Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-scaled.jpg\",\"width\":2560,\"height\":2034},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTREVISTA: Thiago Lima &#8211; Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ENTREVISTA: Thiago Lima - Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU","description":"Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/","og_locale":"pt_BR","og_type":"article","og_title":"ENTREVISTA: Thiago Lima - Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU","og_description":"Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/","og_site_name":"Estrat\u00e9gia Concursos","article_modified_time":"2023-05-22T18:43:22+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/image_50394625-1024x814.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@EstratConcursos","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/","name":"ENTREVISTA: Thiago Lima - Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2022\/06\/image_50394625-1024x814.jpg","datePublished":"2022-06-23T15:06:46+00:00","dateModified":"2023-05-22T18:43:22+00:00","description":"Confira nossa entrevista com Thiago Barbosa de Lima aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/23105831\/image_50394625-scaled.jpg","width":2560,"height":2034},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/concurso-cgu-aprovado-thiago-barbosa-de-lima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ENTREVISTA: Thiago Lima &#8211; Aprovado em 5\u00ba lugar (cotas) para\u00a0Auditor Federal De Finan\u00e7as e Controle na CGU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1048975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/depoimento"}],"version-history":[{"count":9,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1048975\/revisions"}],"predecessor-version":[{"id":1220083,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/depoimento\/1048975\/revisions\/1220083"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1048975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}